{"id":9243,"date":"2017-03-08T12:42:24","date_gmt":"2017-03-08T12:42:24","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=9243"},"modified":"2020-06-29T18:34:58","modified_gmt":"2020-06-29T18:34:58","slug":"fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/","title":{"rendered":"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Con una oferta de 9457 cabezas, hubo mejoras de hasta 1,50 pesos por kilo.<\/p>\n<p class=\"primero\">Pese al aumento de la oferta, que trep\u00f3 de 2419 a 9457 vacunos, el firme inter\u00e9s de los compradores posibilit\u00f3 la suba de los precios de todas las categor\u00edas y clasificaciones expuestas ayer en el Mercado de Liniers. Al cierre de los negocios, las mejoras quedaron en un rango de 40 centavos a 1,50 pesos por kilo.<\/p>\n<p>Dentro de la t\u00f3nica positiva, el \u00cdndice Novillo registr\u00f3 un alza del 1,36% respecto del viernes, al pasar de 29,140 a 29,535 pesos por kilo. Esta categor\u00eda, que ayer represent\u00f3 el 13,23% de la oferta total con 1247 cabezas, logr\u00f3 un m\u00e1ximo de $ 33 para dos lotes con 447 y con 453 kilos de promedio. Se destacaron, asimismo, los $ 32 asignados a 7 lotes de 442 a 483 kilos y los $ 31,50 pagados por 10 conjuntos de 435 a 511 kilos.<\/p>\n<figure class=\"S encolumnada\">\n<div class=\"conModal f-imagenRelacionada\" data-notaid=\"1990959\" data-imagenid=\"2293438\" data-tipo=\"imagen\" data-extension=\"jpg\" data-esrelacionada=\"0\"><img decoding=\"async\" id=\"imagen_2293438\" class=\"f-sinGif\" src=\"http:\/\/bucket3.glanacion.com\/anexos\/fotos\/38\/campo-2293438w280.jpg\" alt=\"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers\" data-imagenid=\"2293438\" \/><\/div><figcaption id=\"epigrafe2293438\"><strong>Fuerte aumento de los precio de la hacienda en el Mercado de Liniers. Foto: Archivo \/ Ricardo Pristupluk<\/strong><\/figcaption><\/figure>\n<aside class=\"banner caja2\" data-adpos=\"caja2\">\n<div id=\"eplAdDivcaja2\">Los mejores valores de la rueda para las haciendas livianas fueron: en terneros, $ 35,60 con 310 kilos; en terneras, $ 35 con 300 kilos; en novillitos, $ 36 con 352 kilos, y en vaquillonas, $ 33,60 con 353 y con 375 kilos.<\/div>\n<\/aside>\n<p>El \u00cdndice General del Mercado de Liniers fue de $ 27,324 y el peso promedio general, de 408 kilos. El \u00cdndice Novillo del Mercado de Liniers qued\u00f3 en $ 29,535 y el valor promedio general de Mercados al D\u00eda fue de $ 29,507. Detalle: novillos 1247; novillitos 2792; vaquillonas 1040; vacas 1148; conservas 1036; terneros 2007, y toros 155. Base 27 cabezas.<\/p>\n<aside class=\"banner caja3\" data-adpos=\"caja3\">\n<div id=\"eplAdDivcaja3\"><b>\u00c1lzaga Unzu\u00e9 y C\u00eda. SA: <\/b>(349) San Carlos t. 84, 301 a 33; 52, 319 a 33; 34, 306 a 34. <b>Blanco Daniel y C\u00eda. SA:<\/b> (540) El Avestruz v. 28, 371 a 14,50; Marinovic t. 31, 316 a 34. <b>Colombo y Colombo SA: <\/b>(90) La Cautiva n. 39, 453 a 31. <b>Colombo y Magliano SA:<\/b> (664) Adm. Duhau nt. 43, 377 a 34,50; Agba n. 35, 435 a 30; Campo Grand t. 44, 338 a 34,30; Clovis Argentina nt. 45, 430 a 32,40; La Alameda Agrop. nt. 32, 369 a 34; t. 34, 300 a 33,30; Lovizio t. 48, 343 a 34; Vitali nt. 45, 401 a 32,80. <b>Consignataria Blanes: <\/b>(40) Opargen nt. 40, 399 a 32,50. <b>Crespo y Rodr\u00edguez:<\/b> (90) Drabble nt. 34, 396 a 33; 34, 359 a 34.<\/div>\n<\/aside>\n<p><b>Da-Nes SRL:<\/b> (141) Da-Nes nt. 30, 363 a 34; t. 33, 333 a 35. <b>Dotras, Ganly SRL: <\/b>(230) Agromarket v. 31, 464 a 18; Salvadori vq. 37, 351 a 32,50; Santa Rosa del Monte nt. 40, 408 a 33. <b>Ganadera Salliquel\u00f3 SA: <\/b>(91) Alerose v. 44, 444 a 26; Herrero nt. 31, 369 a 29. <b>Gogorza y C\u00eda. SRL:<\/b> (454) Balb\u00edn t. 31, 333 a 28; Elortegui t. 28, 337 a 33; Mart\u00ednez n. 120, 462 a 29; Oberti n. 36, 461 a 32; Suc. Arbelbide vq. 44, 372 a 32; Taverna y Maggliolo nt. 27, 369 a 32; Zavala nt. 35, 382 a 29. <b>Harrington y Lafuente SA: <\/b>(271) Etchegaray t. 43, 325 a 28. <b>Iriarte Villanueva Enrique SA: <\/b>(156) Aseguinolaza n. 32, 483 a 32; t. 56, 333 a 34. <b>J\u00e1uregui Lorda SRL: <\/b>(234) Mi Recuerdo nt. 31, 382 a 34; Ruca nt. 32, 399 a 33,80. <b>Lartirigoyen <\/b><b>&amp; Orom\u00ed SA:<\/b> (204) Opargen nt. 40, 391 a 32,50. <b>Llorente-Dura\u00f1ona SA: <\/b>(63) Don Tom\u00e1s nt. 39, 381 a 34.<\/p>\n<aside class=\"banner caja4\" data-adpos=\"caja4\">\n<div id=\"eplAdDivcaja4\"><b>Madelan SA:<\/b> (578) contado, Agrop. Patagonia de Sur nt. 40, 383 a 34,20. <b>Mart\u00edn G. Lalor SA: <\/b>(373) Adm. Duhau nt. 31, 408 a 33,40; 31, 392 a 34; Armentia nt. 40, 426 a 32,50; Niemela nt. 50, 392 a 33; Suc. Romero nt. 42, 421 a 32,50. <b>Mendiz\u00e1bal A. J. y C\u00eda. SA:<\/b> (544) La Mary de Ferreiro nt. 44, 416 a 32,50; Sacagam t. 42, 327 a 34,60. <b>Monasterio Tattersall SA:<\/b> (1131) Adm. Duhau nt. 42, 399 a 33; 42, 365 a 33,60; Agrop. San Diego nt. 43, 430 a 27; Disalvo n. 27, 576 a 29,10; Lahore nt. 35, 390 a 32; Mart\u00ednez t. 33, 301 a 31,14.<\/div>\n<\/aside>\n<p><b>Pedro Genta y C\u00eda. SA: <\/b>(241) pago en el d\u00eda, La Maruja v. 35, 375 a 22; Sausalito Explot. Rurales v. 35, 380 a 14; Tunex nt. 39, 421 a 32,20. <b>Pujol Benito y C\u00eda. SA: <\/b>(79) Dasso t. 34, 326 a 29. <b>S\u00e1enz Valiente, Bullrich y C\u00eda. SA: <\/b>(809) Adm. Duhau nt. 39, 370 a 33,50; Est. La Dorita n. 28, 355 a 32,20; Est. La Llovizna nt. 40, 380 a 33,70; La Cubana nt. 29, 366 a 33,70; La Solita v. 34, 433 a 25; Los Altos de Media Loma t. 30, 346 a 33; Monvale n. 28, 511 a 31,50; Nuevas Chacras v. 33, 391 a 13,50; Tapalgro vq. 43, 379 a 33. <b>Wallace Hermanos SA: <\/b>(509) Berra nt. 27, 375 a 32,30; Valencia vq. 28, 390 a 24. <b>Otras consignaciones:<\/b> Aguirre Urreta Jorge SA (80); Asoc. de Coop. Argentinas (17); Balcarce y C\u00eda. SRL (34); Brandemann Consignataria SRL<b><\/b>(124); Campos y Ganados SA (205); Casa Massola SA (31); Casa Usandizaga SA (55); Consignataria Melicur\u00e1 SA (219); Elissondo Ignacio Hijos de SRL (37); Ferias Agroazul SA (36); Gahan y C\u00eda. SA (135); Hourcade Albelo y C\u00eda. SA (45); Lalor SA (175); Lanusse-Santill\u00e1n y C\u00eda. SA (13); Ledesma y Arana SRL (151); Nieva H. y Asoc. SRL (38); O&#8217;Farrell Iv\u00e1n L. SRL (23); Pryor SA (42); Santamarina e Hijos SA (96).<\/p>\n<p><strong>Fuente: La Naci\u00f3n<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Con una oferta de 9457 cabezas, hubo mejoras de hasta 1,50 pesos por kilo. Pese al aumento de la oferta, que trep\u00f3 de 2419 a 9457 vacunos, el firme inter\u00e9s de los compradores posibilit\u00f3 la suba de los precios de todas las categor\u00edas y clasificaciones expuestas ayer en el Mercado de Liniers. Al cierre de los negocios, las mejoras quedaron en un rango de 40 centavos a 1,50 pesos por kilo. Dentro de la t\u00f3nica positiva, el \u00cdndice Novillo registr\u00f3 un alza del 1,36% respecto del viernes, al pasar de 29,140 a 29,535 pesos por kilo. Esta categor\u00eda, que ayer represent\u00f3 el 13,23% de la oferta total con 1247 cabezas, logr\u00f3 un m\u00e1ximo de $ 33 para dos lotes con 447 y con 453 kilos de promedio. Se destacaron, asimismo, los $ 32 asignados a 7 lotes de 442 a 483 kilos y los $ 31,50 pagados por 10 conjuntos de 435 a 511 kilos. Fuerte aumento de los precio de la hacienda en el Mercado de Liniers. Foto: Archivo \/ Ricardo Pristupluk Los mejores valores de la rueda para las haciendas livianas fueron: en terneros, $ 35,60 con 310 kilos; en terneras, $ 35 con 300 kilos; en novillitos, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9244,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-9243","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fuerte aumento de los precio de la hacienda en el Mercado de Liniers | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers | Proagro\" \/>\n<meta property=\"og:description\" content=\"Con una oferta de 9457 cabezas, hubo mejoras de hasta 1,50 pesos por kilo. Pese al aumento de la oferta, que trep\u00f3 de 2419 a 9457 vacunos, el firme inter\u00e9s de los compradores posibilit\u00f3 la suba de los precios de todas las categor\u00edas y clasificaciones expuestas ayer en el Mercado de Liniers. Al cierre de los negocios, las mejoras quedaron en un rango de 40 centavos a 1,50 pesos por kilo. Dentro de la t\u00f3nica positiva, el \u00cdndice Novillo registr\u00f3 un alza del 1,36% respecto del viernes, al pasar de 29,140 a 29,535 pesos por kilo. Esta categor\u00eda, que ayer represent\u00f3 el 13,23% de la oferta total con 1247 cabezas, logr\u00f3 un m\u00e1ximo de $ 33 para dos lotes con 447 y con 453 kilos de promedio. Se destacaron, asimismo, los $ 32 asignados a 7 lotes de 442 a 483 kilos y los $ 31,50 pagados por 10 conjuntos de 435 a 511 kilos. Fuerte aumento de los precio de la hacienda en el Mercado de Liniers. Foto: Archivo \/ Ricardo Pristupluk Los mejores valores de la rueda para las haciendas livianas fueron: en terneros, $ 35,60 con 310 kilos; en terneras, $ 35 con 300 kilos; en novillitos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-08T12:42:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T18:34:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/03\/svb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1632\" \/>\n\t<meta property=\"og:image:height\" content=\"1224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers\",\"datePublished\":\"2017-03-08T12:42:24+00:00\",\"dateModified\":\"2020-06-29T18:34:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/\"},\"wordCount\":667,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/svb.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/\",\"name\":\"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/svb.jpg\",\"datePublished\":\"2017-03-08T12:42:24+00:00\",\"dateModified\":\"2020-06-29T18:34:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/svb.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/svb.jpg\",\"width\":1632,\"height\":1224},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/","og_locale":"en_US","og_type":"article","og_title":"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers | Proagro","og_description":"Con una oferta de 9457 cabezas, hubo mejoras de hasta 1,50 pesos por kilo. Pese al aumento de la oferta, que trep\u00f3 de 2419 a 9457 vacunos, el firme inter\u00e9s de los compradores posibilit\u00f3 la suba de los precios de todas las categor\u00edas y clasificaciones expuestas ayer en el Mercado de Liniers. Al cierre de los negocios, las mejoras quedaron en un rango de 40 centavos a 1,50 pesos por kilo. Dentro de la t\u00f3nica positiva, el \u00cdndice Novillo registr\u00f3 un alza del 1,36% respecto del viernes, al pasar de 29,140 a 29,535 pesos por kilo. Esta categor\u00eda, que ayer represent\u00f3 el 13,23% de la oferta total con 1247 cabezas, logr\u00f3 un m\u00e1ximo de $ 33 para dos lotes con 447 y con 453 kilos de promedio. Se destacaron, asimismo, los $ 32 asignados a 7 lotes de 442 a 483 kilos y los $ 31,50 pagados por 10 conjuntos de 435 a 511 kilos. Fuerte aumento de los precio de la hacienda en el Mercado de Liniers. Foto: Archivo \/ Ricardo Pristupluk Los mejores valores de la rueda para las haciendas livianas fueron: en terneros, $ 35,60 con 310 kilos; en terneras, $ 35 con 300 kilos; en novillitos, [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2017-03-08T12:42:24+00:00","article_modified_time":"2020-06-29T18:34:58+00:00","og_image":[{"width":1632,"height":1224,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/03\/svb.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers","datePublished":"2017-03-08T12:42:24+00:00","dateModified":"2020-06-29T18:34:58+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/"},"wordCount":667,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/03\/svb.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/","url":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/","name":"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/03\/svb.jpg","datePublished":"2017-03-08T12:42:24+00:00","dateModified":"2020-06-29T18:34:58+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/03\/svb.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/03\/svb.jpg","width":1632,"height":1224},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/fuerte-aumento-de-los-precio-de-la-hacienda-en-el-mercado-de-liniers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Fuerte aumento de los precio de la hacienda en el Mercado de Liniers"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=9243"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9243\/revisions"}],"predecessor-version":[{"id":13814,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9243\/revisions\/13814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/9244"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=9243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=9243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=9243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}