{"id":9135,"date":"2017-02-03T11:53:38","date_gmt":"2017-02-03T11:53:38","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=9135"},"modified":"2017-02-03T11:53:38","modified_gmt":"2017-02-03T11:53:38","slug":"subastas-especiales-en-el-mercado-de-liniers","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/subastas-especiales-en-el-mercado-de-liniers\/","title":{"rendered":"Subastas especiales en el Mercado de Liniers"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Para la cuarta rueda de negocios de la semana ingresaron ayer en el Mercado de Liniers 420 cabezas, que fueron remitidas para dos subastas especiales. En primer t\u00e9rmino, la firma \u00c1lzaga Unzu\u00e9 y C\u00eda. SA comercializ\u00f3 388 vacunos en su remate exclusivo de la raza Angus y sus cruzas y, luego, la consignataria Colombo y Magliano SA vendi\u00f3 82 animales en su remate exclusivo de haciendas de feedlot.<\/p>\n<p>Con lotes que en general reunieron buena calidad racial y terminaci\u00f3n homog\u00e9nea, las ventas se concertaron con tr\u00e1mite \u00e1gil, en tanto que los precios se mantuvieron dentro de los niveles obtenidos en la rueda del mi\u00e9rcoles.<\/p>\n<p>Entre los mejores valores asignados a las haciendas livianas se destacaron los siguientes: en terneros, $ 32 con 3241kg y $ 31,50 con 349 kg; en terneras, $ 31,50 con 312 kg y $ 30 con 342 kg; en novillitos, $ 31 con 379 kg y $ 30,50 con 368 kg, y en vaquillonas, $ 30 con 357 kg y $ 24,50 con 400 kg.<\/p>\n<p>Los novillos, con s\u00f3lo 57 cabezas, se colocaron hasta un m\u00e1ximo de $ 30 para un lote con 435 kg. Le siguieron, $ 29,30 con 459 kg y $ 28,20 con 449 kg. Por las mejores vacas se pago $ 23 con 445 kg y $ 22,30 con 483 kilos.<\/p>\n<p>El \u00cdndice General de Mercado de Liniers SA fue de $ 26,566, mientras que el peso promedio general result\u00f3 de 401 kilos. Detalle de venta: novillos 57; novillitos 44; vaquillonas 81, y vacas 1257. Base 1 cabeza.<\/p>\n<p><strong>\u00c1lzaga Unzu\u00e9 y C\u00eda. SA:<\/strong> (338) Anchorena v. 24, 445 kg a $ 23; vq. 10, 408 a 24; F. G\u00f3mez v. 10, 458 a 20; 15, 411 a 21,40; 43, 446 a 22,70; vq. 9, 360 a 25; Nissin n. 2, 520 a 25; 3, 473 a 28; 6, 458 a 29,30; t. 7, 350 a 27; 7, 330 a 28; v. 1, 500 a 20; 10, 483 a 22,30; Santa Yvonne nt. 26, 368 a 30,50; t. 15, 349 a 31,50; 19, 341 a 32; Sim\u00f3n v. 2, 555 a 16; 14, 466 a 20,30; 12, 533 a 22,10; 8, 476 a 22,40; Vaca Pampa n. 1, 530 a 26; 21, 435 a 30; nt. 18, 379 a 31; t. 17, 342 a 30; vq. 37, 357 a 30.<\/p>\n<p><strong>Colombo y Magliano SA:<\/strong> (82) Estancia El Alba t. 47, 312 kg a $ 31,50; Ruta Nueva n. 2, 600 a 24; 22, 449 a 28,20; v. 1, 460 a 17; vq. 10, 400 a 24,50.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.lanacion.com.ar\/1981442-subastas-especiales-en-el-mercado-de-liniers\" target=\"_blank\">La Naci\u00f3n<\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Para la cuarta rueda de negocios de la semana ingresaron ayer en el Mercado de Liniers 420 cabezas, que fueron remitidas para dos subastas especiales. En primer t\u00e9rmino, la firma \u00c1lzaga Unzu\u00e9 y C\u00eda. SA comercializ\u00f3 388 vacunos en su remate exclusivo de la raza Angus y sus cruzas y, luego, la consignataria Colombo y Magliano SA vendi\u00f3 82 animales en su remate exclusivo de haciendas de feedlot. Con lotes que en general reunieron buena calidad racial y terminaci\u00f3n homog\u00e9nea, las ventas se concertaron con tr\u00e1mite \u00e1gil, en tanto que los precios se mantuvieron dentro de los niveles obtenidos en la rueda del mi\u00e9rcoles. Entre los mejores valores asignados a las haciendas livianas se destacaron los siguientes: en terneros, $ 32 con 3241kg y $ 31,50 con 349 kg; en terneras, $ 31,50 con 312 kg y $ 30 con 342 kg; en novillitos, $ 31 con 379 kg y $ 30,50 con 368 kg, y en vaquillonas, $ 30 con 357 kg y $ 24,50 con 400 kg. Los novillos, con s\u00f3lo 57 cabezas, se colocaron hasta un m\u00e1ximo de $ 30 para un lote con 435 kg. Le siguieron, $ 29,30 con 459 kg y $ 28,20 con [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9136,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-9135","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Subastas especiales en el Mercado de Liniers | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/subastas-especiales-en-el-mercado-de-liniers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subastas especiales en el Mercado de Liniers | Proagro\" \/>\n<meta property=\"og:description\" content=\"Para la cuarta rueda de negocios de la semana ingresaron ayer en el Mercado de Liniers 420 cabezas, que fueron remitidas para dos subastas especiales. En primer t\u00e9rmino, la firma \u00c1lzaga Unzu\u00e9 y C\u00eda. SA comercializ\u00f3 388 vacunos en su remate exclusivo de la raza Angus y sus cruzas y, luego, la consignataria Colombo y Magliano SA vendi\u00f3 82 animales en su remate exclusivo de haciendas de feedlot. Con lotes que en general reunieron buena calidad racial y terminaci\u00f3n homog\u00e9nea, las ventas se concertaron con tr\u00e1mite \u00e1gil, en tanto que los precios se mantuvieron dentro de los niveles obtenidos en la rueda del mi\u00e9rcoles. Entre los mejores valores asignados a las haciendas livianas se destacaron los siguientes: en terneros, $ 32 con 3241kg y $ 31,50 con 349 kg; en terneras, $ 31,50 con 312 kg y $ 30 con 342 kg; en novillitos, $ 31 con 379 kg y $ 30,50 con 368 kg, y en vaquillonas, $ 30 con 357 kg y $ 24,50 con 400 kg. Los novillos, con s\u00f3lo 57 cabezas, se colocaron hasta un m\u00e1ximo de $ 30 para un lote con 435 kg. Le siguieron, $ 29,30 con 459 kg y $ 28,20 con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-03T11:53:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/02\/03022017-1145x395.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Subastas especiales en el Mercado de Liniers\",\"datePublished\":\"2017-02-03T11:53:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/\"},\"wordCount\":303,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/03022017-1145x395.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/\",\"name\":\"Subastas especiales en el Mercado de Liniers | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/03022017-1145x395.jpg\",\"datePublished\":\"2017-02-03T11:53:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/03022017-1145x395.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/03022017-1145x395.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/subastas-especiales-en-el-mercado-de-liniers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Subastas especiales en el Mercado de Liniers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subastas especiales en el Mercado de Liniers | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/subastas-especiales-en-el-mercado-de-liniers\/","og_locale":"en_US","og_type":"article","og_title":"Subastas especiales en el Mercado de Liniers | Proagro","og_description":"Para la cuarta rueda de negocios de la semana ingresaron ayer en el Mercado de Liniers 420 cabezas, que fueron remitidas para dos subastas especiales. En primer t\u00e9rmino, la firma \u00c1lzaga Unzu\u00e9 y C\u00eda. SA comercializ\u00f3 388 vacunos en su remate exclusivo de la raza Angus y sus cruzas y, luego, la consignataria Colombo y Magliano SA vendi\u00f3 82 animales en su remate exclusivo de haciendas de feedlot. Con lotes que en general reunieron buena calidad racial y terminaci\u00f3n homog\u00e9nea, las ventas se concertaron con tr\u00e1mite \u00e1gil, en tanto que los precios se mantuvieron dentro de los niveles obtenidos en la rueda del mi\u00e9rcoles. Entre los mejores valores asignados a las haciendas livianas se destacaron los siguientes: en terneros, $ 32 con 3241kg y $ 31,50 con 349 kg; en terneras, $ 31,50 con 312 kg y $ 30 con 342 kg; en novillitos, $ 31 con 379 kg y $ 30,50 con 368 kg, y en vaquillonas, $ 30 con 357 kg y $ 24,50 con 400 kg. Los novillos, con s\u00f3lo 57 cabezas, se colocaron hasta un m\u00e1ximo de $ 30 para un lote con 435 kg. Le siguieron, $ 29,30 con 459 kg y $ 28,20 con [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2017-02-03T11:53:38+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/02\/03022017-1145x395.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Subastas especiales en el Mercado de Liniers","datePublished":"2017-02-03T11:53:38+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/"},"wordCount":303,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/02\/03022017-1145x395.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/","url":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/","name":"Subastas especiales en el Mercado de Liniers | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/02\/03022017-1145x395.jpg","datePublished":"2017-02-03T11:53:38+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/02\/03022017-1145x395.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/02\/03022017-1145x395.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/subastas-especiales-en-el-mercado-de-liniers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Subastas especiales en el Mercado de Liniers"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=9135"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/9136"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=9135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=9135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=9135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}