{"id":9111,"date":"2017-01-31T18:20:07","date_gmt":"2017-01-31T18:20:07","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=9111"},"modified":"2020-06-29T19:03:44","modified_gmt":"2020-06-29T19:03:44","slug":"una-nueva-oportunidad","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/una-nueva-oportunidad\/","title":{"rendered":"Una nueva oportunidad"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p><em>El comercio mundial de carnes retomar\u00eda en 2017 los vol\u00famenes previos a la crisis de 2014, con precios firmes, si no se ve afectado por nuevos proteccionismos.<\/em><\/p>\n<div class=\"author maincolor mainfont\"><em><span class=\"authortitle\">Por: Miguel Gorelik<\/span><\/em><\/div>\n<div class=\"datetime maincolor mainfont\">\u00a0<\/div>\n<div class=\"datetime maincolor mainfont\">En el segundo semestre de 2016 hubo un repunte de las exportaciones de carnes de los seis pa\u00edses l\u00edderes, que representan el 75% del mercado internacional, saliendo as\u00ed del baj\u00f3n registrado durante el a\u00f1o y medio previo.<\/div>\n<p>Lo m\u00e1s destacado es que <strong>esta mejora se pudo lograr a pesar de la fuerte retracci\u00f3n de las exportaciones australianas y la debilidad de la oferta de Brasil<\/strong>. As\u00ed las cosas, la recuperaci\u00f3n qued\u00f3 en manos de EE.UU., la India y Uruguay.<\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/5890afcc08c5c_626_4341.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9112 alignnone\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/5890afcc08c5c_626_4341-300x208.jpg\" alt=\"5890afcc08c5c_626_434![1]\" width=\"300\" height=\"208\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/5890afcc08c5c_626_4341-300x208.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/5890afcc08c5c_626_4341-600x416.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/5890afcc08c5c_626_4341.jpg 626w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Ampliando la mirada, si se toma todo el \u00faltimo a\u00f1o y se lo compara con el previo, se ve que mientras Australia redujo sus ventas 20%, Brasil y la India las mantuvieron y Paraguay, EE.UU. y Uruguay las incrementaron entre 2 y 11%.<\/p>\n<p>De esta forma, 2016 cerr\u00f3 con una baja de s\u00f3lo 4% en relaci\u00f3n a 2015, aunque con tendencia creciente. M\u00e1s a\u00fan, los vol\u00famenes embarcados en el \u00faltimo semestre fueron alcanzando el promedio de los \u00faltimos dos a\u00f1os. En tanto, los precios tambi\u00e9n se recobraron- a pesar de la baja de los de EE.UU.- pero a\u00fan muestran un cierto rezago con respecto al promedio del trienio.<br \/><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/5890afeb7eb15_626_4341.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9113 alignnone\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/5890afeb7eb15_626_4341-300x208.jpg\" alt=\"5890afeb7eb15_626_434![1]\" width=\"300\" height=\"208\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/5890afeb7eb15_626_4341-300x208.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/5890afeb7eb15_626_4341-600x416.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/5890afeb7eb15_626_4341.jpg 626w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Cabe aclarar que los pa\u00edses que se miden para hacer este an\u00e1lisis son la India, Brasil, Australia, Estados Unidos, Paraguay y Uruguay. Para completar el cuadro con los ocho l\u00edderes est\u00e1n faltando los datos de Canad\u00e1 y Nueva Zelandia, que exportan algo m\u00e1s que Paraguay y Uruguay, pero cuyas estad\u00edsticas no est\u00e1n disponibles con tanta inmediatez.<\/p>\n<p><strong>A 2017<\/strong><\/p>\n<p>De este an\u00e1lisis global, se desprenden dos conclusiones importantes. El mercado mundial de carnes tiene posibilidades de retomar niveles de comercio y precios que no se ve\u00edan desde antes de la crisis financiera y de materias primas de 2014, siempre y cuando fen\u00f3menos como el reciente proteccionismo de Estados Unidos y el Brexit no generen disrupciones importantes en los flujos internacionales.<\/p>\n<p>Un factor que jugar\u00e1 a favor para muchos pa\u00edses exportadores es el &#8220;agujero&#8221; que deja Australia, con la fuerte retracci\u00f3n de su oferta, algo que puede ser aprovechado por sus competidores.<\/p>\n<p>En efecto, a ra\u00edz de una sequ\u00eda muy prologada, el pa\u00eds oce\u00e1nico comenz\u00f3 un raid de exportaciones crecientes a finales de 2012, que pasaron de 950 mil toneladas peso embarque por a\u00f1o a 1,35 millones a mediados de 2015; pero, luego volvieron apenas por encima de su nivel inicial. Es decir, que &#8220;desaparecieron&#8221; de la oferta mundial unas 500\/600 mil toneladas equivalente carcasa (tec) anuales, lo que contribuy\u00f3 a mostrar cifras de comercio m\u00e1s bajas, pero esto no fue acompa\u00f1ado por una menor voluntad de los importadores en comprar carne.<\/p>\n<p><strong>Mirando a China<\/strong><\/p>\n<p>En cuanto al provecho que pueden obtener los principales exportadores de la contracci\u00f3n de la oferta australiana, hay que tener en cuenta que sus ventas est\u00e1n muy concentradas en cuatro mercados: Estados Unidos, Jap\u00f3n, Corea del Sur y China, que en conjunto representan el 80% del total.<\/p>\n<p>El \u00fanico mercado en el que la mayor\u00eda de los pa\u00edses del Mercosur compite abiertamente con Australia es en el chino. En Corea s\u00f3lo lo hace Uruguay y en EE.UU. son \u00e9ste y Brasil desde hace pocos meses. La Argentina podr\u00eda sumarse en cierto plazo.<\/p>\n<p>Tambi\u00e9n hay que considerar que la reducci\u00f3n australiana no ha sido pareja en todos sus mercados. Mientras que hacia EE.UU. y China la ca\u00edda ha sido del orden del 40%, en Jap\u00f3n s\u00f3lo redujo 7% y en Corea aument\u00f3 8%.<\/p>\n<p>En definitiva, para el Mercosur el gran objetivo a analizar es China, al que lamentablemente a\u00fan no ingresa Paraguay, pero tampoco accede la carne de Estados Unidos ni de la India, a pesar de recientes promesas chinas hacia ambos pa\u00edses.<\/p>\n<p>De todas formas, China ya es &#8220;el gran mercado&#8221; para Brasil, Uruguay y la Argentina, representando el 32% (incluyendo los fuertes embarques a Hong Kong), el 43% y el 36%, respectivamente. Como dato contundente, Australia le vendi\u00f3 a China 75 mil tec menos en 2016 que un a\u00f1o atr\u00e1s y cubrir ese faltante puede ser un objetivo interesante.<\/p>\n<p>Fuente:\u00a0<a href=\"http:\/\/www.revistachacra.com.ar\/nota\/11647-una-nueva-oportunidad\/\" target=\"_blank\" rel=\"noopener noreferrer\">revistachacra.com.ar<\/a><\/p>\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El comercio mundial de carnes retomar\u00eda en 2017 los vol\u00famenes previos a la crisis de 2014, con precios firmes, si no se ve afectado por nuevos proteccionismos. Por: Miguel Gorelik \u00a0 En el segundo semestre de 2016 hubo un repunte de las exportaciones de carnes de los seis pa\u00edses l\u00edderes, que representan el 75% del mercado internacional, saliendo as\u00ed del baj\u00f3n registrado durante el a\u00f1o y medio previo. Lo m\u00e1s destacado es que esta mejora se pudo lograr a pesar de la fuerte retracci\u00f3n de las exportaciones australianas y la debilidad de la oferta de Brasil. As\u00ed las cosas, la recuperaci\u00f3n qued\u00f3 en manos de EE.UU., la India y Uruguay. Ampliando la mirada, si se toma todo el \u00faltimo a\u00f1o y se lo compara con el previo, se ve que mientras Australia redujo sus ventas 20%, Brasil y la India las mantuvieron y Paraguay, EE.UU. y Uruguay las incrementaron entre 2 y 11%. De esta forma, 2016 cerr\u00f3 con una baja de s\u00f3lo 4% en relaci\u00f3n a 2015, aunque con tendencia creciente. M\u00e1s a\u00fan, los vol\u00famenes embarcados en el \u00faltimo semestre fueron alcanzando el promedio de los \u00faltimos dos a\u00f1os. En tanto, los precios tambi\u00e9n se recobraron- a pesar de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9114,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-9111","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una nueva oportunidad | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/una-nueva-oportunidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una nueva oportunidad | Proagro\" \/>\n<meta property=\"og:description\" content=\"El comercio mundial de carnes retomar\u00eda en 2017 los vol\u00famenes previos a la crisis de 2014, con precios firmes, si no se ve afectado por nuevos proteccionismos. Por: Miguel Gorelik \u00a0 En el segundo semestre de 2016 hubo un repunte de las exportaciones de carnes de los seis pa\u00edses l\u00edderes, que representan el 75% del mercado internacional, saliendo as\u00ed del baj\u00f3n registrado durante el a\u00f1o y medio previo. Lo m\u00e1s destacado es que esta mejora se pudo lograr a pesar de la fuerte retracci\u00f3n de las exportaciones australianas y la debilidad de la oferta de Brasil. As\u00ed las cosas, la recuperaci\u00f3n qued\u00f3 en manos de EE.UU., la India y Uruguay. Ampliando la mirada, si se toma todo el \u00faltimo a\u00f1o y se lo compara con el previo, se ve que mientras Australia redujo sus ventas 20%, Brasil y la India las mantuvieron y Paraguay, EE.UU. y Uruguay las incrementaron entre 2 y 11%. De esta forma, 2016 cerr\u00f3 con una baja de s\u00f3lo 4% en relaci\u00f3n a 2015, aunque con tendencia creciente. M\u00e1s a\u00fan, los vol\u00famenes embarcados en el \u00faltimo semestre fueron alcanzando el promedio de los \u00faltimos dos a\u00f1os. En tanto, los precios tambi\u00e9n se recobraron- a pesar de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-31T18:20:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T19:03:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/56a7df475e0f2_837_6271.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Una nueva oportunidad\",\"datePublished\":\"2017-01-31T18:20:07+00:00\",\"dateModified\":\"2020-06-29T19:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/\"},\"wordCount\":732,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/56a7df475e0f2_837_6271.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/\",\"name\":\"Una nueva oportunidad | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/56a7df475e0f2_837_6271.jpg\",\"datePublished\":\"2017-01-31T18:20:07+00:00\",\"dateModified\":\"2020-06-29T19:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/56a7df475e0f2_837_6271.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/56a7df475e0f2_837_6271.jpg\",\"width\":837,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-nueva-oportunidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una nueva oportunidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una nueva oportunidad | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/una-nueva-oportunidad\/","og_locale":"en_US","og_type":"article","og_title":"Una nueva oportunidad | Proagro","og_description":"El comercio mundial de carnes retomar\u00eda en 2017 los vol\u00famenes previos a la crisis de 2014, con precios firmes, si no se ve afectado por nuevos proteccionismos. Por: Miguel Gorelik \u00a0 En el segundo semestre de 2016 hubo un repunte de las exportaciones de carnes de los seis pa\u00edses l\u00edderes, que representan el 75% del mercado internacional, saliendo as\u00ed del baj\u00f3n registrado durante el a\u00f1o y medio previo. Lo m\u00e1s destacado es que esta mejora se pudo lograr a pesar de la fuerte retracci\u00f3n de las exportaciones australianas y la debilidad de la oferta de Brasil. As\u00ed las cosas, la recuperaci\u00f3n qued\u00f3 en manos de EE.UU., la India y Uruguay. Ampliando la mirada, si se toma todo el \u00faltimo a\u00f1o y se lo compara con el previo, se ve que mientras Australia redujo sus ventas 20%, Brasil y la India las mantuvieron y Paraguay, EE.UU. y Uruguay las incrementaron entre 2 y 11%. De esta forma, 2016 cerr\u00f3 con una baja de s\u00f3lo 4% en relaci\u00f3n a 2015, aunque con tendencia creciente. M\u00e1s a\u00fan, los vol\u00famenes embarcados en el \u00faltimo semestre fueron alcanzando el promedio de los \u00faltimos dos a\u00f1os. En tanto, los precios tambi\u00e9n se recobraron- a pesar de [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2017-01-31T18:20:07+00:00","article_modified_time":"2020-06-29T19:03:44+00:00","og_image":[{"width":837,"height":627,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/56a7df475e0f2_837_6271.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Una nueva oportunidad","datePublished":"2017-01-31T18:20:07+00:00","dateModified":"2020-06-29T19:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/"},"wordCount":732,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/56a7df475e0f2_837_6271.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/","url":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/","name":"Una nueva oportunidad | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/56a7df475e0f2_837_6271.jpg","datePublished":"2017-01-31T18:20:07+00:00","dateModified":"2020-06-29T19:03:44+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/56a7df475e0f2_837_6271.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/56a7df475e0f2_837_6271.jpg","width":837,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/una-nueva-oportunidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Una nueva oportunidad"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=9111"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9111\/revisions"}],"predecessor-version":[{"id":13926,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9111\/revisions\/13926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/9114"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=9111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=9111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=9111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}