{"id":9050,"date":"2017-01-10T13:51:06","date_gmt":"2017-01-10T13:51:06","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=9050"},"modified":"2020-07-02T12:57:47","modified_gmt":"2020-07-02T12:57:47","slug":"recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/","title":{"rendered":"&#8221;Recen por nosotros&#8221;, el desesperado pedido de una tambera inundada en C\u00f3rdoba"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Ana Pronotti, de la zona de Porte\u00f1a, soporta anegamientos desde hace tres a\u00f1os.<\/p>\n<p class=\"primero\"><em>\u00a0&#8220;Estoy pensando dejar, arrendar el campo o hacer cultivo. Dediqu\u00e9 toda mi vida a esto&#8221;.<\/em> Lo dice<strong> Ana Pronotti a LA NACION.<\/strong> Tiene 56 a\u00f1os y 150 hect\u00e1reas de campo en Porte\u00f1a (departamento San Justo), que maneja desde los 18 a\u00f1os. Desde hace tres a\u00f1os all\u00ed sufren inundaciones y anegamientos.<\/p>\n<aside class=\"banner caja2\" data-adpos=\"caja2\">\n<div id=\"eplAdDivcaja2\">Habl\u00f3 con este diario parada en el potrero y buscando, con la mirada, alg\u00fan lugar m\u00e1s alto donde llevar las 170 vacas del tambo y unas vaquillonas que tiene en <strong>Pueblo Marini,<\/strong> a pocos kil\u00f3metros, que ya qued\u00f3 bajo el agua.<\/div>\n<\/aside>\n<p>En ese campo, donde ten\u00eda reservas de alimentos y unos animales, hay un metro de agua. Ya no puede entrar.<em> &#8220;Es un desastre; s\u00f3lo queda pedir que recen por todos los que estamos con este problema; es desesperante&#8221;<\/em>, dijo.<\/p>\n<aside class=\"banner caja3\" data-adpos=\"caja3\">\n<div id=\"eplAdDivcaja3\">El cami\u00f3n pudo entrar esta ma\u00f1ana al tambo de Porte\u00f1a, pero le advirti\u00f3 que dif\u00edcilmente pueda volver ma\u00f1ana. El enarenado de un camino alternativo se est\u00e1 hundiendo porque no est\u00e1 preparado para los tractores que pasan ahora ante la falta de otras v\u00edas.<\/div>\n<\/aside>\n<p>En medio de un llanto de impotencia, Pronotti cont\u00f3 a este diario que la producci\u00f3n del tambo pas\u00f3 de 2600 litros diarios a 1000 o 1200. <em>&#8220;Y va a ser menos. Las vacas est\u00e1n estresadas, en medio del barro, sin comida&#8221;<\/em>, agreg\u00f3.<\/p>\n<aside class=\"banner caja4\" data-adpos=\"caja4\">\n<div id=\"eplAdDivcaja4\">La mujer no se baja de su tractor hace varios d\u00edas. Mueve lo que puede de alimentos y colabora con otros productores. Habl\u00f3 con uno de San Guillermo, una zona un poco m\u00e1s alta, que tal vez le reciba las vacas del tambo.<\/div>\n<\/aside>\n<p>Las tendr\u00e1 que sacar arreando porque no hay posibilidad de que entre un cami\u00f3n. <em>&#8220;Busco d\u00f3nde moverlas para no perderlas. La alfalfa que hab\u00eda ya se perdi\u00f3 y no tengo m\u00e1s silo. Un mont\u00f3n de gente est\u00e1 mal; hasta el s\u00e1bado hab\u00eda un peque\u00f1o cerco seco, pero ya fue&#8221;<\/em>, explic\u00f3.<\/p>\n<p>El agua que baja desde Santa Fe, m\u00e1s las lluvias locales, profundizan los problemas. Los alcantarillados y elevaciones que se hicieron hace unos meses en la zona cordobesa ya no resisten.<\/p>\n<p><em>&#8220;La luch\u00e9 mucho, pero ya estoy cansada. Son a\u00f1os y a\u00f1os en que se repite la situaci\u00f3n y soy una productora chica, no tengo espalda para seguir as\u00ed&#8221;,<\/em> concluy\u00f3.<\/p>\n<p><strong>Fuente:\u00a0http:\/\/www.lanacion.com.ar\/1974292-recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ana Pronotti, de la zona de Porte\u00f1a, soporta anegamientos desde hace tres a\u00f1os. \u00a0&#8220;Estoy pensando dejar, arrendar el campo o hacer cultivo. Dediqu\u00e9 toda mi vida a esto&#8221;. Lo dice Ana Pronotti a LA NACION. Tiene 56 a\u00f1os y 150 hect\u00e1reas de campo en Porte\u00f1a (departamento San Justo), que maneja desde los 18 a\u00f1os. Desde hace tres a\u00f1os all\u00ed sufren inundaciones y anegamientos. Habl\u00f3 con este diario parada en el potrero y buscando, con la mirada, alg\u00fan lugar m\u00e1s alto donde llevar las 170 vacas del tambo y unas vaquillonas que tiene en Pueblo Marini, a pocos kil\u00f3metros, que ya qued\u00f3 bajo el agua. En ese campo, donde ten\u00eda reservas de alimentos y unos animales, hay un metro de agua. Ya no puede entrar. &#8220;Es un desastre; s\u00f3lo queda pedir que recen por todos los que estamos con este problema; es desesperante&#8221;, dijo. El cami\u00f3n pudo entrar esta ma\u00f1ana al tambo de Porte\u00f1a, pero le advirti\u00f3 que dif\u00edcilmente pueda volver ma\u00f1ana. El enarenado de un camino alternativo se est\u00e1 hundiendo porque no est\u00e1 preparado para los tractores que pasan ahora ante la falta de otras v\u00edas. En medio de un llanto de impotencia, Pronotti cont\u00f3 a este diario que la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9053,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-9050","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Recen por nosotros&quot;, el desesperado pedido de una tambera inundada en C\u00f3rdoba | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Recen por nosotros&quot;, el desesperado pedido de una tambera inundada en C\u00f3rdoba | Proagro\" \/>\n<meta property=\"og:description\" content=\"Ana Pronotti, de la zona de Porte\u00f1a, soporta anegamientos desde hace tres a\u00f1os. \u00a0&#8220;Estoy pensando dejar, arrendar el campo o hacer cultivo. Dediqu\u00e9 toda mi vida a esto&#8221;. Lo dice Ana Pronotti a LA NACION. Tiene 56 a\u00f1os y 150 hect\u00e1reas de campo en Porte\u00f1a (departamento San Justo), que maneja desde los 18 a\u00f1os. Desde hace tres a\u00f1os all\u00ed sufren inundaciones y anegamientos. Habl\u00f3 con este diario parada en el potrero y buscando, con la mirada, alg\u00fan lugar m\u00e1s alto donde llevar las 170 vacas del tambo y unas vaquillonas que tiene en Pueblo Marini, a pocos kil\u00f3metros, que ya qued\u00f3 bajo el agua. En ese campo, donde ten\u00eda reservas de alimentos y unos animales, hay un metro de agua. Ya no puede entrar. &#8220;Es un desastre; s\u00f3lo queda pedir que recen por todos los que estamos con este problema; es desesperante&#8221;, dijo. El cami\u00f3n pudo entrar esta ma\u00f1ana al tambo de Porte\u00f1a, pero le advirti\u00f3 que dif\u00edcilmente pueda volver ma\u00f1ana. El enarenado de un camino alternativo se est\u00e1 hundiendo porque no est\u00e1 preparado para los tractores que pasan ahora ante la falta de otras v\u00edas. En medio de un llanto de impotencia, Pronotti cont\u00f3 a este diario que la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-10T13:51:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-02T12:57:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/campo-2341022w6201.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"618\" \/>\n\t<meta property=\"og:image:height\" content=\"258\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"&#8221;Recen por nosotros&#8221;, el desesperado pedido de una tambera inundada en C\u00f3rdoba\",\"datePublished\":\"2017-01-10T13:51:06+00:00\",\"dateModified\":\"2020-07-02T12:57:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/\"},\"wordCount\":430,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/campo-2341022w6201.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/\",\"name\":\"\\\"Recen por nosotros\\\", el desesperado pedido de una tambera inundada en C\u00f3rdoba | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/campo-2341022w6201.jpg\",\"datePublished\":\"2017-01-10T13:51:06+00:00\",\"dateModified\":\"2020-07-02T12:57:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/campo-2341022w6201.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/campo-2341022w6201.jpg\",\"width\":618,\"height\":258},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abRecen por nosotros\u00bb, el desesperado pedido de una tambera inundada en C\u00f3rdoba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Recen por nosotros\", el desesperado pedido de una tambera inundada en C\u00f3rdoba | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/","og_locale":"en_US","og_type":"article","og_title":"\"Recen por nosotros\", el desesperado pedido de una tambera inundada en C\u00f3rdoba | Proagro","og_description":"Ana Pronotti, de la zona de Porte\u00f1a, soporta anegamientos desde hace tres a\u00f1os. \u00a0&#8220;Estoy pensando dejar, arrendar el campo o hacer cultivo. Dediqu\u00e9 toda mi vida a esto&#8221;. Lo dice Ana Pronotti a LA NACION. Tiene 56 a\u00f1os y 150 hect\u00e1reas de campo en Porte\u00f1a (departamento San Justo), que maneja desde los 18 a\u00f1os. Desde hace tres a\u00f1os all\u00ed sufren inundaciones y anegamientos. Habl\u00f3 con este diario parada en el potrero y buscando, con la mirada, alg\u00fan lugar m\u00e1s alto donde llevar las 170 vacas del tambo y unas vaquillonas que tiene en Pueblo Marini, a pocos kil\u00f3metros, que ya qued\u00f3 bajo el agua. En ese campo, donde ten\u00eda reservas de alimentos y unos animales, hay un metro de agua. Ya no puede entrar. &#8220;Es un desastre; s\u00f3lo queda pedir que recen por todos los que estamos con este problema; es desesperante&#8221;, dijo. El cami\u00f3n pudo entrar esta ma\u00f1ana al tambo de Porte\u00f1a, pero le advirti\u00f3 que dif\u00edcilmente pueda volver ma\u00f1ana. El enarenado de un camino alternativo se est\u00e1 hundiendo porque no est\u00e1 preparado para los tractores que pasan ahora ante la falta de otras v\u00edas. En medio de un llanto de impotencia, Pronotti cont\u00f3 a este diario que la [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2017-01-10T13:51:06+00:00","article_modified_time":"2020-07-02T12:57:47+00:00","og_image":[{"width":618,"height":258,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/campo-2341022w6201.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"&#8221;Recen por nosotros&#8221;, el desesperado pedido de una tambera inundada en C\u00f3rdoba","datePublished":"2017-01-10T13:51:06+00:00","dateModified":"2020-07-02T12:57:47+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/"},"wordCount":430,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/campo-2341022w6201.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/","url":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/","name":"\"Recen por nosotros\", el desesperado pedido de una tambera inundada en C\u00f3rdoba | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/campo-2341022w6201.jpg","datePublished":"2017-01-10T13:51:06+00:00","dateModified":"2020-07-02T12:57:47+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/campo-2341022w6201.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2017\/01\/campo-2341022w6201.jpg","width":618,"height":258},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/recen-por-nosotros-el-desesperado-pedido-de-una-tambera-inundada-en-cordoba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"\u00abRecen por nosotros\u00bb, el desesperado pedido de una tambera inundada en C\u00f3rdoba"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=9050"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9050\/revisions"}],"predecessor-version":[{"id":14640,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9050\/revisions\/14640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/9053"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=9050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=9050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=9050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}