{"id":9014,"date":"2016-12-29T14:12:51","date_gmt":"2016-12-29T14:12:51","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=9014"},"modified":"2020-06-29T18:37:06","modified_gmt":"2020-06-29T18:37:06","slug":"podria-desaparecer-la-cuota-481","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/podria-desaparecer-la-cuota-481\/","title":{"rendered":"Podr\u00eda desaparecer la cuota 481"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<div class=\"bajada\">\n<p>Si EE.UU. decidiera volver a la guerra comercial con la Uni\u00f3n Europea por no poder venderle sus carnes tratadas con hormonas, algo que se dirime hoy en d\u00eda en una consulta p\u00fablica, el bloque europeo tendr\u00eda derecho a eliminar el cupo. Los potenciales perjuicios para la Argentina. <strong>Por Miguel Gorelik.<\/strong><\/p>\n<\/div>\n<div class=\"post-meta\">En estos d\u00edas, la<strong> Oficina del Representante Comercial de los Estados Unidos (USTR)<\/strong> convoc\u00f3 a una audiencia p\u00fablica para evaluar la posibilidad de volver a aplicar represalias sobre productos europeos, a modo de castigo por las trabas de la Uni\u00f3n Europea (UE) para importar carne estadounidense tratada con hormonas.<\/div>\n<p>Si EE.UU. llegara a la conclusi\u00f3n de que ser\u00eda\u00a0m\u00e1s beneficioso volver a la guerra comercial con la UE y aplicara los sobrearanceles eliminados tras la negociaci\u00f3n de la 481, cuota que en su momento fren\u00f3 el conflicto, lo m\u00e1s probable es que la UE elimine el cupo completamente, para todos los pa\u00edses habilitados.<\/p>\n<p><strong>La historia\u00a0<\/strong><\/p>\n<p>Muy sint\u00e9ticamente, en 1998 EE.UU. gan\u00f3 un panel en la <strong>Organizaci\u00f3n Mundial del Comercio<\/strong>, lo que le daba derechos a imponer aranceles adicionales de importaci\u00f3n sobre determinados productos europeos por hasta casi USD120M, algo que instrument\u00f3 desde 1999.<\/p>\n<p>En 2008, iba a cambiar el listado de rubros afectados, principalmente alimentos, pero la UE inici\u00f3 negociaciones de las que surgi\u00f3 la despu\u00e9s llamada cuota 481, a mediados de 2009. Se trataba de una medida unilateral de la UE que inicialmente benefici\u00f3 a contados pa\u00edses (EE.UU, Canad\u00e1 y Australia), a los que se fueron agregando posteriormente Uruguay y luego la Argentina, adem\u00e1s de Nueva Zelandia.<\/p>\n<p>Este contingente tampoco admite carne con hormonas, lo que limita la producci\u00f3n de hacienda apta para ese negocio en los pa\u00edses autorizados del Nafta. Tres a\u00f1os despu\u00e9s, la cuota se iba a ampliar a 45 mil tons, aunque se lleg\u00f3 a 48 mil tons para contar con 3 mil tons exclusivas para Canad\u00e1, pa\u00eds que tambi\u00e9n particip\u00f3 del reclamo original ante la OMC.<\/p>\n<p><strong>La coyuntura<\/strong><\/p>\n<p>En EE.UU. est\u00e1n muy frustrados por la dificultad en producir carne sin hormonas, a lo que se agrega que otros pa\u00edses aprovechan esta cuota mucho m\u00e1s, cuando entienden que estaba destinada para ellos. Adem\u00e1s, con una relaci\u00f3n d\u00f3lar\/euro m\u00e1s desfavorable les resulta hoy dif\u00edcil maximizar su aprovechamiento.<\/p>\n<p>En este marco, la insistencia m\u00e1s reciente de EE.UU. para eliminar la restricci\u00f3n a las hormonas se encontr\u00f3 con el compromiso de la UE de negociarlo en el marco del acuerdo de libre comercio entre ambos (T-TIP por Transatlantic Trade and Investment Partnership).<\/p>\n<p>Como ahora la UE anunci\u00f3 que no iba a completar esa negociaci\u00f3n en este a\u00f1o, el USTR decidi\u00f3 iniciar el camino de las represalias mencionadas, iniciativa que est\u00e1 poniendo al juicio p\u00fablico. Si esto se concretara, lo m\u00e1s probable es que la UE elimine la cuota 481 completamente, algo que tendr\u00eda derechos para hacer ya que se trata de una decisi\u00f3n te\u00f3ricamente unilateral.<\/p>\n<p>Sin embargo, pa\u00edses como Australia y Uruguay, que han venido contribuyendo con unas 10\/15 mil tons anuales\u00a0cada uno a esta cuota, podr\u00edan alegar derechos adquiridos en la OMC, con buenas chances de ganar el reclamo, aunque con la necesaria interrupci\u00f3n por varios meses o a\u00f1os, mientras se dilucida el tema.<\/p>\n<p>Por el contrario, la Argentina, que logr\u00f3 m\u00e1s tarde la autorizaci\u00f3n\u00a0para\u00a0abastecer esta cuota y export\u00f3 muy poquito gracias a la \u201cd\u00e9cada ganada\u201d, tendr\u00eda posibilidades mucho m\u00e1s limitadas.<\/p>\n<p>Ser\u00eda una verdadera picard\u00eda que el pa\u00eds no pudiera aprovechar su potencial en este rengl\u00f3n, ahora que rigen nuevas condiciones para producir y exportar carne. La cuota 481, por sus caracter\u00edsticas productivas, ofrece posibilidades m\u00e1s inmediatas que la Hilton, para cuyo completo cumplimiento habr\u00e1 que esperar a que aparezca una mayor cantidad de novillos trazados. As\u00ed, ser\u00eda una nueva, dura y lamentable lecci\u00f3n para la Argentina acerca de que los trenes de la\u00a0 historia no se pueden perder impunemente.<\/p>\n<p><strong>Por Miguel Gorelik<\/strong><br \/><strong>Director de Valor Carne<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Si EE.UU. decidiera volver a la guerra comercial con la Uni\u00f3n Europea por no poder venderle sus carnes tratadas con hormonas, algo que se dirime hoy en d\u00eda en una consulta p\u00fablica, el bloque europeo tendr\u00eda derecho a eliminar el cupo. Los potenciales perjuicios para la Argentina. Por Miguel Gorelik. En estos d\u00edas, la Oficina del Representante Comercial de los Estados Unidos (USTR) convoc\u00f3 a una audiencia p\u00fablica para evaluar la posibilidad de volver a aplicar represalias sobre productos europeos, a modo de castigo por las trabas de la Uni\u00f3n Europea (UE) para importar carne estadounidense tratada con hormonas. Si EE.UU. llegara a la conclusi\u00f3n de que ser\u00eda\u00a0m\u00e1s beneficioso volver a la guerra comercial con la UE y aplicara los sobrearanceles eliminados tras la negociaci\u00f3n de la 481, cuota que en su momento fren\u00f3 el conflicto, lo m\u00e1s probable es que la UE elimine el cupo completamente, para todos los pa\u00edses habilitados. La historia\u00a0 Muy sint\u00e9ticamente, en 1998 EE.UU. gan\u00f3 un panel en la Organizaci\u00f3n Mundial del Comercio, lo que le daba derechos a imponer aranceles adicionales de importaci\u00f3n sobre determinados productos europeos por hasta casi USD120M, algo que instrument\u00f3 desde 1999. En 2008, iba a cambiar el listado de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9015,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-9014","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Podr\u00eda desaparecer la cuota 481 | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/podria-desaparecer-la-cuota-481\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podr\u00eda desaparecer la cuota 481 | Proagro\" \/>\n<meta property=\"og:description\" content=\"Si EE.UU. decidiera volver a la guerra comercial con la Uni\u00f3n Europea por no poder venderle sus carnes tratadas con hormonas, algo que se dirime hoy en d\u00eda en una consulta p\u00fablica, el bloque europeo tendr\u00eda derecho a eliminar el cupo. Los potenciales perjuicios para la Argentina. Por Miguel Gorelik. En estos d\u00edas, la Oficina del Representante Comercial de los Estados Unidos (USTR) convoc\u00f3 a una audiencia p\u00fablica para evaluar la posibilidad de volver a aplicar represalias sobre productos europeos, a modo de castigo por las trabas de la Uni\u00f3n Europea (UE) para importar carne estadounidense tratada con hormonas. Si EE.UU. llegara a la conclusi\u00f3n de que ser\u00eda\u00a0m\u00e1s beneficioso volver a la guerra comercial con la UE y aplicara los sobrearanceles eliminados tras la negociaci\u00f3n de la 481, cuota que en su momento fren\u00f3 el conflicto, lo m\u00e1s probable es que la UE elimine el cupo completamente, para todos los pa\u00edses habilitados. La historia\u00a0 Muy sint\u00e9ticamente, en 1998 EE.UU. gan\u00f3 un panel en la Organizaci\u00f3n Mundial del Comercio, lo que le daba derechos a imponer aranceles adicionales de importaci\u00f3n sobre determinados productos europeos por hasta casi USD120M, algo que instrument\u00f3 desde 1999. En 2008, iba a cambiar el listado de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-29T14:12:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T18:37:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/CAMPOG1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Podr\u00eda desaparecer la cuota 481\",\"datePublished\":\"2016-12-29T14:12:51+00:00\",\"dateModified\":\"2020-06-29T18:37:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/\"},\"wordCount\":704,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/CAMPOG1-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/\",\"name\":\"Podr\u00eda desaparecer la cuota 481 | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/CAMPOG1-scaled.jpg\",\"datePublished\":\"2016-12-29T14:12:51+00:00\",\"dateModified\":\"2020-06-29T18:37:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/CAMPOG1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/CAMPOG1-scaled.jpg\",\"width\":2560,\"height\":1429},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/podria-desaparecer-la-cuota-481\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podr\u00eda desaparecer la cuota 481\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Podr\u00eda desaparecer la cuota 481 | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/podria-desaparecer-la-cuota-481\/","og_locale":"en_US","og_type":"article","og_title":"Podr\u00eda desaparecer la cuota 481 | Proagro","og_description":"Si EE.UU. decidiera volver a la guerra comercial con la Uni\u00f3n Europea por no poder venderle sus carnes tratadas con hormonas, algo que se dirime hoy en d\u00eda en una consulta p\u00fablica, el bloque europeo tendr\u00eda derecho a eliminar el cupo. Los potenciales perjuicios para la Argentina. Por Miguel Gorelik. En estos d\u00edas, la Oficina del Representante Comercial de los Estados Unidos (USTR) convoc\u00f3 a una audiencia p\u00fablica para evaluar la posibilidad de volver a aplicar represalias sobre productos europeos, a modo de castigo por las trabas de la Uni\u00f3n Europea (UE) para importar carne estadounidense tratada con hormonas. Si EE.UU. llegara a la conclusi\u00f3n de que ser\u00eda\u00a0m\u00e1s beneficioso volver a la guerra comercial con la UE y aplicara los sobrearanceles eliminados tras la negociaci\u00f3n de la 481, cuota que en su momento fren\u00f3 el conflicto, lo m\u00e1s probable es que la UE elimine el cupo completamente, para todos los pa\u00edses habilitados. La historia\u00a0 Muy sint\u00e9ticamente, en 1998 EE.UU. gan\u00f3 un panel en la Organizaci\u00f3n Mundial del Comercio, lo que le daba derechos a imponer aranceles adicionales de importaci\u00f3n sobre determinados productos europeos por hasta casi USD120M, algo que instrument\u00f3 desde 1999. En 2008, iba a cambiar el listado de [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-12-29T14:12:51+00:00","article_modified_time":"2020-06-29T18:37:06+00:00","og_image":[{"width":2560,"height":1429,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/CAMPOG1-scaled.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Podr\u00eda desaparecer la cuota 481","datePublished":"2016-12-29T14:12:51+00:00","dateModified":"2020-06-29T18:37:06+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/"},"wordCount":704,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/CAMPOG1-scaled.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/","url":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/","name":"Podr\u00eda desaparecer la cuota 481 | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/CAMPOG1-scaled.jpg","datePublished":"2016-12-29T14:12:51+00:00","dateModified":"2020-06-29T18:37:06+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/CAMPOG1-scaled.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/CAMPOG1-scaled.jpg","width":2560,"height":1429},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/podria-desaparecer-la-cuota-481\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Podr\u00eda desaparecer la cuota 481"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=9014"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9014\/revisions"}],"predecessor-version":[{"id":13830,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/9014\/revisions\/13830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/9015"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=9014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=9014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=9014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}