{"id":8926,"date":"2016-12-01T16:13:45","date_gmt":"2016-12-01T16:13:45","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=8926"},"modified":"2020-06-29T18:38:51","modified_gmt":"2020-06-29T18:38:51","slug":"crece-la-produccion-de-hacienda-para-la-cuota-481","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/crece-la-produccion-de-hacienda-para-la-cuota-481\/","title":{"rendered":"Crece la producci\u00f3n de hacienda para la Cuota 481"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p><span style=\"color: #000000;\">Este a<\/span>\u00f1o se produjo un importante incremento en los encierres para abastecer de carne vacuna a la <strong>Uni\u00f3n Europea<\/strong> en el marco de la <strong>Cuota 481<\/strong>. Se trata de un cupo de<strong> 48 mil toneladas de carne engordada a corral que tienen arancel cero y permite la colocaci\u00f3n de un n\u00famero de cortes amplio<\/strong>, lo que la ubica en una situaci\u00f3n de ventaja, incluso respecto de la Cuota Hilton que paga aranceles en torno al 20% y que se completa principalmente con lomo cuadril y bife angosto. <\/p>\n<p> Entre enero y septiembre los feedlots encerraron 80.400 vacunos contra los 45.400 animales registrados a lo largo de todo 2015 para abastecer esa cuota. El aumento fue del 77%. <em>&#8220;Si se toma como referencia el primer semestre del a\u00f1o el incremento fue del 100% y adem\u00e1s superaron a todo el registro de 2015&#8221;,<\/em> <strong>se\u00f1ala un informe del Senasa que refleja la evoluci\u00f3n de la actividad en nuestro pa\u00eds.<\/strong><\/p>\n<p class=\"epiItem\"><a href=\"https:\/\/proagrolab.com.ar\/portfolio\/tilmicotin\/\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"width: 401px; border: solid 3px purple;\" title=\"Ver producto\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/08\/tilmicotin.jpg \" alt=\"\" width=\"401\" height=\"240\" \/><\/a><\/p>\n<p> Desde que se comenz\u00f3 a negociar el ingreso de Argentina a la cuota los feedloteros destacaron sus beneficios arancelarios, pero tambi\u00e9n productivos ya que el engorde de novillos implica un mayor agregado de valor a la inversi\u00f3n de compra ya que suma demanda al mercado de la invernada y permite derivar algunos cortes al consumo local.<\/p>\n<p> En el arranque de la participaci\u00f3n argentina en la cuota se produjeron algunos inconvenientes que derivaron en rechazos de la hacienda. Las cuestiones t\u00e9cnicas delimitan que adem\u00e1s de pasar al menos 100 d\u00edas en el engorde a corral, la hacienda debe cumplir con otros requisitos de kilajes, dentici\u00f3n y edad. Esas variables debieron ser ajustadas con el paso del tiempo y la acumulaci\u00f3n de experiencia. En efecto, seg\u00fan un informe oficial que circula entre los industriales en abril de 2015 se toc\u00f3 un pico de rechazos de m\u00e1s del 20% del ganado enviado a faena mientras que en los \u00faltimos meses computados el rechazo fue del 10%.<\/p>\n<p> En cuanto al resultado econ\u00f3mico, la rentabilidad es buena aunque de m\u00e1rgenes ajustados. Un importante engordador destac\u00f3 que el precio por kilo vivo ronda los $33\/34 (en el consumo se paga $28\/30 por kilo de novillo).<em> &#8220;El que encierra para 481 sigue por ese camino y hoy cada vez menos derivan la hacienda para el consumo local<\/em>&#8220;, indic\u00f3.<\/p>\n<p> Por ahora el negocio est\u00e1 concentrado en los frigor\u00edficos exportadores que compran invernada y la llevan a engordar en corrales propios o de terceros mientras que la participaci\u00f3n de los feedlots sin integraci\u00f3n en la industria queda relegada a un segundo lugar. Los engordadores dicen que para incrementar su participaci\u00f3n en la producci\u00f3n de novillos para la Cuota 481 se requiere de herramientas comerciales que le den previsibilidad al negocio. En concreto, reclaman que se instrumente una especie de contrato o compromiso de pago de parte de la industria frigor\u00edfica que les d\u00e9 certezas respecto del precio que cobrar\u00edan al final del ciclo. El reclamo se basa en que la inversi\u00f3n necesaria es muy alta y que el riesgo radica en que el valor que termine pagando la industria no cubra los costos con el agravante de que no es sencillo colocar novillos entre-pesado en el consumo local.<\/p>\n<p> <strong>El Senasa indica que hay 40 feedlots habilitados con registro definitivo (otros 10 con autorizaci\u00f3n provisoria)<\/strong> para producir novillos con destino a esa cuota y que 25 de ellos est\u00e1n en la provincia de Buenos Aires (63%), hay otros 6 en Santa Fe y en Santiago del Estero 3 m\u00e1s.<\/p>\n<p> Del total con registro definitivo s\u00f3lo 27 completaron el ciclo de producci\u00f3n enviando animales para faena. Al mismo tiempo, se destaca que parte de la hacienda encerrada para ese destino termin\u00f3 en otros mercados y de acuerdo con operadores del sector, mayormente se comercializ\u00f3 en el mercado local, que en muchos momentos pag\u00f3 incluso por encima de los mercados internacionales. <\/p>\n<p> De todos modos, esa tendencia se estar\u00eda acotando. En tal sentido el consultor <strong>V\u00edctor Tonelli<\/strong> dijo que<em> &#8220;de acuerdo con la informaci\u00f3n oficial durante los primeros 9 meses de este a\u00f1o salieron para faena como para cubrir la cuota 47.700 cabezas contra las 14.700 de 2015, lo que implica un crecimiento superior al 300%&#8221;<\/em>. Tonelli agreg\u00f3 que <em>&#8220;est\u00e1 claro que hay un importante crecimiento en los encierres y env\u00edos a faena que indican la conveniencia del negocio para frigor\u00edficos y para quienes producen la hacienda&#8221;<\/em>.<\/p>\n<p><strong>Fuente:\u00a0http:\/\/www.ambito.com\/863717-crece-la-produccion-de-hacienda-para-la-cuota-481<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o se produjo un importante incremento en los encierres para abastecer de carne vacuna a la Uni\u00f3n Europea en el marco de la Cuota 481. Se trata de un cupo de 48 mil toneladas de carne engordada a corral que tienen arancel cero y permite la colocaci\u00f3n de un n\u00famero de cortes amplio, lo que la ubica en una situaci\u00f3n de ventaja, incluso respecto de la Cuota Hilton que paga aranceles en torno al 20% y que se completa principalmente con lomo cuadril y bife angosto. Entre enero y septiembre los feedlots encerraron 80.400 vacunos contra los 45.400 animales registrados a lo largo de todo 2015 para abastecer esa cuota. El aumento fue del 77%. &#8220;Si se toma como referencia el primer semestre del a\u00f1o el incremento fue del 100% y adem\u00e1s superaron a todo el registro de 2015&#8221;, se\u00f1ala un informe del Senasa que refleja la evoluci\u00f3n de la actividad en nuestro pa\u00eds. Desde que se comenz\u00f3 a negociar el ingreso de Argentina a la cuota los feedloteros destacaron sus beneficios arancelarios, pero tambi\u00e9n productivos ya que el engorde de novillos implica un mayor agregado de valor a la inversi\u00f3n de compra ya que suma demanda al mercado [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8927,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[159,129,80,200,105],"class_list":["post-8926","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","tag-campo","tag-feedlot","tag-ganaderia","tag-vacas","tag-vacunos","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crece la producci\u00f3n de hacienda para la Cuota 481 | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/crece-la-produccion-de-hacienda-para-la-cuota-481\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crece la producci\u00f3n de hacienda para la Cuota 481 | Proagro\" \/>\n<meta property=\"og:description\" content=\"Este a\u00f1o se produjo un importante incremento en los encierres para abastecer de carne vacuna a la Uni\u00f3n Europea en el marco de la Cuota 481. Se trata de un cupo de 48 mil toneladas de carne engordada a corral que tienen arancel cero y permite la colocaci\u00f3n de un n\u00famero de cortes amplio, lo que la ubica en una situaci\u00f3n de ventaja, incluso respecto de la Cuota Hilton que paga aranceles en torno al 20% y que se completa principalmente con lomo cuadril y bife angosto. Entre enero y septiembre los feedlots encerraron 80.400 vacunos contra los 45.400 animales registrados a lo largo de todo 2015 para abastecer esa cuota. El aumento fue del 77%. &#8220;Si se toma como referencia el primer semestre del a\u00f1o el incremento fue del 100% y adem\u00e1s superaron a todo el registro de 2015&#8221;, se\u00f1ala un informe del Senasa que refleja la evoluci\u00f3n de la actividad en nuestro pa\u00eds. Desde que se comenz\u00f3 a negociar el ingreso de Argentina a la cuota los feedloteros destacaron sus beneficios arancelarios, pero tambi\u00e9n productivos ya que el engorde de novillos implica un mayor agregado de valor a la inversi\u00f3n de compra ya que suma demanda al mercado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-01T16:13:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T18:38:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/not_863717_24_205848_m.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Crece la producci\u00f3n de hacienda para la Cuota 481\",\"datePublished\":\"2016-12-01T16:13:45+00:00\",\"dateModified\":\"2020-06-29T18:38:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/\"},\"wordCount\":748,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/not_863717_24_205848_m.jpg\",\"keywords\":[\"Campo\",\"Feedlot\",\"Ganader\u00eda\",\"vacas\",\"vacunos\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/\",\"name\":\"Crece la producci\u00f3n de hacienda para la Cuota 481 | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/not_863717_24_205848_m.jpg\",\"datePublished\":\"2016-12-01T16:13:45+00:00\",\"dateModified\":\"2020-06-29T18:38:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/not_863717_24_205848_m.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/not_863717_24_205848_m.jpg\",\"width\":768,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/crece-la-produccion-de-hacienda-para-la-cuota-481\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crece la producci\u00f3n de hacienda para la Cuota 481\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crece la producci\u00f3n de hacienda para la Cuota 481 | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/crece-la-produccion-de-hacienda-para-la-cuota-481\/","og_locale":"en_US","og_type":"article","og_title":"Crece la producci\u00f3n de hacienda para la Cuota 481 | Proagro","og_description":"Este a\u00f1o se produjo un importante incremento en los encierres para abastecer de carne vacuna a la Uni\u00f3n Europea en el marco de la Cuota 481. Se trata de un cupo de 48 mil toneladas de carne engordada a corral que tienen arancel cero y permite la colocaci\u00f3n de un n\u00famero de cortes amplio, lo que la ubica en una situaci\u00f3n de ventaja, incluso respecto de la Cuota Hilton que paga aranceles en torno al 20% y que se completa principalmente con lomo cuadril y bife angosto. Entre enero y septiembre los feedlots encerraron 80.400 vacunos contra los 45.400 animales registrados a lo largo de todo 2015 para abastecer esa cuota. El aumento fue del 77%. &#8220;Si se toma como referencia el primer semestre del a\u00f1o el incremento fue del 100% y adem\u00e1s superaron a todo el registro de 2015&#8221;, se\u00f1ala un informe del Senasa que refleja la evoluci\u00f3n de la actividad en nuestro pa\u00eds. Desde que se comenz\u00f3 a negociar el ingreso de Argentina a la cuota los feedloteros destacaron sus beneficios arancelarios, pero tambi\u00e9n productivos ya que el engorde de novillos implica un mayor agregado de valor a la inversi\u00f3n de compra ya que suma demanda al mercado [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-12-01T16:13:45+00:00","article_modified_time":"2020-06-29T18:38:51+00:00","og_image":[{"width":768,"height":415,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/not_863717_24_205848_m.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Crece la producci\u00f3n de hacienda para la Cuota 481","datePublished":"2016-12-01T16:13:45+00:00","dateModified":"2020-06-29T18:38:51+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/"},"wordCount":748,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/not_863717_24_205848_m.jpg","keywords":["Campo","Feedlot","Ganader\u00eda","vacas","vacunos"],"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/","url":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/","name":"Crece la producci\u00f3n de hacienda para la Cuota 481 | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/not_863717_24_205848_m.jpg","datePublished":"2016-12-01T16:13:45+00:00","dateModified":"2020-06-29T18:38:51+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/not_863717_24_205848_m.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/12\/not_863717_24_205848_m.jpg","width":768,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/crece-la-produccion-de-hacienda-para-la-cuota-481\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Crece la producci\u00f3n de hacienda para la Cuota 481"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8926"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8926\/revisions"}],"predecessor-version":[{"id":13834,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8926\/revisions\/13834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/8927"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}