{"id":8902,"date":"2016-11-25T12:52:03","date_gmt":"2016-11-25T12:52:03","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=8902"},"modified":"2016-11-25T16:48:10","modified_gmt":"2016-11-25T16:48:10","slug":"el-avance-para-conocer-la-huella-digital-de-los-bovinos","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/","title":{"rendered":"El avance para conocer la huella digital de los bovinos"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p><span lang=\"ES-TRAD\" xml:lang=\"ES-TRAD\">Un grupo de investigadores de la Facultad de Agronom\u00eda de la UBA (<strong>FAUBA<\/strong>), el Instituto de Gen\u00e9tica Veterinaria de la Universidad Nacional de La Plata (<strong>UNLP<\/strong>) y el <strong>CONICET<\/strong>, desarroll\u00f3 un novedoso <strong>chip<\/strong> con un conjunto de marcadores moleculares, entre un grupo de <strong>640.000<\/strong>, para bovinos de la Argentina de las razas <strong>Brangus, Braford y Brahman<\/strong>. La herramienta permitir\u00e1 a los criadores incorporar informaci\u00f3n <strong>gen\u00f3mica<\/strong> a la selecci\u00f3n de reproductores, para mejorar los rodeos <strong>en menos tiempo<\/strong> y a un <strong>menor costo<\/strong>, respecto de los valores internacionales.<\/span><\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/52efcfab9379a.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8903\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/52efcfab9379a-300x200.jpg\" alt=\"52efcfab9379a\" width=\"300\" height=\"200\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/52efcfab9379a-300x200.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/52efcfab9379a-600x400.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/52efcfab9379a-1024x683.jpg 1024w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/52efcfab9379a.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Esta nueva herramienta se denomin\u00f3 <strong>ArBos1<\/strong> y obtuvo el premio en la categor\u00eda Investigaci\u00f3n Aplicada en la edici\u00f3n 2016 del Concurso Nacional de Innovaciones (<strong>Innovar<\/strong>). Seg\u00fan sus responsables, se trata de un desarrollo \u00fanico en la Argentina. A partir de ahora, los productores ganaderos podr\u00edan acceder en el pa\u00eds a un servicio de gen\u00f3mica que deb\u00edan realizar en el exterior y, con ello, agregar informaci\u00f3n gen\u00f3mica al pedigree y a los caracteres fenot\u00edpicos (caracter\u00edsticas de medici\u00f3n directa en los animales, como pesos y mediciones de res por ultrasonido).<\/p>\n<p><em>\u201cHasta la actualidad exist\u00eda un chip con caracter\u00edsticas similares, desarrollado por la empresa Illumina, que fue concebido para ser muy informativo para las razas Angus y Holando. Pero este chip perd\u00eda calidad de informaci\u00f3n (todos los animales de esa raza son iguales para ese marcador) al aplicarlo a las razas Brahman, Brangus o Bradford, que son importante por su difusi\u00f3n en la Argentina\u201d<\/em>, explic\u00f3 <strong>Cantet<\/strong>, quien particip\u00f3 en la investigaci\u00f3n desde la <strong>FAUBA<\/strong> junto a <strong>Sebasti\u00e1n Munilla<\/strong>, al sitio de divulgaci\u00f3n cient\u00edfica Sobre la Tierra.<\/p>\n<p>Adem\u00e1s, se\u00f1al\u00f3:<em> \u201cHicimos una placa m\u00e1s econ\u00f3mica, con tecnolog\u00eda de la empresa Affymetrix, totalmente informativa para razas compuestas brit\u00e1nico-\u00edndicas, y le introducimos marcadores que indican algunas enfermedades hereditarias, coloraci\u00f3n del pelaje y largo del prepucio, por ejemplo\u201d.<\/em><\/p>\n<p>El chip desarrollado por la <strong>FAUBA y la UNLP<\/strong> permite diagnosticar enfermedades de origen gen\u00e9tico y realizar ensayos de paternidad y estudios de linajes. <em>\u201cTiene muchas aplicaciones. Quiz\u00e1s la m\u00e1s importante es la selecci\u00f3n, pero tambi\u00e9n permite hacer una verificaci\u00f3n de paternidad o la trazabilidad del animal. Por ejemplo, al exportar carne a China podr\u00edas certificar que ese producto viene de la Argentina y saber cu\u00e1les son los padres\u201d<\/em>, coment\u00f3 el investigador de la FAUBA.<\/p>\n<p>Cantet explic\u00f3 que los marcadores moleculares permiten identificar polimorfismos:<em> \u201cSer\u00eda una manera de conocer cada animal en particular a trav\u00e9s de una huella digital\u201d<\/em>. Para graficarlo, se refiri\u00f3 a los marcadores como luces:<em> \u201cEl ADN (material gen\u00e9tico) de una persona podr\u00eda verse como una serie de veladores colocados uno a cierta distancia del otro (por ejemplo, cada 50 metros), desde Buenos Aires a Mar del Plata. Evaluar qu\u00e9 marcadores lleva el animal es conocer cu\u00e1l es el patr\u00f3n de luces prendidas (P) o apagadas (A): por ejemplo, AAAPPAPAPP. Este patr\u00f3n es \u00fanico para cada animal. Pero como se trata de una tecnolog\u00eda muy costosa, decidimos mirar una l\u00e1mpara cada 200 metros, sabiendo que en Brangus, Braford y Brahman, para cualquiera de esas luces habr\u00e1 animales A y otros P. Esa es justamente la presencia del polimorfismo, que si fueran todas A o P no marcar\u00edan nada en esa raza\u201d.<\/em>\u00a0<\/p>\n<p><strong>Fuente:\u00a0Por <span class=\"author\">Juan Manuel Repetto <\/span>| <span class=\"source\">Prensa FAUBA<\/span><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Un grupo de investigadores de la Facultad de Agronom\u00eda de la UBA (FAUBA), el Instituto de Gen\u00e9tica Veterinaria de la Universidad Nacional de La Plata (UNLP) y el CONICET, desarroll\u00f3 un novedoso chip con un conjunto de marcadores moleculares, entre un grupo de 640.000, para bovinos de la Argentina de las razas Brangus, Braford y Brahman. La herramienta permitir\u00e1 a los criadores incorporar informaci\u00f3n gen\u00f3mica a la selecci\u00f3n de reproductores, para mejorar los rodeos en menos tiempo y a un menor costo, respecto de los valores internacionales. Esta nueva herramienta se denomin\u00f3 ArBos1 y obtuvo el premio en la categor\u00eda Investigaci\u00f3n Aplicada en la edici\u00f3n 2016 del Concurso Nacional de Innovaciones (Innovar). Seg\u00fan sus responsables, se trata de un desarrollo \u00fanico en la Argentina. A partir de ahora, los productores ganaderos podr\u00edan acceder en el pa\u00eds a un servicio de gen\u00f3mica que deb\u00edan realizar en el exterior y, con ello, agregar informaci\u00f3n gen\u00f3mica al pedigree y a los caracteres fenot\u00edpicos (caracter\u00edsticas de medici\u00f3n directa en los animales, como pesos y mediciones de res por ultrasonido). \u201cHasta la actualidad exist\u00eda un chip con caracter\u00edsticas similares, desarrollado por la empresa Illumina, que fue concebido para ser muy informativo para las razas Angus [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8912,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-8902","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El avance para conocer la huella digital de los bovinos | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El avance para conocer la huella digital de los bovinos | Proagro\" \/>\n<meta property=\"og:description\" content=\"Un grupo de investigadores de la Facultad de Agronom\u00eda de la UBA (FAUBA), el Instituto de Gen\u00e9tica Veterinaria de la Universidad Nacional de La Plata (UNLP) y el CONICET, desarroll\u00f3 un novedoso chip con un conjunto de marcadores moleculares, entre un grupo de 640.000, para bovinos de la Argentina de las razas Brangus, Braford y Brahman. La herramienta permitir\u00e1 a los criadores incorporar informaci\u00f3n gen\u00f3mica a la selecci\u00f3n de reproductores, para mejorar los rodeos en menos tiempo y a un menor costo, respecto de los valores internacionales. Esta nueva herramienta se denomin\u00f3 ArBos1 y obtuvo el premio en la categor\u00eda Investigaci\u00f3n Aplicada en la edici\u00f3n 2016 del Concurso Nacional de Innovaciones (Innovar). Seg\u00fan sus responsables, se trata de un desarrollo \u00fanico en la Argentina. A partir de ahora, los productores ganaderos podr\u00edan acceder en el pa\u00eds a un servicio de gen\u00f3mica que deb\u00edan realizar en el exterior y, con ello, agregar informaci\u00f3n gen\u00f3mica al pedigree y a los caracteres fenot\u00edpicos (caracter\u00edsticas de medici\u00f3n directa en los animales, como pesos y mediciones de res por ultrasonido). \u201cHasta la actualidad exist\u00eda un chip con caracter\u00edsticas similares, desarrollado por la empresa Illumina, que fue concebido para ser muy informativo para las razas Angus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-25T12:52:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-25T16:48:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/20161125-1145x395.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"El avance para conocer la huella digital de los bovinos\",\"datePublished\":\"2016-11-25T12:52:03+00:00\",\"dateModified\":\"2016-11-25T16:48:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/\"},\"wordCount\":589,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/20161125-1145x395.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/\",\"name\":\"El avance para conocer la huella digital de los bovinos | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/20161125-1145x395.jpg\",\"datePublished\":\"2016-11-25T12:52:03+00:00\",\"dateModified\":\"2016-11-25T16:48:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/20161125-1145x395.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/20161125-1145x395.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El avance para conocer la huella digital de los bovinos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El avance para conocer la huella digital de los bovinos | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/","og_locale":"en_US","og_type":"article","og_title":"El avance para conocer la huella digital de los bovinos | Proagro","og_description":"Un grupo de investigadores de la Facultad de Agronom\u00eda de la UBA (FAUBA), el Instituto de Gen\u00e9tica Veterinaria de la Universidad Nacional de La Plata (UNLP) y el CONICET, desarroll\u00f3 un novedoso chip con un conjunto de marcadores moleculares, entre un grupo de 640.000, para bovinos de la Argentina de las razas Brangus, Braford y Brahman. La herramienta permitir\u00e1 a los criadores incorporar informaci\u00f3n gen\u00f3mica a la selecci\u00f3n de reproductores, para mejorar los rodeos en menos tiempo y a un menor costo, respecto de los valores internacionales. Esta nueva herramienta se denomin\u00f3 ArBos1 y obtuvo el premio en la categor\u00eda Investigaci\u00f3n Aplicada en la edici\u00f3n 2016 del Concurso Nacional de Innovaciones (Innovar). Seg\u00fan sus responsables, se trata de un desarrollo \u00fanico en la Argentina. A partir de ahora, los productores ganaderos podr\u00edan acceder en el pa\u00eds a un servicio de gen\u00f3mica que deb\u00edan realizar en el exterior y, con ello, agregar informaci\u00f3n gen\u00f3mica al pedigree y a los caracteres fenot\u00edpicos (caracter\u00edsticas de medici\u00f3n directa en los animales, como pesos y mediciones de res por ultrasonido). \u201cHasta la actualidad exist\u00eda un chip con caracter\u00edsticas similares, desarrollado por la empresa Illumina, que fue concebido para ser muy informativo para las razas Angus [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-11-25T12:52:03+00:00","article_modified_time":"2016-11-25T16:48:10+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/20161125-1145x395.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"El avance para conocer la huella digital de los bovinos","datePublished":"2016-11-25T12:52:03+00:00","dateModified":"2016-11-25T16:48:10+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/"},"wordCount":589,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/20161125-1145x395.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/","url":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/","name":"El avance para conocer la huella digital de los bovinos | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/20161125-1145x395.jpg","datePublished":"2016-11-25T12:52:03+00:00","dateModified":"2016-11-25T16:48:10+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/20161125-1145x395.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/11\/20161125-1145x395.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/el-avance-para-conocer-la-huella-digital-de-los-bovinos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"El avance para conocer la huella digital de los bovinos"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8902"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/8912"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}