{"id":8782,"date":"2016-10-27T12:09:30","date_gmt":"2016-10-27T12:09:30","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=8782"},"modified":"2020-06-29T19:07:39","modified_gmt":"2020-06-29T19:07:39","slug":"dramatica-evacuacion-de-animales-en-los-campos-inundados","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/","title":{"rendered":"Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p><em>&#8220;Cruzamos tres lotes con un promedio de 80 cent\u00edmetros de agua&#8221;<\/em>. La frase es de <strong>Marcelo Boschi<\/strong> y describe una situaci\u00f3n dram\u00e1tica que vivi\u00f3 en el campo de su padre, ubicado a 5 kil\u00f3metros de <strong>General Villegas.<\/strong><\/p>\n<p>El s\u00e1bado pasado, luego de la muerte de tres animales, Boschi decidi\u00f3 trasladar la hacienda que estaba siendo amenazada por el agua. De zapatillas, con un equipo de gimnasia y la ayuda de un empleado, arre\u00f3 unos 100 animales para llevarlos hasta un lugar m\u00e1s seco.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"media-image\" title=\"dramatica evacuacion animales campos inundados\" src=\"http:\/\/news.agrofy.com.ar\/sites\/default\/files\/productor_hacienda_campo_agrofy_news.jpg\" alt=\"dramatica evacuacion animales campos inundados\" width=\"417\" height=\"309\" \/><\/p>\n<p><strong><em>Marcelo Boschi, con el agua hasta la cintura. Foto: Gentileza Marcelo Boschi.<\/em><\/strong><\/p>\n<p><em>&#8220;Fue de terror; los arreamos como pudimos. Hab\u00eda partes donde tapaba la altura de la tranquera, que es de 1,5 metros&#8221;<\/em>, cont\u00f3. <em>&#8220;En cualquier momento te tapa&#8221;<\/em>, le hab\u00eda avisado el empleado antes.<\/p>\n<p>Los animales quedaron en una loma de dos hect\u00e1reas. Ayer Boschi fue a verlos. Ahora espera que el agua empiece a correr.<em> &#8220;Si el tiempo acompa\u00f1a y el agua corre, no tendr\u00edamos que tener otro problema&#8221;<\/em>, cont\u00f3.<\/p>\n<p>En 2001, la zona tambi\u00e9n vivi\u00f3 un panorama complicado por los excesos de lluvias. Para Boschi, la situaci\u00f3n actual <em>&#8220;es muy parecida&#8221;<\/em> a ese entonces. Dice que su padre tiene <em>&#8220;angustia&#8221;<\/em> por lo que pasa en la regi\u00f3n. <em>&#8220;Contra el clima no se puede hacer nada, es una pena esto&#8221;<\/em>, subray\u00f3.<\/p>\n<p><strong>Fuente: http:\/\/www.lanacion.com.ar\/1950656-dramatica-evacuacion-de-animales-en-los-campos-inundados<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8220;Cruzamos tres lotes con un promedio de 80 cent\u00edmetros de agua&#8221;. La frase es de Marcelo Boschi y describe una situaci\u00f3n dram\u00e1tica que vivi\u00f3 en el campo de su padre, ubicado a 5 kil\u00f3metros de General Villegas. El s\u00e1bado pasado, luego de la muerte de tres animales, Boschi decidi\u00f3 trasladar la hacienda que estaba siendo amenazada por el agua. De zapatillas, con un equipo de gimnasia y la ayuda de un empleado, arre\u00f3 unos 100 animales para llevarlos hasta un lugar m\u00e1s seco. Marcelo Boschi, con el agua hasta la cintura. Foto: Gentileza Marcelo Boschi. &#8220;Fue de terror; los arreamos como pudimos. Hab\u00eda partes donde tapaba la altura de la tranquera, que es de 1,5 metros&#8221;, cont\u00f3. &#8220;En cualquier momento te tapa&#8221;, le hab\u00eda avisado el empleado antes. Los animales quedaron en una loma de dos hect\u00e1reas. Ayer Boschi fue a verlos. Ahora espera que el agua empiece a correr. &#8220;Si el tiempo acompa\u00f1a y el agua corre, no tendr\u00edamos que tener otro problema&#8221;, cont\u00f3. En 2001, la zona tambi\u00e9n vivi\u00f3 un panorama complicado por los excesos de lluvias. Para Boschi, la situaci\u00f3n actual &#8220;es muy parecida&#8221; a ese entonces. Dice que su padre tiene &#8220;angustia&#8221; por lo que pasa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8783,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-8782","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados | Proagro\" \/>\n<meta property=\"og:description\" content=\"&#8220;Cruzamos tres lotes con un promedio de 80 cent\u00edmetros de agua&#8221;. La frase es de Marcelo Boschi y describe una situaci\u00f3n dram\u00e1tica que vivi\u00f3 en el campo de su padre, ubicado a 5 kil\u00f3metros de General Villegas. El s\u00e1bado pasado, luego de la muerte de tres animales, Boschi decidi\u00f3 trasladar la hacienda que estaba siendo amenazada por el agua. De zapatillas, con un equipo de gimnasia y la ayuda de un empleado, arre\u00f3 unos 100 animales para llevarlos hasta un lugar m\u00e1s seco. Marcelo Boschi, con el agua hasta la cintura. Foto: Gentileza Marcelo Boschi. &#8220;Fue de terror; los arreamos como pudimos. Hab\u00eda partes donde tapaba la altura de la tranquera, que es de 1,5 metros&#8221;, cont\u00f3. &#8220;En cualquier momento te tapa&#8221;, le hab\u00eda avisado el empleado antes. Los animales quedaron en una loma de dos hect\u00e1reas. Ayer Boschi fue a verlos. Ahora espera que el agua empiece a correr. &#8220;Si el tiempo acompa\u00f1a y el agua corre, no tendr\u00edamos que tener otro problema&#8221;, cont\u00f3. En 2001, la zona tambi\u00e9n vivi\u00f3 un panorama complicado por los excesos de lluvias. Para Boschi, la situaci\u00f3n actual &#8220;es muy parecida&#8221; a ese entonces. Dice que su padre tiene &#8220;angustia&#8221; por lo que pasa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-27T12:09:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T19:07:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/10\/campo-2292061w620.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados\",\"datePublished\":\"2016-10-27T12:09:30+00:00\",\"dateModified\":\"2020-06-29T19:07:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/\"},\"wordCount\":244,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/campo-2292061w620.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/\",\"name\":\"Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/campo-2292061w620.jpg\",\"datePublished\":\"2016-10-27T12:09:30+00:00\",\"dateModified\":\"2020-06-29T19:07:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/campo-2292061w620.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/campo-2292061w620.jpg\",\"width\":620,\"height\":348},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/dramatica-evacuacion-de-animales-en-los-campos-inundados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/","og_locale":"en_US","og_type":"article","og_title":"Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados | Proagro","og_description":"&#8220;Cruzamos tres lotes con un promedio de 80 cent\u00edmetros de agua&#8221;. La frase es de Marcelo Boschi y describe una situaci\u00f3n dram\u00e1tica que vivi\u00f3 en el campo de su padre, ubicado a 5 kil\u00f3metros de General Villegas. El s\u00e1bado pasado, luego de la muerte de tres animales, Boschi decidi\u00f3 trasladar la hacienda que estaba siendo amenazada por el agua. De zapatillas, con un equipo de gimnasia y la ayuda de un empleado, arre\u00f3 unos 100 animales para llevarlos hasta un lugar m\u00e1s seco. Marcelo Boschi, con el agua hasta la cintura. Foto: Gentileza Marcelo Boschi. &#8220;Fue de terror; los arreamos como pudimos. Hab\u00eda partes donde tapaba la altura de la tranquera, que es de 1,5 metros&#8221;, cont\u00f3. &#8220;En cualquier momento te tapa&#8221;, le hab\u00eda avisado el empleado antes. Los animales quedaron en una loma de dos hect\u00e1reas. Ayer Boschi fue a verlos. Ahora espera que el agua empiece a correr. &#8220;Si el tiempo acompa\u00f1a y el agua corre, no tendr\u00edamos que tener otro problema&#8221;, cont\u00f3. En 2001, la zona tambi\u00e9n vivi\u00f3 un panorama complicado por los excesos de lluvias. Para Boschi, la situaci\u00f3n actual &#8220;es muy parecida&#8221; a ese entonces. Dice que su padre tiene &#8220;angustia&#8221; por lo que pasa [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-10-27T12:09:30+00:00","article_modified_time":"2020-06-29T19:07:39+00:00","og_image":[{"width":620,"height":348,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/10\/campo-2292061w620.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados","datePublished":"2016-10-27T12:09:30+00:00","dateModified":"2020-06-29T19:07:39+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/"},"wordCount":244,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/10\/campo-2292061w620.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/","url":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/","name":"Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/10\/campo-2292061w620.jpg","datePublished":"2016-10-27T12:09:30+00:00","dateModified":"2020-06-29T19:07:39+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/10\/campo-2292061w620.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/10\/campo-2292061w620.jpg","width":620,"height":348},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/dramatica-evacuacion-de-animales-en-los-campos-inundados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Dram\u00e1tica evacuaci\u00f3n de animales en los campos inundados"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8782"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8782\/revisions"}],"predecessor-version":[{"id":13953,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8782\/revisions\/13953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/8783"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}