{"id":8711,"date":"2016-10-14T14:37:18","date_gmt":"2016-10-14T14:37:18","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=8711"},"modified":"2016-10-14T18:08:26","modified_gmt":"2016-10-14T18:08:26","slug":"la-burlanda-gana-peso-estrategico-como-insumo-ganadero","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/","title":{"rendered":"La burlanda gana peso estrat\u00e9gico como insumo ganadero"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>El co-producto de la industria de biocombustibles es\u00a0clave para la intensificaci\u00f3n ganadera y cambi\u00f3 la producci\u00f3n de leche y carne en Estados Unidos.<\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/10\/burlanda-contiene-proteina-central-feedlotera_CLAIMA20161011_0307_28.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8712\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/10\/burlanda-contiene-proteina-central-feedlotera_CLAIMA20161011_0307_28-300x169.jpg\" alt=\"burlanda-contiene-proteina-central-feedlotera_claima20161011_0307_28\" width=\"300\" height=\"169\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/10\/burlanda-contiene-proteina-central-feedlotera_CLAIMA20161011_0307_28-300x169.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/10\/burlanda-contiene-proteina-central-feedlotera_CLAIMA20161011_0307_28.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p class=\"first-paragraph\">La burlanda h\u00fameda se convirti\u00f3 en el eje sobre el cual pivotea el proceso de intensificaci\u00f3n ganadera. Este co-producto de la agroindustria de fermentaci\u00f3n de cereales, particularmente ma\u00edz y sorgo, cambi\u00f3 el paradigma de la producci\u00f3n de carne y leche en los EE.UU.<\/p>\n<p>Los corrales de engorde, que en los 70 hab\u00edan migrado del corn belt a las zonas \u00e1ridas, de pronto se encontraron ante el desaf\u00edo de la abundancia de los WDGS (Wet Distillers Grains with Solubles). Es el residuo h\u00famedo que queda luego de la fermentaci\u00f3n y destilaci\u00f3n de granos para la obtenci\u00f3n de etanol y otros derivados.<\/p>\n<p>Entre el a\u00f1o 2000 y el 2010, se instalaron m\u00e1s de 200 nuevas plantas de etanol en el Medio Oeste de los EE.UU. En este per\u00edodo, el etanol se convirti\u00f3 en el mayor consumidor de ma\u00edz, superando al uso como forraje, jarabe de fructosa y otros destinos tradicionales. Hoy, un tercio de la cosecha norteamericana se destina a etanol, que ha sustituido al 10% de la nafta.<\/p>\n<p>Por cada 3 toneladas de ma\u00edz que se procesan para obtener este biocombustible, se obtiene una tonelada de etanol y 3 toneladas de WDGS, con un contenido de humedad del 25 al 30%. Este producto contiene hasta 30% de prote\u00edna y de 6 a 8% de aceite.<\/p>\n<p>En consecuencia, sustituye buena parte de la prote\u00edna necesaria en las raciones de engorde, y tiene una densidad energ\u00e9tica superior a la del ma\u00edz.<\/p>\n<p>El <strong>ing. agr. Carlos Mazzini<\/strong>,<strong> titular de Delam SA<\/strong>, dijo a<strong> Clar\u00edn Rural\u00a0<\/strong>que se puede incorporar un 40% en las raciones sin inconvenientes. Viene trabajando con burlanda h\u00fameda desde hace m\u00e1s de 20 a\u00f1os. Arranc\u00f3 con el feedlot Proteco, de Ignacio Rivarola. La burlanda proviene de una planta de alcohol de San Pedro que no tiene por destino el uso como combustible.<\/p>\n<p>Pero desde hace un tiempo, con la llegada al mercado de grandes vol\u00famenes de burlanda de las nuevas plantas del biocombustible instaladas en C\u00f3rdoba, Mazzini se encontr\u00f3 con nuevas necesidades. Y oportunidades.<\/p>\n<p>Las empresas del eje Villa Mar\u00eda-Rio Cuarto-Alejandro Roca necesitan evacuar continuamente este producto, que es altamente perecedero. La demanda, por su parte, requiere seguridad de abastecimiento, no puede estar sometida a alguna eventual parada t\u00e9cnica del proveedor. Lo que hizo Delam SA fue establecer una log\u00edstica que permite garantizar una salida continua y un abastecimiento seguro durante todo el a\u00f1o. Para ello, coordina con sus clientes la entrega \u201cjust in time\u201d de los vol\u00famenes programados.<\/p>\n<p>El precio de la burlanda est\u00e1 relacionado con el del ma\u00edz. <em>\u201cCuando se est\u00e1 cerca de la planta, puede valer de un 10 a un 15% menos \u2013sostiene-. A medida que el consumidor se aleja, el descuento desaparece y puede llegar a valer un 10% m\u00e1s. Igual, es un insumo muy barato, expresado en materia seca, si se considera el precio de la prote\u00edna y la energ\u00eda de otras fuentes\u201d<\/em>.<\/p>\n<p>La aceptaci\u00f3n del producto y la nueva log\u00edstica se expresan en un fuerte crecimiento de la demanda. Hace un a\u00f1o, Mazzini se preocupaba por la posible instalaci\u00f3n de nuevas plantas de etanol, que podr\u00edan generar una sobreoferta de WDGS.<em> \u201cAhora tenemos una expectativa muy favorable, porque los productores ya se convencieron del valor de este recurso\u201d.<\/em><\/p>\n<p>Un paso clave en la era de la ganader\u00eda 360.<\/p>\n<p><strong>Por H\u00e9ctor Huergo.\u00a0http:\/\/www.clarin.com\/rural\/burlanda-peso-estrategico-insumo-ganadero_0_1666633462.html<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El co-producto de la industria de biocombustibles es\u00a0clave para la intensificaci\u00f3n ganadera y cambi\u00f3 la producci\u00f3n de leche y carne en Estados Unidos. La burlanda h\u00fameda se convirti\u00f3 en el eje sobre el cual pivotea el proceso de intensificaci\u00f3n ganadera. Este co-producto de la agroindustria de fermentaci\u00f3n de cereales, particularmente ma\u00edz y sorgo, cambi\u00f3 el paradigma de la producci\u00f3n de carne y leche en los EE.UU. Los corrales de engorde, que en los 70 hab\u00edan migrado del corn belt a las zonas \u00e1ridas, de pronto se encontraron ante el desaf\u00edo de la abundancia de los WDGS (Wet Distillers Grains with Solubles). Es el residuo h\u00famedo que queda luego de la fermentaci\u00f3n y destilaci\u00f3n de granos para la obtenci\u00f3n de etanol y otros derivados. Entre el a\u00f1o 2000 y el 2010, se instalaron m\u00e1s de 200 nuevas plantas de etanol en el Medio Oeste de los EE.UU. En este per\u00edodo, el etanol se convirti\u00f3 en el mayor consumidor de ma\u00edz, superando al uso como forraje, jarabe de fructosa y otros destinos tradicionales. Hoy, un tercio de la cosecha norteamericana se destina a etanol, que ha sustituido al 10% de la nafta. Por cada 3 toneladas de ma\u00edz que se procesan para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8718,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-8711","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La burlanda gana peso estrat\u00e9gico como insumo ganadero | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La burlanda gana peso estrat\u00e9gico como insumo ganadero | Proagro\" \/>\n<meta property=\"og:description\" content=\"El co-producto de la industria de biocombustibles es\u00a0clave para la intensificaci\u00f3n ganadera y cambi\u00f3 la producci\u00f3n de leche y carne en Estados Unidos. La burlanda h\u00fameda se convirti\u00f3 en el eje sobre el cual pivotea el proceso de intensificaci\u00f3n ganadera. Este co-producto de la agroindustria de fermentaci\u00f3n de cereales, particularmente ma\u00edz y sorgo, cambi\u00f3 el paradigma de la producci\u00f3n de carne y leche en los EE.UU. Los corrales de engorde, que en los 70 hab\u00edan migrado del corn belt a las zonas \u00e1ridas, de pronto se encontraron ante el desaf\u00edo de la abundancia de los WDGS (Wet Distillers Grains with Solubles). Es el residuo h\u00famedo que queda luego de la fermentaci\u00f3n y destilaci\u00f3n de granos para la obtenci\u00f3n de etanol y otros derivados. Entre el a\u00f1o 2000 y el 2010, se instalaron m\u00e1s de 200 nuevas plantas de etanol en el Medio Oeste de los EE.UU. En este per\u00edodo, el etanol se convirti\u00f3 en el mayor consumidor de ma\u00edz, superando al uso como forraje, jarabe de fructosa y otros destinos tradicionales. Hoy, un tercio de la cosecha norteamericana se destina a etanol, que ha sustituido al 10% de la nafta. Por cada 3 toneladas de ma\u00edz que se procesan para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-14T14:37:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-14T18:08:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/14102016-1145x395.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"La burlanda gana peso estrat\u00e9gico como insumo ganadero\",\"datePublished\":\"2016-10-14T14:37:18+00:00\",\"dateModified\":\"2016-10-14T18:08:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/\"},\"wordCount\":617,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/14102016-1145x395.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/\",\"name\":\"La burlanda gana peso estrat\u00e9gico como insumo ganadero | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/14102016-1145x395.jpg\",\"datePublished\":\"2016-10-14T14:37:18+00:00\",\"dateModified\":\"2016-10-14T18:08:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/14102016-1145x395.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/14102016-1145x395.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La burlanda gana peso estrat\u00e9gico como insumo ganadero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La burlanda gana peso estrat\u00e9gico como insumo ganadero | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/","og_locale":"en_US","og_type":"article","og_title":"La burlanda gana peso estrat\u00e9gico como insumo ganadero | Proagro","og_description":"El co-producto de la industria de biocombustibles es\u00a0clave para la intensificaci\u00f3n ganadera y cambi\u00f3 la producci\u00f3n de leche y carne en Estados Unidos. La burlanda h\u00fameda se convirti\u00f3 en el eje sobre el cual pivotea el proceso de intensificaci\u00f3n ganadera. Este co-producto de la agroindustria de fermentaci\u00f3n de cereales, particularmente ma\u00edz y sorgo, cambi\u00f3 el paradigma de la producci\u00f3n de carne y leche en los EE.UU. Los corrales de engorde, que en los 70 hab\u00edan migrado del corn belt a las zonas \u00e1ridas, de pronto se encontraron ante el desaf\u00edo de la abundancia de los WDGS (Wet Distillers Grains with Solubles). Es el residuo h\u00famedo que queda luego de la fermentaci\u00f3n y destilaci\u00f3n de granos para la obtenci\u00f3n de etanol y otros derivados. Entre el a\u00f1o 2000 y el 2010, se instalaron m\u00e1s de 200 nuevas plantas de etanol en el Medio Oeste de los EE.UU. En este per\u00edodo, el etanol se convirti\u00f3 en el mayor consumidor de ma\u00edz, superando al uso como forraje, jarabe de fructosa y otros destinos tradicionales. Hoy, un tercio de la cosecha norteamericana se destina a etanol, que ha sustituido al 10% de la nafta. Por cada 3 toneladas de ma\u00edz que se procesan para [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-10-14T14:37:18+00:00","article_modified_time":"2016-10-14T18:08:26+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/14102016-1145x395.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"La burlanda gana peso estrat\u00e9gico como insumo ganadero","datePublished":"2016-10-14T14:37:18+00:00","dateModified":"2016-10-14T18:08:26+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/"},"wordCount":617,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/14102016-1145x395.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/","url":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/","name":"La burlanda gana peso estrat\u00e9gico como insumo ganadero | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/14102016-1145x395.jpg","datePublished":"2016-10-14T14:37:18+00:00","dateModified":"2016-10-14T18:08:26+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/14102016-1145x395.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/14102016-1145x395.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/la-burlanda-gana-peso-estrategico-como-insumo-ganadero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"La burlanda gana peso estrat\u00e9gico como insumo ganadero"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8711"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8711\/revisions"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}