{"id":8402,"date":"2016-08-19T15:16:39","date_gmt":"2016-08-19T15:16:39","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=8402"},"modified":"2016-08-19T15:33:23","modified_gmt":"2016-08-19T15:33:23","slug":"inundaciones-destinan-casi-50-millones-a-productores-cordobeses","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/","title":{"rendered":"Inundaciones: destinan casi $ 50 millones a productores cordobeses"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p class=\"primero\"><strong>Ministerio de Agroindustria<\/strong> firm\u00f3 hoy dos convenios para asistir a productores tamberos y ganaderos de carne de la provincia de C\u00f3rdoba. La ayuda se da en el marco de la situaci\u00f3n de emergencia agropecuaria de la provincia por las \u00faltimas contingencias clim\u00e1ticas.<\/p>\n<p>El primer convenio destinar\u00e1 $ 9.979.540 a la reparaci\u00f3n y recuperaci\u00f3n parcial de los caminos troncales de la red secundaria no pavimentada de la zona afectada, en el centro sur y este cordob\u00e9s.<\/p>\n<aside class=\"banner caja2\" data-adpos=\"caja2\">\n<div id=\"eplAdDivcaja2\">En tanto, el segundo acuerdo ser\u00e1 por $ 39.997.250 entre ayuda directa a los productores e indirecta, en este \u00faltimo caso con la reparaci\u00f3n de caminos rurales y el aporte de suplementaci\u00f3n alimentaria para el ganado bovino de carne y leche y la reparaci\u00f3n de caminos.<\/div>\n<\/aside>\n<figure class=\"S encolumnada relacionada\">\n<div class=\"conModal f-imagenRelacionada\" data-notaid=\"1929470\" data-imagenid=\"2254911\" data-tipo=\"imagen\" data-extension=\"jpg\" data-esrelacionada=\"1\"><img decoding=\"async\" id=\"imagen_2254911\" class=\"f-sinGif\" src=\"http:\/\/bucket2.glanacion.com\/anexos\/fotos\/11\/campo-2254911w280.jpg\" alt=\"El gobierno nacional asistir\u00e1 a productores de C\u00f3rdoba\" data-imagenid=\"2254911\" \/><\/div><figcaption id=\"epigrafe2254911\"><\/figcaption><\/figure>\n<p>En este contexto, el secretario de <strong>Coordinaci\u00f3n y Desarrollo Territorial del Ministerio de Agroindustria, Santiago Hardie<\/strong>, y el <strong>subsecretario de Coordinaci\u00f3n Pol\u00edtica, Hugo Rossi,<\/strong> visitaron junto al <strong>ministro de Agricultura y Ganader\u00eda de C\u00f3rdoba, Sergio Busso,<\/strong> a productores de la provincia.<\/p>\n<p><strong>Fuente: La Naci\u00f3n<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ministerio de Agroindustria firm\u00f3 hoy dos convenios para asistir a productores tamberos y ganaderos de carne de la provincia de C\u00f3rdoba. La ayuda se da en el marco de la situaci\u00f3n de emergencia agropecuaria de la provincia por las \u00faltimas contingencias clim\u00e1ticas. El primer convenio destinar\u00e1 $ 9.979.540 a la reparaci\u00f3n y recuperaci\u00f3n parcial de los caminos troncales de la red secundaria no pavimentada de la zona afectada, en el centro sur y este cordob\u00e9s. En tanto, el segundo acuerdo ser\u00e1 por $ 39.997.250 entre ayuda directa a los productores e indirecta, en este \u00faltimo caso con la reparaci\u00f3n de caminos rurales y el aporte de suplementaci\u00f3n alimentaria para el ganado bovino de carne y leche y la reparaci\u00f3n de caminos. En este contexto, el secretario de Coordinaci\u00f3n y Desarrollo Territorial del Ministerio de Agroindustria, Santiago Hardie, y el subsecretario de Coordinaci\u00f3n Pol\u00edtica, Hugo Rossi, visitaron junto al ministro de Agricultura y Ganader\u00eda de C\u00f3rdoba, Sergio Busso, a productores de la provincia. Fuente: La Naci\u00f3n<\/p>\n","protected":false},"author":3,"featured_media":8409,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-8402","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inundaciones: destinan casi $ 50 millones a productores cordobeses | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inundaciones: destinan casi $ 50 millones a productores cordobeses | Proagro\" \/>\n<meta property=\"og:description\" content=\"Ministerio de Agroindustria firm\u00f3 hoy dos convenios para asistir a productores tamberos y ganaderos de carne de la provincia de C\u00f3rdoba. La ayuda se da en el marco de la situaci\u00f3n de emergencia agropecuaria de la provincia por las \u00faltimas contingencias clim\u00e1ticas. El primer convenio destinar\u00e1 $ 9.979.540 a la reparaci\u00f3n y recuperaci\u00f3n parcial de los caminos troncales de la red secundaria no pavimentada de la zona afectada, en el centro sur y este cordob\u00e9s. En tanto, el segundo acuerdo ser\u00e1 por $ 39.997.250 entre ayuda directa a los productores e indirecta, en este \u00faltimo caso con la reparaci\u00f3n de caminos rurales y el aporte de suplementaci\u00f3n alimentaria para el ganado bovino de carne y leche y la reparaci\u00f3n de caminos. En este contexto, el secretario de Coordinaci\u00f3n y Desarrollo Territorial del Ministerio de Agroindustria, Santiago Hardie, y el subsecretario de Coordinaci\u00f3n Pol\u00edtica, Hugo Rossi, visitaron junto al ministro de Agricultura y Ganader\u00eda de C\u00f3rdoba, Sergio Busso, a productores de la provincia. Fuente: La Naci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-19T15:16:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-19T15:33:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/15082016-1145x395.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Inundaciones: destinan casi $ 50 millones a productores cordobeses\",\"datePublished\":\"2016-08-19T15:16:39+00:00\",\"dateModified\":\"2016-08-19T15:33:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/\"},\"wordCount\":185,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/15082016-1145x395.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/\",\"name\":\"Inundaciones: destinan casi $ 50 millones a productores cordobeses | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/15082016-1145x395.jpg\",\"datePublished\":\"2016-08-19T15:16:39+00:00\",\"dateModified\":\"2016-08-19T15:33:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/15082016-1145x395.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/15082016-1145x395.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inundaciones: destinan casi $ 50 millones a productores cordobeses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inundaciones: destinan casi $ 50 millones a productores cordobeses | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/","og_locale":"en_US","og_type":"article","og_title":"Inundaciones: destinan casi $ 50 millones a productores cordobeses | Proagro","og_description":"Ministerio de Agroindustria firm\u00f3 hoy dos convenios para asistir a productores tamberos y ganaderos de carne de la provincia de C\u00f3rdoba. La ayuda se da en el marco de la situaci\u00f3n de emergencia agropecuaria de la provincia por las \u00faltimas contingencias clim\u00e1ticas. El primer convenio destinar\u00e1 $ 9.979.540 a la reparaci\u00f3n y recuperaci\u00f3n parcial de los caminos troncales de la red secundaria no pavimentada de la zona afectada, en el centro sur y este cordob\u00e9s. En tanto, el segundo acuerdo ser\u00e1 por $ 39.997.250 entre ayuda directa a los productores e indirecta, en este \u00faltimo caso con la reparaci\u00f3n de caminos rurales y el aporte de suplementaci\u00f3n alimentaria para el ganado bovino de carne y leche y la reparaci\u00f3n de caminos. En este contexto, el secretario de Coordinaci\u00f3n y Desarrollo Territorial del Ministerio de Agroindustria, Santiago Hardie, y el subsecretario de Coordinaci\u00f3n Pol\u00edtica, Hugo Rossi, visitaron junto al ministro de Agricultura y Ganader\u00eda de C\u00f3rdoba, Sergio Busso, a productores de la provincia. Fuente: La Naci\u00f3n","og_url":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-08-19T15:16:39+00:00","article_modified_time":"2016-08-19T15:33:23+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/15082016-1145x395.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Inundaciones: destinan casi $ 50 millones a productores cordobeses","datePublished":"2016-08-19T15:16:39+00:00","dateModified":"2016-08-19T15:33:23+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/"},"wordCount":185,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/15082016-1145x395.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/","url":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/","name":"Inundaciones: destinan casi $ 50 millones a productores cordobeses | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/15082016-1145x395.jpg","datePublished":"2016-08-19T15:16:39+00:00","dateModified":"2016-08-19T15:33:23+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/15082016-1145x395.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/15082016-1145x395.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/inundaciones-destinan-casi-50-millones-a-productores-cordobeses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Inundaciones: destinan casi $ 50 millones a productores cordobeses"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8402"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8402\/revisions"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}