{"id":8368,"date":"2016-08-16T19:44:50","date_gmt":"2016-08-16T19:44:50","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=8368"},"modified":"2020-06-29T19:11:06","modified_gmt":"2020-06-29T19:11:06","slug":"aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/","title":{"rendered":"Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72%"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>El mes pasado\u00a0se registr\u00f3 el mayor porcentaje de los \u00faltimos 4 a\u00f1os. Y ya se hacen animales m\u00e1s pesados, a pesar del alto precio del ma\u00edz.<\/p>\n<p class=\"first-paragraph\">En julio, la ocupaci\u00f3n de los establecimientos de engorde a corral fue del 72 por ciento, marcando por segundo mes consecutivo un aumento en la cantidad de animales ingresados a los sistemas intensivos y la mayor ocupaci\u00f3n de los \u00faltimos cuatro a\u00f1os para el mes de julio. As\u00ed lo asegur\u00f3 la<strong> C\u00e1mara Argentina de Feedlot (CAF) en su \u00faltimo informe.<\/strong><\/p>\n<p><em>\u201cLas se\u00f1ales positivas que mostraba mayo para el negocio se mantienen. M\u00e1s all\u00e1 de continuar con un precio del ma\u00edz muy elevado, la mejor relaci\u00f3n entre la compra de invernada y la venta de animales a faena se mantiene y los valores de ternero y novillito gordos contin\u00faan cercanos, sosteniendo el inter\u00e9s por llevar al mercado animales terminados m\u00e1s pesados, mejorando la eficiencia del sistema\u201d<\/em>, afirm\u00f3 la CAF.<\/p>\n<p>Pero luego advirti\u00f3 que a pesar de la foto positiva, es incierto el valor que tendr\u00e1 el novillo\/ternero gordo dentro de tres o cuatro meses, cuando se vuelquen al mercado los animales hoy encerrados.<\/p>\n<p>El informe enumer\u00f3 diversas razones por las que el env\u00edo de animales a faena ser\u00eda m\u00e1s gradual, y destac\u00f3 que el mercado contin\u00faa valorizando la calidad y homogeneidad que aportan los animales terminados en feedlot.<\/p>\n<p><em>\u201cM\u00e1s all\u00e1 de la rentabilidad actual del negocio, estamos en un momento de cambio en la producci\u00f3n, donde la eficiencia pasa a ser clave y donde podemos lograr una consolidaci\u00f3n de toda la cadena. Es necesario para poder lograr esto que las reglas sean establecidas de manera clara y que las medidas de gobierno no generen un desaliento frente a este momento de cambio que se vislumbra como favorable. En este sentido, es un buen auspicio la consolidaci\u00f3n y crecimiento de la Mesa Nacional de Carnes\u201d<\/em>, remarc\u00f3 la C\u00e1mara.<\/p>\n<p><strong>Fuente:\u00a0http:\/\/www.clarin.com\/rural\/Aumento-ocupacion-feedlots-julio-llego_0_1630637041.html<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El mes pasado\u00a0se registr\u00f3 el mayor porcentaje de los \u00faltimos 4 a\u00f1os. Y ya se hacen animales m\u00e1s pesados, a pesar del alto precio del ma\u00edz. En julio, la ocupaci\u00f3n de los establecimientos de engorde a corral fue del 72 por ciento, marcando por segundo mes consecutivo un aumento en la cantidad de animales ingresados a los sistemas intensivos y la mayor ocupaci\u00f3n de los \u00faltimos cuatro a\u00f1os para el mes de julio. As\u00ed lo asegur\u00f3 la C\u00e1mara Argentina de Feedlot (CAF) en su \u00faltimo informe. \u201cLas se\u00f1ales positivas que mostraba mayo para el negocio se mantienen. M\u00e1s all\u00e1 de continuar con un precio del ma\u00edz muy elevado, la mejor relaci\u00f3n entre la compra de invernada y la venta de animales a faena se mantiene y los valores de ternero y novillito gordos contin\u00faan cercanos, sosteniendo el inter\u00e9s por llevar al mercado animales terminados m\u00e1s pesados, mejorando la eficiencia del sistema\u201d, afirm\u00f3 la CAF. Pero luego advirti\u00f3 que a pesar de la foto positiva, es incierto el valor que tendr\u00e1 el novillo\/ternero gordo dentro de tres o cuatro meses, cuando se vuelquen al mercado los animales hoy encerrados. El informe enumer\u00f3 diversas razones por las que el env\u00edo de animales [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8370,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-8368","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72% | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72% | Proagro\" \/>\n<meta property=\"og:description\" content=\"El mes pasado\u00a0se registr\u00f3 el mayor porcentaje de los \u00faltimos 4 a\u00f1os. Y ya se hacen animales m\u00e1s pesados, a pesar del alto precio del ma\u00edz. En julio, la ocupaci\u00f3n de los establecimientos de engorde a corral fue del 72 por ciento, marcando por segundo mes consecutivo un aumento en la cantidad de animales ingresados a los sistemas intensivos y la mayor ocupaci\u00f3n de los \u00faltimos cuatro a\u00f1os para el mes de julio. As\u00ed lo asegur\u00f3 la C\u00e1mara Argentina de Feedlot (CAF) en su \u00faltimo informe. \u201cLas se\u00f1ales positivas que mostraba mayo para el negocio se mantienen. M\u00e1s all\u00e1 de continuar con un precio del ma\u00edz muy elevado, la mejor relaci\u00f3n entre la compra de invernada y la venta de animales a faena se mantiene y los valores de ternero y novillito gordos contin\u00faan cercanos, sosteniendo el inter\u00e9s por llevar al mercado animales terminados m\u00e1s pesados, mejorando la eficiencia del sistema\u201d, afirm\u00f3 la CAF. Pero luego advirti\u00f3 que a pesar de la foto positiva, es incierto el valor que tendr\u00e1 el novillo\/ternero gordo dentro de tres o cuatro meses, cuando se vuelquen al mercado los animales hoy encerrados. El informe enumer\u00f3 diversas razones por las que el env\u00edo de animales [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-16T19:44:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T19:11:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/08\/feedloteros-mercado-calidad-homogeneidad-producen_CLAIMA20160812_0220_28.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72%\",\"datePublished\":\"2016-08-16T19:44:50+00:00\",\"dateModified\":\"2020-06-29T19:11:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/\"},\"wordCount\":359,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/feedloteros-mercado-calidad-homogeneidad-producen_CLAIMA20160812_0220_28.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/\",\"name\":\"Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72% | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/feedloteros-mercado-calidad-homogeneidad-producen_CLAIMA20160812_0220_28.jpg\",\"datePublished\":\"2016-08-16T19:44:50+00:00\",\"dateModified\":\"2020-06-29T19:11:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/feedloteros-mercado-calidad-homogeneidad-producen_CLAIMA20160812_0220_28.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/feedloteros-mercado-calidad-homogeneidad-producen_CLAIMA20160812_0220_28.jpg\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72% | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/","og_locale":"en_US","og_type":"article","og_title":"Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72% | Proagro","og_description":"El mes pasado\u00a0se registr\u00f3 el mayor porcentaje de los \u00faltimos 4 a\u00f1os. Y ya se hacen animales m\u00e1s pesados, a pesar del alto precio del ma\u00edz. En julio, la ocupaci\u00f3n de los establecimientos de engorde a corral fue del 72 por ciento, marcando por segundo mes consecutivo un aumento en la cantidad de animales ingresados a los sistemas intensivos y la mayor ocupaci\u00f3n de los \u00faltimos cuatro a\u00f1os para el mes de julio. As\u00ed lo asegur\u00f3 la C\u00e1mara Argentina de Feedlot (CAF) en su \u00faltimo informe. \u201cLas se\u00f1ales positivas que mostraba mayo para el negocio se mantienen. M\u00e1s all\u00e1 de continuar con un precio del ma\u00edz muy elevado, la mejor relaci\u00f3n entre la compra de invernada y la venta de animales a faena se mantiene y los valores de ternero y novillito gordos contin\u00faan cercanos, sosteniendo el inter\u00e9s por llevar al mercado animales terminados m\u00e1s pesados, mejorando la eficiencia del sistema\u201d, afirm\u00f3 la CAF. Pero luego advirti\u00f3 que a pesar de la foto positiva, es incierto el valor que tendr\u00e1 el novillo\/ternero gordo dentro de tres o cuatro meses, cuando se vuelquen al mercado los animales hoy encerrados. El informe enumer\u00f3 diversas razones por las que el env\u00edo de animales [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-08-16T19:44:50+00:00","article_modified_time":"2020-06-29T19:11:06+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/08\/feedloteros-mercado-calidad-homogeneidad-producen_CLAIMA20160812_0220_28.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72%","datePublished":"2016-08-16T19:44:50+00:00","dateModified":"2020-06-29T19:11:06+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/"},"wordCount":359,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/08\/feedloteros-mercado-calidad-homogeneidad-producen_CLAIMA20160812_0220_28.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/","url":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/","name":"Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72% | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/08\/feedloteros-mercado-calidad-homogeneidad-producen_CLAIMA20160812_0220_28.jpg","datePublished":"2016-08-16T19:44:50+00:00","dateModified":"2020-06-29T19:11:06+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/08\/feedloteros-mercado-calidad-homogeneidad-producen_CLAIMA20160812_0220_28.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/08\/feedloteros-mercado-calidad-homogeneidad-producen_CLAIMA20160812_0220_28.jpg","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/aumento-el-nivel-de-ocupacion-en-los-feedlots-y-en-julio-llego-al-72\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Aument\u00f3 el nivel de ocupaci\u00f3n en los feedlots y en julio lleg\u00f3 al 72%"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8368"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8368\/revisions"}],"predecessor-version":[{"id":13973,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8368\/revisions\/13973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/8370"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}