{"id":8207,"date":"2016-07-18T14:14:17","date_gmt":"2016-07-18T14:14:17","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=8207"},"modified":"2020-06-29T19:13:16","modified_gmt":"2020-06-29T19:13:16","slug":"comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/","title":{"rendered":"Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Despu\u00e9s de 14 a\u00f1os, un presidente volver\u00e1 a la muestra. Adem\u00e1s, la Sociedad\u00a0Rural\u00a0festeja sus 150 a\u00f1os. Hay 450 stands y 4.500 expositores.<\/p>\n<p class=\"first-paragraph\">El 16 de julio comenz\u00f3 una nueva edici\u00f3n de <strong>La Rural de Palermo,<\/strong> en un a\u00f1o en el que adem\u00e1s de las tradicionales juras de las razas bovinas, equinas y ovinas, entre otros animales, y los stands de las empresas de maquinaria agr\u00edcola habr\u00e1 conferencias sobre ganader\u00eda y agronegocios, en el marco del <strong>150 aniversario de la expo<\/strong>.<\/p>\n<p>Hay dos eventos que se desarrollar\u00e1n en estas dos semanas: el Congreso de Agronegocios, que se realizar\u00e1 el 18 y 19 de julio en el auditorio principal -bajo el lema \u201cLa Competitividad\u201d-, y el Foro Argentino de Gen\u00e9tica Bovina, que se llevar\u00e1 adelante el 23 de julio.<\/p>\n<p>Tambi\u00e9n se organizar\u00e1n charlas muy interesantes todos los d\u00edas. El 20 de julio, por ejemplo, la Mesa de Carnes organiza la jornada \u201cCarnes para la Argentina y el Mundo\u201d (en el auditorio rojo, de 10 a 13). Disertar\u00e1n, entre otros, los asesores <strong>Fernando Canosa<\/strong> y <strong>V\u00edctor Tonelli, David Lacroze<\/strong> (coordinador de la Cadena de Carnes) y Nicol\u00e1s Braun (La An\u00f3nima).<\/p>\n<p>Adem\u00e1s, dialogar\u00e1n los referentes de las 25 instituciones que forman la Mesa de las Carnes y est\u00e1n previstas las conferencias de <strong>Ricardo Buryaile<\/strong>, ministro de Agroindustria, y el economista<strong> Javier Gonz\u00e1lez Fraga<\/strong> (inscripciones al mail: mesadelascarnes@gmail.com).<\/p>\n<p>Este a\u00f1o, el primer animal que lleg\u00f3 a la feria fue Bautista, un ternero de 10 meses de la raza Angus y un peso de 430 kilos, que pertenece a la caba\u00f1a \u201cDon Rodolfo\u201d de Tres Sargentos, provincia de Buenos Aires.<\/p>\n<p>La exposici\u00f3n, que contar\u00e1 con m\u00e1s de 450 stands y 4.500 expositores, se podr\u00e1 visitar hasta el 31 de julio de 9 a 20. El costo de la entrada es de 90 pesos los d\u00edas de semana y de 100 pesos los feriados. Los menores de 8 a\u00f1os ingresan sin cargo, lo mismo que los estudiantes de agronom\u00eda y veterinaria que presenten su libreta. Tambi\u00e9n hay descuentos especiales para jubilados.<\/p>\n<p><strong>Fuentes:\u00a0http:\/\/www.clarin.com\/rural\/Comenzo-predio-Palermo-exposicion-diferente_0_1613838790.html<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de 14 a\u00f1os, un presidente volver\u00e1 a la muestra. Adem\u00e1s, la Sociedad\u00a0Rural\u00a0festeja sus 150 a\u00f1os. Hay 450 stands y 4.500 expositores. El 16 de julio comenz\u00f3 una nueva edici\u00f3n de La Rural de Palermo, en un a\u00f1o en el que adem\u00e1s de las tradicionales juras de las razas bovinas, equinas y ovinas, entre otros animales, y los stands de las empresas de maquinaria agr\u00edcola habr\u00e1 conferencias sobre ganader\u00eda y agronegocios, en el marco del 150 aniversario de la expo. Hay dos eventos que se desarrollar\u00e1n en estas dos semanas: el Congreso de Agronegocios, que se realizar\u00e1 el 18 y 19 de julio en el auditorio principal -bajo el lema \u201cLa Competitividad\u201d-, y el Foro Argentino de Gen\u00e9tica Bovina, que se llevar\u00e1 adelante el 23 de julio. Tambi\u00e9n se organizar\u00e1n charlas muy interesantes todos los d\u00edas. El 20 de julio, por ejemplo, la Mesa de Carnes organiza la jornada \u201cCarnes para la Argentina y el Mundo\u201d (en el auditorio rojo, de 10 a 13). Disertar\u00e1n, entre otros, los asesores Fernando Canosa y V\u00edctor Tonelli, David Lacroze (coordinador de la Cadena de Carnes) y Nicol\u00e1s Braun (La An\u00f3nima). Adem\u00e1s, dialogar\u00e1n los referentes de las 25 instituciones que forman la Mesa de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8208,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[80,191],"class_list":["post-8207","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","tag-ganaderia","tag-la-rural","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente | Proagro\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de 14 a\u00f1os, un presidente volver\u00e1 a la muestra. Adem\u00e1s, la Sociedad\u00a0Rural\u00a0festeja sus 150 a\u00f1os. Hay 450 stands y 4.500 expositores. El 16 de julio comenz\u00f3 una nueva edici\u00f3n de La Rural de Palermo, en un a\u00f1o en el que adem\u00e1s de las tradicionales juras de las razas bovinas, equinas y ovinas, entre otros animales, y los stands de las empresas de maquinaria agr\u00edcola habr\u00e1 conferencias sobre ganader\u00eda y agronegocios, en el marco del 150 aniversario de la expo. Hay dos eventos que se desarrollar\u00e1n en estas dos semanas: el Congreso de Agronegocios, que se realizar\u00e1 el 18 y 19 de julio en el auditorio principal -bajo el lema \u201cLa Competitividad\u201d-, y el Foro Argentino de Gen\u00e9tica Bovina, que se llevar\u00e1 adelante el 23 de julio. Tambi\u00e9n se organizar\u00e1n charlas muy interesantes todos los d\u00edas. El 20 de julio, por ejemplo, la Mesa de Carnes organiza la jornada \u201cCarnes para la Argentina y el Mundo\u201d (en el auditorio rojo, de 10 a 13). Disertar\u00e1n, entre otros, los asesores Fernando Canosa y V\u00edctor Tonelli, David Lacroze (coordinador de la Cadena de Carnes) y Nicol\u00e1s Braun (La An\u00f3nima). Adem\u00e1s, dialogar\u00e1n los referentes de las 25 instituciones que forman la Mesa de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-18T14:14:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T19:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/DSC03984-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente\",\"datePublished\":\"2016-07-18T14:14:17+00:00\",\"dateModified\":\"2020-06-29T19:13:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/\"},\"wordCount\":367,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/DSC03984-scaled.jpg\",\"keywords\":[\"Ganader\u00eda\",\"la rural\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/\",\"name\":\"Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/DSC03984-scaled.jpg\",\"datePublished\":\"2016-07-18T14:14:17+00:00\",\"dateModified\":\"2020-06-29T19:13:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/DSC03984-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/DSC03984-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/","og_locale":"en_US","og_type":"article","og_title":"Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente | Proagro","og_description":"Despu\u00e9s de 14 a\u00f1os, un presidente volver\u00e1 a la muestra. Adem\u00e1s, la Sociedad\u00a0Rural\u00a0festeja sus 150 a\u00f1os. Hay 450 stands y 4.500 expositores. El 16 de julio comenz\u00f3 una nueva edici\u00f3n de La Rural de Palermo, en un a\u00f1o en el que adem\u00e1s de las tradicionales juras de las razas bovinas, equinas y ovinas, entre otros animales, y los stands de las empresas de maquinaria agr\u00edcola habr\u00e1 conferencias sobre ganader\u00eda y agronegocios, en el marco del 150 aniversario de la expo. Hay dos eventos que se desarrollar\u00e1n en estas dos semanas: el Congreso de Agronegocios, que se realizar\u00e1 el 18 y 19 de julio en el auditorio principal -bajo el lema \u201cLa Competitividad\u201d-, y el Foro Argentino de Gen\u00e9tica Bovina, que se llevar\u00e1 adelante el 23 de julio. Tambi\u00e9n se organizar\u00e1n charlas muy interesantes todos los d\u00edas. El 20 de julio, por ejemplo, la Mesa de Carnes organiza la jornada \u201cCarnes para la Argentina y el Mundo\u201d (en el auditorio rojo, de 10 a 13). Disertar\u00e1n, entre otros, los asesores Fernando Canosa y V\u00edctor Tonelli, David Lacroze (coordinador de la Cadena de Carnes) y Nicol\u00e1s Braun (La An\u00f3nima). Adem\u00e1s, dialogar\u00e1n los referentes de las 25 instituciones que forman la Mesa de [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-07-18T14:14:17+00:00","article_modified_time":"2020-06-29T19:13:16+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/DSC03984-scaled.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente","datePublished":"2016-07-18T14:14:17+00:00","dateModified":"2020-06-29T19:13:16+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/"},"wordCount":367,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/DSC03984-scaled.jpg","keywords":["Ganader\u00eda","la rural"],"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/","url":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/","name":"Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/DSC03984-scaled.jpg","datePublished":"2016-07-18T14:14:17+00:00","dateModified":"2020-06-29T19:13:16+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/DSC03984-scaled.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/DSC03984-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/comenzo-en-el-predio-de-palermo-una-exposicion-rural-diferente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Comenz\u00f3 en el predio de Palermo una exposici\u00f3n rural diferente"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8207"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8207\/revisions"}],"predecessor-version":[{"id":13991,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8207\/revisions\/13991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/8208"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}