{"id":8167,"date":"2016-07-12T13:41:43","date_gmt":"2016-07-12T13:41:43","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=8167"},"modified":"2020-06-29T19:12:57","modified_gmt":"2020-06-29T19:12:57","slug":"los-feedlots-volvieron-a-ser-rentables","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/los-feedlots-volvieron-a-ser-rentables\/","title":{"rendered":"Los feedlots volvieron a ser rentables"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<h5>\u00a0<\/h5>\n<div class=\"extras\"><a class=\"thickbox\" title=\"Para los fabricantes de prote\u00ednas c\u00e1rnicas existe la vida m\u00e1s all\u00e1 del ma\u00edz subsidiado: los feedlots volvieron a ser rentables\" href=\"http:\/\/www.valorsoja.com\/wp-content\/uploads\/Feedlot2-1024x680.jpg\" rel=\"fancybox\"><img decoding=\"async\" class=\"border medium\" title=\"Para los fabricantes de prote\u00ednas c\u00e1rnicas existe la vida m\u00e1s all\u00e1 del ma\u00edz subsidiado: los feedlots volvieron a ser rentables\" src=\"http:\/\/www.valorsoja.com\/wp-content\/uploads\/Feedlot2-280x186.jpg\" alt=\"Para los fabricantes de prote\u00ednas c\u00e1rnicas existe la vida m\u00e1s all\u00e1 del ma\u00edz subsidiado: los feedlots volvieron a ser rentables\" \/><\/a><\/div>\n<div class=\"texto\">\n<div id=\"HOTWordsTxt\">\n<p>El negocio de terminaci\u00f3n de hacienda bovina en corrales volvi\u00f3 a ser rentable seg\u00fan un informe oficial elaborado con datos provistos por la <strong>C\u00e1mara Argentina de Feedlot<\/strong>.<\/p>\n<p>El modelo de feedlot propio con compra de hacienda analizado por t\u00e9cnicos de la <strong>Subsecretar\u00eda de Ganader\u00eda de la Naci\u00f3n<\/strong>, correspondientes a una escala de 2500 cabezas engordadas por ciclo en el sudeste bonaerense, muestran un resultado neto \u2013con datos actualizados a mayo pasado\u2013 de 1,45 millones de pesos con 1,50 ciclos por a\u00f1o, mientras que con 2,50 ciclos la misma es de 4,24 M\/$.<\/p>\n<p>En febrero de este a\u00f1o es mismo modelo reflejaba una p\u00e9rdida de 2,03 y 1,73 M\/$ para 1,50 y 2,50 ciclos anuales. <em>\u201cLa relaci\u00f3n ternero-novillo pas\u00f3 de 1,61 en noviembre (de 2015) a 1,37 en febrero y 1,19 en mayo de 2016. De acuerdo a estos n\u00fameros, los m\u00e1rgenes pasaron de muy negativos a positivo \u2013aun cuando el precio del ma\u00edz se multiplic\u00f3 por 2,2 en ese per\u00edodo\u2013 y es de suponer que todos los feedlots deben estar aprovision\u00e1ndose de terneros que aseguren la rentabilidad de los futuros engordes\u201d<\/em>, <a href=\"http:\/\/www.agroindustria.gob.ar\/site\/ganaderia\/bovinos\/03=Modelos%20productivos%20regionales\/00-Resultados%20economicos\/_archivos\/000000-2016\/000000_Bolet%C3%ADn%20N%C2%BA%2018%20-%20JUNIO%202016.pdf\">indica el informe del Ministerio de Agroindustria.<\/a><\/p>\n<p>En cuanto al modelo de feedlot que brinda servicio de hoteler\u00eda a terceros \u2013con los mismos supuestos anterior\u2013 en mayo de este a\u00f1o necesitaba 2,25 ciclos productivos por a\u00f1o para comenzar a ser rentable, mientras que en febrero pasado generaba quebrantos en todos los escenarios posibles.<\/p>\n<p>En el esquema de feedlot de hoteler\u00eda tambi\u00e9n se calcula que en mayo el propietario de la hacienda \u2013cliente del corral de engorde\u2013 tendr\u00eda un margen bruto superior a 580 $\/cabeza\/ciclo versus una p\u00e9rdida de unos 380 $\/cabeza\/ciclo en febrero de este a\u00f1o.<\/p>\n<p>En ambos casos el modelo representativo considera un peso de ingreso promedio de 190 kilos con uno de egreso medio de 330 kilos, una mortandad del 1%, una ganancia diaria de 1,20 kg\/cabeza\/d\u00eda durante 117 d\u00edas, un precio de compra bruto de 31,9 $\/kg y otro de venta de 34,0 $\/kg.<\/p>\n<p>Vale recordar que el actual subsecretario de <strong>Ganader\u00eda de la Naci\u00f3n, Rodrigo Troncoso<\/strong>, era hasta el a\u00f1o pasado el gerente general de la C\u00e1mara Argentina de Feedlot.<\/p>\n<p><strong>Fuente:\u00a0http:\/\/www.valorsoja.com\/2016\/07\/12\/para-los-fabricantes-de-proteinas-carnicas-existe-la-vida-mas-alla-del-maiz-subsidiado-los-feedlots-volvieron-a-ser-rentables\/#.V4TpLtLhDb0<\/strong><\/p>\n<\/div>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 El negocio de terminaci\u00f3n de hacienda bovina en corrales volvi\u00f3 a ser rentable seg\u00fan un informe oficial elaborado con datos provistos por la C\u00e1mara Argentina de Feedlot. El modelo de feedlot propio con compra de hacienda analizado por t\u00e9cnicos de la Subsecretar\u00eda de Ganader\u00eda de la Naci\u00f3n, correspondientes a una escala de 2500 cabezas engordadas por ciclo en el sudeste bonaerense, muestran un resultado neto \u2013con datos actualizados a mayo pasado\u2013 de 1,45 millones de pesos con 1,50 ciclos por a\u00f1o, mientras que con 2,50 ciclos la misma es de 4,24 M\/$. En febrero de este a\u00f1o es mismo modelo reflejaba una p\u00e9rdida de 2,03 y 1,73 M\/$ para 1,50 y 2,50 ciclos anuales. \u201cLa relaci\u00f3n ternero-novillo pas\u00f3 de 1,61 en noviembre (de 2015) a 1,37 en febrero y 1,19 en mayo de 2016. De acuerdo a estos n\u00fameros, los m\u00e1rgenes pasaron de muy negativos a positivo \u2013aun cuando el precio del ma\u00edz se multiplic\u00f3 por 2,2 en ese per\u00edodo\u2013 y es de suponer que todos los feedlots deben estar aprovision\u00e1ndose de terneros que aseguren la rentabilidad de los futuros engordes\u201d, indica el informe del Ministerio de Agroindustria. En cuanto al modelo de feedlot que brinda servicio de hoteler\u00eda [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[129,185,190],"class_list":["post-8167","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","tag-feedlot","tag-ganado","tag-rentabilidad","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los feedlots volvieron a ser rentables | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/los-feedlots-volvieron-a-ser-rentables\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los feedlots volvieron a ser rentables | Proagro\" \/>\n<meta property=\"og:description\" content=\"\u00a0 El negocio de terminaci\u00f3n de hacienda bovina en corrales volvi\u00f3 a ser rentable seg\u00fan un informe oficial elaborado con datos provistos por la C\u00e1mara Argentina de Feedlot. El modelo de feedlot propio con compra de hacienda analizado por t\u00e9cnicos de la Subsecretar\u00eda de Ganader\u00eda de la Naci\u00f3n, correspondientes a una escala de 2500 cabezas engordadas por ciclo en el sudeste bonaerense, muestran un resultado neto \u2013con datos actualizados a mayo pasado\u2013 de 1,45 millones de pesos con 1,50 ciclos por a\u00f1o, mientras que con 2,50 ciclos la misma es de 4,24 M\/$. En febrero de este a\u00f1o es mismo modelo reflejaba una p\u00e9rdida de 2,03 y 1,73 M\/$ para 1,50 y 2,50 ciclos anuales. \u201cLa relaci\u00f3n ternero-novillo pas\u00f3 de 1,61 en noviembre (de 2015) a 1,37 en febrero y 1,19 en mayo de 2016. De acuerdo a estos n\u00fameros, los m\u00e1rgenes pasaron de muy negativos a positivo \u2013aun cuando el precio del ma\u00edz se multiplic\u00f3 por 2,2 en ese per\u00edodo\u2013 y es de suponer que todos los feedlots deben estar aprovision\u00e1ndose de terneros que aseguren la rentabilidad de los futuros engordes\u201d, indica el informe del Ministerio de Agroindustria. En cuanto al modelo de feedlot que brinda servicio de hoteler\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-12T13:41:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T19:12:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/feedlot2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2311\" \/>\n\t<meta property=\"og:image:height\" content=\"845\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Los feedlots volvieron a ser rentables\",\"datePublished\":\"2016-07-12T13:41:43+00:00\",\"dateModified\":\"2020-06-29T19:12:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/\"},\"wordCount\":380,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/feedlot2.jpg\",\"keywords\":[\"Feedlot\",\"Ganado\",\"rentabilidad\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/\",\"name\":\"Los feedlots volvieron a ser rentables | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/feedlot2.jpg\",\"datePublished\":\"2016-07-12T13:41:43+00:00\",\"dateModified\":\"2020-06-29T19:12:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/feedlot2.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/feedlot2.jpg\",\"width\":2311,\"height\":845},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/los-feedlots-volvieron-a-ser-rentables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los feedlots volvieron a ser rentables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los feedlots volvieron a ser rentables | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/los-feedlots-volvieron-a-ser-rentables\/","og_locale":"en_US","og_type":"article","og_title":"Los feedlots volvieron a ser rentables | Proagro","og_description":"\u00a0 El negocio de terminaci\u00f3n de hacienda bovina en corrales volvi\u00f3 a ser rentable seg\u00fan un informe oficial elaborado con datos provistos por la C\u00e1mara Argentina de Feedlot. El modelo de feedlot propio con compra de hacienda analizado por t\u00e9cnicos de la Subsecretar\u00eda de Ganader\u00eda de la Naci\u00f3n, correspondientes a una escala de 2500 cabezas engordadas por ciclo en el sudeste bonaerense, muestran un resultado neto \u2013con datos actualizados a mayo pasado\u2013 de 1,45 millones de pesos con 1,50 ciclos por a\u00f1o, mientras que con 2,50 ciclos la misma es de 4,24 M\/$. En febrero de este a\u00f1o es mismo modelo reflejaba una p\u00e9rdida de 2,03 y 1,73 M\/$ para 1,50 y 2,50 ciclos anuales. \u201cLa relaci\u00f3n ternero-novillo pas\u00f3 de 1,61 en noviembre (de 2015) a 1,37 en febrero y 1,19 en mayo de 2016. De acuerdo a estos n\u00fameros, los m\u00e1rgenes pasaron de muy negativos a positivo \u2013aun cuando el precio del ma\u00edz se multiplic\u00f3 por 2,2 en ese per\u00edodo\u2013 y es de suponer que todos los feedlots deben estar aprovision\u00e1ndose de terneros que aseguren la rentabilidad de los futuros engordes\u201d, indica el informe del Ministerio de Agroindustria. En cuanto al modelo de feedlot que brinda servicio de hoteler\u00eda [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-07-12T13:41:43+00:00","article_modified_time":"2020-06-29T19:12:57+00:00","og_image":[{"width":2311,"height":845,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/feedlot2.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Los feedlots volvieron a ser rentables","datePublished":"2016-07-12T13:41:43+00:00","dateModified":"2020-06-29T19:12:57+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/"},"wordCount":380,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/feedlot2.jpg","keywords":["Feedlot","Ganado","rentabilidad"],"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/","url":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/","name":"Los feedlots volvieron a ser rentables | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/feedlot2.jpg","datePublished":"2016-07-12T13:41:43+00:00","dateModified":"2020-06-29T19:12:57+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/feedlot2.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/feedlot2.jpg","width":2311,"height":845},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/los-feedlots-volvieron-a-ser-rentables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Los feedlots volvieron a ser rentables"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8167"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8167\/revisions"}],"predecessor-version":[{"id":13988,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8167\/revisions\/13988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/8170"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}