{"id":8140,"date":"2016-07-07T14:21:56","date_gmt":"2016-07-07T14:21:56","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=8140"},"modified":"2016-07-07T16:24:49","modified_gmt":"2016-07-07T16:24:49","slug":"la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/","title":{"rendered":"La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p class=\"primero\">Los robots ya son una realidad en la producci\u00f3n lechera de varios pa\u00edses y en Chile no se quieren quedar atr\u00e1s.<strong> El Risquillo<\/strong>, un tambo con 6500 vacas propiedad de la firma Agr\u00edcola <strong>Ancali y Grupo Bethia<\/strong>, \u00e9ste \u00faltimo uno de los due\u00f1os de empresas reconocidas como Falabella y Latam, acaba de firmar con la compa\u00f1\u00eda sueca DeLaval, proveedora de equipamiento para tambo, un acuerdo para la instalaci\u00f3n de 64 robots de orde\u00f1e autom\u00e1tico.<\/p>\n<p class=\"primero\"><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/campo-2231265w620.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8141\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/campo-2231265w620-300x200.jpg\" alt=\"campo-2231265w620\" width=\"300\" height=\"200\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/campo-2231265w620-300x200.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/campo-2231265w620-600x400.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/campo-2231265w620.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<aside class=\"banner caja2\" data-adpos=\"caja2\">\n<div id=\"eplAdDivcaja2\">El robot para orde\u00f1e apareci\u00f3 en el mundo en 1992. En la actualidad hay m\u00e1s de 20.000 tambos en funcionamiento con 34.000 robots. En la Argentina se inaugur\u00f3 el a\u00f1o pasado un tambo robotizado en el INTA Rafaela, el primero del pa\u00eds. En estos sistemas autom\u00e1ticos la totalidad del proceso est\u00e1 automatizada. La llegada de la vaca a la estaci\u00f3n de orde\u00f1e, la preparaci\u00f3n de la ubre, la colocaci\u00f3n y el retiro de las unidades de orde\u00f1o se concreta sin la interacci\u00f3n de una persona, seg\u00fan explicaron en DeLaval.<\/div>\n<\/aside>\n<p>En el mundo, despu\u00e9s del avance con la m\u00e1quina de orde\u00f1ar y los extractores autom\u00e1ticos de pezoneras, que reemplazaron el trabajo manual, el robot era el \u00faltimo paso que faltaba para la completa automatizaci\u00f3n del proceso de orde\u00f1o. En este sentido, lo central del desarrollo es un brazo rob\u00f3tico que limpia los pezones y luego coloca las unidades de orde\u00f1o a la vaca.<\/p>\n<aside class=\"banner caja3\" data-adpos=\"caja3\">\n<div id=\"eplAdDivcaja3\">Ese brazo posee una c\u00e1mara de video, un sistema de procesamiento de im\u00e1genes para encontrar el pez\u00f3n y un sistema de l\u00e1ser para ubicarlos. Un robot tiene capacidad para hacer 150 orde\u00f1es por d\u00eda.<\/div>\n<\/aside>\n<p>Seg\u00fan explic\u00f3 la empresa sueca, todo el sistema est\u00e1 controlado por un software con la informaci\u00f3n de cada vaca. Ese mismo software provee informaci\u00f3n acerca de la producci\u00f3n, reproducci\u00f3n, alimentaci\u00f3n, salud y performance del tambo.<\/p>\n<aside class=\"banner caja4\" data-adpos=\"caja4\">\n<div id=\"eplAdDivcaja4\">En el tambo El Risquillo, ubicado a 500 kil\u00f3metros al sur de Santiago de Chile, ya tienen 16 robots en funcionamiento y dicen que aumentaron 10% la producci\u00f3n. Empezaron con 500 vacas con el sistema rob\u00f3tico y apuntan a tener sus mejores 4500 vacas con este sistema. Los 64 robots van a estar funcionando a principios de 2017.<\/div>\n<\/aside>\n<p><em>&#8220;El foco de la implementaci\u00f3n de estas tecnolog\u00edas es reducir costos, aumentar la eficiencia, la calidad y consistencia de la informaci\u00f3n&#8221;<\/em>, expresaron en la compa\u00f1\u00eda, donde no obstante aclararon que<em> &#8220;estas tecnolog\u00edas no trabajan solas&#8221;.<\/em><\/p>\n<p>Seg\u00fan la firma, las personas pueden dedicar m\u00e1s tiempo a otras tareas que generan valor, como el an\u00e1lisis de datos.<\/p>\n<p><em>&#8220;Sin dudas la forma de trabajo cambia. En un tambo con orde\u00f1o autom\u00e1tico, los horarios se vuelven m\u00e1s flexibles y se asemejan mucho m\u00e1s a horarios de trabajo normales, permite el descanso de los trabajadores y se gana tiempo para dedicarle a otro tipo de tareas que son las que van a generar valor y traer resultados positivos. Aparecen nuevas tareas, pasa a ser clave el trabajo en la computadora, viendo y analizando diferentes indicadores de performance claves, que son los que van a determinar c\u00f3mo est\u00e1 trabajando el sistema&#8221;<\/em>, remarcaron en la empresa.<\/p>\n<p><strong>Fuente:\u00a0http:\/\/www.lanacion.com.ar\/1915859-la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Los robots ya son una realidad en la producci\u00f3n lechera de varios pa\u00edses y en Chile no se quieren quedar atr\u00e1s. El Risquillo, un tambo con 6500 vacas propiedad de la firma Agr\u00edcola Ancali y Grupo Bethia, \u00e9ste \u00faltimo uno de los due\u00f1os de empresas reconocidas como Falabella y Latam, acaba de firmar con la compa\u00f1\u00eda sueca DeLaval, proveedora de equipamiento para tambo, un acuerdo para la instalaci\u00f3n de 64 robots de orde\u00f1e autom\u00e1tico. El robot para orde\u00f1e apareci\u00f3 en el mundo en 1992. En la actualidad hay m\u00e1s de 20.000 tambos en funcionamiento con 34.000 robots. En la Argentina se inaugur\u00f3 el a\u00f1o pasado un tambo robotizado en el INTA Rafaela, el primero del pa\u00eds. En estos sistemas autom\u00e1ticos la totalidad del proceso est\u00e1 automatizada. La llegada de la vaca a la estaci\u00f3n de orde\u00f1e, la preparaci\u00f3n de la ubre, la colocaci\u00f3n y el retiro de las unidades de orde\u00f1o se concreta sin la interacci\u00f3n de una persona, seg\u00fan explicaron en DeLaval. En el mundo, despu\u00e9s del avance con la m\u00e1quina de orde\u00f1ar y los extractores autom\u00e1ticos de pezoneras, que reemplazaron el trabajo manual, el robot era el \u00faltimo paso que faltaba para la completa automatizaci\u00f3n del proceso de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8147,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-8140","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo | Proagro\" \/>\n<meta property=\"og:description\" content=\"Los robots ya son una realidad en la producci\u00f3n lechera de varios pa\u00edses y en Chile no se quieren quedar atr\u00e1s. El Risquillo, un tambo con 6500 vacas propiedad de la firma Agr\u00edcola Ancali y Grupo Bethia, \u00e9ste \u00faltimo uno de los due\u00f1os de empresas reconocidas como Falabella y Latam, acaba de firmar con la compa\u00f1\u00eda sueca DeLaval, proveedora de equipamiento para tambo, un acuerdo para la instalaci\u00f3n de 64 robots de orde\u00f1e autom\u00e1tico. El robot para orde\u00f1e apareci\u00f3 en el mundo en 1992. En la actualidad hay m\u00e1s de 20.000 tambos en funcionamiento con 34.000 robots. En la Argentina se inaugur\u00f3 el a\u00f1o pasado un tambo robotizado en el INTA Rafaela, el primero del pa\u00eds. En estos sistemas autom\u00e1ticos la totalidad del proceso est\u00e1 automatizada. La llegada de la vaca a la estaci\u00f3n de orde\u00f1e, la preparaci\u00f3n de la ubre, la colocaci\u00f3n y el retiro de las unidades de orde\u00f1o se concreta sin la interacci\u00f3n de una persona, seg\u00fan explicaron en DeLaval. En el mundo, despu\u00e9s del avance con la m\u00e1quina de orde\u00f1ar y los extractores autom\u00e1ticos de pezoneras, que reemplazaron el trabajo manual, el robot era el \u00faltimo paso que faltaba para la completa automatizaci\u00f3n del proceso de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-07T14:21:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-07T16:24:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/78d93788-793a-4f04-8a87-1ae649734e40.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1146\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo\",\"datePublished\":\"2016-07-07T14:21:56+00:00\",\"dateModified\":\"2016-07-07T16:24:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/\"},\"wordCount\":571,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/78d93788-793a-4f04-8a87-1ae649734e40.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/\",\"name\":\"La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/78d93788-793a-4f04-8a87-1ae649734e40.jpg\",\"datePublished\":\"2016-07-07T14:21:56+00:00\",\"dateModified\":\"2016-07-07T16:24:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/78d93788-793a-4f04-8a87-1ae649734e40.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/78d93788-793a-4f04-8a87-1ae649734e40.jpg\",\"width\":1146,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/","og_locale":"en_US","og_type":"article","og_title":"La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo | Proagro","og_description":"Los robots ya son una realidad en la producci\u00f3n lechera de varios pa\u00edses y en Chile no se quieren quedar atr\u00e1s. El Risquillo, un tambo con 6500 vacas propiedad de la firma Agr\u00edcola Ancali y Grupo Bethia, \u00e9ste \u00faltimo uno de los due\u00f1os de empresas reconocidas como Falabella y Latam, acaba de firmar con la compa\u00f1\u00eda sueca DeLaval, proveedora de equipamiento para tambo, un acuerdo para la instalaci\u00f3n de 64 robots de orde\u00f1e autom\u00e1tico. El robot para orde\u00f1e apareci\u00f3 en el mundo en 1992. En la actualidad hay m\u00e1s de 20.000 tambos en funcionamiento con 34.000 robots. En la Argentina se inaugur\u00f3 el a\u00f1o pasado un tambo robotizado en el INTA Rafaela, el primero del pa\u00eds. En estos sistemas autom\u00e1ticos la totalidad del proceso est\u00e1 automatizada. La llegada de la vaca a la estaci\u00f3n de orde\u00f1e, la preparaci\u00f3n de la ubre, la colocaci\u00f3n y el retiro de las unidades de orde\u00f1o se concreta sin la interacci\u00f3n de una persona, seg\u00fan explicaron en DeLaval. En el mundo, despu\u00e9s del avance con la m\u00e1quina de orde\u00f1ar y los extractores autom\u00e1ticos de pezoneras, que reemplazaron el trabajo manual, el robot era el \u00faltimo paso que faltaba para la completa automatizaci\u00f3n del proceso de [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-07-07T14:21:56+00:00","article_modified_time":"2016-07-07T16:24:49+00:00","og_image":[{"width":1146,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/78d93788-793a-4f04-8a87-1ae649734e40.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo","datePublished":"2016-07-07T14:21:56+00:00","dateModified":"2016-07-07T16:24:49+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/"},"wordCount":571,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/78d93788-793a-4f04-8a87-1ae649734e40.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/","url":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/","name":"La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/78d93788-793a-4f04-8a87-1ae649734e40.jpg","datePublished":"2016-07-07T14:21:56+00:00","dateModified":"2016-07-07T16:24:49+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/78d93788-793a-4f04-8a87-1ae649734e40.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/78d93788-793a-4f04-8a87-1ae649734e40.jpg","width":1146,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/la-hora-de-los-robots-instalan-en-chile-el-tambo-robotizado-mas-grande-del-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"La hora de los robots: instalan en Chile el tambo robotizado m\u00e1s grande del mundo"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8140"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8140\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/8147"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}