{"id":8093,"date":"2016-07-01T13:17:32","date_gmt":"2016-07-01T13:17:32","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=8093"},"modified":"2016-07-01T15:19:52","modified_gmt":"2016-07-01T15:19:52","slug":"feedlots-donde-la-medida-si-importa","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/feedlots-donde-la-medida-si-importa\/","title":{"rendered":"FEEDLOTS &#8211; Donde la medida s\u00ed importa"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>El 60% de la faena total del pa\u00eds pasa por este sistema que brinda uniformidad, calidad y terminaci\u00f3n prematura, a animales que en el <strong>Mercado de Liniers<\/strong> valen un 20-25% m\u00e1s que los terminados a campo.<\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/8259_principal.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8098\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/8259_principal-300x198.jpg\" alt=\"8259_principal\" width=\"300\" height=\"198\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/8259_principal-300x198.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/07\/8259_principal.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Actualmente la Argentina cuenta con 51 millones de cabezas de ganado, y de los 12 millones que se faenan anualmente, unos 7 millones, o sea el 60%, pasa por los sistemas de encierre a corral tipo feedlot, siendo un eslab\u00f3n muy importante de una cadena productiva muy interesante, que brinda uniformidad, calidad y terminaci\u00f3n prematura a la hacienda.<\/p>\n<p>Estos establecimientos de encierre a corral se vienen incrementando entre un 7 y 10% por a\u00f1o, y en promedio trabajan con unos 2.000 animales.<\/p>\n<p>Como todo sistema intensivo, genera valor agregado al grano y muchos puestos de trabajo en forma directa e indirecta, ya que requiere una gran cantidad de servicios de terceros. Se estima que en forma directa, en promedio, trabajan entre 12 y 15 personas por feedlot.<\/p>\n<p>El engorde bovino bajo sistema de encierre a corral es un tipo de explotaci\u00f3n ganadera que vino para quedarse definitivamente en la Argentina, y como hoy en el pa\u00eds los n\u00fameros est\u00e1n muy \u201cfinos\u201d, todo pasa por la eficiencia de conversi\u00f3n de alimento en carne. Hoy el negocio es rentable.<\/p>\n<p>Para conocer en profundidad la actualidad del negocio del feedlot, <strong>Nuevo ABC Rural<\/strong> dialog\u00f3 con el m\u00e9dico veterinario <strong>Oscar Ferrero<\/strong>, especialista en producci\u00f3n bovina y asesor externo en nutrici\u00f3n y manejo de negocios ganaderos, quien desde hace varios a\u00f1os trabaja en diferentes feedlots y establecimientos de cr\u00eda y recr\u00eda. <br \/><b><br \/>El sistema vino para quedarse definitivamente <br \/><\/b><em>\u201cEl 60% de la faena total pasa por los sistemas de encierre a corral tipo feedlot, siendo un eslab\u00f3n muy importante de una cadena productiva muy interesante, que brinda uniformidad, calidad y terminaci\u00f3n prematura a la hacienda\u201d<\/em>, expres\u00f3 Ferrero.<em> \u201cEst\u00e1 demostrado en el Mercado de Liniers que un animal terminado en feedlots vale un 20-25% m\u00e1s que uno terminado a campo\u201d<\/em>, asegur\u00f3.<\/p>\n<p>En ese sentido, explic\u00f3 que \u201c<em>esta valoraci\u00f3n se debe a que la calidad de carne cambi\u00f3 mucho, no digo que la terminada a pasto no sea buena, pero la de feedlot presenta grasa blanca, coloraci\u00f3n adecuada y, normalmente, se termina con el mismo kilaje que a pasto, pero con mucha menos edad\u201d<\/em>.<\/p>\n<p>Para graficar esta ventaja en la terminaci\u00f3n prematura de la hacienda que tiene el sistema, Ferrero indic\u00f3 que <em>\u201cun animal terminado a pasto con 420-450 kilos, hoy a un productor de punta argentino no le llevar\u00eda menos de 2,5 a 3 a\u00f1os de terminaci\u00f3n; mientras que bajo sistema de feedlot en el medio, con una cr\u00eda y recr\u00eda bien manejada, ese kilaje para la venta se logra entre los 17 y 19 meses, ahorrando un a\u00f1o en la edad del animal\u201d<\/em>. <br \/>Por eso el especialista afirma que <em>\u201cel feedlot vino para quedarse definitivamente en la Argentina\u201d.<\/em><br \/><b><br \/>M\u00e1s feedlots, valor agregado y fuentes de trabajo <br \/><\/b>Los n\u00fameros suministrados por Ferrero, indican que en los \u00faltimos tiempos, estos establecimientos de encierre a corral se vienen incrementando entre un 7 y 10% por a\u00f1o, teniendo en cuenta que anualmente se matan en total 12 millones de cabezas y que el 60% pasa por feedlots, lo que significan unas 7 millones de cabezas, trabajando en promedio cada establecimiento con unos 2.000 animales.<\/p>\n<p><em>\u201cEn la regi\u00f3n agr\u00edcola la soja corri\u00f3 a los animales de los mejores campos y la mayor\u00eda de la hacienda se encuentra bajo este sistema. En el norte, en tanto, cuentan con la ventaja de tener campos recriadores y le est\u00e1n agregando los corrales para darle valor agregado al grano y mejor terminaci\u00f3n de la hacienda\u201d<\/em>, justific\u00f3.<\/p>\n<p>Como todo sistema intensivo, el engorde bovino a corral genera valor agregado al grano y muchos puestos de trabajo en forma directa e indirecta, ya que se requieren numerosos servicios de terceros. <em>\u201cSe estima que en forma directa trabajan entre 12 y 15 personas en promedio por feedlot, un n\u00famero muy interesante\u201d<\/em>, se\u00f1al\u00f3. <em>\u201cHoy la relaci\u00f3n es una persona cada 600-700 cabezas, cuando antes era una cada 1.000, cambio que se debe a una mejora en la eficiencia de trabajo, con mayor limpieza y administraci\u00f3n, ya que cada vez se va profesionalizando m\u00e1s todo el sistema, a trav\u00e9s de mayores mediciones y recaudos\u201d<\/em>, destac\u00f3. <br \/><b><br \/>\u201cEl negocio pasa por la eficiencia de conversi\u00f3n\u201d <br \/><\/b>El especialista remarc\u00f3 que para que el negocio del feedlot tenga resultado positivo, <em>\u201cno queda otra que medir y medir, ya que el negocio pasa por la eficiencia de conversi\u00f3n de alimento en carne\u201d<\/em>.<\/p>\n<p>En ese sentido, respecto al precio del ma\u00edz, dijo que los feedloteros cuentan con una ecuaci\u00f3n muy simple y r\u00e1pida. <em>\u201cCuando un kilo de ma\u00edz a precio pizarra es igual o menor a un kilo de hacienda en pie, el negocio del feedlot cierra\u201d<\/em>, asegur\u00f3.<em> \u201cSi hoy (mediados de mayo) tomamos que el kilo de ma\u00edz sale 25-26 pesos y el de la hacienda en pie 30-32 pesos, el negocio es rentable, y lo mejor para hacer n\u00famero en el feedlot, es la eficiencia de conversi\u00f3n\u201d<\/em>, remarc\u00f3. Por eso insisti\u00f3 en la necesidad de medir, probar e innovar, con pesajes individuales y en conjunto, para que el n\u00famero resulte positivo. <br \/>Asimismo, Ferrero recomend\u00f3 que para la alimentaci\u00f3n se utilicen los insumos que se tengan m\u00e1s a \u201cmano\u201d, seg\u00fan los que ofrezca cada zona. <em>\u201cPara formular el alimento, trato de utilizar la menor cantidad posible de subproducto, sino productos que aporten fibra, energ\u00eda, prote\u00ednas y alg\u00fan n\u00facleo vitam\u00ednico mineral, adapt\u00e1ndome a las diferentes zonas y estando en contra de traer productos desde mucha distancia, ya que necesito abaratar costos y darle sustentabilidad al alimento y no estar cambi\u00e1ndolo constantemente, y mejorar la eficiencia\u201d<\/em>, detall\u00f3. <br \/><b><br \/>Explotaci\u00f3n mixta para transformar grano producido en carne<br \/><\/b>De todas maneras, el entrevistado record\u00f3 que tambi\u00e9n hubo un gran aumento de los gastos de estructura como gasoil, electricidad, mantenimiento y amortizaciones de bienes, lo que hace que, seg\u00fan las regiones, el negocio del feedlot est\u00e9 con resultados m\u00e1s justos que en otros. <em>\u201cDe la Ruta Nacional 19 hacia el sur, en la regi\u00f3n agr\u00edcola n\u00facleo, tenemos la ventaja de estar rodeados de empresas faenadoras de hacienda, pero con la desventaja que el ma\u00edz se ofrece a precio lleno de pizarra\u201d<\/em>, explic\u00f3. <em>\u201cDe esa ruta hacia el norte, en el NOA y NEA, como el flete del ma\u00edz tiene mucha incidencia, hoy se ofrece a 1.700-1.800 pesos el quintal, vi\u00e9ndose favorecidas esas dos regiones por un precio de ma\u00edz m\u00e1s bajo que en la agr\u00edcola n\u00facleo\u201d<\/em>, continu\u00f3.<\/p>\n<p>Por eso el especialista opin\u00f3 que <em>\u201ctenemos que llegar a una integraci\u00f3n de explotaci\u00f3n mixta con agricultura y ganader\u00eda, para poder darle valor a ese grano producido y que salga del campo \u201ccaminando\u201d<\/em>, transformado en carne.<\/p>\n<p>Sobre la disyuntiva de la conveniencia de contar con log\u00edstica propia o contratada, se\u00f1al\u00f3 que <em>\u201ccuando se cuenta con grandes vol\u00famenes de hacienda, tener maquinaria y veh\u00edculos propios es muy importante para no depender de terceros, y m\u00e1s a\u00fan bajo situaciones de contingencia clim\u00e1tica como el temporal de lluvias que se dio durante abril\u201d<\/em>. <br \/><b><br \/>Servicio de hoteler\u00eda para terceros <br \/><\/b><strong>&#8211; \u00bfCu\u00e1nto se est\u00e1 cobrando el servicio de hoteler\u00eda?<\/strong> <br \/>&#8211; Hay dos formas de cobrar. La m\u00e1s impuesta es con servicio de atenci\u00f3n que vale 2,50 pesos diarios por animal, y adem\u00e1s se cobra el alimento que se entrega diariamente, que cuesta 2,20-2,30 pesos por kilo. Tambi\u00e9n se suele cobrar por kilo ganado por d\u00eda, que hoy equivale a unos 21 pesos, incluyendo atenci\u00f3n y alimento, ya que si entr\u00e1s con un animal de 200 kilos y sal\u00eds con uno de 300 kilos, pagas 21 pesos por cada uno de esos 100 kilos de diferencia que lograste. <br \/><strong>&#8211; \u00bfEstos sistemas dan rentabilidad al engordador?<\/strong><br \/>&#8211; S\u00ed, pero es variable. Ese kilo ganado est\u00e1 muy atado todos los meses a la actualizaci\u00f3n del mercado de ma\u00edz, por lo que se toma una cantidad del cereal para calcular ese costo de kilo ganado. <br \/><b><br \/>Novillitos m\u00e1s pesados para incrementar las exportaciones<br \/><\/b><strong>&#8211; \u00bfEstamos preparados para recuperar el stock ganadero perdido?<\/strong><br \/>&#8211; S\u00ed. Estamos preparados y el feedlot tendr\u00e1 un papel preponderante para eso. Ser\u00e1 un proceso lento que debemos diferenciar, ya que una cosa es el stock y otra la producci\u00f3n de carne. En cuanto a lo \u00faltimo, creo que debemos conseguir mayor producci\u00f3n de carne por animal faenado. Tenemos que dejar de lado la locura de matar terneros de 320 kilos y apostar a lograr terneros de 360 kilos en un primer momento y novillitos de 400 kilos despu\u00e9s, manteniendo la misma calidad de animal joven. Esto no es dif\u00edcil porque la mayor\u00eda de los feedlots lo estamos haciendo; adem\u00e1s el consumidor y los carniceros deben entender que al lograrse un animal joven de mayor kilaje, no se altera la terneza, ni el sabor de la carne. <br \/><strong>&#8211; \u00bfQu\u00e9 producir\u00e1 esta decisi\u00f3n de lograr animales m\u00e1s grandes?<\/strong><br \/>&#8211; Es una cuenta f\u00e1cil. Si con 12 millones de cabezas que faenamos le pudi\u00e9ramos agregar 30 kilos m\u00e1s de rendimiento en carne, mantendr\u00edamos el consumo per c\u00e1pita de 60 kilos\/habitante\/a\u00f1o, y nos sobrar\u00edan unas 360 mil toneladas para exportar. <br \/>Esto no es volver a las mejores \u00e9pocas, pero s\u00ed comenzar a ocupar nuestro lugar en la ganader\u00eda mundial. Estamos en pleno crecimiento y necesitamos para el a\u00f1o 2050 duplicar la producci\u00f3n de carne bovina y triplicar la prote\u00edna animal. Creo que vamos por buen camino. <br \/><strong>&#8211; \u00bfC\u00f3mo ve a la ganader\u00eda argentina en la actualidad?<\/strong><br \/>&#8211; A pesar que no pudimos cumplir con los contratos de exportaci\u00f3n, debido a las malas pol\u00edticas de los \u00faltimos 20 a\u00f1os, el mundo espera la carne argentina y esa es una buena noticia. Hay muchos contratos sobre la mesa que debemos respetar y estamos seguros que podremos cumplir si hacemos las cosas ordenadamente. Hay que seguir con la Cuota 481 -que solo pueden hacer seis pa\u00edses- que permitir\u00e1 a los feedlots principalmente, continuar exportando a Europa animales de m\u00e1xima calidad, cumpliendo con la dieta que se exige desde ese destino demandante. <\/p>\n<p><strong>Fuente: Luciano Venini\u00a0http:\/\/www.nuevoabcrural.com.ar\/2014\/nota_seccion.php?seccion_id=41<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El 60% de la faena total del pa\u00eds pasa por este sistema que brinda uniformidad, calidad y terminaci\u00f3n prematura, a animales que en el Mercado de Liniers valen un 20-25% m\u00e1s que los terminados a campo. Actualmente la Argentina cuenta con 51 millones de cabezas de ganado, y de los 12 millones que se faenan anualmente, unos 7 millones, o sea el 60%, pasa por los sistemas de encierre a corral tipo feedlot, siendo un eslab\u00f3n muy importante de una cadena productiva muy interesante, que brinda uniformidad, calidad y terminaci\u00f3n prematura a la hacienda. Estos establecimientos de encierre a corral se vienen incrementando entre un 7 y 10% por a\u00f1o, y en promedio trabajan con unos 2.000 animales. Como todo sistema intensivo, genera valor agregado al grano y muchos puestos de trabajo en forma directa e indirecta, ya que requiere una gran cantidad de servicios de terceros. Se estima que en forma directa, en promedio, trabajan entre 12 y 15 personas por feedlot. El engorde bovino bajo sistema de encierre a corral es un tipo de explotaci\u00f3n ganadera que vino para quedarse definitivamente en la Argentina, y como hoy en el pa\u00eds los n\u00fameros est\u00e1n muy \u201cfinos\u201d, todo pasa por [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8108,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-8093","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FEEDLOTS - Donde la medida s\u00ed importa | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/feedlots-donde-la-medida-si-importa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FEEDLOTS - Donde la medida s\u00ed importa | Proagro\" \/>\n<meta property=\"og:description\" content=\"El 60% de la faena total del pa\u00eds pasa por este sistema que brinda uniformidad, calidad y terminaci\u00f3n prematura, a animales que en el Mercado de Liniers valen un 20-25% m\u00e1s que los terminados a campo. Actualmente la Argentina cuenta con 51 millones de cabezas de ganado, y de los 12 millones que se faenan anualmente, unos 7 millones, o sea el 60%, pasa por los sistemas de encierre a corral tipo feedlot, siendo un eslab\u00f3n muy importante de una cadena productiva muy interesante, que brinda uniformidad, calidad y terminaci\u00f3n prematura a la hacienda. Estos establecimientos de encierre a corral se vienen incrementando entre un 7 y 10% por a\u00f1o, y en promedio trabajan con unos 2.000 animales. Como todo sistema intensivo, genera valor agregado al grano y muchos puestos de trabajo en forma directa e indirecta, ya que requiere una gran cantidad de servicios de terceros. Se estima que en forma directa, en promedio, trabajan entre 12 y 15 personas por feedlot. El engorde bovino bajo sistema de encierre a corral es un tipo de explotaci\u00f3n ganadera que vino para quedarse definitivamente en la Argentina, y como hoy en el pa\u00eds los n\u00fameros est\u00e1n muy \u201cfinos\u201d, todo pasa por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-01T13:17:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-01T15:19:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/01072016-1145x395.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"FEEDLOTS &#8211; Donde la medida s\u00ed importa\",\"datePublished\":\"2016-07-01T13:17:32+00:00\",\"dateModified\":\"2016-07-01T15:19:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/\"},\"wordCount\":1770,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/01072016-1145x395.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/\",\"name\":\"FEEDLOTS - Donde la medida s\u00ed importa | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/01072016-1145x395.jpg\",\"datePublished\":\"2016-07-01T13:17:32+00:00\",\"dateModified\":\"2016-07-01T15:19:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/01072016-1145x395.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/01072016-1145x395.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/feedlots-donde-la-medida-si-importa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FEEDLOTS &#8211; Donde la medida s\u00ed importa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FEEDLOTS - Donde la medida s\u00ed importa | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/feedlots-donde-la-medida-si-importa\/","og_locale":"en_US","og_type":"article","og_title":"FEEDLOTS - Donde la medida s\u00ed importa | Proagro","og_description":"El 60% de la faena total del pa\u00eds pasa por este sistema que brinda uniformidad, calidad y terminaci\u00f3n prematura, a animales que en el Mercado de Liniers valen un 20-25% m\u00e1s que los terminados a campo. Actualmente la Argentina cuenta con 51 millones de cabezas de ganado, y de los 12 millones que se faenan anualmente, unos 7 millones, o sea el 60%, pasa por los sistemas de encierre a corral tipo feedlot, siendo un eslab\u00f3n muy importante de una cadena productiva muy interesante, que brinda uniformidad, calidad y terminaci\u00f3n prematura a la hacienda. Estos establecimientos de encierre a corral se vienen incrementando entre un 7 y 10% por a\u00f1o, y en promedio trabajan con unos 2.000 animales. Como todo sistema intensivo, genera valor agregado al grano y muchos puestos de trabajo en forma directa e indirecta, ya que requiere una gran cantidad de servicios de terceros. Se estima que en forma directa, en promedio, trabajan entre 12 y 15 personas por feedlot. El engorde bovino bajo sistema de encierre a corral es un tipo de explotaci\u00f3n ganadera que vino para quedarse definitivamente en la Argentina, y como hoy en el pa\u00eds los n\u00fameros est\u00e1n muy \u201cfinos\u201d, todo pasa por [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-07-01T13:17:32+00:00","article_modified_time":"2016-07-01T15:19:52+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/01072016-1145x395.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"FEEDLOTS &#8211; Donde la medida s\u00ed importa","datePublished":"2016-07-01T13:17:32+00:00","dateModified":"2016-07-01T15:19:52+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/"},"wordCount":1770,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/01072016-1145x395.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/","url":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/","name":"FEEDLOTS - Donde la medida s\u00ed importa | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/01072016-1145x395.jpg","datePublished":"2016-07-01T13:17:32+00:00","dateModified":"2016-07-01T15:19:52+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/01072016-1145x395.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/01072016-1145x395.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/feedlots-donde-la-medida-si-importa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"FEEDLOTS &#8211; Donde la medida s\u00ed importa"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8093"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/8093\/revisions"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}