{"id":7982,"date":"2016-06-13T14:56:46","date_gmt":"2016-06-13T14:56:46","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7982"},"modified":"2020-06-29T19:15:40","modified_gmt":"2020-06-29T19:15:40","slug":"en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/","title":{"rendered":"En la cuenca del Salado, la flexibilidad hace la diferencia"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>En Gral. Conesa, los Buzeta hacen cr\u00eda y engorde con ideas sencillas y flexibles, pero muy eficientes. El \u00e9xito, contado por dos generaciones.<\/p>\n<p class=\"first-paragraph\">La relaci\u00f3n de la familia Buzeta con el campo es como un matrimonio fiel: no est\u00e1 libre de desastres, pero con confianza y adaptaci\u00f3n al cambio logra sobrevivir a las adversidades. En 1982, <strong>Carlos Buzeta<\/strong> decidi\u00f3 dejar su empresa constructora para volcarse a la actividad pecuaria. Compr\u00f3 un campo de 2.000 hect\u00e1reas en General Conesa, a mitad de camino entre la ciudad de Buenos Aires y Mar del Plata, y empez\u00f3 a aprender desde cero los secretos de la ganader\u00eda. <em>\u201cLas vacas, los toros, los terneros\u2026 para m\u00ed eran todos iguales\u201d<\/em>, recuerda el hombre en di\u00e1logo con <strong>Clar\u00edn Rural<\/strong>.<\/p>\n<p>En aquel entonces en el campo hab\u00eda apenas trescientos animales. De a poco, los Buzeta fueron arreglando las aguadas, los alambrados e implantaron las primeras pasturas de raigr\u00e1s, y el rodeo se agrand\u00f3 hasta llegar a los 2.000 animales. Pero en el 85 lleg\u00f3 el primer gran desaf\u00edo, una inundaci\u00f3n, y en el 92 hubo otra que fue un golpe casi definitivo. Pero lograron levantarse de la lona antes del knock out. <em>\u201cSe rompieron las pasturas que con tanto esfuerzo hab\u00edamos ido implantando y hubo que sacar a toda la hacienda que hab\u00edamos ido mejorando con el tiempo. En aquel momento pensamos en vender el campo\u201d<\/em>, dice <strong>Mariano Buzeta<\/strong>, hijo de Carlos, que estuvo involucrado en la empresa desde el comienzo y hoy es quien lleva las riendas.<\/p>\n<p>Con esquemas de capitalizaci\u00f3n, los Buzeta lograron volver a crecer. <em>\u201cFuimos reconstruyendonos de a poco; llev\u00f3 unos cuantos a\u00f1os recomponer el rodeo\u201d,<\/em> aclara Carlos mientras observa un lote de hembras reci\u00e9n pre\u00f1adas. Con toda esta historia, los Buzeta son un ejemplo de productores de la zona, raz\u00f3n por la cual hace poco su campo fue elegido por el <strong>Instituto de Promoci\u00f3n de la Carne Vacuna Argentina (IPCVA)<\/strong>, para realizar una importante jornada.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"cont-embedImage\"><img decoding=\"async\" class=\"embedImage\" src=\"http:\/\/images.clarin.com\/rural\/terneros-destetados-pocas-semanas-festuca_CLAIMA20160610_0099_17.jpg\" alt=\"Los terneros destetados hace pocas semanas sobre un lote de festuca.\" \/><\/div>\n<p><strong><em>Terneros destetados hace pocas semanas sobre un lote de festuca.<\/em><\/strong><\/p>\n<p>En 1997, los Buzeta compraron 200 vientres Angus colorados, y esa podr\u00eda considerarse como la segunda fundaci\u00f3n de El Recreo. <em>\u201cA partir de ah\u00ed se empez\u00f3 a trabajar en agrandar el rodeo con inseminaci\u00f3n y con gen\u00e9tica de calidad\u201d<\/em>, explica Carlos. El campo cuenta actualmente con un plantel de 900 madres y un porcentaje de pre\u00f1ez que ronda el 93%. Y el esquema productivo se adapt\u00f3 con manejo y recursos forrajeros a los tiempos que corren.<\/p>\n<p>\u201c<em>Hist\u00f3ricamente, en este campo se hac\u00edan novillos pesados, para terceros o propios. En la medida que ten\u00edamos menos vacas ten\u00edamos m\u00e1s lugar para hacer ese novillo de exportaci\u00f3n con engordes de dos a\u00f1os, pero cuando fuimos aumentando la cantidad de vacas lleg\u00f3 un punto en que decidimos que ten\u00edamos que hacer m\u00e1s corto el ciclo de engorde\u201d<\/em>, explica Mariano.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"cont-embedImage\"><img decoding=\"async\" class=\"embedImage\" src=\"http:\/\/images.clarin.com\/rural\/raigras-recursos-fundamentales-esquema_CLAIMA20160610_0098_17.jpg\" alt=\"El raigr\u00e1s es uno de los recursos fundamentales en el esquema.\" \/><\/div>\n<p><strong><em>El raigr\u00e1s es uno de los recursos que se dan muy bien en la zona.<\/em><\/strong><\/p>\n<p>Mientras acomodaban sus objetivos, en los \u00faltimos quince a\u00f1os fueron evolucionando con la introducci\u00f3n de verdeos y otros recursos forrajeros como sorgos para comer en pie<em>. \u201cDespu\u00e9s de los sorgos hicimos raigr\u00e1s, que en algunos lotes ya lleva siete a\u00f1os de promoci\u00f3n\u201d<\/em>, detalla el productor, y explica que esos cultivos se producen en las 130 hect\u00e1reas m\u00e1s altas del campo, a las que llaman \u201cel m\u00e9dano\u201d, porque es arenoso e incluso tiene conchilla. Es que El Recreo est\u00e1 bastante cerca de la costa bonaerense, en el extremo sur de la Bah\u00eda de Samboromb\u00f3n, y probablemente en alg\u00fan momento haya estado cubierto por el mar. El resto del campo es un bajo dulce sobre el que van avanzando de a poco con la siembra de agropiros (en partes de inferior calidad) y festucas (en las mejores zonas).<\/p>\n<p>&nbsp;<\/p>\n<div class=\"cont-embedImage\"><img decoding=\"async\" class=\"embedImage\" src=\"http:\/\/images.clarin.com\/rural\/vacas-base-sistema_CLAIMA20160610_0100_17.jpg\" alt=\"Las vacas son la base del sistema.\" \/><\/div>\n<p><strong><em>Las vacas son la base estable del sistema.<\/em><\/strong><\/p>\n<p><em>\u00a0\u201cCombinando las pasturas con la suplementaci\u00f3n logramos acortar pr\u00e1cticamente un a\u00f1o el tiempo de engorde\u201d<\/em>, comenta Mariano. Despu\u00e9s, para evitar los problemas que el clima -por h\u00famedo o por seco- genera en el momento de engorde, decidieron instalar corrales en la parte alta del campo. \u201c<em>Comprando el ma\u00edz y los componentes proteicos descubrimos el feedlot, con lo que nos independizamos del clima. Dos meses antes de necesitar la plata, encerr\u00e1s y listo\u201d<\/em>, explica.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"cont-embedImage\"><img decoding=\"async\" class=\"embedImage\" src=\"http:\/\/images.clarin.com\/rural\/NA160611_CLAIMA20160610_0174_17.jpg\" alt=\"NA160611\" \/><\/div>\n<p><strong><em>La festuca ocupa gran parte de las zonas medias.<\/em><\/strong><\/p>\n<p>Los Buzeta hacen el destete a los seis meses, en marzo, cuando los terneros tienen alrededor de 200 kilos. Despu\u00e9s los animales se recr\u00edan sobre lotes de festuca o en campo natural, y con 230-250 kilos -a medida que lo demande el presupuesto financiero- entran a los corrales. Seg\u00fan la \u00e9poca del a\u00f1o venden los animales terminados con 320 kilos o hasta con 380 kilos.<\/p>\n<p>\u00a0Las hembras, por su parte, se seleccionan, se recr\u00edan sobre campo natural o en pasturas y algunas -las que llegan a 270 kilos- son entoradas a los quince meses. Otras se entoran en invierno para ser vendidas luego con el valor agregado de la pre\u00f1ez.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"cont-embedImage\"><img decoding=\"async\" class=\"embedImage\" src=\"http:\/\/images.clarin.com\/rural\/Maiz-partido-suplemento-proteico-suplementacion_CLAIMA20160610_0101_17.jpg\" alt=\"Ma\u00edz partido m\u00e1s suplemento proteico, el men\u00fa de suplementaci\u00f3n.\" \/><\/div>\n<p><strong><em>Ma\u00edz partido m\u00e1s suplemento proteico, para la suplementaci\u00f3n.<\/em><\/strong><\/p>\n<p><em>\u201cEl n\u00famero de vientres es la base que siempre hay que cuidar -remarca Mariano-. El fusible ante problemas clim\u00e1ticos es el ternero de invernada\u201d<\/em>. De esta manera mantienen un esquema flexible, adaptable a los vaivenes del mercado y el clima, pero no hipotecan el futuro. Por ejemplo, un lote de terneros que hab\u00eda sido destetado en noviembre y para el que ten\u00edan reservado un sorgo en pie, se termin\u00f3 vendiendo para invernada porque hab\u00eda buen precio, 35 pesos el kilo.<em> \u201cBuen negocio\u201d<\/em>, dicen.<\/p>\n<p><em>\u00a0\u201cEl feedlot es una muy buena herramienta financiera porque me permite vender animales gordos todo el a\u00f1o, pero todo depende de la evoluci\u00f3n del precio del ma\u00edz. Hay que tener flexibilidad. Si en el futuro el ma\u00edz se pone muy caro y deja de ser negocio el engorde, venderemos los terneros para invernada<\/em>\u201d, expresa Mariano. Y la explicaci\u00f3n refleja toda la estrategia: medidas simples y flexibilidad.\u00a0<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"cont-embedImage\"><img decoding=\"async\" class=\"embedImage\" src=\"http:\/\/images.clarin.com\/rural\/NA160611_CLAIMA20160610_0176_17.jpg\" alt=\"NA160611\" \/><\/div>\n<p><strong><em>Tres molinos bombean el agua desde las zonas dulces al resto del campo.<\/em><\/strong><\/p>\n<p><strong>Si&#8230; \u00a1gracias a los bancos!<\/strong><\/p>\n<p>Entre las claves para crecer como productor, Carlos Buzeta rescata en primer lugar el apoyo de un equipo s\u00f3lido de empleados y de asesores externos. Y, en segundo lugar, el apoyo de los bancos, que les permiti\u00f3 adquirir su propia maquinaria e independizarse de los contratistas. <em>\u201cEn el campo hay cuatro personas trabajando, y con esos empleados logramos hacer todas las labores. Nos fuimos independizando un poco gracias a las inversiones que hicimos en sembradora, fumigadora, mixer\u2026 No hay que tener miedo a los pr\u00e9stamos del banco. Si uno puede devolver la plata, son una buena herramienta para el crecimiento. Nosotros hemos sido corajudos\u2026\u201d<\/em>, concluye.\u00a0<\/p>\n<p>&nbsp;<\/p>\n<div class=\"cont-embedImage\"><img decoding=\"async\" class=\"embedImage\" src=\"http:\/\/images.clarin.com\/rural\/NA160611_CLAIMA20160610_0175_17.jpg\" alt=\"NA160611\" \/><\/div>\n<p><strong><em>El mixer, una herramienta que facilita el manejo del engorde.<\/em><\/strong><\/p>\n<p><strong>Los &#8220;campos de invierno&#8221;<\/strong><\/p>\n<p><em>\u201cLo normal en esta zona son los campos de cr\u00eda y los campos de invierno, que permiten recibir animales a partir de abril-mayo\u201d<\/em>, describe el productor de General Conesa Mariano Buzeta. Seg\u00fan explica, los campos de invierno son lotes que durante el verano no se pastorean porque tienen duraznillo, una especie cuyo consumo causa el enteque seco, enfermedad que calcifica las articulaciones de los animales. El enteque aparece en diciembre, cuando caen las hojas secas del duraznillo y se mezclan con los pastos que consumen las vacas. Pero en invierno, cuando el duraznillo no pierde las hojas, estos lotes son especialmente buenos.<em> \u201cEn verano estos campos se vac\u00edan totalmente y eso genera una gran producci\u00f3n de especies como cebadilla, raigr\u00e1s, tr\u00e9bol blanco y lotus. Genera engordes extraordinarios en los novillos con buena sanidad que vienen comiendo forraje regular en oto\u00f1o y entran a estos lotes en la fase final\u201d<\/em>.\u00a0<\/p>\n<p><strong>Fuente: Por Lucas Villamil<\/strong><\/p>\n<p><strong>http:\/\/www.clarin.com\/rural\/cuenca-Salado-flexibilidad-hace-diferencia_0_1592840777.html<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>En Gral. Conesa, los Buzeta hacen cr\u00eda y engorde con ideas sencillas y flexibles, pero muy eficientes. El \u00e9xito, contado por dos generaciones. La relaci\u00f3n de la familia Buzeta con el campo es como un matrimonio fiel: no est\u00e1 libre de desastres, pero con confianza y adaptaci\u00f3n al cambio logra sobrevivir a las adversidades. En 1982, Carlos Buzeta decidi\u00f3 dejar su empresa constructora para volcarse a la actividad pecuaria. Compr\u00f3 un campo de 2.000 hect\u00e1reas en General Conesa, a mitad de camino entre la ciudad de Buenos Aires y Mar del Plata, y empez\u00f3 a aprender desde cero los secretos de la ganader\u00eda. \u201cLas vacas, los toros, los terneros\u2026 para m\u00ed eran todos iguales\u201d, recuerda el hombre en di\u00e1logo con Clar\u00edn Rural. En aquel entonces en el campo hab\u00eda apenas trescientos animales. De a poco, los Buzeta fueron arreglando las aguadas, los alambrados e implantaron las primeras pasturas de raigr\u00e1s, y el rodeo se agrand\u00f3 hasta llegar a los 2.000 animales. Pero en el 85 lleg\u00f3 el primer gran desaf\u00edo, una inundaci\u00f3n, y en el 92 hubo otra que fue un golpe casi definitivo. Pero lograron levantarse de la lona antes del knock out. \u201cSe rompieron las pasturas que con [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7983,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7982","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En la cuenca del Salado, la flexibilidad hace la diferencia | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En la cuenca del Salado, la flexibilidad hace la diferencia | Proagro\" \/>\n<meta property=\"og:description\" content=\"En Gral. Conesa, los Buzeta hacen cr\u00eda y engorde con ideas sencillas y flexibles, pero muy eficientes. El \u00e9xito, contado por dos generaciones. La relaci\u00f3n de la familia Buzeta con el campo es como un matrimonio fiel: no est\u00e1 libre de desastres, pero con confianza y adaptaci\u00f3n al cambio logra sobrevivir a las adversidades. En 1982, Carlos Buzeta decidi\u00f3 dejar su empresa constructora para volcarse a la actividad pecuaria. Compr\u00f3 un campo de 2.000 hect\u00e1reas en General Conesa, a mitad de camino entre la ciudad de Buenos Aires y Mar del Plata, y empez\u00f3 a aprender desde cero los secretos de la ganader\u00eda. \u201cLas vacas, los toros, los terneros\u2026 para m\u00ed eran todos iguales\u201d, recuerda el hombre en di\u00e1logo con Clar\u00edn Rural. En aquel entonces en el campo hab\u00eda apenas trescientos animales. De a poco, los Buzeta fueron arreglando las aguadas, los alambrados e implantaron las primeras pasturas de raigr\u00e1s, y el rodeo se agrand\u00f3 hasta llegar a los 2.000 animales. Pero en el 85 lleg\u00f3 el primer gran desaf\u00edo, una inundaci\u00f3n, y en el 92 hubo otra que fue un golpe casi definitivo. Pero lograron levantarse de la lona antes del knock out. \u201cSe rompieron las pasturas que con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-13T14:56:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T19:15:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/06\/Carlos-Mariano-Buzeta-General-Conesa_CLAIMA20160611_0077_28.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"En la cuenca del Salado, la flexibilidad hace la diferencia\",\"datePublished\":\"2016-06-13T14:56:46+00:00\",\"dateModified\":\"2020-06-29T19:15:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/\"},\"wordCount\":1358,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Carlos-Mariano-Buzeta-General-Conesa_CLAIMA20160611_0077_28.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/\",\"name\":\"En la cuenca del Salado, la flexibilidad hace la diferencia | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Carlos-Mariano-Buzeta-General-Conesa_CLAIMA20160611_0077_28.jpg\",\"datePublished\":\"2016-06-13T14:56:46+00:00\",\"dateModified\":\"2020-06-29T19:15:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Carlos-Mariano-Buzeta-General-Conesa_CLAIMA20160611_0077_28.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Carlos-Mariano-Buzeta-General-Conesa_CLAIMA20160611_0077_28.jpg\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En la cuenca del Salado, la flexibilidad hace la diferencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En la cuenca del Salado, la flexibilidad hace la diferencia | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/","og_locale":"en_US","og_type":"article","og_title":"En la cuenca del Salado, la flexibilidad hace la diferencia | Proagro","og_description":"En Gral. Conesa, los Buzeta hacen cr\u00eda y engorde con ideas sencillas y flexibles, pero muy eficientes. El \u00e9xito, contado por dos generaciones. La relaci\u00f3n de la familia Buzeta con el campo es como un matrimonio fiel: no est\u00e1 libre de desastres, pero con confianza y adaptaci\u00f3n al cambio logra sobrevivir a las adversidades. En 1982, Carlos Buzeta decidi\u00f3 dejar su empresa constructora para volcarse a la actividad pecuaria. Compr\u00f3 un campo de 2.000 hect\u00e1reas en General Conesa, a mitad de camino entre la ciudad de Buenos Aires y Mar del Plata, y empez\u00f3 a aprender desde cero los secretos de la ganader\u00eda. \u201cLas vacas, los toros, los terneros\u2026 para m\u00ed eran todos iguales\u201d, recuerda el hombre en di\u00e1logo con Clar\u00edn Rural. En aquel entonces en el campo hab\u00eda apenas trescientos animales. De a poco, los Buzeta fueron arreglando las aguadas, los alambrados e implantaron las primeras pasturas de raigr\u00e1s, y el rodeo se agrand\u00f3 hasta llegar a los 2.000 animales. Pero en el 85 lleg\u00f3 el primer gran desaf\u00edo, una inundaci\u00f3n, y en el 92 hubo otra que fue un golpe casi definitivo. Pero lograron levantarse de la lona antes del knock out. \u201cSe rompieron las pasturas que con [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-06-13T14:56:46+00:00","article_modified_time":"2020-06-29T19:15:40+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/06\/Carlos-Mariano-Buzeta-General-Conesa_CLAIMA20160611_0077_28.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"En la cuenca del Salado, la flexibilidad hace la diferencia","datePublished":"2016-06-13T14:56:46+00:00","dateModified":"2020-06-29T19:15:40+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/"},"wordCount":1358,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/06\/Carlos-Mariano-Buzeta-General-Conesa_CLAIMA20160611_0077_28.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/","url":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/","name":"En la cuenca del Salado, la flexibilidad hace la diferencia | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/06\/Carlos-Mariano-Buzeta-General-Conesa_CLAIMA20160611_0077_28.jpg","datePublished":"2016-06-13T14:56:46+00:00","dateModified":"2020-06-29T19:15:40+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/06\/Carlos-Mariano-Buzeta-General-Conesa_CLAIMA20160611_0077_28.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/06\/Carlos-Mariano-Buzeta-General-Conesa_CLAIMA20160611_0077_28.jpg","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/en-la-cuenca-del-salado-la-flexibilidad-hace-la-diferencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"En la cuenca del Salado, la flexibilidad hace la diferencia"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7982"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7982\/revisions"}],"predecessor-version":[{"id":14012,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7982\/revisions\/14012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/7983"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}