{"id":7901,"date":"2016-05-31T14:15:13","date_gmt":"2016-05-31T14:15:13","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7901"},"modified":"2020-06-29T19:14:31","modified_gmt":"2020-06-29T19:14:31","slug":"la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/","title":{"rendered":"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<h5>Comienza a regir de manera efectiva en cinco meses.<\/h5>\n<div class=\"extras\"><a class=\"thickbox\" title=\"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar\" href=\"http:\/\/www.valorsoja.com\/wp-content\/uploads\/AfipHome.jpg\" rel=\"fancybox\"><img decoding=\"async\" class=\"border medium\" title=\"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar\" src=\"http:\/\/www.valorsoja.com\/wp-content\/uploads\/AfipHome-280x148.jpg\" alt=\"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar\" \/><\/a><\/div>\n<div class=\"texto\">\n<div id=\"HOTWordsTxt\">\n<p>Las autoridades de la Afip crearon un registro con el prop\u00f3sito de reducir la evasi\u00f3n presente en el sector c\u00e1rnico a trav\u00e9s de la determinaci\u00f3n de nuevas exigencias tributarias.<\/p>\n<p>El <strong>\u201cRegistro Fiscal de Operadores de la Cadena de Producci\u00f3n y Comercializaci\u00f3n de Haciendas y Carnes Bovinas y Bubalinas\u201d <\/strong>\u2013tal es el nombre completo\u2013 abarcar\u00e1 a todos los integrantes de la cadena c\u00e1rnica con excepci\u00f3n de los transportistas.<\/p>\n<p><em>\u201cLa permanencia en el Registro estar\u00e1 condicionada a que el contribuyente mantenga una correcta conducta fiscal\u201d<\/em>, indica la resoluci\u00f3n 3873\/16 de la Afip (<a href=\"https:\/\/www.boletinoficial.gob.ar\/#!DetalleNorma\/145869\/20160530\">publicada hoy en el Bolet\u00edn Oficial<\/a>). Cuando se constate alguna irregularidad, el organismo <em>\u201cdispondr\u00e1 su inmediata suspensi\u00f3n\u201d<\/em>.<\/p>\n<p>El plazo m\u00e1ximo para corregir una irregularidad detectada ser\u00e1 de sesenta d\u00edas; una vez cumplido el mismo, el operador ser\u00e1 excluido en caso de no haber solucionado la inadecuaci\u00f3n tributaria. La Afip tambi\u00e9n podr\u00e1 excluir operadores cuando detecte el empleo de documentos ap\u00f3crifos o falseamiento de datos fiscales.<\/p>\n<p>Todos los operadores que se encuentren suspendidos, no incluidos o excluidos del Registro pasar\u00e1n a quedar alcanzados por al\u00edcuotas y valores diferenciales en los reg\u00edmenes de percepci\u00f3n, pagos a cuenta y\/o retenci\u00f3n (los cuales van a ser actualizados por la Afip cada seis meses).<\/p>\n<p>Por ejemplo: un usuario de faena que compre hacienda de manera directa al productor y que est\u00e9 incluido en el Registro, deber\u00e1 pagar IVA a cuenta por un monto de 40 $\/cabeza faenada, mientras que, en caso de no estar activo en el Registro, deber\u00e1 abonar 65 $\/cabeza (<a href=\"https:\/\/www.boletinoficial.gob.ar\/imagenes\/getImagen\/01\/2016\/05\/30\/Im%C3%A1genes\/2016053001_10_fmt.jpeg\" rel=\"fancybox\">la planilla completa con las diferentes situaciones puede verse aqu\u00ed<\/a>).<\/p>\n<p>El monto del pago a cuenta a cargo de IVA deber\u00e1 abonarse por las operaciones realizadas en cada quincena del mes<em> \u201caunque no se produzca la venta posterior de la carne por cualquier causa\u201d<\/em>.<\/p>\n<p>La normativa indica adem\u00e1s que quedan obligados a actuar como agentes de percepci\u00f3n \u2013en tanto re\u00fanan la condici\u00f3n de responsables inscriptos en IVA\u2013 los propietarios, locatarios, arrendatarios o concesionarios de establecimientos de faena, los usuarios del servicio de faena y los consignatarios de hacienda.<\/p>\n<p>Tambi\u00e9n estar\u00e1n obligados a actuar como agentes de retenci\u00f3n los usuarios del servicio de faena y los responsables de los establecimientos faenadores por las compras de hacienda en pie realizada a responsables inscriptos en el IVA que se encuentren suspendidos, no incluidos o excluidos del Registro. El importe a retener ser\u00e1 el 5% del valor neto de la hacienda adquirida.<\/p>\n<p>El plazo para darse de alta en el nuevo registro es de 90 d\u00edas corridos contados a partir de hoy lunes 30 de mayo, mientras que la nueva modalidad por aplicar en el r\u00e9gimen de percepci\u00f3n, pago a cuenta y retenci\u00f3n del IVA en el sector comenzar\u00e1 a regir de manera efectiva a partir de un plazo de 60 d\u00edas corridos contados desde la vigencia del Registro (el d\u00eda 91 del plazo\u00a0anterior).<\/p>\n<p><strong>Fuente:\u00a0www.valorsoja.com\/2016\/05\/30\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/#.V02P1dLhDb1<\/strong><\/p>\n<\/div>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comienza a regir de manera efectiva en cinco meses. Las autoridades de la Afip crearon un registro con el prop\u00f3sito de reducir la evasi\u00f3n presente en el sector c\u00e1rnico a trav\u00e9s de la determinaci\u00f3n de nuevas exigencias tributarias. El \u201cRegistro Fiscal de Operadores de la Cadena de Producci\u00f3n y Comercializaci\u00f3n de Haciendas y Carnes Bovinas y Bubalinas\u201d \u2013tal es el nombre completo\u2013 abarcar\u00e1 a todos los integrantes de la cadena c\u00e1rnica con excepci\u00f3n de los transportistas. \u201cLa permanencia en el Registro estar\u00e1 condicionada a que el contribuyente mantenga una correcta conducta fiscal\u201d, indica la resoluci\u00f3n 3873\/16 de la Afip (publicada hoy en el Bolet\u00edn Oficial). Cuando se constate alguna irregularidad, el organismo \u201cdispondr\u00e1 su inmediata suspensi\u00f3n\u201d. El plazo m\u00e1ximo para corregir una irregularidad detectada ser\u00e1 de sesenta d\u00edas; una vez cumplido el mismo, el operador ser\u00e1 excluido en caso de no haber solucionado la inadecuaci\u00f3n tributaria. La Afip tambi\u00e9n podr\u00e1 excluir operadores cuando detecte el empleo de documentos ap\u00f3crifos o falseamiento de datos fiscales. Todos los operadores que se encuentren suspendidos, no incluidos o excluidos del Registro pasar\u00e1n a quedar alcanzados por al\u00edcuotas y valores diferenciales en los reg\u00edmenes de percepci\u00f3n, pagos a cuenta y\/o retenci\u00f3n (los cuales van a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7902,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7901","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar | Proagro\" \/>\n<meta property=\"og:description\" content=\"Comienza a regir de manera efectiva en cinco meses. Las autoridades de la Afip crearon un registro con el prop\u00f3sito de reducir la evasi\u00f3n presente en el sector c\u00e1rnico a trav\u00e9s de la determinaci\u00f3n de nuevas exigencias tributarias. El \u201cRegistro Fiscal de Operadores de la Cadena de Producci\u00f3n y Comercializaci\u00f3n de Haciendas y Carnes Bovinas y Bubalinas\u201d \u2013tal es el nombre completo\u2013 abarcar\u00e1 a todos los integrantes de la cadena c\u00e1rnica con excepci\u00f3n de los transportistas. \u201cLa permanencia en el Registro estar\u00e1 condicionada a que el contribuyente mantenga una correcta conducta fiscal\u201d, indica la resoluci\u00f3n 3873\/16 de la Afip (publicada hoy en el Bolet\u00edn Oficial). Cuando se constate alguna irregularidad, el organismo \u201cdispondr\u00e1 su inmediata suspensi\u00f3n\u201d. El plazo m\u00e1ximo para corregir una irregularidad detectada ser\u00e1 de sesenta d\u00edas; una vez cumplido el mismo, el operador ser\u00e1 excluido en caso de no haber solucionado la inadecuaci\u00f3n tributaria. La Afip tambi\u00e9n podr\u00e1 excluir operadores cuando detecte el empleo de documentos ap\u00f3crifos o falseamiento de datos fiscales. Todos los operadores que se encuentren suspendidos, no incluidos o excluidos del Registro pasar\u00e1n a quedar alcanzados por al\u00edcuotas y valores diferenciales en los reg\u00edmenes de percepci\u00f3n, pagos a cuenta y\/o retenci\u00f3n (los cuales van a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-31T14:15:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T19:14:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/f1a3r20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"263\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar\",\"datePublished\":\"2016-05-31T14:15:13+00:00\",\"dateModified\":\"2020-06-29T19:14:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/\"},\"wordCount\":542,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/f1a3r20.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/\",\"name\":\"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/f1a3r20.jpg\",\"datePublished\":\"2016-05-31T14:15:13+00:00\",\"dateModified\":\"2020-06-29T19:14:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/f1a3r20.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/f1a3r20.jpg\",\"width\":590,\"height\":263},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/","og_locale":"en_US","og_type":"article","og_title":"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar | Proagro","og_description":"Comienza a regir de manera efectiva en cinco meses. Las autoridades de la Afip crearon un registro con el prop\u00f3sito de reducir la evasi\u00f3n presente en el sector c\u00e1rnico a trav\u00e9s de la determinaci\u00f3n de nuevas exigencias tributarias. El \u201cRegistro Fiscal de Operadores de la Cadena de Producci\u00f3n y Comercializaci\u00f3n de Haciendas y Carnes Bovinas y Bubalinas\u201d \u2013tal es el nombre completo\u2013 abarcar\u00e1 a todos los integrantes de la cadena c\u00e1rnica con excepci\u00f3n de los transportistas. \u201cLa permanencia en el Registro estar\u00e1 condicionada a que el contribuyente mantenga una correcta conducta fiscal\u201d, indica la resoluci\u00f3n 3873\/16 de la Afip (publicada hoy en el Bolet\u00edn Oficial). Cuando se constate alguna irregularidad, el organismo \u201cdispondr\u00e1 su inmediata suspensi\u00f3n\u201d. El plazo m\u00e1ximo para corregir una irregularidad detectada ser\u00e1 de sesenta d\u00edas; una vez cumplido el mismo, el operador ser\u00e1 excluido en caso de no haber solucionado la inadecuaci\u00f3n tributaria. La Afip tambi\u00e9n podr\u00e1 excluir operadores cuando detecte el empleo de documentos ap\u00f3crifos o falseamiento de datos fiscales. Todos los operadores que se encuentren suspendidos, no incluidos o excluidos del Registro pasar\u00e1n a quedar alcanzados por al\u00edcuotas y valores diferenciales en los reg\u00edmenes de percepci\u00f3n, pagos a cuenta y\/o retenci\u00f3n (los cuales van a [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-05-31T14:15:13+00:00","article_modified_time":"2020-06-29T19:14:31+00:00","og_image":[{"width":590,"height":263,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/f1a3r20.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar","datePublished":"2016-05-31T14:15:13+00:00","dateModified":"2020-06-29T19:14:31+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/"},"wordCount":542,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/f1a3r20.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/","url":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/","name":"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/f1a3r20.jpg","datePublished":"2016-05-31T14:15:13+00:00","dateModified":"2020-06-29T19:14:31+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/f1a3r20.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/f1a3r20.jpg","width":590,"height":263},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/la-afip-implementara-un-registro-fiscal-ganadero-para-intentar-reducir-la-evasion-en-el-sector-carnico-los-operadores-excluidos-tendran-grandes-dificultades-para-trabajar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"La Afip implementar\u00e1 un Registro Fiscal Ganadero para intentar reducir la evasi\u00f3n en el sector c\u00e1rnico: los operadores excluidos tendr\u00e1n grandes dificultades para trabajar"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7901"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7901\/revisions"}],"predecessor-version":[{"id":14001,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7901\/revisions\/14001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/7902"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}