{"id":7869,"date":"2016-05-27T15:30:42","date_gmt":"2016-05-27T15:30:42","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7869"},"modified":"2016-05-27T19:05:01","modified_gmt":"2016-05-27T19:05:01","slug":"english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/","title":{"rendered":"Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>La medida, anunciada por el ministro de Agroindustria, <strong>Ricardo Buryaile<\/strong>, apunta, entre otros casos, a quienes sufrieron p\u00e9rdidas por las \u00faltimas inundaciones.<\/p>\n<p class=\"primero\">El ministro de Agroindustria,<strong> Ricardo Buryaile<\/strong>, anunci\u00f3 una l\u00ednea de cr\u00e9ditos por $ 5000 millones para los productores que se encuentran en situaci\u00f3n de emergencia. La medida, en cuya presentaci\u00f3n adem\u00e1s asistieron directivos del Banco Naci\u00f3n, apunta, entre otras situaciones, a los productores afectados por las \u00faltimas inundaciones.<\/p>\n<aside class=\"banner caja2\" data-adpos=\"caja2\">\n<div id=\"eplAdDivcaja2\">La l\u00ednea por 5000 millones de pesos es con un monto m\u00e1ximo de hasta $ 500.000 por solicitante. Alcanzar\u00e1 a unos 10.000 productores, seg\u00fan el Gobierno.<\/div>\n<\/aside>\n<p><em>&#8220;Esta medida brindar\u00e1 una reducci\u00f3n del 5% en la tasa de inter\u00e9s para los productores agropecuarios de provincias en emergencia agropecuaria que cuenten con el certificado individual expedido en los t\u00e9rminos de la Ley 26.509 (de emergencia agropecuaria)<\/em>&#8220;, destac\u00f3<strong> Buryaile<\/strong>. <em>&#8220;Es importante remarcar que los productores que no cuentan con los certificados de emergencia van a poder acceder a una l\u00ednea productiva a una tasa del 22%, mientras que quienes presenten el certificado acceder\u00e1n a una tasa de 5 puntos porcentuales menos&#8221;<\/em>, dijo<strong> Santiago Hardie<\/strong>, secretario de Coordinaci\u00f3n y Desarrollo Territorial.<\/p>\n<aside class=\"banner caja3\" data-adpos=\"caja3\">\n<div id=\"eplAdDivcaja3\">La l\u00ednea tendr\u00e1 un a\u00f1o de bonificaci\u00f3n y un plazo de 36 hasta 48 meses. En tanto, a trav\u00e9s del <strong>Apoyo Financiero para Cooperativas y Mutuales (INAES)<\/strong> se inform\u00f3 el subsidio de tasas a cooperativas cuyos productores fueron afectados por las inundaciones por un monto por productor de hasta $ 50.000.<\/div>\n<\/aside>\n<p>En lo que va del a\u00f1o se declar\u00f3 la emergencia para La Rioja, Corrientes, Chaco, Entre R\u00edos, C\u00f3rdoba, Santa Fe, Formosa, Catamarca, Mendoza, y R\u00edo Negro.<\/p>\n<p><strong>Fuente:\u00a0www.lanacion.com.ar\/1902849-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La medida, anunciada por el ministro de Agroindustria, Ricardo Buryaile, apunta, entre otros casos, a quienes sufrieron p\u00e9rdidas por las \u00faltimas inundaciones. El ministro de Agroindustria, Ricardo Buryaile, anunci\u00f3 una l\u00ednea de cr\u00e9ditos por $ 5000 millones para los productores que se encuentran en situaci\u00f3n de emergencia. La medida, en cuya presentaci\u00f3n adem\u00e1s asistieron directivos del Banco Naci\u00f3n, apunta, entre otras situaciones, a los productores afectados por las \u00faltimas inundaciones. La l\u00ednea por 5000 millones de pesos es con un monto m\u00e1ximo de hasta $ 500.000 por solicitante. Alcanzar\u00e1 a unos 10.000 productores, seg\u00fan el Gobierno. &#8220;Esta medida brindar\u00e1 una reducci\u00f3n del 5% en la tasa de inter\u00e9s para los productores agropecuarios de provincias en emergencia agropecuaria que cuenten con el certificado individual expedido en los t\u00e9rminos de la Ley 26.509 (de emergencia agropecuaria)&#8220;, destac\u00f3 Buryaile. &#8220;Es importante remarcar que los productores que no cuentan con los certificados de emergencia van a poder acceder a una l\u00ednea productiva a una tasa del 22%, mientras que quienes presenten el certificado acceder\u00e1n a una tasa de 5 puntos porcentuales menos&#8221;, dijo Santiago Hardie, secretario de Coordinaci\u00f3n y Desarrollo Territorial. La l\u00ednea tendr\u00e1 un a\u00f1o de bonificaci\u00f3n y un plazo de 36 hasta [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7878,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7869","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria | Proagro\" \/>\n<meta property=\"og:description\" content=\"La medida, anunciada por el ministro de Agroindustria, Ricardo Buryaile, apunta, entre otros casos, a quienes sufrieron p\u00e9rdidas por las \u00faltimas inundaciones. El ministro de Agroindustria, Ricardo Buryaile, anunci\u00f3 una l\u00ednea de cr\u00e9ditos por $ 5000 millones para los productores que se encuentran en situaci\u00f3n de emergencia. La medida, en cuya presentaci\u00f3n adem\u00e1s asistieron directivos del Banco Naci\u00f3n, apunta, entre otras situaciones, a los productores afectados por las \u00faltimas inundaciones. La l\u00ednea por 5000 millones de pesos es con un monto m\u00e1ximo de hasta $ 500.000 por solicitante. Alcanzar\u00e1 a unos 10.000 productores, seg\u00fan el Gobierno. &#8220;Esta medida brindar\u00e1 una reducci\u00f3n del 5% en la tasa de inter\u00e9s para los productores agropecuarios de provincias en emergencia agropecuaria que cuenten con el certificado individual expedido en los t\u00e9rminos de la Ley 26.509 (de emergencia agropecuaria)&#8220;, destac\u00f3 Buryaile. &#8220;Es importante remarcar que los productores que no cuentan con los certificados de emergencia van a poder acceder a una l\u00ednea productiva a una tasa del 22%, mientras que quienes presenten el certificado acceder\u00e1n a una tasa de 5 puntos porcentuales menos&#8221;, dijo Santiago Hardie, secretario de Coordinaci\u00f3n y Desarrollo Territorial. La l\u00ednea tendr\u00e1 un a\u00f1o de bonificaci\u00f3n y un plazo de 36 hasta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-27T15:30:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-27T19:05:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/1145x395-27052016-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria\",\"datePublished\":\"2016-05-27T15:30:42+00:00\",\"dateModified\":\"2016-05-27T19:05:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/\"},\"wordCount\":293,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/1145x395-27052016-blog.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/\",\"name\":\"Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/1145x395-27052016-blog.jpg\",\"datePublished\":\"2016-05-27T15:30:42+00:00\",\"dateModified\":\"2016-05-27T19:05:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/1145x395-27052016-blog.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/1145x395-27052016-blog.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/","og_locale":"en_US","og_type":"article","og_title":"Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria | Proagro","og_description":"La medida, anunciada por el ministro de Agroindustria, Ricardo Buryaile, apunta, entre otros casos, a quienes sufrieron p\u00e9rdidas por las \u00faltimas inundaciones. El ministro de Agroindustria, Ricardo Buryaile, anunci\u00f3 una l\u00ednea de cr\u00e9ditos por $ 5000 millones para los productores que se encuentran en situaci\u00f3n de emergencia. La medida, en cuya presentaci\u00f3n adem\u00e1s asistieron directivos del Banco Naci\u00f3n, apunta, entre otras situaciones, a los productores afectados por las \u00faltimas inundaciones. La l\u00ednea por 5000 millones de pesos es con un monto m\u00e1ximo de hasta $ 500.000 por solicitante. Alcanzar\u00e1 a unos 10.000 productores, seg\u00fan el Gobierno. &#8220;Esta medida brindar\u00e1 una reducci\u00f3n del 5% en la tasa de inter\u00e9s para los productores agropecuarios de provincias en emergencia agropecuaria que cuenten con el certificado individual expedido en los t\u00e9rminos de la Ley 26.509 (de emergencia agropecuaria)&#8220;, destac\u00f3 Buryaile. &#8220;Es importante remarcar que los productores que no cuentan con los certificados de emergencia van a poder acceder a una l\u00ednea productiva a una tasa del 22%, mientras que quienes presenten el certificado acceder\u00e1n a una tasa de 5 puntos porcentuales menos&#8221;, dijo Santiago Hardie, secretario de Coordinaci\u00f3n y Desarrollo Territorial. La l\u00ednea tendr\u00e1 un a\u00f1o de bonificaci\u00f3n y un plazo de 36 hasta [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-05-27T15:30:42+00:00","article_modified_time":"2016-05-27T19:05:01+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/1145x395-27052016-blog.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria","datePublished":"2016-05-27T15:30:42+00:00","dateModified":"2016-05-27T19:05:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/"},"wordCount":293,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/1145x395-27052016-blog.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/","url":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/","name":"Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/1145x395-27052016-blog.jpg","datePublished":"2016-05-27T15:30:42+00:00","dateModified":"2016-05-27T19:05:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/1145x395-27052016-blog.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2014\/12\/1145x395-27052016-blog.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/english-destinan-5000-millones-para-productores-en-situacion-de-emergencia-agropecuaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Destinan $ 5000 millones para productores en situaci\u00f3n de emergencia agropecuaria"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7869"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7869\/revisions"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}