{"id":7822,"date":"2016-05-20T13:41:47","date_gmt":"2016-05-20T13:41:47","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7822"},"modified":"2016-05-20T16:13:06","modified_gmt":"2016-05-20T16:13:06","slug":"hoy-se-oficializan-los-subsidios-para-los-productores-tamberos","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/","title":{"rendered":"Hoy se oficializan los subsidios para los productores tamberos"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Lo confirm\u00f3 a <strong>CASTELLANOS<\/strong> el<strong> Subsecretario de Lecher\u00eda de la Naci\u00f3n<\/strong>, al tiempo que indic\u00f3 que se pagar\u00edan los subsidios la semana pr\u00f3xima. Adem\u00e1s de visitar ayer entidades de la regi\u00f3n, <strong>Alejandro Sammartino<\/strong> estar\u00e1 hoy en el <strong>INTA Rafaela<\/strong> en una capacitaci\u00f3n para reestructurar el programa<strong> Cambio Rural Lechero<\/strong>.<\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Hoy-se-oficializan-lo-subsidios-para-los-productores-tamberos-300x300.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7823\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Hoy-se-oficializan-lo-subsidios-para-los-productores-tamberos-300x300.jpg\" alt=\"Hoy-se-oficializan-lo-subsidios-para-los-productores-tamberos-300x300\" width=\"300\" height=\"300\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Hoy-se-oficializan-lo-subsidios-para-los-productores-tamberos-300x300.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Hoy-se-oficializan-lo-subsidios-para-los-productores-tamberos-300x300-100x100.jpg 100w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Hoy-se-oficializan-lo-subsidios-para-los-productores-tamberos-300x300-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Durante esta ma\u00f1ana, en el <strong>INTA Rafaela<\/strong> se cumplir\u00e1 con una jornada de capacitaci\u00f3n de asesores del programa <strong>Cambio Rural Lechero<\/strong>, para poder iniciar una nueva etapa, con otra visi\u00f3n para este programa orientado a peque\u00f1os y medianos productores, desde el \u00e1ngulo de una mejora integral de sus sistemas. Es por ello que desde ayer est\u00e1 en la ciudad de Rafaela el <strong>Subsecretario de Lecher\u00eda de la Naci\u00f3n<\/strong>, quien entiende que este nuevo comienzo puede tender a que <em>\u201chaya cada vez m\u00e1s grupos de Cambio Rural, m\u00e1s consistentes y con m\u00e1s oportunidades\u201d<\/em>.<\/p>\n<p>De todas maneras, la visita a la regi\u00f3n se inici\u00f3 en la <strong>Cooperativa Guillermo Lehmann<\/strong> de Pilar, siguiendo por la <strong>Sociedad Rural de Rafaela<\/strong> y finalmente en la sede de la<strong> Mesa de Productores de Leche de Santa Fe<\/strong>. Es as\u00ed que <strong>Alejandro Sammartino<\/strong> remarc\u00f3 que <em>\u201centendiendo la gravedad de la situaci\u00f3n productiva es que estamos reuni\u00e9ndonos, en un trabajo que ya venimos teniendo y llevamos una agenda de trabajo. Fue un intercambio muy lindo con los productores, tratamos de establecer diagn\u00f3sticos, les contamos nosotros c\u00f3mo estamos viendo la situaci\u00f3n en t\u00e9rminos de lo que ha sido el endeudamiento, en lo que es el d\u00e9ficit operativo que estamos teniendo y en lo que tenemos que trabajar juntos, en procura de los sistemas productivos de los tamberos<\/em>\u201d.<\/p>\n<p>Una de las confirmaciones que esta visita deja es la publicaci\u00f3n en la jornada de hoy de las compensaciones, en el Bolet\u00edn Oficial, correspondientes a la producci\u00f3n de los meses de enero y febrero, con lo cual<em> \u201cla semana que viene se efectivizar\u00eda el pago de los 50 centavos por litro\u201d<\/em>, donde intervienen la Naci\u00f3n y las provincias en estas ayudas, adem\u00e1s de iniciarse el giro de fondos, por ejemplo para el aporte a peque\u00f1os productores, con 400 pesos por animal que dispuso Santa Fe, con un fondo de 41 millones,<em> \u201cen un trabajo coordinado, en procura de no dejar productores afuera\u201d<\/em>.<\/p>\n<p>Lo que plantea el funcionario es que <em>\u201cpas\u00f3 el tiempo de la catarsis al tiempo de la acci\u00f3n, para entender qu\u00e9 vamos a hacer para levantarnos, teniendo en cuenta que la recuperaci\u00f3n del precio es consistente y ahora tenemos que trabajar desde el punto de vista productivo\u201d<\/em>, aunque reconoce que en estos encuentros con productores lo que percibe es<em> \u201cla necesidad de ser escuchados, con una primera etapa en la que \u00b4te quiero contar todo lo que me est\u00e1 pasando y las necesidades que tengo\u00b4; y creo que terminamos con un clima de esperanza, de buena onda, entendiendo desde la honestidad que contamos lo que podemos hacer y lo que no podemos hacer, en un camino de confianza y transparencia. Lo reitero, van a ser las dos banderas del Ministerio y de la Argentina, por la confianza en saber que vos est\u00e1s haciendo las cosas de la mejor manera; y transparencia haciendo p\u00fablico todo el trabajo, sin mentir y sin prometer las cosas que no se van a poder cumplir; y pidiendo disculpas cuando las cosas no se dan en los tiempos que uno desear\u00eda\u201d<\/em>, argument\u00f3 contando 108 d\u00edas de gesti\u00f3n para<em> \u201centender qu\u00e9 Estado recibimos, qu\u00e9 Estado tenemos que organizar\u201d<\/em>.<\/p>\n<p>El dato que aporta es que<em> \u201ca tambos constantes, la ca\u00edda de la producci\u00f3n abril contra abril, es del 16 por ciento. La realidad es que la situaci\u00f3n es tan compleja que no existe una soluci\u00f3n simple, existen un paquete de medidas que se van aplicando como son las medidas fiscales, las financieras, porque en el Banco Naci\u00f3n hemos sacado tres cr\u00e9ditos ya\u201d<\/em>, para poder acompa\u00f1ar las diferentes necesidades de los productores, claro que queda pendiente la explicitaci\u00f3n a las entidades sobre la agilizaci\u00f3n de pr\u00e9stamos, e incluso la extensi\u00f3n de ayudas sobre todo a los productores que tienen certificados de emergencia.<\/p>\n<p><strong>Evaluaci\u00f3n<\/strong><\/p>\n<p><strong>Sammartino<\/strong> le agradeci\u00f3 a los productores, muchos representantes de cooperativas de la regi\u00f3n, sobre todo porque <em>\u201cpodr\u00edan haber tenido reproches m\u00e1s duros\u201d<\/em>, pero destac\u00f3 el conocimiento que <em>\u201cla crisis tiene nombre y apellido; y familias detr\u00e1s\u201d<\/em>.<\/p>\n<p>Con niveles fluctuantes de tensi\u00f3n durante el encuentro en la sede de la calle Pellegrini, al concluir el encuentro <strong>Marcelo Aimaro<\/strong>, el presidente de <strong>Meprolsafe<\/strong>, evalu\u00f3 que<em> \u201clo bueno es que el Subsecretario vino y dio respuestas, sobre las posibilidades de hacer cosas, pero lo que pasa es que los tamberos necesitamos las soluciones ma\u00f1ana, si no vamos a seguir desapareciendo\u201d<\/em>, sin embargo sostiene que<em> \u201cvamos a seguir llevando propuestas, golpeando puertas, para que alg\u00fan d\u00eda se pueda ordenar esta cadena, en la que sabemos todos que la plata est\u00e1, no queremos compensaciones, pero s\u00ed lo que nos corresponde desde la g\u00f3ndola, no que se sigan haciendo comisiones para saber cu\u00e1l es el costo del tambero\u201d<\/em>, aludiendo a que la leche subi\u00f3 cuatro pesos de golpe y reci\u00e9n ahora los productores se acercar\u00edan a ese valor por litro. De todas maneras, se debe repensar el tema de los cr\u00e9ditos a un a\u00f1o de plazo, porque no es tiempo suficiente para recuperar la producci\u00f3n y poder devolver los pr\u00e9stamos.<\/p>\n<p><strong>SanCor y lo que no quieren<\/strong><\/p>\n<p>En el encuentro con los productores <strong>Sammartino<\/strong> sostuvo en cuanto a la crisis de SanCor, <em>\u201cno podemos dejar que sea una Cresta Roja\u201d<\/em>, en alusi\u00f3n a la av\u00edcola que debi\u00f3 ser auxiliada para su reactivaci\u00f3n.<\/p>\n<p>Con m\u00e1s impacto en el territorio y el peso de la mayor cooperativa l\u00e1ctea, el funcionario explicit\u00f3 que<em> \u201chay que encontrar una soluci\u00f3n m\u00e1s definitiva, no queremos desguazarla o descapitalizarla, queremos encontrar una alternativa que sea m\u00e1s integral para la regi\u00f3n\u201d<\/em>, remarc\u00f3. De todas maneras en las \u00faltimas horas siguieron las reuniones, aunque lejos de los despachos de presidencia, sobre lo cual reci\u00e9n se podr\u00e1 hablar en algunos d\u00edas, m\u00e1s concretamente.<\/p>\n<p>El Subsecretario complet\u00f3 que en el caso,<em> \u201cestamos acompa\u00f1ando en las resupuesta posibles, en t\u00e9rminos de lo que podemos hacer nosotros y m\u00e1s all\u00e1 que esto sali\u00f3 como noticias, lo cierto es que SanCor viene teniendo dificultades como la mayor\u00eda de la industria y venimos tratando de acompa\u00f1ar en resolver cuestiones de corto plazo, por eso intentamos acompa\u00f1arlos en un proceso de reestructuraci\u00f3n en procura de pasar de la coyuntura a soluciones m\u00e1s estructurales\u201d<\/em>.<\/p>\n<p><strong>Sigue pendiente<\/strong><\/p>\n<p>Claro que teniendo en cuenta los puntos a\u00fan pendientes del acuerdo-marco de Venado Tuerto, la cita completa entre el <strong>Ministerio de Agroindustria<\/strong> y la fase comercial de la lecher\u00eda es una de las claves para ordenar la coyuntura, mucho m\u00e1s all\u00e1 de la crisis h\u00eddrica. Textual y seg\u00fan lo indic\u00f3 <strong>Sammartino<\/strong>,<em> \u201cel Gobierno est\u00e1 trabajando por primera vez en un estudio de competencia de la cadena, junto con la Comisi\u00f3n Nacional de Defensa de la Competencia, que es una de las once actividades que est\u00e1n siendo miradas con preocupaci\u00f3n , eso por un lado, que no es un tema menor empezar a analizarlo y ver lo que est\u00e1 pasando; y despu\u00e9s el Ministerio est\u00e1 convocando a la mesa que hab\u00edamos quedado, que depende del Ministro y su agenda y esperamos que sea pronto\u201d<\/em>. El Subsecretario se refiere a la lecher\u00eda y conoce la necesidad de acercar las partes, pero reconoce, <em>\u201cdepende del Ministro y no de m\u00ed\u201d<\/em>.<\/p>\n<p><strong>Fuente:\u00a0http:\/\/lecherialatina.com\/noticias\/hoy-se-oficializan-lo-subsidios-para-los-productores-tamberos-76449\/<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Lo confirm\u00f3 a CASTELLANOS el Subsecretario de Lecher\u00eda de la Naci\u00f3n, al tiempo que indic\u00f3 que se pagar\u00edan los subsidios la semana pr\u00f3xima. Adem\u00e1s de visitar ayer entidades de la regi\u00f3n, Alejandro Sammartino estar\u00e1 hoy en el INTA Rafaela en una capacitaci\u00f3n para reestructurar el programa Cambio Rural Lechero. Durante esta ma\u00f1ana, en el INTA Rafaela se cumplir\u00e1 con una jornada de capacitaci\u00f3n de asesores del programa Cambio Rural Lechero, para poder iniciar una nueva etapa, con otra visi\u00f3n para este programa orientado a peque\u00f1os y medianos productores, desde el \u00e1ngulo de una mejora integral de sus sistemas. Es por ello que desde ayer est\u00e1 en la ciudad de Rafaela el Subsecretario de Lecher\u00eda de la Naci\u00f3n, quien entiende que este nuevo comienzo puede tender a que \u201chaya cada vez m\u00e1s grupos de Cambio Rural, m\u00e1s consistentes y con m\u00e1s oportunidades\u201d. De todas maneras, la visita a la regi\u00f3n se inici\u00f3 en la Cooperativa Guillermo Lehmann de Pilar, siguiendo por la Sociedad Rural de Rafaela y finalmente en la sede de la Mesa de Productores de Leche de Santa Fe. Es as\u00ed que Alejandro Sammartino remarc\u00f3 que \u201centendiendo la gravedad de la situaci\u00f3n productiva es que estamos reuni\u00e9ndonos, en un [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7822","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hoy se oficializan los subsidios para los productores tamberos | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoy se oficializan los subsidios para los productores tamberos | Proagro\" \/>\n<meta property=\"og:description\" content=\"Lo confirm\u00f3 a CASTELLANOS el Subsecretario de Lecher\u00eda de la Naci\u00f3n, al tiempo que indic\u00f3 que se pagar\u00edan los subsidios la semana pr\u00f3xima. Adem\u00e1s de visitar ayer entidades de la regi\u00f3n, Alejandro Sammartino estar\u00e1 hoy en el INTA Rafaela en una capacitaci\u00f3n para reestructurar el programa Cambio Rural Lechero. Durante esta ma\u00f1ana, en el INTA Rafaela se cumplir\u00e1 con una jornada de capacitaci\u00f3n de asesores del programa Cambio Rural Lechero, para poder iniciar una nueva etapa, con otra visi\u00f3n para este programa orientado a peque\u00f1os y medianos productores, desde el \u00e1ngulo de una mejora integral de sus sistemas. Es por ello que desde ayer est\u00e1 en la ciudad de Rafaela el Subsecretario de Lecher\u00eda de la Naci\u00f3n, quien entiende que este nuevo comienzo puede tender a que \u201chaya cada vez m\u00e1s grupos de Cambio Rural, m\u00e1s consistentes y con m\u00e1s oportunidades\u201d. De todas maneras, la visita a la regi\u00f3n se inici\u00f3 en la Cooperativa Guillermo Lehmann de Pilar, siguiendo por la Sociedad Rural de Rafaela y finalmente en la sede de la Mesa de Productores de Leche de Santa Fe. Es as\u00ed que Alejandro Sammartino remarc\u00f3 que \u201centendiendo la gravedad de la situaci\u00f3n productiva es que estamos reuni\u00e9ndonos, en un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-20T13:41:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-20T16:13:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/20052016-1145x395.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Hoy se oficializan los subsidios para los productores tamberos\",\"datePublished\":\"2016-05-20T13:41:47+00:00\",\"dateModified\":\"2016-05-20T16:13:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/\"},\"wordCount\":1330,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/20052016-1145x395.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/\",\"name\":\"Hoy se oficializan los subsidios para los productores tamberos | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/20052016-1145x395.jpg\",\"datePublished\":\"2016-05-20T13:41:47+00:00\",\"dateModified\":\"2016-05-20T16:13:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/20052016-1145x395.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/20052016-1145x395.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoy se oficializan los subsidios para los productores tamberos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoy se oficializan los subsidios para los productores tamberos | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/","og_locale":"en_US","og_type":"article","og_title":"Hoy se oficializan los subsidios para los productores tamberos | Proagro","og_description":"Lo confirm\u00f3 a CASTELLANOS el Subsecretario de Lecher\u00eda de la Naci\u00f3n, al tiempo que indic\u00f3 que se pagar\u00edan los subsidios la semana pr\u00f3xima. Adem\u00e1s de visitar ayer entidades de la regi\u00f3n, Alejandro Sammartino estar\u00e1 hoy en el INTA Rafaela en una capacitaci\u00f3n para reestructurar el programa Cambio Rural Lechero. Durante esta ma\u00f1ana, en el INTA Rafaela se cumplir\u00e1 con una jornada de capacitaci\u00f3n de asesores del programa Cambio Rural Lechero, para poder iniciar una nueva etapa, con otra visi\u00f3n para este programa orientado a peque\u00f1os y medianos productores, desde el \u00e1ngulo de una mejora integral de sus sistemas. Es por ello que desde ayer est\u00e1 en la ciudad de Rafaela el Subsecretario de Lecher\u00eda de la Naci\u00f3n, quien entiende que este nuevo comienzo puede tender a que \u201chaya cada vez m\u00e1s grupos de Cambio Rural, m\u00e1s consistentes y con m\u00e1s oportunidades\u201d. De todas maneras, la visita a la regi\u00f3n se inici\u00f3 en la Cooperativa Guillermo Lehmann de Pilar, siguiendo por la Sociedad Rural de Rafaela y finalmente en la sede de la Mesa de Productores de Leche de Santa Fe. Es as\u00ed que Alejandro Sammartino remarc\u00f3 que \u201centendiendo la gravedad de la situaci\u00f3n productiva es que estamos reuni\u00e9ndonos, en un [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-05-20T13:41:47+00:00","article_modified_time":"2016-05-20T16:13:06+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/20052016-1145x395.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Hoy se oficializan los subsidios para los productores tamberos","datePublished":"2016-05-20T13:41:47+00:00","dateModified":"2016-05-20T16:13:06+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/"},"wordCount":1330,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/20052016-1145x395.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/","url":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/","name":"Hoy se oficializan los subsidios para los productores tamberos | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/20052016-1145x395.jpg","datePublished":"2016-05-20T13:41:47+00:00","dateModified":"2016-05-20T16:13:06+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/20052016-1145x395.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/20052016-1145x395.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/hoy-se-oficializan-los-subsidios-para-los-productores-tamberos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Hoy se oficializan los subsidios para los productores tamberos"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7822"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/7837"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}