{"id":7768,"date":"2016-05-11T13:42:59","date_gmt":"2016-05-11T13:42:59","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7768"},"modified":"2020-06-29T18:43:16","modified_gmt":"2020-06-29T18:43:16","slug":"santa-fe-360-000-vacunos-en-emergencia","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/santa-fe-360-000-vacunos-en-emergencia\/","title":{"rendered":"Santa Fe: 360.000 vacunos en emergencia"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>El descenso de las aguas, tanto en zonas anegadas por lluvias como por la crecida del r\u00edo Paran\u00e1, comienza a dejar al descubierto los impresionantes da\u00f1os a la producci\u00f3n ganadera, particularmente en el nordeste de esta provincia. S\u00f3lo en el departamento San Javier -el m\u00e1s afectado, con lluvias que en un mes totalizaron algo m\u00e1s de 1000 mil\u00edmetros- hay 360.000 vacunos en emergencia.<\/p>\n<p><em>&#8220;El problema reci\u00e9n comienza. El agua se est\u00e1 yendo, pero los efectos sobre la ganader\u00eda se est\u00e1n empezando a notar en este momento con deficiencias en la alimentaci\u00f3n, problemas de los animales que se han venido abajo&#8221;<\/em>, coment\u00f3 a LA NACION el presidente de la Sociedad Rural de San Javier, Leonardo Sosa Bayer.<\/p>\n<p><em>&#8220;Vamos a poder evaluar los efectos (de esta inundaci\u00f3n) reci\u00e9n en un a\u00f1o y los vamos a sentir\u00a0durante tres a\u00f1os como m\u00ednimo, y esto para productores peque\u00f1os, medianos y grandes, para todos&#8221;<\/em>, subray\u00f3.<\/p>\n<p><em>&#8220;Los problemas los vamos a tener con la pastura, estuvimos con casi un 90% de la superficie de tierra firme inundada y ahora la situaci\u00f3n es desastrosa&#8221;<\/em>, precis\u00f3 Sosa Bayer.<\/p>\n<p>Ante una consulta sobre el panorama en la regi\u00f3n despu\u00e9s de 21 d\u00edas sin precipitaciones, el titular de la SR San Javier, admiti\u00f3 que <em>&#8220;los productores, al bajar las aguas, comienzan a volver a las islas. En las islas hay pasturas muy buenas, pero los que intentaron llevar nuevamente los animales a esos lugares se encontraron con piso blando. Muchos ejemplares murieron al quedar empantanados durante d\u00edas&#8221;<\/em>, grafic\u00f3. Jorge Pane, especialista en rodeos de cr\u00eda de INTA San Javier, consider\u00f3 que <em>&#8220;los porcentajes de p\u00e9rdida econ\u00f3mica podr\u00edan ser del 40% en\u00a0situaci\u00f3n de anegamiento&#8221;<\/em>, resalt\u00f3.<\/p>\n<p>Debe recordarse que la situaci\u00f3n de emergencia h\u00eddrica comenz\u00f3 en noviembre del a\u00f1o pasado con la crecida del r\u00edo Paran\u00e1, lo que provoc\u00f3 la retirada de la hacienda de zona de islas a inicios del verano hacia zonas del domo oriental y zona de Bajos Submeridionales (en la zona norte), aumentando significativamente la carga animal en estas \u00e1reas.<\/p>\n<p>El especialista del INTA explic\u00f3 que la actividad de cr\u00eda se ve comprometida por el traslado de los animales en \u00e9pocas de parici\u00f3n y servicios.<em> &#8220;El estr\u00e9s provocado por las excesivas lluvias causaron efectos en el estado corporal de los vientres, que provocar\u00e1 una ca\u00edda en los \u00edndices productivos (falta de ganancia de peso, ca\u00edda en el porcentaje de pre\u00f1es, muerte de terneros de parici\u00f3n tard\u00eda y ca\u00edda del \u00edndice de destete de 2017)&#8221;<\/em>, se inform\u00f3.<\/p>\n<p>Las p\u00e9rdidas en la ganader\u00eda se suman al grave da\u00f1o que padeci\u00f3 la agricultura.<\/p>\n<p><strong>Fuente:\u00a0<\/strong><\/p>\n<p class=\"authoring\"><strong>Por <span class=\"author\">Jos\u00e9 E. Bord\u00f3n <\/span>| <span class=\"source\">Diario La Naci\u00f3n<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El descenso de las aguas, tanto en zonas anegadas por lluvias como por la crecida del r\u00edo Paran\u00e1, comienza a dejar al descubierto los impresionantes da\u00f1os a la producci\u00f3n ganadera, particularmente en el nordeste de esta provincia. S\u00f3lo en el departamento San Javier -el m\u00e1s afectado, con lluvias que en un mes totalizaron algo m\u00e1s de 1000 mil\u00edmetros- hay 360.000 vacunos en emergencia. &#8220;El problema reci\u00e9n comienza. El agua se est\u00e1 yendo, pero los efectos sobre la ganader\u00eda se est\u00e1n empezando a notar en este momento con deficiencias en la alimentaci\u00f3n, problemas de los animales que se han venido abajo&#8221;, coment\u00f3 a LA NACION el presidente de la Sociedad Rural de San Javier, Leonardo Sosa Bayer. &#8220;Vamos a poder evaluar los efectos (de esta inundaci\u00f3n) reci\u00e9n en un a\u00f1o y los vamos a sentir\u00a0durante tres a\u00f1os como m\u00ednimo, y esto para productores peque\u00f1os, medianos y grandes, para todos&#8221;, subray\u00f3. &#8220;Los problemas los vamos a tener con la pastura, estuvimos con casi un 90% de la superficie de tierra firme inundada y ahora la situaci\u00f3n es desastrosa&#8221;, precis\u00f3 Sosa Bayer. Ante una consulta sobre el panorama en la regi\u00f3n despu\u00e9s de 21 d\u00edas sin precipitaciones, el titular de la SR San [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7768","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Fe: 360.000 vacunos en emergencia | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/santa-fe-360-000-vacunos-en-emergencia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Fe: 360.000 vacunos en emergencia | Proagro\" \/>\n<meta property=\"og:description\" content=\"El descenso de las aguas, tanto en zonas anegadas por lluvias como por la crecida del r\u00edo Paran\u00e1, comienza a dejar al descubierto los impresionantes da\u00f1os a la producci\u00f3n ganadera, particularmente en el nordeste de esta provincia. S\u00f3lo en el departamento San Javier -el m\u00e1s afectado, con lluvias que en un mes totalizaron algo m\u00e1s de 1000 mil\u00edmetros- hay 360.000 vacunos en emergencia. &#8220;El problema reci\u00e9n comienza. El agua se est\u00e1 yendo, pero los efectos sobre la ganader\u00eda se est\u00e1n empezando a notar en este momento con deficiencias en la alimentaci\u00f3n, problemas de los animales que se han venido abajo&#8221;, coment\u00f3 a LA NACION el presidente de la Sociedad Rural de San Javier, Leonardo Sosa Bayer. &#8220;Vamos a poder evaluar los efectos (de esta inundaci\u00f3n) reci\u00e9n en un a\u00f1o y los vamos a sentir\u00a0durante tres a\u00f1os como m\u00ednimo, y esto para productores peque\u00f1os, medianos y grandes, para todos&#8221;, subray\u00f3. &#8220;Los problemas los vamos a tener con la pastura, estuvimos con casi un 90% de la superficie de tierra firme inundada y ahora la situaci\u00f3n es desastrosa&#8221;, precis\u00f3 Sosa Bayer. Ante una consulta sobre el panorama en la regi\u00f3n despu\u00e9s de 21 d\u00edas sin precipitaciones, el titular de la SR San [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-11T13:42:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T18:43:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/inundaciones060315.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Santa Fe: 360.000 vacunos en emergencia\",\"datePublished\":\"2016-05-11T13:42:59+00:00\",\"dateModified\":\"2020-06-29T18:43:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/\"},\"wordCount\":479,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/inundaciones060315.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/\",\"name\":\"Santa Fe: 360.000 vacunos en emergencia | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/inundaciones060315.jpg\",\"datePublished\":\"2016-05-11T13:42:59+00:00\",\"dateModified\":\"2020-06-29T18:43:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/inundaciones060315.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/inundaciones060315.jpg\",\"width\":1920,\"height\":1079},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-360-000-vacunos-en-emergencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Fe: 360.000 vacunos en emergencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Fe: 360.000 vacunos en emergencia | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/santa-fe-360-000-vacunos-en-emergencia\/","og_locale":"en_US","og_type":"article","og_title":"Santa Fe: 360.000 vacunos en emergencia | Proagro","og_description":"El descenso de las aguas, tanto en zonas anegadas por lluvias como por la crecida del r\u00edo Paran\u00e1, comienza a dejar al descubierto los impresionantes da\u00f1os a la producci\u00f3n ganadera, particularmente en el nordeste de esta provincia. S\u00f3lo en el departamento San Javier -el m\u00e1s afectado, con lluvias que en un mes totalizaron algo m\u00e1s de 1000 mil\u00edmetros- hay 360.000 vacunos en emergencia. &#8220;El problema reci\u00e9n comienza. El agua se est\u00e1 yendo, pero los efectos sobre la ganader\u00eda se est\u00e1n empezando a notar en este momento con deficiencias en la alimentaci\u00f3n, problemas de los animales que se han venido abajo&#8221;, coment\u00f3 a LA NACION el presidente de la Sociedad Rural de San Javier, Leonardo Sosa Bayer. &#8220;Vamos a poder evaluar los efectos (de esta inundaci\u00f3n) reci\u00e9n en un a\u00f1o y los vamos a sentir\u00a0durante tres a\u00f1os como m\u00ednimo, y esto para productores peque\u00f1os, medianos y grandes, para todos&#8221;, subray\u00f3. &#8220;Los problemas los vamos a tener con la pastura, estuvimos con casi un 90% de la superficie de tierra firme inundada y ahora la situaci\u00f3n es desastrosa&#8221;, precis\u00f3 Sosa Bayer. Ante una consulta sobre el panorama en la regi\u00f3n despu\u00e9s de 21 d\u00edas sin precipitaciones, el titular de la SR San [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-05-11T13:42:59+00:00","article_modified_time":"2020-06-29T18:43:16+00:00","og_image":[{"width":1920,"height":1079,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/inundaciones060315.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Santa Fe: 360.000 vacunos en emergencia","datePublished":"2016-05-11T13:42:59+00:00","dateModified":"2020-06-29T18:43:16+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/"},"wordCount":479,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/inundaciones060315.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/","url":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/","name":"Santa Fe: 360.000 vacunos en emergencia | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/inundaciones060315.jpg","datePublished":"2016-05-11T13:42:59+00:00","dateModified":"2020-06-29T18:43:16+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/inundaciones060315.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/inundaciones060315.jpg","width":1920,"height":1079},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/santa-fe-360-000-vacunos-en-emergencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Santa Fe: 360.000 vacunos en emergencia"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7768"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7768\/revisions"}],"predecessor-version":[{"id":13861,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7768\/revisions\/13861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/7771"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}