{"id":7724,"date":"2016-05-05T13:56:01","date_gmt":"2016-05-05T13:56:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7724"},"modified":"2020-06-29T18:43:57","modified_gmt":"2020-06-29T18:43:57","slug":"santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/","title":{"rendered":"Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p><strong class=\"volanta\">Emergencia h\u00eddrica.<\/strong><\/p>\n<p>Lo estima un informe de la filial santafesina de CRA por el impacto de las intensas lluvias en lotes agr\u00edcolas, potreros ganaderos y tamberos.<\/p>\n<p class=\"first-paragraph\">La mitad de las 13,6 millones de hect\u00e1reas de Santa Fe se inundaron, en distintos grados, por las constantes lluvias de abril, un escenario que provocar\u00e1 p\u00e9rdidas por m\u00e1s de 2.724 millones de d\u00f3lares, de acuerdo a una estimaci\u00f3n que realiz\u00f3 la Confederaci\u00f3n de Asociaciones Rurales de Santa Fe (Carsfe), la filial de Confederaciones Rurales Argentinas (CRA) en esta provincia.<\/p>\n<p>Seg\u00fan este estudio, las p\u00e9rdidas en el sector lechero alcanzan los 768 millones de d\u00f3lares, por los da\u00f1os a las pasturas, los problemas sanitarios en los animales y la fuerte ca\u00edda en la producci\u00f3n de leche. Adem\u00e1s se proyecta que los productores ganaderos de carne tambi\u00e9n deber\u00e1n asumir \u201cun rojo\u201d de 689 millones de d\u00f3lares.<\/p>\n<p>Los da\u00f1os a los cultivos implican, adem\u00e1s, una p\u00e9rdida econ\u00f3mica de 1.017 millones de d\u00f3lares, a lo que hay que agregar otros 250 millones de d\u00f3lares que se resignar\u00e1n en otras actividades agropecuarias (arroz, frutillas y ca\u00f1a de az\u00facar, etc.).<em> \u201cEn Entre R\u00edos, las p\u00e9rdidas tambi\u00e9n son muy importantes y superan los 1.300 millones de d\u00f3lares\u201d<\/em>, agreg\u00f3 Dardo Chiesa, presidente de CRA.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"cont-embedImage\"><img decoding=\"async\" class=\"embedImage\" src=\"http:\/\/images.clarin.com\/rural\/rafaelacampos-FTP-CLARIN-inundaciones015JPG-Almeida_CLAIMA20160502_0220_17.jpg\" alt=\"foto gentileza diario la opinion de rafaela\ncampos y tambos inundados en la localidad de presidente roca  departamento castellanos - centro oeste de la provincia de santa fe\n25-04-2016 - FTP CLARIN - inundaciones015.JPG - Z FTP Almeida - almeida santa fe  inundaciones en santa fe por el fenomeno de el ni\u00f1o inundacion por las fuertes lluvias y tormentas ganado vacas\" \/><\/div>\n<p><em>Cerca de Rafaela, la mayor\u00eda de los tambos est\u00e1n afectados por las inundaciones. \/ Foto: gentileza diario La Opini\u00f3n.<\/em><\/p>\n<p>Un informe de la Bolsa de Comercio de Rosario (BCR) precisa que durante abril se acumularon entre 600 y 700 mil\u00edmetros de lluvia en Santa Fe, con picos todav\u00eda m\u00e1s altos en el centro y el noreste de la provincia.<\/p>\n<p><em>\u201cLa situaci\u00f3n en muchas zonas es desesperante y el desaliento de las poblaciones rurales va en aumento a medida que avanza la cosecha y se constatan los resultados negativos de la explotaci\u00f3n. No es un problema de los productores solamente. Esto tendr\u00e1 un impacto fuertemente nocivo sobre la econom\u00eda rural y el interior de la provincia\u201d<\/em>, advirti\u00f3 Julio Calzada, jefe de los economista de la Bolsa rosarina, en un informe que analiza las consecuencias de este verdadero diluvio.<\/p>\n<p>Solo en los lotes santafesinos, las proyecciones de los exportadores, operadores de granos y Carsfe coinciden en que las p\u00e9rdidas en soja oscilar\u00edan entre las 3,4 y 3,8 millones de toneladas, por la ca\u00edda en los rindes y la p\u00e9rdidas de calidad por los \u201cporotos\u201d brotados y podridos.<\/p>\n<p>El \u00faltimo informe de la Gu\u00eda Estrat\u00e9gica del Agro (GEA), de la Bolsa rosarina, destaca que cayeron en un 24% los rendimientos de la soja en el centro y sur de Santa Fe, norte de Buenos Aires y este de Entre R\u00edos. Es lo que midieron los t\u00e9cnicos una vez que las cosechadoras pudieron ingresar a los lotes despu\u00e9s de semanas de estar \u201cparadas\u201d por la falta de piso. En el sur de C\u00f3rdoba, el repliegue en los rindes es del 21%. Este relevamiento no incluye las p\u00e9rdidas que se producir\u00e1n por granos podridos, chuzos, livianos, brotados y h\u00famedos, una serie de da\u00f1os que sobre todo afectan a las variedades de ciclo cortos.<\/p>\n<p>En el centro y sur de Santa Fe se concentra el mayor porcentaje de granos da\u00f1ados, con valores que van del 25% al 80%. Un escal\u00f3n debajo est\u00e1 el sureste de C\u00f3rdoba, que alcanza valores del 10% al 40%, y en el resto de la regi\u00f3n n\u00facleo el nivel de da\u00f1os trepa hasta el 20%. <em>\u201cLa alta variabilidad de calidades se debe a las distintas fechas de siembra, el manejo que se llev\u00f3 adelante, el relieve del lote y los mil\u00edmetros que recibi\u00f3\u201d,<\/em> explic\u00f3 Calzada.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"cont-embedImage\"><img decoding=\"async\" class=\"embedImage\" src=\"http:\/\/images.clarin.com\/rural\/rios25-04-2016-FTP-CLARIN-DSC1161JPG-Almeida_CLAIMA20160502_0225_17.jpg\" alt=\"foto jose almeida\ncampos y cultivos afectados por las inundaciones en l departamento la paz, provincia de entre rios.\n25-04-2016 - FTP CLARIN - DSC_1161.JPG - Z FTP Almeida - almeida entre rios la paz  inundaciones en entre rios por el fenomeno de el ni\u00f1o inundacion por las fuertes lluvias y tormentas campos inundados\" \/><\/div>\n<p><em>La p\u00e9rdida de calidad en los porotos de soja es muy grave por los anegamientos y la alta humedad.<\/em><\/p>\n<p>El Ministerio de Agroindustria, en su informe semanal de estimaciones agr\u00edcolas, reconoci\u00f3 que en algunas zonas de Santa Fe, por ejemplo en Ca\u00f1ada de G\u00f3mez, pr\u00e1cticamente toda la soja que faltaba trillar est\u00e1 en su totalidad da\u00f1ada y los lotes que aun as\u00ed son cosechados tienen una aver\u00eda en sus granos que va de un 50% a un 100% y una humedad del grano por encima de la tolerancia de recibo, lo que dificulta la comercializaci\u00f3n y el dep\u00f3sitos de dichos granos, ya que ni los acopios ni los puertos lo est\u00e1n recibiendo.<\/p>\n<p>Las plantas de soja est\u00e1n en condiciones muy vulnerables, cuentan los t\u00e9cnicos, y las perdidas por desgrane pueden ir en aumento cuando todav\u00eda falta trillar cerca de un 60% de la producci\u00f3n sojera.<em> \u201cEn sojas de segunda, de momento se esperan menores niveles de da\u00f1os porque durante abril los cultivares se encontraban en etapas previas a la madurez comercial\u201d<\/em>, aclar\u00f3 la Bolsa rosarina.<\/p>\n<p>Otro problema que est\u00e1n enfrentando los productores es la falta de m\u00e1quinas para cosechar. Es que algunos contratistas \u201cemigraron\u201d a zonas con mayores posibilidades de trabajar y hay una fuerte demanda por los que est\u00e1n operando en esta zona.<\/p>\n<p><em>\u201cEl escenario de cosecha es el m\u00e1s dif\u00edcil en la historia de la regi\u00f3n. Entre barro y anegamientos, lentamente, las m\u00e1quinas sortean los caminos para ingresar a lotes con panoramas desoladores\u201d,<\/em> reconoci\u00f3 Calzada.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"cont-embedImage\"><img decoding=\"async\" class=\"embedImage\" src=\"http:\/\/images.clarin.com\/rural\/provincial-nro1evaciados-leyessanta-inundaciones-anegadas_CLAIMA20160502_0222_17.jpg\" alt=\"foto jose almeida comuna de arroyo leyes sobre ruta provincial nro.1\nevaciados sobre la ruta y vistas del barrio con agua por el desborde del arroyo leyes\nsanta fe 20-04-2016 santa fe  inundaciones en entre rios vistas zonas anegadas lluvias inundaciones crecida rio da\u00f1os comuna de arroyo leyes sobre ruta provincial nro.1\" \/><\/div>\n<p><em>En en centro y el noreste de Santa Fe se acumularon m\u00e1s de 600 mil\u00edmetros durante abril, precisa la Bolsa rosarina.<\/em><\/p>\n<p>La transitabilidad de la mayor\u00eda de los caminos rurales es muy mala por lo cual resulta imposible el traslado de la producci\u00f3n. Adem\u00e1s es complicado encontrar lugares secos en los lotes para instalar los silos bolsa.<\/p>\n<p>\u00a0Frente a este panorama, en una reuni\u00f3n de la que particip\u00f3 el gobernador de Santa Fe, Miguel Lifschitz, la Bolsa rosarina, Carsfe, Federaci\u00f3n Agraria, Coninagro y Acsoja, entre otras entidades, se acord\u00f3 impulsar subsidios directos a productores lecheros y hort\u00edcolas, diferir el pago de las facturas el\u00e9ctricas y lanzar una l\u00ednea de cr\u00e9ditos blandos, con baja tasa de inter\u00e9s, para que los productores inundados puedan afrontar el nuevo ciclo productivo.<\/p>\n<p>Tambi\u00e9n se le va a solicitar al Gobierno nacional un aporte extraordinario para la reconstrucci\u00f3n de rutas, caminos rurales, puentes y obras hidr\u00e1ulicas.<\/p>\n<p><strong>Fuente:\u00a0www.clarin.com\/rural\/Santa-Fe-perderian-US-inundaciones_0_1569443152.html<\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Emergencia h\u00eddrica. Lo estima un informe de la filial santafesina de CRA por el impacto de las intensas lluvias en lotes agr\u00edcolas, potreros ganaderos y tamberos. La mitad de las 13,6 millones de hect\u00e1reas de Santa Fe se inundaron, en distintos grados, por las constantes lluvias de abril, un escenario que provocar\u00e1 p\u00e9rdidas por m\u00e1s de 2.724 millones de d\u00f3lares, de acuerdo a una estimaci\u00f3n que realiz\u00f3 la Confederaci\u00f3n de Asociaciones Rurales de Santa Fe (Carsfe), la filial de Confederaciones Rurales Argentinas (CRA) en esta provincia. Seg\u00fan este estudio, las p\u00e9rdidas en el sector lechero alcanzan los 768 millones de d\u00f3lares, por los da\u00f1os a las pasturas, los problemas sanitarios en los animales y la fuerte ca\u00edda en la producci\u00f3n de leche. Adem\u00e1s se proyecta que los productores ganaderos de carne tambi\u00e9n deber\u00e1n asumir \u201cun rojo\u201d de 689 millones de d\u00f3lares. Los da\u00f1os a los cultivos implican, adem\u00e1s, una p\u00e9rdida econ\u00f3mica de 1.017 millones de d\u00f3lares, a lo que hay que agregar otros 250 millones de d\u00f3lares que se resignar\u00e1n en otras actividades agropecuarias (arroz, frutillas y ca\u00f1a de az\u00facar, etc.). \u201cEn Entre R\u00edos, las p\u00e9rdidas tambi\u00e9n son muy importantes y superan los 1.300 millones de d\u00f3lares\u201d, agreg\u00f3 Dardo Chiesa, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7725,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7724","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones | Proagro\" \/>\n<meta property=\"og:description\" content=\"Emergencia h\u00eddrica. Lo estima un informe de la filial santafesina de CRA por el impacto de las intensas lluvias en lotes agr\u00edcolas, potreros ganaderos y tamberos. La mitad de las 13,6 millones de hect\u00e1reas de Santa Fe se inundaron, en distintos grados, por las constantes lluvias de abril, un escenario que provocar\u00e1 p\u00e9rdidas por m\u00e1s de 2.724 millones de d\u00f3lares, de acuerdo a una estimaci\u00f3n que realiz\u00f3 la Confederaci\u00f3n de Asociaciones Rurales de Santa Fe (Carsfe), la filial de Confederaciones Rurales Argentinas (CRA) en esta provincia. Seg\u00fan este estudio, las p\u00e9rdidas en el sector lechero alcanzan los 768 millones de d\u00f3lares, por los da\u00f1os a las pasturas, los problemas sanitarios en los animales y la fuerte ca\u00edda en la producci\u00f3n de leche. Adem\u00e1s se proyecta que los productores ganaderos de carne tambi\u00e9n deber\u00e1n asumir \u201cun rojo\u201d de 689 millones de d\u00f3lares. Los da\u00f1os a los cultivos implican, adem\u00e1s, una p\u00e9rdida econ\u00f3mica de 1.017 millones de d\u00f3lares, a lo que hay que agregar otros 250 millones de d\u00f3lares que se resignar\u00e1n en otras actividades agropecuarias (arroz, frutillas y ca\u00f1a de az\u00facar, etc.). \u201cEn Entre R\u00edos, las p\u00e9rdidas tambi\u00e9n son muy importantes y superan los 1.300 millones de d\u00f3lares\u201d, agreg\u00f3 Dardo Chiesa, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-05T13:56:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T18:43:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Santa-Rios-Foto-Jose-Almeida_CLAIMA20160502_0223_28.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones\",\"datePublished\":\"2016-05-05T13:56:01+00:00\",\"dateModified\":\"2020-06-29T18:43:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/\"},\"wordCount\":1081,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Santa-Rios-Foto-Jose-Almeida_CLAIMA20160502_0223_28.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/\",\"name\":\"Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Santa-Rios-Foto-Jose-Almeida_CLAIMA20160502_0223_28.jpg\",\"datePublished\":\"2016-05-05T13:56:01+00:00\",\"dateModified\":\"2020-06-29T18:43:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Santa-Rios-Foto-Jose-Almeida_CLAIMA20160502_0223_28.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Santa-Rios-Foto-Jose-Almeida_CLAIMA20160502_0223_28.jpg\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/","og_locale":"en_US","og_type":"article","og_title":"Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones | Proagro","og_description":"Emergencia h\u00eddrica. Lo estima un informe de la filial santafesina de CRA por el impacto de las intensas lluvias en lotes agr\u00edcolas, potreros ganaderos y tamberos. La mitad de las 13,6 millones de hect\u00e1reas de Santa Fe se inundaron, en distintos grados, por las constantes lluvias de abril, un escenario que provocar\u00e1 p\u00e9rdidas por m\u00e1s de 2.724 millones de d\u00f3lares, de acuerdo a una estimaci\u00f3n que realiz\u00f3 la Confederaci\u00f3n de Asociaciones Rurales de Santa Fe (Carsfe), la filial de Confederaciones Rurales Argentinas (CRA) en esta provincia. Seg\u00fan este estudio, las p\u00e9rdidas en el sector lechero alcanzan los 768 millones de d\u00f3lares, por los da\u00f1os a las pasturas, los problemas sanitarios en los animales y la fuerte ca\u00edda en la producci\u00f3n de leche. Adem\u00e1s se proyecta que los productores ganaderos de carne tambi\u00e9n deber\u00e1n asumir \u201cun rojo\u201d de 689 millones de d\u00f3lares. Los da\u00f1os a los cultivos implican, adem\u00e1s, una p\u00e9rdida econ\u00f3mica de 1.017 millones de d\u00f3lares, a lo que hay que agregar otros 250 millones de d\u00f3lares que se resignar\u00e1n en otras actividades agropecuarias (arroz, frutillas y ca\u00f1a de az\u00facar, etc.). \u201cEn Entre R\u00edos, las p\u00e9rdidas tambi\u00e9n son muy importantes y superan los 1.300 millones de d\u00f3lares\u201d, agreg\u00f3 Dardo Chiesa, [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-05-05T13:56:01+00:00","article_modified_time":"2020-06-29T18:43:57+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Santa-Rios-Foto-Jose-Almeida_CLAIMA20160502_0223_28.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones","datePublished":"2016-05-05T13:56:01+00:00","dateModified":"2020-06-29T18:43:57+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/"},"wordCount":1081,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Santa-Rios-Foto-Jose-Almeida_CLAIMA20160502_0223_28.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/","url":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/","name":"Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Santa-Rios-Foto-Jose-Almeida_CLAIMA20160502_0223_28.jpg","datePublished":"2016-05-05T13:56:01+00:00","dateModified":"2020-06-29T18:43:57+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Santa-Rios-Foto-Jose-Almeida_CLAIMA20160502_0223_28.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/05\/Santa-Rios-Foto-Jose-Almeida_CLAIMA20160502_0223_28.jpg","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/santa-fe-se-perderian-us-2-700-millones-por-las-inundaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Santa Fe: se perder\u00edan U$S 2.700 millones por las inundaciones"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7724"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7724\/revisions"}],"predecessor-version":[{"id":13866,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7724\/revisions\/13866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/7725"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}