{"id":7642,"date":"2016-04-22T12:05:03","date_gmt":"2016-04-22T12:05:03","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7642"},"modified":"2016-04-22T12:47:43","modified_gmt":"2016-04-22T12:47:43","slug":"alerta-neumonia-en-rodeos","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/alerta-neumonia-en-rodeos\/","title":{"rendered":"Alerta: neumon\u00eda en rodeos."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>De acuerdo a la casu\u00edstica del Servicio de Diagn\u00f3stico Veterinario Especializado (SDVE) del INTA EEA Balcarce y el Programa de Interacci\u00f3n Profesional de Veterinarios de la Cuenca del Saldado, la principal categor\u00eda afectada por la neumon\u00eda son los terneros. Seg\u00fan, Germ\u00e1n Cant\u00f3n de INTA Balcarce, en algunos episodios muy severos se han visto afectados hasta el 9,5% de los terneros al pie de la madre, provocando una mortandad que no supera al 1,6% cuando la enfermedad se diagnostica a tiempo y se trata apropiadamente.<\/p>\n<p>\u201c<em>En cambio, cuando los sistemas ganaderos se intensifican, esta problem\u00e1tica pasa a ser m\u00e1s prevalente\u201d<\/em> sostiene el profesional. En los tambos, por ejemplo, las neumon\u00edas representaron el 11,4% de los casos reportados por los productores lecheros en sus rodeos. Y sin dudas, el principal sistema ganadero afectado es la recr\u00eda y engorde a corral, representando las neumon\u00edas casi la mitad de todos los problemas sanitarios que afectan a esos rodeos.<\/p>\n<p><em>\u201cLa enfermedad respiratoria es compleja y multifactorial, ya que involucra factores relacionados al animal (estr\u00e9s) e infecciones virales que afectan sus defensas naturales, favoreciendo luego a las infecciones bacterianas. Adem\u00e1s, factores clim\u00e1ticos\/ambientales pueden tambi\u00e9n empeorar estos cuadros. Por esta raz\u00f3n, es de dif\u00edcil control y prevenci\u00f3n\u201d<\/em> destaca Cant\u00f3n.<\/p>\n<p>En este sentido, Cant\u00f3n agrega que la neumon\u00eda genera grandes p\u00e9rdidas econ\u00f3micas en los sistemas ganaderos, ya sea por los costos directos por la muerte de animales, la aplicaci\u00f3n de tratamientos (drogas y mano de obra), o animales convalecientes que quedan en el sistema con baja eficiencia de conversi\u00f3n y baja calidad de sus carcasas.<\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/decision-ganadera.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7643\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/decision-ganadera-300x176.jpg\" alt=\"decision ganadera\" width=\"300\" height=\"176\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/decision-ganadera-300x176.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/decision-ganadera-600x352.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/decision-ganadera-1024x601.jpg 1024w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/decision-ganadera.jpg 1041w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>Factor animal<\/strong><\/p>\n<p>Es fundamental tener en cuenta el manejo de los animales. El principal factor a considerar es el estr\u00e9s. <em>\u201cLas maniobras m\u00e1s estresantes en la vida de los bovinos son el destete y transporte. Los terneros de destete precoz son una de las categor\u00edas m\u00e1s susceptibles a esta enfermedad, con la aparici\u00f3n de cuadros severos de neumon\u00edas si no se realiza apropiadamente\u201d<\/em> explica Cant\u00f3n.<\/p>\n<p>Otro factor es la alta carga animal (hacinamiento de los animales), permitiendo que la tasa de contacto entre ellos sea elevada. Por esta raz\u00f3n, los engordes a corral son el principal sistema afectado por las neumon\u00edas.<\/p>\n<p>Asimismo, en aquellos corrales en los que se mezclan terneros de diferente origen o terneros de diferente edad\/tama\u00f1o, las neumon\u00edas suelen ser m\u00e1s frecuentes. Esto se debe a la posibilidad de animales portadores, fuente de contagio de los agentes infecciosos involucrados en la enfermedad respiratoria, o animales cr\u00f3nicamente infectados o con enfermedad subcl\u00ednica, y la presencia de animales m\u00e1s j\u00f3venes sin inmunidad espec\u00edfica, por lo tanto, m\u00e1s susceptibles.<\/p>\n<p><strong>Prevenci\u00f3n<\/strong><\/p>\n<p>Aparte de lograr una reducci\u00f3n en los factores estresantes y de manejo, el profesional de INTA Balcarce sostiene que es importante incorporar \u00a0contra estos agentes. Esto no permitir\u00e1 erradicar la enfermedad respiratoria, sino que generar\u00e1n una inmunidad poblacional que lograr\u00e1 reducir las implicancias que estas patolog\u00edas tienen, sobre todo, en sistemas de engorde intensivos.<\/p>\n<p>Se recomienda su aplicaci\u00f3n en los terneros predestete, antes de este factor estresante, para generar una inmunidad apropiada con tiempo. En el caso que se traten de terneros de destete precoz, se recomienda su aplicaci\u00f3n de 2 dosis predestete y una tercera revacunaci\u00f3n a los 6 meses. En el caso de un destete tradicional (6 a 8 meses de edad), si se realiza recr\u00eda propia, de la misma manera, se recomienda la aplicaci\u00f3n de 2 dosis de vacuna predestete.<\/p>\n<p><em>\u201cEs importante lograr el diagn\u00f3stico etiol\u00f3gico de la enfermedad respiratoria, sobre todo cuando se observe que los tratamientos con antibi\u00f3ticos no est\u00e1n funcionando apropiadamente\u201d<\/em> conlcuye Cant\u00f3n. Y recalca que se deben aplicar estrategias de control integrales que no s\u00f3lo incluyan la aplicaci\u00f3n de vacunas, sino medidas de manejo adecuadas, el diagn\u00f3stico cl\u00ednico temprano y la instauraci\u00f3n r\u00e1pida de tratamientos apropiados.<\/p>\n<p>Para esta enfermedad existen antibi\u00f3ticos, que atacan la enfermedad o la previenen.\u00a0<a href=\"https:\/\/proagrolab.com.ar\/productos\/\">Click aqu\u00ed<\/a><\/p>\n<p>Fuente:\u00a0http:\/\/decisionganadera.com.ar\/alerta-neumonia-en-rodeos\/<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>De acuerdo a la casu\u00edstica del Servicio de Diagn\u00f3stico Veterinario Especializado (SDVE) del INTA EEA Balcarce y el Programa de Interacci\u00f3n Profesional de Veterinarios de la Cuenca del Saldado, la principal categor\u00eda afectada por la neumon\u00eda son los terneros. Seg\u00fan, Germ\u00e1n Cant\u00f3n de INTA Balcarce, en algunos episodios muy severos se han visto afectados hasta el 9,5% de los terneros al pie de la madre, provocando una mortandad que no supera al 1,6% cuando la enfermedad se diagnostica a tiempo y se trata apropiadamente. \u201cEn cambio, cuando los sistemas ganaderos se intensifican, esta problem\u00e1tica pasa a ser m\u00e1s prevalente\u201d sostiene el profesional. En los tambos, por ejemplo, las neumon\u00edas representaron el 11,4% de los casos reportados por los productores lecheros en sus rodeos. Y sin dudas, el principal sistema ganadero afectado es la recr\u00eda y engorde a corral, representando las neumon\u00edas casi la mitad de todos los problemas sanitarios que afectan a esos rodeos. \u201cLa enfermedad respiratoria es compleja y multifactorial, ya que involucra factores relacionados al animal (estr\u00e9s) e infecciones virales que afectan sus defensas naturales, favoreciendo luego a las infecciones bacterianas. Adem\u00e1s, factores clim\u00e1ticos\/ambientales pueden tambi\u00e9n empeorar estos cuadros. Por esta raz\u00f3n, es de dif\u00edcil control y prevenci\u00f3n\u201d [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7644,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7642","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-infoganadero","post_format-post-format-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alerta: neumon\u00eda en rodeos. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/alerta-neumonia-en-rodeos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alerta: neumon\u00eda en rodeos. | Proagro\" \/>\n<meta property=\"og:description\" content=\"De acuerdo a la casu\u00edstica del Servicio de Diagn\u00f3stico Veterinario Especializado (SDVE) del INTA EEA Balcarce y el Programa de Interacci\u00f3n Profesional de Veterinarios de la Cuenca del Saldado, la principal categor\u00eda afectada por la neumon\u00eda son los terneros. Seg\u00fan, Germ\u00e1n Cant\u00f3n de INTA Balcarce, en algunos episodios muy severos se han visto afectados hasta el 9,5% de los terneros al pie de la madre, provocando una mortandad que no supera al 1,6% cuando la enfermedad se diagnostica a tiempo y se trata apropiadamente. \u201cEn cambio, cuando los sistemas ganaderos se intensifican, esta problem\u00e1tica pasa a ser m\u00e1s prevalente\u201d sostiene el profesional. En los tambos, por ejemplo, las neumon\u00edas representaron el 11,4% de los casos reportados por los productores lecheros en sus rodeos. Y sin dudas, el principal sistema ganadero afectado es la recr\u00eda y engorde a corral, representando las neumon\u00edas casi la mitad de todos los problemas sanitarios que afectan a esos rodeos. \u201cLa enfermedad respiratoria es compleja y multifactorial, ya que involucra factores relacionados al animal (estr\u00e9s) e infecciones virales que afectan sus defensas naturales, favoreciendo luego a las infecciones bacterianas. Adem\u00e1s, factores clim\u00e1ticos\/ambientales pueden tambi\u00e9n empeorar estos cuadros. Por esta raz\u00f3n, es de dif\u00edcil control y prevenci\u00f3n\u201d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-22T12:05:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-22T12:47:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/4acfa14a-0f78-4731-bd3a-d7400058e75a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Alerta: neumon\u00eda en rodeos.\",\"datePublished\":\"2016-04-22T12:05:03+00:00\",\"dateModified\":\"2016-04-22T12:47:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/\"},\"wordCount\":707,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/4acfa14a-0f78-4731-bd3a-d7400058e75a.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/\",\"name\":\"Alerta: neumon\u00eda en rodeos. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/4acfa14a-0f78-4731-bd3a-d7400058e75a.jpg\",\"datePublished\":\"2016-04-22T12:05:03+00:00\",\"dateModified\":\"2016-04-22T12:47:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/4acfa14a-0f78-4731-bd3a-d7400058e75a.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/4acfa14a-0f78-4731-bd3a-d7400058e75a.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/alerta-neumonia-en-rodeos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alerta: neumon\u00eda en rodeos.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alerta: neumon\u00eda en rodeos. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/alerta-neumonia-en-rodeos\/","og_locale":"en_US","og_type":"article","og_title":"Alerta: neumon\u00eda en rodeos. | Proagro","og_description":"De acuerdo a la casu\u00edstica del Servicio de Diagn\u00f3stico Veterinario Especializado (SDVE) del INTA EEA Balcarce y el Programa de Interacci\u00f3n Profesional de Veterinarios de la Cuenca del Saldado, la principal categor\u00eda afectada por la neumon\u00eda son los terneros. Seg\u00fan, Germ\u00e1n Cant\u00f3n de INTA Balcarce, en algunos episodios muy severos se han visto afectados hasta el 9,5% de los terneros al pie de la madre, provocando una mortandad que no supera al 1,6% cuando la enfermedad se diagnostica a tiempo y se trata apropiadamente. \u201cEn cambio, cuando los sistemas ganaderos se intensifican, esta problem\u00e1tica pasa a ser m\u00e1s prevalente\u201d sostiene el profesional. En los tambos, por ejemplo, las neumon\u00edas representaron el 11,4% de los casos reportados por los productores lecheros en sus rodeos. Y sin dudas, el principal sistema ganadero afectado es la recr\u00eda y engorde a corral, representando las neumon\u00edas casi la mitad de todos los problemas sanitarios que afectan a esos rodeos. \u201cLa enfermedad respiratoria es compleja y multifactorial, ya que involucra factores relacionados al animal (estr\u00e9s) e infecciones virales que afectan sus defensas naturales, favoreciendo luego a las infecciones bacterianas. Adem\u00e1s, factores clim\u00e1ticos\/ambientales pueden tambi\u00e9n empeorar estos cuadros. Por esta raz\u00f3n, es de dif\u00edcil control y prevenci\u00f3n\u201d [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-04-22T12:05:03+00:00","article_modified_time":"2016-04-22T12:47:43+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/4acfa14a-0f78-4731-bd3a-d7400058e75a.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Alerta: neumon\u00eda en rodeos.","datePublished":"2016-04-22T12:05:03+00:00","dateModified":"2016-04-22T12:47:43+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/"},"wordCount":707,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/4acfa14a-0f78-4731-bd3a-d7400058e75a.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/","url":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/","name":"Alerta: neumon\u00eda en rodeos. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/4acfa14a-0f78-4731-bd3a-d7400058e75a.jpg","datePublished":"2016-04-22T12:05:03+00:00","dateModified":"2016-04-22T12:47:43+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/4acfa14a-0f78-4731-bd3a-d7400058e75a.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/04\/4acfa14a-0f78-4731-bd3a-d7400058e75a.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/alerta-neumonia-en-rodeos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Alerta: neumon\u00eda en rodeos."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7642"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/7644"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}