{"id":7460,"date":"2016-02-05T12:42:00","date_gmt":"2016-02-05T12:42:00","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7460"},"modified":"2016-02-05T12:42:00","modified_gmt":"2016-02-05T12:42:00","slug":"carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/","title":{"rendered":"Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Una nueva importaci\u00f3n a Uruguay de muslos de pollo de Estados Unidos, la reimplataci\u00f3n del IVA a las carnes blancas que el gobierno impuso en 2015 y un sector pr\u00e1cticamente sin mercados, vuelven a desatar el miedo en el sector av\u00edcolas. Diputado Pe\u00f1a dijo que se perder\u00e1n m\u00e1s productores locales.<\/p>\n<p><span lang=\"ES-AR\" xml:lang=\"ES-AR\">El diputado <strong>Adri\u00e1n Pe\u00f1a<\/strong>, perteneciente a Vamos Uruguay, planteo su preocupaci\u00f3n sobre la situaci\u00f3n del <strong>sector av\u00edcola<\/strong> ante la confirmaci\u00f3n de recientes <strong>importaciones<\/strong> de Estados Unidos.<\/span><\/p>\n<p><span lang=\"ES-AR\" xml:lang=\"ES-AR\">La <a href=\"http:\/\/www.fyo.com\/noticia\/155161\/uruguay-produccion-carne-aviar-cayo-11-2015\" target=\"_blank\">producci\u00f3n av\u00edcola uruguaya<\/a> pasa por un momento complicado y una serie de decisiones del gobierno han empeorado las cosas, seg\u00fan la visi\u00f3n del diputado Pe\u00f1a. &#8220;Por un lado la<strong>capacidad de producci\u00f3n <\/strong>supera ampliamente la <strong>demanda interna<\/strong>, no se abrieron nuevos mercados y se viene muy lento en su b\u00fasqueda, se incumpli\u00f3 el acuerdo por parte de Venezuela que se compromet\u00eda a comprar <strong>9.000 toneladas<\/strong> antes de finales del 2015 y no han llevado ni medio pollo&#8221;, remarc\u00f3. A eso hay que sumar que &#8220;desde el primero de julio del 2015 le aplicaron de nuevo el <strong>mazazo del IVA<\/strong> y ahora hemos confirmado que ingresaron al pa\u00eds procedente de Estados Unidos <strong>2,5000 kilos de muslos a $22<\/strong>&#8220;.<\/span><\/p>\n<p><span lang=\"ES-AR\" xml:lang=\"ES-AR\">Pe\u00f1a aclar\u00f3 que &#8220;toda esta combinaci\u00f3n deriva en <strong>baja de la demanda<\/strong>, aumento de la informalidad, aumento del contrabando y por tanto baja de la producci\u00f3n y baja en el trabajo&#8221;. El a\u00f1o pasado el contrabando de pollos desde Brasil fue importante e incluso probado por la C\u00e1mara Uruguay de Productores Av\u00edcolas (Cupra).<\/span><\/p>\n<p><span lang=\"ES-AR\" xml:lang=\"ES-AR\">Pe\u00f1a se\u00f1alo que el sector av\u00edcola\u00a0es fundamental en la cadena de producci\u00f3n de Canelones y que genera miles de puesto de trabajo y que ese sector ha sido siempre defendido a ultranza por el Partido Colorado. &#8220;Nosotros creemos que deben existir <strong>pol\u00edticas activas y reales<\/strong> para defender un sector que consideramos estrat\u00e9gico, por la potencialidad de desarrollo que tiene pero adem\u00e1s por su importancia desde el punto de vista social&#8221;.<\/span><\/p>\n<p><span lang=\"ES-AR\" xml:lang=\"ES-AR\">Seg\u00fan Pe\u00f1a el que m\u00e1s se perjudica &#8220;es el <strong>peque\u00f1o productor<\/strong>, el eslab\u00f3n m\u00e1s fino y por el que siempre se corta. En lugar de ayudar en un momento complejo desde el gobierno se complica m\u00e1s y m\u00e1s&#8221;. Por todo eso, Manos Uruguay elev\u00f3 un pedido de informes para que &#8220;nos expliquen las razones por las cuales se <strong>habilit\u00f3 la importaci\u00f3n<\/strong>. Por otro lado apoyamos a los productores reclamando desde ya la vuelta al sistema de <strong>exoneraci\u00f3n del IVA<\/strong> para la cadena y aplicar la medida de trato nacional, para evitar el ingreso de competencia desleal al pa\u00eds&#8221;.<\/span><\/p>\n<p><span lang=\"ES-AR\" xml:lang=\"ES-AR\">El diputado de Manos Uruguay destac\u00f3 que &#8220;se juega la supervivencia de un sector productivo y no podemos permitir que <strong>desaparezca <\/strong>como est\u00e1 desapareciendo el sector de <strong>cr\u00eda de cerdos<\/strong>&#8220;, afirm\u00f3 el representante nacional.<\/span><\/p>\n<p><a href=\"http:\/\/www.fyo.com\/noticia\/155681\/carne-aviar-nuevo-ingreso-muslos-estados-unidos-aporta-incertidumbre\">http:\/\/www.fyo.com\/noticia\/155681\/carne-aviar-nuevo-ingreso-muslos-estados-unidos-aporta-incertidumbre<\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Una nueva importaci\u00f3n a Uruguay de muslos de pollo de Estados Unidos, la reimplataci\u00f3n del IVA a las carnes blancas que el gobierno impuso en 2015 y un sector pr\u00e1cticamente sin mercados, vuelven a desatar el miedo en el sector av\u00edcolas. Diputado Pe\u00f1a dijo que se perder\u00e1n m\u00e1s productores locales. El diputado Adri\u00e1n Pe\u00f1a, perteneciente a Vamos Uruguay, planteo su preocupaci\u00f3n sobre la situaci\u00f3n del sector av\u00edcola ante la confirmaci\u00f3n de recientes importaciones de Estados Unidos. La producci\u00f3n av\u00edcola uruguaya pasa por un momento complicado y una serie de decisiones del gobierno han empeorado las cosas, seg\u00fan la visi\u00f3n del diputado Pe\u00f1a. &#8220;Por un lado lacapacidad de producci\u00f3n supera ampliamente la demanda interna, no se abrieron nuevos mercados y se viene muy lento en su b\u00fasqueda, se incumpli\u00f3 el acuerdo por parte de Venezuela que se compromet\u00eda a comprar 9.000 toneladas antes de finales del 2015 y no han llevado ni medio pollo&#8221;, remarc\u00f3. A eso hay que sumar que &#8220;desde el primero de julio del 2015 le aplicaron de nuevo el mazazo del IVA y ahora hemos confirmado que ingresaron al pa\u00eds procedente de Estados Unidos 2,5000 kilos de muslos a $22&#8220;. Pe\u00f1a aclar\u00f3 que &#8220;toda esta combinaci\u00f3n deriva [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7461,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre | Proagro\" \/>\n<meta property=\"og:description\" content=\"Una nueva importaci\u00f3n a Uruguay de muslos de pollo de Estados Unidos, la reimplataci\u00f3n del IVA a las carnes blancas que el gobierno impuso en 2015 y un sector pr\u00e1cticamente sin mercados, vuelven a desatar el miedo en el sector av\u00edcolas. Diputado Pe\u00f1a dijo que se perder\u00e1n m\u00e1s productores locales. El diputado Adri\u00e1n Pe\u00f1a, perteneciente a Vamos Uruguay, planteo su preocupaci\u00f3n sobre la situaci\u00f3n del sector av\u00edcola ante la confirmaci\u00f3n de recientes importaciones de Estados Unidos. La producci\u00f3n av\u00edcola uruguaya pasa por un momento complicado y una serie de decisiones del gobierno han empeorado las cosas, seg\u00fan la visi\u00f3n del diputado Pe\u00f1a. &#8220;Por un lado lacapacidad de producci\u00f3n supera ampliamente la demanda interna, no se abrieron nuevos mercados y se viene muy lento en su b\u00fasqueda, se incumpli\u00f3 el acuerdo por parte de Venezuela que se compromet\u00eda a comprar 9.000 toneladas antes de finales del 2015 y no han llevado ni medio pollo&#8221;, remarc\u00f3. A eso hay que sumar que &#8220;desde el primero de julio del 2015 le aplicaron de nuevo el mazazo del IVA y ahora hemos confirmado que ingresaron al pa\u00eds procedente de Estados Unidos 2,5000 kilos de muslos a $22&#8220;. Pe\u00f1a aclar\u00f3 que &#8220;toda esta combinaci\u00f3n deriva [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-05T12:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/02\/produccion_de_pollo_fyo_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre\",\"datePublished\":\"2016-02-05T12:42:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/\"},\"wordCount\":509,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/produccion_de_pollo_fyo_0.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/\",\"name\":\"Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/produccion_de_pollo_fyo_0.jpg\",\"datePublished\":\"2016-02-05T12:42:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/produccion_de_pollo_fyo_0.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/produccion_de_pollo_fyo_0.jpg\",\"width\":620,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/","og_locale":"en_US","og_type":"article","og_title":"Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre | Proagro","og_description":"Una nueva importaci\u00f3n a Uruguay de muslos de pollo de Estados Unidos, la reimplataci\u00f3n del IVA a las carnes blancas que el gobierno impuso en 2015 y un sector pr\u00e1cticamente sin mercados, vuelven a desatar el miedo en el sector av\u00edcolas. Diputado Pe\u00f1a dijo que se perder\u00e1n m\u00e1s productores locales. El diputado Adri\u00e1n Pe\u00f1a, perteneciente a Vamos Uruguay, planteo su preocupaci\u00f3n sobre la situaci\u00f3n del sector av\u00edcola ante la confirmaci\u00f3n de recientes importaciones de Estados Unidos. La producci\u00f3n av\u00edcola uruguaya pasa por un momento complicado y una serie de decisiones del gobierno han empeorado las cosas, seg\u00fan la visi\u00f3n del diputado Pe\u00f1a. &#8220;Por un lado lacapacidad de producci\u00f3n supera ampliamente la demanda interna, no se abrieron nuevos mercados y se viene muy lento en su b\u00fasqueda, se incumpli\u00f3 el acuerdo por parte de Venezuela que se compromet\u00eda a comprar 9.000 toneladas antes de finales del 2015 y no han llevado ni medio pollo&#8221;, remarc\u00f3. A eso hay que sumar que &#8220;desde el primero de julio del 2015 le aplicaron de nuevo el mazazo del IVA y ahora hemos confirmado que ingresaron al pa\u00eds procedente de Estados Unidos 2,5000 kilos de muslos a $22&#8220;. Pe\u00f1a aclar\u00f3 que &#8220;toda esta combinaci\u00f3n deriva [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2016-02-05T12:42:00+00:00","og_image":[{"width":620,"height":375,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/02\/produccion_de_pollo_fyo_0.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre","datePublished":"2016-02-05T12:42:00+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/"},"wordCount":509,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/02\/produccion_de_pollo_fyo_0.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/","url":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/","name":"Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/02\/produccion_de_pollo_fyo_0.jpg","datePublished":"2016-02-05T12:42:00+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/02\/produccion_de_pollo_fyo_0.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2016\/02\/produccion_de_pollo_fyo_0.jpg","width":620,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/carne-aviar-nuevo-ingreso-de-muslos-de-estados-unidos-aporta-incertidumbre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Carne aviar: nuevo ingreso de muslos de Estados Unidos aporta incertidumbre"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7460"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/7461"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}