{"id":7413,"date":"2015-12-18T15:28:48","date_gmt":"2015-12-18T15:28:48","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7413"},"modified":"2015-12-18T15:28:48","modified_gmt":"2015-12-18T15:28:48","slug":"nutricion-en-soja-del-circulo-vicioso-al-virtuoso","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/","title":{"rendered":"Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Los excesos h\u00eddricos de un fuerte a\u00f1o Ni\u00f1o generan problemas que no siempre se consideran. La nutrici\u00f3n de la soja es fundamental para maximizar retornos.<\/p>\n<p>Cuando el pron\u00f3stico clim\u00e1tico anuncia un a\u00f1o agr\u00edcola en fase Ni\u00f1o, la primera conclusi\u00f3n es pensar en importantes<strong> potenciales de rendimiento<\/strong>.<\/p>\n<p>Esto es cierto para el <strong>ma\u00edz <\/strong>pero no necesariamente para la <strong>soja<\/strong>, ya que se encuentra sometida a niveles de <strong>estr\u00e9s por saturaci\u00f3n h\u00eddrica<\/strong> en la riz\u00f3sfera, que genera demoras en el desarrollo inicial de la planta, menores niveles de simbiosis con el inoculante y mayor presi\u00f3n de enfermedades, entre otras cosas. A su vez, aparecen m\u00e1s <strong>malezas<\/strong> (especialmente gram\u00edneas) que deben ser controladas, no s\u00f3lo en base a herbicidas sino tambi\u00e9n utilizando el sombreo del cultivo.<\/p>\n<p>En a\u00f1os como este, la <em>soja<\/em> puede entrar f\u00e1cilmente en un <strong>c\u00edrculo vicioso<\/strong> donde la falta de desarrollo radicular y de simbiosis con las bacterias del inoculante lleva a un menor desarrollo inicial, con m\u00e1s predisposici\u00f3n a la acci\u00f3n subcl\u00ednica de enfermedades y a un cierre de cultivo m\u00e1s lento, y por lo tanto <strong>mayores problemas<\/strong> de <em>malezas<\/em>.<\/p>\n<p>Una forma de entrar en un <strong>c\u00edrculo virtuoso<\/strong> de generaci\u00f3n de \u00e1rea foliar para maximizar la cantidad de granos, es aprovechar las condiciones ambientales con un programa nutricional balanceado, que permita corregir eventuales d\u00e9ficit de macro, oligo y micronutrientes.<\/p>\n<p>Tambi\u00e9n el uso de <strong>bioestimulantes<\/strong> que ayuden a que los procesos fisiol\u00f3gicos de la planta se realicen en forma eficiente, bajando la incidencia de enfermedades foliares, colaborando con un r\u00e1pido cierre de surco y maximizando el control de malezas\u00a0a partir de la eficiencia del sombreado del cultivo.<\/p>\n<p><a href=\"http:\/\/www.fyo.com\/noticia\/154583\/nutricion-soja-circulo-vicioso-virtuoso\">http:\/\/www.fyo.com\/noticia\/154583\/nutricion-soja-circulo-vicioso-virtuoso<\/a><\/p>\n<h2 class=\"h2-subtitle-news-inf\">\u00a0<\/h2>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Los excesos h\u00eddricos de un fuerte a\u00f1o Ni\u00f1o generan problemas que no siempre se consideran. La nutrici\u00f3n de la soja es fundamental para maximizar retornos. Cuando el pron\u00f3stico clim\u00e1tico anuncia un a\u00f1o agr\u00edcola en fase Ni\u00f1o, la primera conclusi\u00f3n es pensar en importantes potenciales de rendimiento. Esto es cierto para el ma\u00edz pero no necesariamente para la soja, ya que se encuentra sometida a niveles de estr\u00e9s por saturaci\u00f3n h\u00eddrica en la riz\u00f3sfera, que genera demoras en el desarrollo inicial de la planta, menores niveles de simbiosis con el inoculante y mayor presi\u00f3n de enfermedades, entre otras cosas. A su vez, aparecen m\u00e1s malezas (especialmente gram\u00edneas) que deben ser controladas, no s\u00f3lo en base a herbicidas sino tambi\u00e9n utilizando el sombreo del cultivo. En a\u00f1os como este, la soja puede entrar f\u00e1cilmente en un c\u00edrculo vicioso donde la falta de desarrollo radicular y de simbiosis con las bacterias del inoculante lleva a un menor desarrollo inicial, con m\u00e1s predisposici\u00f3n a la acci\u00f3n subcl\u00ednica de enfermedades y a un cierre de cultivo m\u00e1s lento, y por lo tanto mayores problemas de malezas. Una forma de entrar en un c\u00edrculo virtuoso de generaci\u00f3n de \u00e1rea foliar para maximizar la cantidad de granos, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7414,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso | Proagro\" \/>\n<meta property=\"og:description\" content=\"Los excesos h\u00eddricos de un fuerte a\u00f1o Ni\u00f1o generan problemas que no siempre se consideran. La nutrici\u00f3n de la soja es fundamental para maximizar retornos. Cuando el pron\u00f3stico clim\u00e1tico anuncia un a\u00f1o agr\u00edcola en fase Ni\u00f1o, la primera conclusi\u00f3n es pensar en importantes potenciales de rendimiento. Esto es cierto para el ma\u00edz pero no necesariamente para la soja, ya que se encuentra sometida a niveles de estr\u00e9s por saturaci\u00f3n h\u00eddrica en la riz\u00f3sfera, que genera demoras en el desarrollo inicial de la planta, menores niveles de simbiosis con el inoculante y mayor presi\u00f3n de enfermedades, entre otras cosas. A su vez, aparecen m\u00e1s malezas (especialmente gram\u00edneas) que deben ser controladas, no s\u00f3lo en base a herbicidas sino tambi\u00e9n utilizando el sombreo del cultivo. En a\u00f1os como este, la soja puede entrar f\u00e1cilmente en un c\u00edrculo vicioso donde la falta de desarrollo radicular y de simbiosis con las bacterias del inoculante lleva a un menor desarrollo inicial, con m\u00e1s predisposici\u00f3n a la acci\u00f3n subcl\u00ednica de enfermedades y a un cierre de cultivo m\u00e1s lento, y por lo tanto mayores problemas de malezas. Una forma de entrar en un c\u00edrculo virtuoso de generaci\u00f3n de \u00e1rea foliar para maximizar la cantidad de granos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-18T15:28:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/12\/nutricion_de_soja_en_ano_nino_fyo_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso\",\"datePublished\":\"2015-12-18T15:28:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/\"},\"wordCount\":320,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/nutricion_de_soja_en_ano_nino_fyo_0.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/\",\"name\":\"Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/nutricion_de_soja_en_ano_nino_fyo_0.jpg\",\"datePublished\":\"2015-12-18T15:28:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/nutricion_de_soja_en_ano_nino_fyo_0.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/nutricion_de_soja_en_ano_nino_fyo_0.jpg\",\"width\":620,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/","og_locale":"en_US","og_type":"article","og_title":"Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso | Proagro","og_description":"Los excesos h\u00eddricos de un fuerte a\u00f1o Ni\u00f1o generan problemas que no siempre se consideran. La nutrici\u00f3n de la soja es fundamental para maximizar retornos. Cuando el pron\u00f3stico clim\u00e1tico anuncia un a\u00f1o agr\u00edcola en fase Ni\u00f1o, la primera conclusi\u00f3n es pensar en importantes potenciales de rendimiento. Esto es cierto para el ma\u00edz pero no necesariamente para la soja, ya que se encuentra sometida a niveles de estr\u00e9s por saturaci\u00f3n h\u00eddrica en la riz\u00f3sfera, que genera demoras en el desarrollo inicial de la planta, menores niveles de simbiosis con el inoculante y mayor presi\u00f3n de enfermedades, entre otras cosas. A su vez, aparecen m\u00e1s malezas (especialmente gram\u00edneas) que deben ser controladas, no s\u00f3lo en base a herbicidas sino tambi\u00e9n utilizando el sombreo del cultivo. En a\u00f1os como este, la soja puede entrar f\u00e1cilmente en un c\u00edrculo vicioso donde la falta de desarrollo radicular y de simbiosis con las bacterias del inoculante lleva a un menor desarrollo inicial, con m\u00e1s predisposici\u00f3n a la acci\u00f3n subcl\u00ednica de enfermedades y a un cierre de cultivo m\u00e1s lento, y por lo tanto mayores problemas de malezas. Una forma de entrar en un c\u00edrculo virtuoso de generaci\u00f3n de \u00e1rea foliar para maximizar la cantidad de granos, [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2015-12-18T15:28:48+00:00","og_image":[{"width":620,"height":375,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/12\/nutricion_de_soja_en_ano_nino_fyo_0.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso","datePublished":"2015-12-18T15:28:48+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/"},"wordCount":320,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/12\/nutricion_de_soja_en_ano_nino_fyo_0.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/","url":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/","name":"Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/12\/nutricion_de_soja_en_ano_nino_fyo_0.jpg","datePublished":"2015-12-18T15:28:48+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/12\/nutricion_de_soja_en_ano_nino_fyo_0.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/12\/nutricion_de_soja_en_ano_nino_fyo_0.jpg","width":620,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/nutricion-en-soja-del-circulo-vicioso-al-virtuoso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Nutrici\u00f3n en soja: del c\u00edrculo vicioso al virtuoso"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7413"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/7414"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}