{"id":7355,"date":"2015-11-26T15:20:21","date_gmt":"2015-11-26T15:20:21","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7355"},"modified":"2015-11-26T15:20:21","modified_gmt":"2015-11-26T15:20:21","slug":"condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/","title":{"rendered":"Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7356\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg\" alt=\"tormentas_interrumpen_cosecha_fyo_0\" width=\"300\" height=\"181\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0-600x363.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Un nuevo evento clim\u00e1tico que se registr\u00f3 en la semana, fue el condicionante para que las actividades de siembra y cosecha se vieran interrumpidas y restringieron la fluidez con que se ven\u00edan concretando en el norte de Santa Fe.<\/p>\n<p>Los mil\u00edmetros ca\u00eddos fluctuaron entre\u00a0<strong style=\"font-style: inherit;\">05 y 130<\/strong><span style=\"font-style: inherit; font-weight: inherit;\">\u00a0<\/span>siendo su cobertura geogr\u00e1fica del 100 % del \u00e1rea de estudio. Pero la particularidad que present\u00f3 fue que el mismo se expres\u00f3 con\u00a0<strong style=\"font-style: inherit;\">vientos medios<\/strong><span style=\"font-style: inherit; font-weight: inherit;\">\u00a0<\/span>y\u00a0<strong style=\"font-style: inherit;\">r\u00e1fagas de fuerte intensidad<\/strong><span style=\"font-style: inherit; font-weight: inherit;\">, ca\u00edda de granizo<\/span><span style=\"font-style: inherit; font-weight: inherit;\">\u00a0por mangas, tambi\u00e9n de variadas intensidades y magnitudes, las cuales se registraron en los departamentos Castellanos, Las Colonias y San Justo.<\/span><\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">Posterior a dicho evento\u00a0<strong style=\"font-style: inherit;\">d\u00edas soleados<\/strong>, seminublados y nublados con algunas\u00a0<strong style=\"font-style: inherit;\">precipitaciones <\/strong>de leves intensidades, temperaturas medias a levemente altas y humedad ambiente de medio a levemente alto &#8211; alto, posibilit\u00f3 que el movimiento de equipos,\u00a0<strong style=\"font-style: inherit;\">sembradoras y cosechadoras<\/strong>\u00a0en los distintos departamentos del centro norte de la provincia se reanude y se aprovechen las horas y d\u00edas de buenas condiciones clim\u00e1ticas para avanzar en superficies\u00a0<strong style=\"font-style: inherit;\">sembradas y cosechadas<\/strong>. Los\u00a0<strong style=\"font-style: inherit;\">pron\u00f3sticos<\/strong>\u00a0prev\u00e9n inestabilidad clim\u00e1tica con\u00a0<em style=\"font-weight: inherit;\">precipitaciones<\/em>\u00a0diversas, chaparrones con intensidades variables y cierta uniformidad en toda el \u00e1rea de estudio, con ocurrencia de los mayores registros en los departamentos del sector este.<\/p>\n<p>Dicha situaci\u00f3n generar\u00e1 algunos\u00a0<strong style=\"font-style: inherit;\">inconvenientes<\/strong><strong>\u00a0<\/strong>en el desarrollo de todas las actividades agr\u00edcolas, dependiendo de los mil\u00edmetros ca\u00eddos y los porcentajes de humedad, particularmente en los sectores o \u00e1reas m\u00e1s deprimidas porque tras la secuencia de precipitaciones los suelos comenzaron a manifestar cierta\u00a0<strong style=\"font-style: inherit;\">saturaci\u00f3n h\u00eddrica<\/strong>\u00a0en sus perfiles.<\/p>\n<h2 style=\"font-style: inherit;\">COSECHA<\/h2>\n<h3 style=\"font-style: inherit;\">Trigo<\/h3>\n<p style=\"font-style: inherit; font-weight: inherit;\">El proceso de\u00a0<em style=\"font-weight: inherit;\">cosecha<\/em>\u00a0se vio\u00a0<strong style=\"font-style: inherit;\">interrumpido<\/strong><strong>\u00a0<\/strong>por las precipitaciones mencionadas, pero ni bien se presentaron d\u00edas soleados con temperaturas medias a altas el proceso de cosecha avanz\u00f3, ante los temores de\u00a0<strong style=\"font-style: inherit;\">nuevos pron\u00f3sticos de lluvia<\/strong>\u00a0para los pr\u00f3ximos d\u00edas.<\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">Hubo\u00a0<strong style=\"font-style: inherit;\">da\u00f1os<\/strong>\u00a0en sectores (lotes) de variadas intensidades en cultivos que a\u00fan no se han cosechado, dicha situaci\u00f3n no repercuti\u00f3 por su bajo porcentaje en las estimaciones que se ven\u00edan realizando.<\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">Las estimaciones de los\u00a0<strong style=\"font-style: inherit;\">rindes promedios<\/strong>\u00a0para esta campa\u00f1a 2015, en las distintas zonas es:<\/p>\n<ul>\n<li>para los tres departamentos del norte del \u00e1rea un rinde promedio estimado entre 23 a 25 qq\/ha<\/li>\n<li><span style=\"font-style: inherit; font-weight: inherit;\">para los departamentos del centro del \u00e1rea un rinde promedio estimado entre 28 a 30 qq\/ha y<\/span><\/li>\n<li><span style=\"font-style: inherit; font-weight: inherit;\">para los departamentos del sur del \u00e1rea un rinde promedio estimado entre 32 a 35 qq\/ha<\/span><\/li>\n<\/ul>\n<h2 style=\"font-style: inherit;\">SIEMBRA<\/h2>\n<h3 style=\"font-style: inherit;\">Soja de primera<\/h3>\n<p style=\"font-style: inherit; font-weight: inherit;\">El proceso de siembra\u00a0mostr\u00f3 fluidez y ritmo, con un grado de avance del\u00a0<strong style=\"font-style: inherit;\">80 %<\/strong>\u00a0representando aproximadamente unas\u00a0<strong style=\"font-style: inherit;\">720.000 ha<\/strong>, sobre una intenci\u00f3n de siembra de\u00a0<strong style=\"font-style: inherit;\">900.000 ha<\/strong>.<\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">Este escenario manifest\u00f3 similar situaci\u00f3n en\u00a0<strong style=\"font-style: inherit;\">porcentaje de siembra<\/strong>\u00a0a la misma fecha de la campa\u00f1a pasada 2014\/2015, pero con la particularidad de muy buenas condiciones ed\u00e1ficas en la cama de siembra, como ser disponibilidad de agua \u00fatil y temperatura.<\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">Tras las\u00a0<strong style=\"font-style: inherit;\">precipitaciones<\/strong>\u00a0registradas y la\u00a0<strong style=\"font-style: inherit;\">recarga de los perfiles<\/strong>\u00a0de suelos comenzaron a observarse \u00e1reas de 8 encharcamiento y saturaci\u00f3n h\u00eddrica, en particular las posiciones topogr\u00e1ficas m\u00e1s bajas condicionando el proceso de siembra.<\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">Ma\u00edz temprano (de primera)<\/p>\n<p>Loscultivares implantados\u00a0en los diferentes departamentos del \u00e1rea presentaron estados muy buenos a excelentes con muy buena estructura de plantas, uniformidad de lotes, con buenas respuestas a la refertilizaci\u00f3n nitrogenada, la cual permiti\u00f3 un\u00a0<strong style=\"font-style: inherit;\">muy buen crecimiento y desarrollo<\/strong><strong>.<\/strong><\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">Tambi\u00e9n la\u00a0<strong style=\"font-style: inherit;\">ca\u00edda de granizo<\/strong>\u00a0afect\u00f3 a cultivares causando diversos da\u00f1os en los sectores de los departamentos mencionados en la introducci\u00f3n.<\/p>\n<p style=\"font-style: inherit; font-weight: inherit;\">Sigue el inter\u00e9s en consulta y\/o demanda de semillas para futuras siembras de\u00a0<strong style=\"font-style: inherit;\">ma\u00edz de <\/strong><strong>segunda<\/strong><strong>,<\/strong> pero se estima que dicho movimiento no cambiar\u00e1 o revertir\u00e1 la situaci\u00f3n del ma\u00edz (menor superficie) para esta campa\u00f1a.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.fyo.com\/noticia\/154092\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\">http:\/\/www.fyo.com\/noticia\/154092\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha<\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Un nuevo evento clim\u00e1tico que se registr\u00f3 en la semana, fue el condicionante para que las actividades de siembra y cosecha se vieran interrumpidas y restringieron la fluidez con que se ven\u00edan concretando en el norte de Santa Fe. Los mil\u00edmetros ca\u00eddos fluctuaron entre\u00a005 y 130\u00a0siendo su cobertura geogr\u00e1fica del 100 % del \u00e1rea de estudio. Pero la particularidad que present\u00f3 fue que el mismo se expres\u00f3 con\u00a0vientos medios\u00a0y\u00a0r\u00e1fagas de fuerte intensidad, ca\u00edda de granizo\u00a0por mangas, tambi\u00e9n de variadas intensidades y magnitudes, las cuales se registraron en los departamentos Castellanos, Las Colonias y San Justo. Posterior a dicho evento\u00a0d\u00edas soleados, seminublados y nublados con algunas\u00a0precipitaciones de leves intensidades, temperaturas medias a levemente altas y humedad ambiente de medio a levemente alto &#8211; alto, posibilit\u00f3 que el movimiento de equipos,\u00a0sembradoras y cosechadoras\u00a0en los distintos departamentos del centro norte de la provincia se reanude y se aprovechen las horas y d\u00edas de buenas condiciones clim\u00e1ticas para avanzar en superficies\u00a0sembradas y cosechadas. Los\u00a0pron\u00f3sticos\u00a0prev\u00e9n inestabilidad clim\u00e1tica con\u00a0precipitaciones\u00a0diversas, chaparrones con intensidades variables y cierta uniformidad en toda el \u00e1rea de estudio, con ocurrencia de los mayores registros en los departamentos del sector este. Dicha situaci\u00f3n generar\u00e1 algunos\u00a0inconvenientes\u00a0en el desarrollo de todas las actividades agr\u00edcolas, dependiendo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7355","post","type-post","status-publish","format-standard","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha. | Proagro\" \/>\n<meta property=\"og:description\" content=\"Un nuevo evento clim\u00e1tico que se registr\u00f3 en la semana, fue el condicionante para que las actividades de siembra y cosecha se vieran interrumpidas y restringieron la fluidez con que se ven\u00edan concretando en el norte de Santa Fe. Los mil\u00edmetros ca\u00eddos fluctuaron entre\u00a005 y 130\u00a0siendo su cobertura geogr\u00e1fica del 100 % del \u00e1rea de estudio. Pero la particularidad que present\u00f3 fue que el mismo se expres\u00f3 con\u00a0vientos medios\u00a0y\u00a0r\u00e1fagas de fuerte intensidad, ca\u00edda de granizo\u00a0por mangas, tambi\u00e9n de variadas intensidades y magnitudes, las cuales se registraron en los departamentos Castellanos, Las Colonias y San Justo. Posterior a dicho evento\u00a0d\u00edas soleados, seminublados y nublados con algunas\u00a0precipitaciones de leves intensidades, temperaturas medias a levemente altas y humedad ambiente de medio a levemente alto &#8211; alto, posibilit\u00f3 que el movimiento de equipos,\u00a0sembradoras y cosechadoras\u00a0en los distintos departamentos del centro norte de la provincia se reanude y se aprovechen las horas y d\u00edas de buenas condiciones clim\u00e1ticas para avanzar en superficies\u00a0sembradas y cosechadas. Los\u00a0pron\u00f3sticos\u00a0prev\u00e9n inestabilidad clim\u00e1tica con\u00a0precipitaciones\u00a0diversas, chaparrones con intensidades variables y cierta uniformidad en toda el \u00e1rea de estudio, con ocurrencia de los mayores registros en los departamentos del sector este. Dicha situaci\u00f3n generar\u00e1 algunos\u00a0inconvenientes\u00a0en el desarrollo de todas las actividades agr\u00edcolas, dependiendo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-26T15:20:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha.\",\"datePublished\":\"2015-11-26T15:20:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/\"},\"wordCount\":648,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/\",\"name\":\"Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg\",\"datePublished\":\"2015-11-26T15:20:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/","og_locale":"en_US","og_type":"article","og_title":"Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha. | Proagro","og_description":"Un nuevo evento clim\u00e1tico que se registr\u00f3 en la semana, fue el condicionante para que las actividades de siembra y cosecha se vieran interrumpidas y restringieron la fluidez con que se ven\u00edan concretando en el norte de Santa Fe. Los mil\u00edmetros ca\u00eddos fluctuaron entre\u00a005 y 130\u00a0siendo su cobertura geogr\u00e1fica del 100 % del \u00e1rea de estudio. Pero la particularidad que present\u00f3 fue que el mismo se expres\u00f3 con\u00a0vientos medios\u00a0y\u00a0r\u00e1fagas de fuerte intensidad, ca\u00edda de granizo\u00a0por mangas, tambi\u00e9n de variadas intensidades y magnitudes, las cuales se registraron en los departamentos Castellanos, Las Colonias y San Justo. Posterior a dicho evento\u00a0d\u00edas soleados, seminublados y nublados con algunas\u00a0precipitaciones de leves intensidades, temperaturas medias a levemente altas y humedad ambiente de medio a levemente alto &#8211; alto, posibilit\u00f3 que el movimiento de equipos,\u00a0sembradoras y cosechadoras\u00a0en los distintos departamentos del centro norte de la provincia se reanude y se aprovechen las horas y d\u00edas de buenas condiciones clim\u00e1ticas para avanzar en superficies\u00a0sembradas y cosechadas. Los\u00a0pron\u00f3sticos\u00a0prev\u00e9n inestabilidad clim\u00e1tica con\u00a0precipitaciones\u00a0diversas, chaparrones con intensidades variables y cierta uniformidad en toda el \u00e1rea de estudio, con ocurrencia de los mayores registros en los departamentos del sector este. Dicha situaci\u00f3n generar\u00e1 algunos\u00a0inconvenientes\u00a0en el desarrollo de todas las actividades agr\u00edcolas, dependiendo [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2015-11-26T15:20:21+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg","type":"","width":"","height":""}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha.","datePublished":"2015-11-26T15:20:21+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/"},"wordCount":648,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/","url":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/","name":"Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg","datePublished":"2015-11-26T15:20:21+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/11\/tormentas_interrumpen_cosecha_fyo_0-300x181.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/condiciones-climaticas-adversas-interrumpieron-siembra-y-cosecha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Condiciones clim\u00e1ticas adversas interrumpieron siembra y cosecha."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7355"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7355\/revisions"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}