{"id":7299,"date":"2015-10-30T17:26:58","date_gmt":"2015-10-30T17:26:58","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7299"},"modified":"2015-10-30T17:26:58","modified_gmt":"2015-10-30T17:26:58","slug":"la-demanda-vuelve-a-ser-protagonista","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/la-demanda-vuelve-a-ser-protagonista\/","title":{"rendered":"La demanda vuelve a ser protagonista"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Los precios de la hacienda suben, en un contexto en el que se consumen 64 kilos por habitante. El mercado de terneros transita por los meses de menor oferta.<\/p>\n<p>En los se agregan kilos en funci\u00f3n de que el ma\u00edz todav\u00eda est\u00e1 barato y el valor de la invernada<br \/>El mercado est\u00e1 firme, con una oferta condicionada por la<strong> incertidumbre electoral<\/strong> y por la <strong>demora en los engordes.<\/strong> <br \/>En los feedlots se agregan kilos en funci\u00f3n de que el<strong> ma\u00edz todav\u00eda est\u00e1 barato<\/strong> y el valor de la invernada es prohibitivo. <br \/>En el sistema pastoril suplementado predominan los <strong>mismos argumentos<\/strong> para alargar el engorde, agregado a que la primavera ha venido muy fr\u00eda y con un menor volumen de pasto del que podr\u00eda<strong> esperarse para la \u00e9poca<\/strong>. <br \/>Pero el protagonismo es de la demanda: los precios de la hacienda est\u00e1n <strong>subiendo en el contexto<\/strong> de una oferta que alcanza para consumir 63-64 kilos. Si el consumo est\u00e1 alto y creciente, y los precios de la hacienda suben, se puede deducir que la demanda del <strong>consumo interno<\/strong> todav\u00eda est\u00e1 s\u00f3lida.<\/p>\n<p>POR CATEGOR\u00cdAS<\/p>\n<p>El escenario muestra muy firme la<strong> demanda del novillo<\/strong>, una especie en extinci\u00f3n, y la vaca, muy buscada por los \u201cvaqueros\u201d del consumo de las orillas y por la exportaci\u00f3n, que la necesita como suced\u00e1nea obligada del<strong> novillo que falta.<\/strong> <br \/>No desentona la hacienda liviana de corral, pese a que estamos atravesando en el<strong> pico estacional de oferta<\/strong>. En un a\u00f1o justo, o sea desde fines de octubre del 2014, el novillo ha subido un 26,6 por ciento; el <strong>novillito de 351-390 kilos<\/strong>, creci\u00f3 28 por ciento y el ternero, 29 por ciento. <br \/>En 2009, como consecuencia en buena medida de la seca, los<strong> feedlots registrados por Senasa<\/strong> engordaron 5,5 millones de cabezas con destino a faena, volumen que cay\u00f3 luego abruptamente con el cambio de fase del <strong>ciclo ganadero<\/strong>, para tocar s\u00f3lo 3,20 millones en el 2011. <br \/>Desde entonces, el n\u00famero de cabezas terminadas a corral creci\u00f3 hasta lograr los<strong> 3,8 millones el a\u00f1o pasado.<\/strong> <br \/>Para este a\u00f1o, y como consecuencia de la in\u00e9dita <strong>relaci\u00f3n carne\/grano,<\/strong> se espera otro incremento. <br \/>Seg\u00fan nuestros c\u00e1lculos, el a\u00f1o terminar\u00e1 con unas<strong> 3,90 millones de cabezas<\/strong> gordas, lo que representa un aumento de 1,8 por ciento. <br \/>Llama la atenci\u00f3n que mientras las entradas de<strong> invernada al feedlot<\/strong> muestran fuertes oscilaciones, con m\u00ednimos (en 2014) de 247 mil animales en octubre pasado y m\u00e1ximos de 461 mil en abril, las salidas a faena muestran una llamativa estabilidad, con un m\u00ednimo de 274 mil cabezas en enero y un m\u00e1ximo de <strong>354 mil animales en diciembre.<\/strong> <br \/>As\u00ed, en el cuatrimestre marzo-junio se registra el 51,5 por ciento de la zafra, mientras que en el cuatrimestre septiembre-diciembre (momento de invernada escasa y cara), la estacionalidad indica que se vende s\u00f3lo el 20,7 por ciento de la oferta anual. Como los n\u00fameros de entrada a los feedlots del cuatrimestre marzo-junio son bien inferiores a los terneros de invernada comercializados en esos mismos meses, puede colegirse que un n\u00famero significativo de terneros se deriva a recr\u00eda \u2013por cuenta de los mismos feedlots \u2013 o es comprado por invernadores o ganaderos tradicionales.<\/p>\n<p><a href=\"http:\/\/www.fyo.com\/noticia\/153428\/demanda-vuelve-ser-protagonista\">http:\/\/www.fyo.com\/noticia\/153428\/demanda-vuelve-ser-protagonista<\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Los precios de la hacienda suben, en un contexto en el que se consumen 64 kilos por habitante. El mercado de terneros transita por los meses de menor oferta. En los se agregan kilos en funci\u00f3n de que el ma\u00edz todav\u00eda est\u00e1 barato y el valor de la invernadaEl mercado est\u00e1 firme, con una oferta condicionada por la incertidumbre electoral y por la demora en los engordes. En los feedlots se agregan kilos en funci\u00f3n de que el ma\u00edz todav\u00eda est\u00e1 barato y el valor de la invernada es prohibitivo. En el sistema pastoril suplementado predominan los mismos argumentos para alargar el engorde, agregado a que la primavera ha venido muy fr\u00eda y con un menor volumen de pasto del que podr\u00eda esperarse para la \u00e9poca. Pero el protagonismo es de la demanda: los precios de la hacienda est\u00e1n subiendo en el contexto de una oferta que alcanza para consumir 63-64 kilos. Si el consumo est\u00e1 alto y creciente, y los precios de la hacienda suben, se puede deducir que la demanda del consumo interno todav\u00eda est\u00e1 s\u00f3lida. POR CATEGOR\u00cdAS El escenario muestra muy firme la demanda del novillo, una especie en extinci\u00f3n, y la vaca, muy buscada por los [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7312,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-7299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La demanda vuelve a ser protagonista | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/la-demanda-vuelve-a-ser-protagonista\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La demanda vuelve a ser protagonista | Proagro\" \/>\n<meta property=\"og:description\" content=\"Los precios de la hacienda suben, en un contexto en el que se consumen 64 kilos por habitante. El mercado de terneros transita por los meses de menor oferta. En los se agregan kilos en funci\u00f3n de que el ma\u00edz todav\u00eda est\u00e1 barato y el valor de la invernadaEl mercado est\u00e1 firme, con una oferta condicionada por la incertidumbre electoral y por la demora en los engordes. En los feedlots se agregan kilos en funci\u00f3n de que el ma\u00edz todav\u00eda est\u00e1 barato y el valor de la invernada es prohibitivo. En el sistema pastoril suplementado predominan los mismos argumentos para alargar el engorde, agregado a que la primavera ha venido muy fr\u00eda y con un menor volumen de pasto del que podr\u00eda esperarse para la \u00e9poca. Pero el protagonismo es de la demanda: los precios de la hacienda est\u00e1n subiendo en el contexto de una oferta que alcanza para consumir 63-64 kilos. Si el consumo est\u00e1 alto y creciente, y los precios de la hacienda suben, se puede deducir que la demanda del consumo interno todav\u00eda est\u00e1 s\u00f3lida. POR CATEGOR\u00cdAS El escenario muestra muy firme la demanda del novillo, una especie en extinci\u00f3n, y la vaca, muy buscada por los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-30T17:26:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/1145x395-26102015.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/\"},\"author\":{\"name\":\"Editor Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\"},\"headline\":\"La demanda vuelve a ser protagonista\",\"datePublished\":\"2015-10-30T17:26:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/\"},\"wordCount\":552,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/1145x395-26102015.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/\",\"name\":\"La demanda vuelve a ser protagonista | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/1145x395-26102015.jpg\",\"datePublished\":\"2015-10-30T17:26:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/1145x395-26102015.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/1145x395-26102015.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-demanda-vuelve-a-ser-protagonista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La demanda vuelve a ser protagonista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/b23080c7caf108441a11c7bf48f17d4d\",\"name\":\"Editor Proagro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La demanda vuelve a ser protagonista | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/la-demanda-vuelve-a-ser-protagonista\/","og_locale":"en_US","og_type":"article","og_title":"La demanda vuelve a ser protagonista | Proagro","og_description":"Los precios de la hacienda suben, en un contexto en el que se consumen 64 kilos por habitante. El mercado de terneros transita por los meses de menor oferta. En los se agregan kilos en funci\u00f3n de que el ma\u00edz todav\u00eda est\u00e1 barato y el valor de la invernadaEl mercado est\u00e1 firme, con una oferta condicionada por la incertidumbre electoral y por la demora en los engordes. En los feedlots se agregan kilos en funci\u00f3n de que el ma\u00edz todav\u00eda est\u00e1 barato y el valor de la invernada es prohibitivo. En el sistema pastoril suplementado predominan los mismos argumentos para alargar el engorde, agregado a que la primavera ha venido muy fr\u00eda y con un menor volumen de pasto del que podr\u00eda esperarse para la \u00e9poca. Pero el protagonismo es de la demanda: los precios de la hacienda est\u00e1n subiendo en el contexto de una oferta que alcanza para consumir 63-64 kilos. Si el consumo est\u00e1 alto y creciente, y los precios de la hacienda suben, se puede deducir que la demanda del consumo interno todav\u00eda est\u00e1 s\u00f3lida. POR CATEGOR\u00cdAS El escenario muestra muy firme la demanda del novillo, una especie en extinci\u00f3n, y la vaca, muy buscada por los [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2015-10-30T17:26:58+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/1145x395-26102015.jpg","type":"image\/jpeg"}],"author":"Editor Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/"},"author":{"name":"Editor Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d"},"headline":"La demanda vuelve a ser protagonista","datePublished":"2015-10-30T17:26:58+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/"},"wordCount":552,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/1145x395-26102015.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/","url":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/","name":"La demanda vuelve a ser protagonista | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/1145x395-26102015.jpg","datePublished":"2015-10-30T17:26:58+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/1145x395-26102015.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/1145x395-26102015.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/la-demanda-vuelve-a-ser-protagonista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"La demanda vuelve a ser protagonista"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/b23080c7caf108441a11c7bf48f17d4d","name":"Editor Proagro"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7299"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/7312"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}