{"id":7272,"date":"2015-10-15T13:32:19","date_gmt":"2015-10-15T13:32:19","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=7272"},"modified":"2020-06-29T18:48:11","modified_gmt":"2020-06-29T18:48:11","slug":"campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/","title":{"rendered":"Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><font color=\"Black\"><\/p>\n<p><em><strong>La vacunaci\u00f3n es una de las principales estrategias de prevenci\u00f3n y permite mantener la situaci\u00f3n epidemiol\u00f3gica estable en el pa\u00eds.\u00a0En Salta se vacunaron 1.011.851 cabezas bovinas.<\/strong><\/em><br \/>\n<em>Por Agro Noa.<\/em><\/p>\n<p>\nM\u00e1s de 40 millones de bovinos fueron vacunados contra la fiebre aftosa durante la primera campa\u00f1a de 2015. El <strong>SENASA<\/strong> la llev\u00f3 a cabo, seg\u00fan el cronograma previsto, en el cual se aplicaron distintas estrategias de vacunaci\u00f3n, dependiendo de la provincia o regi\u00f3n.<\/p>\n<p>Las provincias de <strong>Buenos Aires<\/strong> (salvo el partido de Patagones), <strong>Entre R\u00edos y Corrientes<\/strong> vacunaron a los bovinos y bubalinos de las categor\u00edas menores (terneros\/as, vaquillonas, toritos, novillitos y novillos). En el resto de las provincias, la vacunaci\u00f3n incluy\u00f3 todas las categor\u00edas. La zona denominada <strong>Cord\u00f3n Fronterizo<\/strong>, contin\u00faa con dos vacunaciones anuales de todas las categor\u00edas etarias de los rodeos.<\/p>\n<p>La vacunaci\u00f3n contra la fiebre aftosa es una de las <strong>principales estrategias de prevenci\u00f3n que permite mantener una situaci\u00f3n epidemiol\u00f3gica estable de esa enfermedad en la Rep\u00fablica Argentina<\/strong>. Para conocer la cantidad de bovinos vacunados durante la campa\u00f1a por provincia y categor\u00eda,\u00a0<a href=\"http:\/\/nuevaweb.senasa.gob.ar\/sites\/default\/files\/datos_finales_web_1-2015_-_provincias.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">haga clic aqu\u00ed<\/a>.\u00a0Para los n\u00fameros discriminados por departamento y categor\u00eda, <a href=\"http:\/\/nuevaweb.senasa.gob.ar\/sites\/default\/files\/datos_finales_web_1-2015_-_partidos.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">haga clic aqu\u00ed<\/a>.<\/p>\n<p><em>Fuente:\u00a0http:\/\/www.fyo.com\/noticia\/153057\/campana-anti-aftosa-mas-40-millones-bovinos-vacunados<\/em><\/p>\n<p><\/font><\/p>","protected":false},"excerpt":{"rendered":"<p>La vacunaci\u00f3n es una de las principales estrategias de prevenci\u00f3n y permite mantener la situaci\u00f3n epidemiol\u00f3gica estable en el pa\u00eds.\u00a0En Salta se vacunaron 1.011.851 cabezas bovinas. Por Agro Noa. M\u00e1s de 40 millones de bovinos fueron vacunados contra la fiebre aftosa durante la primera campa\u00f1a de 2015. El SENASA la llev\u00f3 a cabo, seg\u00fan el cronograma previsto, en el cual se aplicaron distintas estrategias de vacunaci\u00f3n, dependiendo de la provincia o regi\u00f3n. Las provincias de Buenos Aires (salvo el partido de Patagones), Entre R\u00edos y Corrientes vacunaron a los bovinos y bubalinos de las categor\u00edas menores (terneros\/as, vaquillonas, toritos, novillitos y novillos). En el resto de las provincias, la vacunaci\u00f3n incluy\u00f3 todas las categor\u00edas. La zona denominada Cord\u00f3n Fronterizo, contin\u00faa con dos vacunaciones anuales de todas las categor\u00edas etarias de los rodeos. La vacunaci\u00f3n contra la fiebre aftosa es una de las principales estrategias de prevenci\u00f3n que permite mantener una situaci\u00f3n epidemiol\u00f3gica estable de esa enfermedad en la Rep\u00fablica Argentina. Para conocer la cantidad de bovinos vacunados durante la campa\u00f1a por provincia y categor\u00eda,\u00a0haga clic aqu\u00ed.\u00a0Para los n\u00fameros discriminados por departamento y categor\u00eda, haga clic aqu\u00ed. Fuente:\u00a0http:\/\/www.fyo.com\/noticia\/153057\/campana-anti-aftosa-mas-40-millones-bovinos-vacunados<\/p>\n","protected":false},"author":6,"featured_media":7274,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[81,80,79],"class_list":["post-7272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero","tag-bovinos","tag-ganaderia","tag-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados | Proagro\" \/>\n<meta property=\"og:description\" content=\"La vacunaci\u00f3n es una de las principales estrategias de prevenci\u00f3n y permite mantener la situaci\u00f3n epidemiol\u00f3gica estable en el pa\u00eds.\u00a0En Salta se vacunaron 1.011.851 cabezas bovinas. Por Agro Noa. M\u00e1s de 40 millones de bovinos fueron vacunados contra la fiebre aftosa durante la primera campa\u00f1a de 2015. El SENASA la llev\u00f3 a cabo, seg\u00fan el cronograma previsto, en el cual se aplicaron distintas estrategias de vacunaci\u00f3n, dependiendo de la provincia o regi\u00f3n. Las provincias de Buenos Aires (salvo el partido de Patagones), Entre R\u00edos y Corrientes vacunaron a los bovinos y bubalinos de las categor\u00edas menores (terneros\/as, vaquillonas, toritos, novillitos y novillos). En el resto de las provincias, la vacunaci\u00f3n incluy\u00f3 todas las categor\u00edas. La zona denominada Cord\u00f3n Fronterizo, contin\u00faa con dos vacunaciones anuales de todas las categor\u00edas etarias de los rodeos. La vacunaci\u00f3n contra la fiebre aftosa es una de las principales estrategias de prevenci\u00f3n que permite mantener una situaci\u00f3n epidemiol\u00f3gica estable de esa enfermedad en la Rep\u00fablica Argentina. Para conocer la cantidad de bovinos vacunados durante la campa\u00f1a por provincia y categor\u00eda,\u00a0haga clic aqu\u00ed.\u00a0Para los n\u00fameros discriminados por departamento y categor\u00eda, haga clic aqu\u00ed. Fuente:\u00a0http:\/\/www.fyo.com\/noticia\/153057\/campana-anti-aftosa-mas-40-millones-bovinos-vacunados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-15T13:32:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T18:48:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/Aftosa-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados\",\"datePublished\":\"2015-10-15T13:32:19+00:00\",\"dateModified\":\"2020-06-29T18:48:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/\"},\"wordCount\":234,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Aftosa-1.jpg\",\"keywords\":[\"bovinos\",\"Ganader\u00eda\",\"Noticias\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/\",\"name\":\"Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Aftosa-1.jpg\",\"datePublished\":\"2015-10-15T13:32:19+00:00\",\"dateModified\":\"2020-06-29T18:48:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Aftosa-1.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Aftosa-1.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/","og_locale":"en_US","og_type":"article","og_title":"Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados | Proagro","og_description":"La vacunaci\u00f3n es una de las principales estrategias de prevenci\u00f3n y permite mantener la situaci\u00f3n epidemiol\u00f3gica estable en el pa\u00eds.\u00a0En Salta se vacunaron 1.011.851 cabezas bovinas. Por Agro Noa. M\u00e1s de 40 millones de bovinos fueron vacunados contra la fiebre aftosa durante la primera campa\u00f1a de 2015. El SENASA la llev\u00f3 a cabo, seg\u00fan el cronograma previsto, en el cual se aplicaron distintas estrategias de vacunaci\u00f3n, dependiendo de la provincia o regi\u00f3n. Las provincias de Buenos Aires (salvo el partido de Patagones), Entre R\u00edos y Corrientes vacunaron a los bovinos y bubalinos de las categor\u00edas menores (terneros\/as, vaquillonas, toritos, novillitos y novillos). En el resto de las provincias, la vacunaci\u00f3n incluy\u00f3 todas las categor\u00edas. La zona denominada Cord\u00f3n Fronterizo, contin\u00faa con dos vacunaciones anuales de todas las categor\u00edas etarias de los rodeos. La vacunaci\u00f3n contra la fiebre aftosa es una de las principales estrategias de prevenci\u00f3n que permite mantener una situaci\u00f3n epidemiol\u00f3gica estable de esa enfermedad en la Rep\u00fablica Argentina. Para conocer la cantidad de bovinos vacunados durante la campa\u00f1a por provincia y categor\u00eda,\u00a0haga clic aqu\u00ed.\u00a0Para los n\u00fameros discriminados por departamento y categor\u00eda, haga clic aqu\u00ed. Fuente:\u00a0http:\/\/www.fyo.com\/noticia\/153057\/campana-anti-aftosa-mas-40-millones-bovinos-vacunados","og_url":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2015-10-15T13:32:19+00:00","article_modified_time":"2020-06-29T18:48:11+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/Aftosa-1.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados","datePublished":"2015-10-15T13:32:19+00:00","dateModified":"2020-06-29T18:48:11+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/"},"wordCount":234,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/Aftosa-1.jpg","keywords":["bovinos","Ganader\u00eda","Noticias"],"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/","url":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/","name":"Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/Aftosa-1.jpg","datePublished":"2015-10-15T13:32:19+00:00","dateModified":"2020-06-29T18:48:11+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/Aftosa-1.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/10\/Aftosa-1.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/campana-anti-aftosa-mas-de-40-millones-de-bovinos-vacunados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Campa\u00f1a anti aftosa: m\u00e1s de 40 millones de bovinos vacunados"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=7272"}],"version-history":[{"count":1,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7272\/revisions"}],"predecessor-version":[{"id":13882,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/7272\/revisions\/13882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/7274"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=7272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=7272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=7272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}