{"id":4829,"date":"2012-02-28T00:00:01","date_gmt":"2012-02-28T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/"},"modified":"2012-02-28T00:00:01","modified_gmt":"2012-02-28T00:00:01","slug":"suba-ocasional-de-las-cotizaciones-2","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/suba-ocasional-de-las-cotizaciones-2\/","title":{"rendered":"Suba ocasional de las cotizaciones."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>Se obtuvo hasta $ 11,20 por novillos livianos.<\/p>\n<p><span style=\"font-style: italic;\">Por Esteban D\u00b4Apice.<\/span><\/p>\n<p>Los operadores de compra que act\u00faan en el Mercado de Liniers debieron pagar esta semana precios que eran impensados al comienzo de febrero, y mucho menos en la primera quincena del a\u00f1o, cuando el ingreso de hacienda -posiblemente retenida en diciembre por razones fiscales- influy\u00f3 negativamente.<\/p>\n<p>Con las ruedas de lunes y martes anuladas por el feriado de Carnaval, la oferta sum\u00f3 entre el mi\u00e9rcoles y anteayer s\u00f3lo 10.545 cabezas, stock muy inferior al m\u00ednimo necesario para distribuir en los miles de despachos minoristas de la Capital Federal y del Gran Buenos Aires, donde llegan los repartos de los frigor\u00edficos consumeros y de los denominados abastecedores.<\/p>\n<p>En consecuencia, sin tener certeza alguna de si podr\u00edan trasladarse al valor de los distintos cortes las diferencias a la suba impuestas por la t\u00f3nica de firmeza de la plaza, los compradores compitieron para cumplir sus compromisos m\u00ednimos, pr\u00e1cticamente sin topes preestablecidos, seg\u00fan se dijo a La Nacion.<\/p>\n<p>Pero si bien los guarismos nominales parecen alentadores para quienes siguen apostando por la ganader\u00eda, la estad\u00edstica demuestra que en moneda constante el balance no es siempre positivo. La reflexi\u00f3n surge, por ejemplo, cuando se considera las condiciones en que fueron negociadas las diversas categor\u00edas de novillos, que con 1148 animales adjudicados representaron s\u00f3lo el 10,93% del total general.<\/p>\n<p>El indicador de Liniers, que suele tenerse en cuenta para contratos de arrendamientos, entre otros negocios, es en lo que va del a\u00f1o de $ 8,263, con 188.835 vacunos ingresados en el recinto, frente al de igual segmento de 2011, de $ 7,527, con una oferta de 174.048 cabezas. La variante a favor, de $ 0,736 y equivalente al 9,78%, es an\u00e1loga a la de inflaci\u00f3n originada en los despachos oficiales, pero muy alejada de las mediciones difundidas desde el \u00e1mbito legislativo nacional.<\/p>\n<p>Habida cuenta de la influencia ejercida por los feriados -pasado ma\u00f1ana tampoco habr\u00e1 actividad por el Bicentenario de la Bandera Nacional-, cabe calificar de ocasionales los promedios del segmento clausurado ayer, cuyo detalle es el siguiente: $ 9,90\/11 por novillos livianos con 431\/460 kg; $ 9,60\/10,60 con 461\/490 kg; $ 9,30\/9,60 con 491\/520 kg, y $ 9,10\/9,50 con m\u00e1s de 520 kg.<\/p>\n<p>Para destacar, $ 11,20 por livianos de 438 y de 440 kg; $ 11 con 465 kg; $ 10,10 con 480 kg, y $ 10,20 con 500 kg,<\/p>\n<p>Con lluvias que habr\u00edan abarcado a m\u00e1s del 80% de las explotaciones pecuarias, es probable que se trate de ganar kilos para aprovechar precios que, sin homologar los registros ocasionales de estos d\u00edas -se piensa-, oscilar\u00e1n en marcas convenientes.<\/p>\n<p>Para negocios directos se pactaban anteayer $ 17,80\/18 por kilo de carne de novillos con certificado, para exportaci\u00f3n, valor que declinaba a $ 17,30\/17,40 para jaulas de 500\/510 kg, en tanto que en los requeridos para el abasto local, de hasta 140 kg la media res, podr\u00edan acordarse $ 18,10 por kilo de carne.<\/p>\n<p><span style=\"font-style: italic;\">Haciendas livianas<\/span><br \/>Las haciendas del tipo consumo liviano constituyeron el 63,74% de la oferta, equivalente a 6692 animales, con 3503 novillitos, 2527 terneros y con s\u00f3lo 1112 vaquillonas. Ante una fuerte presi\u00f3n de varias de las empresas &#8220;consumeras&#8221;, estas categor\u00edas fueron comercializadas en una plaza muy firme y con saldo favorable para sus precios.<\/p>\n<p>Los niveles corrientes oscilaron de la siguiente manera: en novillitos, $ 10,20\/11,60 por medianos de 351\/390 kg; $ 9,90\/11,50 con 391\/430 kg, y $ 8\/9,80 por los regulares; en vaquillonas, $ 9,40\/10,60 con 351\/390 kg; $ 8,80\/9,50 con 391\/430 kg, y $ 8\/9,10 por las incompletas en preparaci\u00f3n, y en terneros, la oscilaci\u00f3n fue $ 11\/11,70 para especiales a buenos y $ 9\/11 por los regulares.<\/p>\n<p>Sobresalieron los $ 12 pagados por terneros de feedlot de 303 y de 312 kg; $ 11,92 con 326 kg; $ 11,95 por novillitos de 372 kg; $ 11,70 con 391 kg, y $ 11,90 por pesados de 419 kg, mientras que se logr\u00f3 $ 11,50 por hembras de 354 kg; $ 10,90 con 353 kg, y $ 10 con 415 kg.<\/p>\n<p>La empresa Coto encabez\u00f3 la estad\u00edstica de compras, con 896 vacunos entre mi\u00e9rcoles y jueves, por los que pag\u00f3 hasta $ 11,70 con 391 y con 393 kg, y $ 11,60 con 427 kg.<\/p>\n<p>Las vacas especiales, bien conformadas y &#8220;levantadas&#8221; que pueden destinarse para cortes -algunas con &#8220;rindes&#8221; no muy diferentes a los del novillo- se comercializaron en forma \u00e1gil y conveniente, a saber: $ 7\/7,80, con m\u00e1ximos de $ 9 con 441 kg; $ 8,50 con 468 kg; $ 7,97 con 460 kg, y $ 7,88 con 557 kg. Las regulares se negociaron en $ 5\/7 y en el tipo conserva, con declinaciones notorias, $ 4\/4,80 por la buena y $ 3,50\/4 por la inferior.<\/p>\n<p>Fuente: La Naci\u00f3n, Suplemento Campo, 25 de febrero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Se obtuvo hasta $ 11,20 por novillos livianos. Por Esteban D\u00b4Apice. Los operadores de compra que act\u00faan en el Mercado de Liniers debieron pagar esta semana precios que eran impensados al comienzo de febrero, y mucho menos en la primera quincena del a\u00f1o, cuando el ingreso de hacienda -posiblemente retenida en diciembre por razones fiscales- influy\u00f3 negativamente. Con las ruedas de lunes y martes anuladas por el feriado de Carnaval, la oferta sum\u00f3 entre el mi\u00e9rcoles y anteayer s\u00f3lo 10.545 cabezas, stock muy inferior al m\u00ednimo necesario para distribuir en los miles de despachos minoristas de la Capital Federal y del Gran Buenos Aires, donde llegan los repartos de los frigor\u00edficos consumeros y de los denominados abastecedores. En consecuencia, sin tener certeza alguna de si podr\u00edan trasladarse al valor de los distintos cortes las diferencias a la suba impuestas por la t\u00f3nica de firmeza de la plaza, los compradores compitieron para cumplir sus compromisos m\u00ednimos, pr\u00e1cticamente sin topes preestablecidos, seg\u00fan se dijo a La Nacion. Pero si bien los guarismos nominales parecen alentadores para quienes siguen apostando por la ganader\u00eda, la estad\u00edstica demuestra que en moneda constante el balance no es siempre positivo. La reflexi\u00f3n surge, por ejemplo, cuando se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1351,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suba ocasional de las cotizaciones. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/suba-ocasional-de-las-cotizaciones-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suba ocasional de las cotizaciones. | Proagro\" \/>\n<meta property=\"og:description\" content=\"Se obtuvo hasta $ 11,20 por novillos livianos. Por Esteban D\u00b4Apice. Los operadores de compra que act\u00faan en el Mercado de Liniers debieron pagar esta semana precios que eran impensados al comienzo de febrero, y mucho menos en la primera quincena del a\u00f1o, cuando el ingreso de hacienda -posiblemente retenida en diciembre por razones fiscales- influy\u00f3 negativamente. Con las ruedas de lunes y martes anuladas por el feriado de Carnaval, la oferta sum\u00f3 entre el mi\u00e9rcoles y anteayer s\u00f3lo 10.545 cabezas, stock muy inferior al m\u00ednimo necesario para distribuir en los miles de despachos minoristas de la Capital Federal y del Gran Buenos Aires, donde llegan los repartos de los frigor\u00edficos consumeros y de los denominados abastecedores. En consecuencia, sin tener certeza alguna de si podr\u00edan trasladarse al valor de los distintos cortes las diferencias a la suba impuestas por la t\u00f3nica de firmeza de la plaza, los compradores compitieron para cumplir sus compromisos m\u00ednimos, pr\u00e1cticamente sin topes preestablecidos, seg\u00fan se dijo a La Nacion. Pero si bien los guarismos nominales parecen alentadores para quienes siguen apostando por la ganader\u00eda, la estad\u00edstica demuestra que en moneda constante el balance no es siempre positivo. La reflexi\u00f3n surge, por ejemplo, cuando se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-28T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_c16l4fg7l__Mercado-de-Liniers-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"Suba ocasional de las cotizaciones.\",\"datePublished\":\"2012-02-28T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/\"},\"wordCount\":711,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_c16l4fg7l__Mercado-de-Liniers-6.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/\",\"name\":\"Suba ocasional de las cotizaciones. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_c16l4fg7l__Mercado-de-Liniers-6.jpg\",\"datePublished\":\"2012-02-28T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_c16l4fg7l__Mercado-de-Liniers-6.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_c16l4fg7l__Mercado-de-Liniers-6.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/suba-ocasional-de-las-cotizaciones-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suba ocasional de las cotizaciones.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suba ocasional de las cotizaciones. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/suba-ocasional-de-las-cotizaciones-2\/","og_locale":"en_US","og_type":"article","og_title":"Suba ocasional de las cotizaciones. | Proagro","og_description":"Se obtuvo hasta $ 11,20 por novillos livianos. Por Esteban D\u00b4Apice. Los operadores de compra que act\u00faan en el Mercado de Liniers debieron pagar esta semana precios que eran impensados al comienzo de febrero, y mucho menos en la primera quincena del a\u00f1o, cuando el ingreso de hacienda -posiblemente retenida en diciembre por razones fiscales- influy\u00f3 negativamente. Con las ruedas de lunes y martes anuladas por el feriado de Carnaval, la oferta sum\u00f3 entre el mi\u00e9rcoles y anteayer s\u00f3lo 10.545 cabezas, stock muy inferior al m\u00ednimo necesario para distribuir en los miles de despachos minoristas de la Capital Federal y del Gran Buenos Aires, donde llegan los repartos de los frigor\u00edficos consumeros y de los denominados abastecedores. En consecuencia, sin tener certeza alguna de si podr\u00edan trasladarse al valor de los distintos cortes las diferencias a la suba impuestas por la t\u00f3nica de firmeza de la plaza, los compradores compitieron para cumplir sus compromisos m\u00ednimos, pr\u00e1cticamente sin topes preestablecidos, seg\u00fan se dijo a La Nacion. Pero si bien los guarismos nominales parecen alentadores para quienes siguen apostando por la ganader\u00eda, la estad\u00edstica demuestra que en moneda constante el balance no es siempre positivo. La reflexi\u00f3n surge, por ejemplo, cuando se [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-02-28T00:00:01+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_c16l4fg7l__Mercado-de-Liniers-6.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"Suba ocasional de las cotizaciones.","datePublished":"2012-02-28T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/"},"wordCount":711,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_c16l4fg7l__Mercado-de-Liniers-6.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/","url":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/","name":"Suba ocasional de las cotizaciones. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_c16l4fg7l__Mercado-de-Liniers-6.jpg","datePublished":"2012-02-28T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_c16l4fg7l__Mercado-de-Liniers-6.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_c16l4fg7l__Mercado-de-Liniers-6.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/suba-ocasional-de-las-cotizaciones-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Suba ocasional de las cotizaciones."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4829"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1351"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}