{"id":4807,"date":"2012-02-16T00:00:01","date_gmt":"2012-02-16T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/"},"modified":"2012-02-16T00:00:01","modified_gmt":"2012-02-16T00:00:01","slug":"senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/","title":{"rendered":"SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>El Servicio Nacional de Sanidad y Calidad Agroalimentaria (SENASA) cre\u00f3 un subregistro de exportaciones ganaderas, cumpliendo condiciones exigidas por la Uni\u00f3n Europea (UE).<\/p>\n<p>Las autoridades argentinas deben presentarse a la UE, para satisfacer los requisitos previstos en los reglamentos mencionados. As\u00ed resulta necesario tener un registro espec\u00edfico para este tipo de establecimientos pecuarios.<\/p>\n<p>La Uni\u00f3n Europea ha adoptado ciertas condiciones para la gesti\u00f3n de un contingente arancelario de importaci\u00f3n de carne vacuna de calidad superior, &#8220;mediante dicho reglamento&#8221;, dice el documento.<\/p>\n<p>Tambi\u00e9n agreg\u00f3 que ese &#8220;mercado ha abierto un contingente arancelario aut\u00f3nomo para la importaci\u00f3n mencionada precedentemente, normado mediante el Reglamento (CE) N\u00ba 617\/2009&#8221;.<\/p>\n<p>&#8220;Dichos establecimientos deber\u00e1n contar con una verificaci\u00f3n de procedimientos e inspecciones peri\u00f3dicas en el \u00e1mbito de las oficinas locales del SENASA, de acuerdo con las instrucciones espec\u00edficas emanadas por las \u00e1reas de competencia fiscalizadoras del contingente detallado&#8221;, aclar\u00f3.<\/p>\n<p>Fuente: Carnetec, 13 de febrero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>El Servicio Nacional de Sanidad y Calidad Agroalimentaria (SENASA) cre\u00f3 un subregistro de exportaciones ganaderas, cumpliendo condiciones exigidas por la Uni\u00f3n Europea (UE). Las autoridades argentinas deben presentarse a la UE, para satisfacer los requisitos previstos en los reglamentos mencionados. As\u00ed resulta necesario tener un registro espec\u00edfico para este tipo de establecimientos pecuarios. La Uni\u00f3n Europea ha adoptado ciertas condiciones para la gesti\u00f3n de un contingente arancelario de importaci\u00f3n de carne vacuna de calidad superior, &#8220;mediante dicho reglamento&#8221;, dice el documento. Tambi\u00e9n agreg\u00f3 que ese &#8220;mercado ha abierto un contingente arancelario aut\u00f3nomo para la importaci\u00f3n mencionada precedentemente, normado mediante el Reglamento (CE) N\u00ba 617\/2009&#8221;. &#8220;Dichos establecimientos deber\u00e1n contar con una verificaci\u00f3n de procedimientos e inspecciones peri\u00f3dicas en el \u00e1mbito de las oficinas locales del SENASA, de acuerdo con las instrucciones espec\u00edficas emanadas por las \u00e1reas de competencia fiscalizadoras del contingente detallado&#8221;, aclar\u00f3. Fuente: Carnetec, 13 de febrero.<\/p>\n","protected":false},"author":2,"featured_media":1330,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea. | Proagro\" \/>\n<meta property=\"og:description\" content=\"El Servicio Nacional de Sanidad y Calidad Agroalimentaria (SENASA) cre\u00f3 un subregistro de exportaciones ganaderas, cumpliendo condiciones exigidas por la Uni\u00f3n Europea (UE). Las autoridades argentinas deben presentarse a la UE, para satisfacer los requisitos previstos en los reglamentos mencionados. As\u00ed resulta necesario tener un registro espec\u00edfico para este tipo de establecimientos pecuarios. La Uni\u00f3n Europea ha adoptado ciertas condiciones para la gesti\u00f3n de un contingente arancelario de importaci\u00f3n de carne vacuna de calidad superior, &#8220;mediante dicho reglamento&#8221;, dice el documento. Tambi\u00e9n agreg\u00f3 que ese &#8220;mercado ha abierto un contingente arancelario aut\u00f3nomo para la importaci\u00f3n mencionada precedentemente, normado mediante el Reglamento (CE) N\u00ba 617\/2009&#8221;. &#8220;Dichos establecimientos deber\u00e1n contar con una verificaci\u00f3n de procedimientos e inspecciones peri\u00f3dicas en el \u00e1mbito de las oficinas locales del SENASA, de acuerdo con las instrucciones espec\u00edficas emanadas por las \u00e1reas de competencia fiscalizadoras del contingente detallado&#8221;, aclar\u00f3. Fuente: Carnetec, 13 de febrero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-16T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_obthm5j65__Frigor\u00edfico-cortes-premiados.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea.\",\"datePublished\":\"2012-02-16T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/\"},\"wordCount\":167,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_obthm5j65__Frigor\u00edfico-cortes-premiados.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/\",\"name\":\"SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_obthm5j65__Frigor\u00edfico-cortes-premiados.jpg\",\"datePublished\":\"2012-02-16T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_obthm5j65__Frigor\u00edfico-cortes-premiados.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_obthm5j65__Frigor\u00edfico-cortes-premiados.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/","og_locale":"en_US","og_type":"article","og_title":"SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea. | Proagro","og_description":"El Servicio Nacional de Sanidad y Calidad Agroalimentaria (SENASA) cre\u00f3 un subregistro de exportaciones ganaderas, cumpliendo condiciones exigidas por la Uni\u00f3n Europea (UE). Las autoridades argentinas deben presentarse a la UE, para satisfacer los requisitos previstos en los reglamentos mencionados. As\u00ed resulta necesario tener un registro espec\u00edfico para este tipo de establecimientos pecuarios. La Uni\u00f3n Europea ha adoptado ciertas condiciones para la gesti\u00f3n de un contingente arancelario de importaci\u00f3n de carne vacuna de calidad superior, &#8220;mediante dicho reglamento&#8221;, dice el documento. Tambi\u00e9n agreg\u00f3 que ese &#8220;mercado ha abierto un contingente arancelario aut\u00f3nomo para la importaci\u00f3n mencionada precedentemente, normado mediante el Reglamento (CE) N\u00ba 617\/2009&#8221;. &#8220;Dichos establecimientos deber\u00e1n contar con una verificaci\u00f3n de procedimientos e inspecciones peri\u00f3dicas en el \u00e1mbito de las oficinas locales del SENASA, de acuerdo con las instrucciones espec\u00edficas emanadas por las \u00e1reas de competencia fiscalizadoras del contingente detallado&#8221;, aclar\u00f3. Fuente: Carnetec, 13 de febrero.","og_url":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-02-16T00:00:01+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_obthm5j65__Frigor\u00edfico-cortes-premiados.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea.","datePublished":"2012-02-16T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/"},"wordCount":167,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_obthm5j65__Frigor\u00edfico-cortes-premiados.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/","url":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/","name":"SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_obthm5j65__Frigor\u00edfico-cortes-premiados.jpg","datePublished":"2012-02-16T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_obthm5j65__Frigor\u00edfico-cortes-premiados.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_obthm5j65__Frigor\u00edfico-cortes-premiados.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/senasa-crea-subregistro-para-exportaciones-ganaderas-a-union-europea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"SENASA crea subregistro para exportaciones ganaderas a Uni\u00f3n Europea."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4807"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1330"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}