{"id":4771,"date":"2012-02-08T00:00:01","date_gmt":"2012-02-08T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/"},"modified":"2012-02-08T00:00:01","modified_gmt":"2012-02-08T00:00:01","slug":"argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/","title":{"rendered":"Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>Moreno distribuy\u00f3 apenas un 40 por ciento del cupo entre los frigor\u00edficos cuando restan cuatro meses para la finalizaci\u00f3n del ciclo comercial<\/p>\n<p>En el sector frigor\u00edfico ya todos lo dan como un hecho: Argentina incumplir\u00e1 por cuarto a\u00f1o consecutivo la cuota Hilton 2012 como consecuencia de la an\u00f3mala distribuci\u00f3n del cupo exportador por parte del secretario de Comercio Interior Guillermo Moreno.<\/p>\n<p>Es que, seg\u00fan pudo averiguar La Pol\u00edtica Online, a m\u00e1s de seis meses del inicio del actual ciclo comercial el funcionario apenas distribuy\u00f3 un 40 por ciento del total del cupo de cortes de alta calidad asignado por la Uni\u00f3n Europea (UE-27).<\/p>\n<p>Es decir, de las 30.000 toneladas dispuestas por la cuota Hilton de este a\u00f1o, a la fecha menos de 12.000 toneladas fueron entregadas a los frigor\u00edficos exportadores cuando restan apenas 4 meses y medio para finalizar el ciclo 2011\/12.<\/p>\n<p>\u0093Lo m\u00e1s pr\u00e1ctico hubiera sido que se distribuya de entrada (en agosto pasado) para que las empresas puedan ir regulando sus ofertas y as\u00ed captar los mejores precios del mercado\u0094, coment\u00f3 a LPO el consultor ganadero V\u00edctor Tonelli.<\/p>\n<p>\u0093Esta situaci\u00f3n no le suma ni al productor, ni a las empresas, ni al pa\u00eds\u0094, advirti\u00f3 Tonelli, y luego agreg\u00f3 que \u0093ahora lo que va a ocurrir es que sobre el final del ciclo va a haber un sobreoferta que lo \u00fanico que producir\u00e1 son menores precios\u0094.<\/p>\n<p>En tanto, fuentes del sector frigor\u00edfico estiman que, de continuar este ritmo, unas 10.000 toneladas de la cuota quedar\u00edan sin exportarse en 2012, lo que significa una merma de ingresos para el pa\u00eds del orden de los 25 a 30 millones de d\u00f3lares.<\/p>\n<p>\u0093Es incre\u00edble que estemos atravesando una circunstancia de esta caracter\u00edstica en un contexto de escasez de divisas y de reducci\u00f3n de importaciones\u0094, se\u00f1al\u00f3 un directivo de un frigor\u00edfico que prefiri\u00f3 no dar su nombre por temor a represalias oficiales.<\/p>\n<p>La misma fuente cont\u00f3 que las autoridades de los frigor\u00edficos m\u00e1s importantes del pa\u00eds intentaron convencer a Moreno de que garantice la entrega de 2500 toneladas mensuales (aunque, ya qued\u00f3 a la vista, el pedido no obtuvo buenos resultados).<\/p>\n<p>Asimismo, actualmente el valor de la tonelada Hilton (que representa un negocio de 450 millones de d\u00f3lares) se ubica entre 15.000 y 15.500 d\u00f3lares, un precio que contin\u00faa siendo atractivo a pesar de que en octubre pasado lleg\u00f3 a tocar los 19.500 d\u00f3lares.<\/p>\n<p>A diferencia de las anteriores campa\u00f1as, este a\u00f1o la encargada de administrar la cuota Hilton es la Unidad de Coordinaci\u00f3n y Evaluaci\u00f3n de Subsidios al Consumo Interno (Ucesci), cuyo titular es Lisandro Tanzi, un hombre del ri\u00f1\u00f3n de Moreno.<\/p>\n<p>Por su parte, las exportaciones argentinas de cortes c\u00e1rnicos bovinos (no Hilton) en 2011 fueron de 240.00 toneladas, una cifra que coloca al pa\u00eds en el octavo lugar de exportadores mundiales por debajo de socios minoritarios del Mercosur como Paraguay.<\/p>\n<p>Dej\u00e1 vu<br \/>Pero esta situaci\u00f3n de no es nueva. Lo mismo ocurri\u00f3 durante los ciclos 2008\/09, 2009\/10 y 2010\/11 y el resultado fue que en esos a\u00f1os la Argentina no logr\u00f3 cumplir con el 100 por ciento de la cuota Hilton de 28.000 toneladas anuales en ese entonces.<\/p>\n<p>El peor de estos a\u00f1os fue indudablemente el 2009\/10 cuando las exportaciones de cortes Hilton fueron de apenas 12.865 toneladas, una cifra que represent\u00f3 un 46 por ciento del total del cupo, mientras que el a\u00f1o pasado se lleg\u00f3 a exportar un 84 por ciento. <br \/>Pero lo m\u00e1s grave que se ve en el horizonte es el cr\u00edtico panorama que prev\u00e9n algunos especialistas del sector de cara al futuro de las exportaciones Hilton, debido a la fenomenal ca\u00edda del stock ganadero registrada durante los a\u00f1os 2006 y 2009.<\/p>\n<p>Es que, al parecer, durante los pr\u00f3ximos ciclos comerciales, la Argentina tambi\u00e9n se ver\u00eda obligada a incumplir la Hilton dado que para enviar las 30.000 toneladas se necesita una cierta cantidad de novillos pesados que hoy d\u00eda el mercado local no ofrece. <\/p>\n<p>Fuente: LPO, 8 de febrero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Moreno distribuy\u00f3 apenas un 40 por ciento del cupo entre los frigor\u00edficos cuando restan cuatro meses para la finalizaci\u00f3n del ciclo comercial En el sector frigor\u00edfico ya todos lo dan como un hecho: Argentina incumplir\u00e1 por cuarto a\u00f1o consecutivo la cuota Hilton 2012 como consecuencia de la an\u00f3mala distribuci\u00f3n del cupo exportador por parte del secretario de Comercio Interior Guillermo Moreno. Es que, seg\u00fan pudo averiguar La Pol\u00edtica Online, a m\u00e1s de seis meses del inicio del actual ciclo comercial el funcionario apenas distribuy\u00f3 un 40 por ciento del total del cupo de cortes de alta calidad asignado por la Uni\u00f3n Europea (UE-27). Es decir, de las 30.000 toneladas dispuestas por la cuota Hilton de este a\u00f1o, a la fecha menos de 12.000 toneladas fueron entregadas a los frigor\u00edficos exportadores cuando restan apenas 4 meses y medio para finalizar el ciclo 2011\/12. \u0093Lo m\u00e1s pr\u00e1ctico hubiera sido que se distribuya de entrada (en agosto pasado) para que las empresas puedan ir regulando sus ofertas y as\u00ed captar los mejores precios del mercado\u0094, coment\u00f3 a LPO el consultor ganadero V\u00edctor Tonelli. \u0093Esta situaci\u00f3n no le suma ni al productor, ni a las empresas, ni al pa\u00eds\u0094, advirti\u00f3 Tonelli, y luego agreg\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1294,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo. | Proagro\" \/>\n<meta property=\"og:description\" content=\"Moreno distribuy\u00f3 apenas un 40 por ciento del cupo entre los frigor\u00edficos cuando restan cuatro meses para la finalizaci\u00f3n del ciclo comercial En el sector frigor\u00edfico ya todos lo dan como un hecho: Argentina incumplir\u00e1 por cuarto a\u00f1o consecutivo la cuota Hilton 2012 como consecuencia de la an\u00f3mala distribuci\u00f3n del cupo exportador por parte del secretario de Comercio Interior Guillermo Moreno. Es que, seg\u00fan pudo averiguar La Pol\u00edtica Online, a m\u00e1s de seis meses del inicio del actual ciclo comercial el funcionario apenas distribuy\u00f3 un 40 por ciento del total del cupo de cortes de alta calidad asignado por la Uni\u00f3n Europea (UE-27). Es decir, de las 30.000 toneladas dispuestas por la cuota Hilton de este a\u00f1o, a la fecha menos de 12.000 toneladas fueron entregadas a los frigor\u00edficos exportadores cuando restan apenas 4 meses y medio para finalizar el ciclo 2011\/12. \u0093Lo m\u00e1s pr\u00e1ctico hubiera sido que se distribuya de entrada (en agosto pasado) para que las empresas puedan ir regulando sus ofertas y as\u00ed captar los mejores precios del mercado\u0094, coment\u00f3 a LPO el consultor ganadero V\u00edctor Tonelli. \u0093Esta situaci\u00f3n no le suma ni al productor, ni a las empresas, ni al pa\u00eds\u0094, advirti\u00f3 Tonelli, y luego agreg\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-08T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_bk0dmbtf5__Frigor\u00edfico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo.\",\"datePublished\":\"2012-02-08T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/\"},\"wordCount\":687,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_bk0dmbtf5__Frigor\u00edfico.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/\",\"name\":\"Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_bk0dmbtf5__Frigor\u00edfico.jpg\",\"datePublished\":\"2012-02-08T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_bk0dmbtf5__Frigor\u00edfico.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_bk0dmbtf5__Frigor\u00edfico.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/","og_locale":"en_US","og_type":"article","og_title":"Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo. | Proagro","og_description":"Moreno distribuy\u00f3 apenas un 40 por ciento del cupo entre los frigor\u00edficos cuando restan cuatro meses para la finalizaci\u00f3n del ciclo comercial En el sector frigor\u00edfico ya todos lo dan como un hecho: Argentina incumplir\u00e1 por cuarto a\u00f1o consecutivo la cuota Hilton 2012 como consecuencia de la an\u00f3mala distribuci\u00f3n del cupo exportador por parte del secretario de Comercio Interior Guillermo Moreno. Es que, seg\u00fan pudo averiguar La Pol\u00edtica Online, a m\u00e1s de seis meses del inicio del actual ciclo comercial el funcionario apenas distribuy\u00f3 un 40 por ciento del total del cupo de cortes de alta calidad asignado por la Uni\u00f3n Europea (UE-27). Es decir, de las 30.000 toneladas dispuestas por la cuota Hilton de este a\u00f1o, a la fecha menos de 12.000 toneladas fueron entregadas a los frigor\u00edficos exportadores cuando restan apenas 4 meses y medio para finalizar el ciclo 2011\/12. \u0093Lo m\u00e1s pr\u00e1ctico hubiera sido que se distribuya de entrada (en agosto pasado) para que las empresas puedan ir regulando sus ofertas y as\u00ed captar los mejores precios del mercado\u0094, coment\u00f3 a LPO el consultor ganadero V\u00edctor Tonelli. \u0093Esta situaci\u00f3n no le suma ni al productor, ni a las empresas, ni al pa\u00eds\u0094, advirti\u00f3 Tonelli, y luego agreg\u00f3 [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-02-08T00:00:01+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_bk0dmbtf5__Frigor\u00edfico.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo.","datePublished":"2012-02-08T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/"},"wordCount":687,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_bk0dmbtf5__Frigor\u00edfico.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/","url":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/","name":"Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_bk0dmbtf5__Frigor\u00edfico.jpg","datePublished":"2012-02-08T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_bk0dmbtf5__Frigor\u00edfico.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_bk0dmbtf5__Frigor\u00edfico.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/argentina-se-encamina-a-incumplir-la-cuota-hilton-por-cuarto-ano-consecutivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Argentina se encamina a incumplir la cuota Hilton por cuarto a\u00f1o consecutivo."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4771"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1294"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}