{"id":4770,"date":"2012-02-08T00:00:01","date_gmt":"2012-02-08T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/"},"modified":"2012-02-08T00:00:01","modified_gmt":"2012-02-08T00:00:01","slug":"leve-mejora-del-valor-de-los-novillos","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/leve-mejora-del-valor-de-los-novillos\/","title":{"rendered":"Leve mejora del valor de los novillos."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>El \u00edndice de la categor\u00eda subi\u00f3 un 0,62 por ciento, al pasar de 8,364 a 8,416 pesos por kilo.<\/p>\n<p>La segunda rueda de ventas de la semana en el Mercado de Liniers se desarroll\u00f3 ayer con una oferta de 8259 cabezas, integrada en su mayor proporci\u00f3n por lotes con calidad y terminaci\u00f3n satisfactorias. Atento a ello, se impuso un ritmo \u00e1gil en las subastas y los precios ratificaron los registros satisfactorios de las jornadas precedentes, con valores destacados para los novillos y para las vaquillonas de feedlot medianas, muy disputadas por la demanda.<\/p>\n<p>En el caso particular de los novillos, con un total comercializado de 855 cabezas, prevaleci\u00f3 t\u00f3nica de invariable animaci\u00f3n y se lograron los siguientes registros destacados: $ 9,40 por livianos de 431, 442 y de 442 kg; $ 9,35 con 479 kg, y $ 9 por pesados de 506 y de 514 kg. El Indice Liniers, de $ 8,416, evidenci\u00f3 una mejora del 0,62% respecto del indicador del viernes, de 8,364 pesos.<\/p>\n<p>Los ganados del tipo consumo liviano constituyeron el 64,76% del total adjudicado. Entre los mejores valores se ubicaron los siguientes: en novillitos, $ 10,20 con 355 kilos; $ 10,04 con 362 kg; $ 9,70 con 371 kg, y $ 9,67 con 410 kg; en terneros, hasta $ 11,02 por livianos de 310 kg; $ 10,65 con 300 kg; $ 10,56 con 302 kg, y $ 10,50 por entrepesados de 325 kilos, y en vaquillonas, $ 9,50 por tres lotes que pesaron 356, 360 y 360 kg; $ 9,40 con 353 y con 365 kg; $ 9,27 con 364 kg, y $ 9,20 con 377 kg.<\/p>\n<p>Con sostenida gesti\u00f3n del sector de la industria, agilizada cuando se aceptaron plazos de pago extendidos, se negociaron los diversos tipos de vacas, sin alterar los promedios de anteayer. El precio m\u00e1ximo fue de $ 7,70 y correspondi\u00f3 a un lote liviano, de 445 kg, le siguieron $ 7,58 con 445 kg; $ 7,50 con 521 kg; $ 7,42 con 566 kg, y $ 7,10 por un corte de 652 kilos. El Indice General de Mercado de Liniers SA fue de $ 7,904, mientras que el peso promedio general de los 8186 vacunos negociados result\u00f3 de 401 kilos, con un total de 3.279.300 kg registrados en b\u00e1sculas.<\/p>\n<p>El Indice Novillo del Mercado de Liniers result\u00f3 de $ 8,416. En tanto que el precio promedio general de Mercados al D\u00eda fue de $ 8,420. El valor sugerido para arrendamientos qued\u00f3 en $ 8,725.<\/p>\n<p><span style=\"font-style: italic;\">Cotizaciones m\u00e1ximas<\/span><br \/>Novillos livianos, $ 9,40 por 3 lotes de 431 a 442 kg; novillos medianos, $ 9,35 por 19 animales con 479 kg; novillos pesados, $ 9 por 3 lotes de 506 a 514 kg; novillos muy pesados, $ 8,90 por 34 con 525 kg; novillitos, $ 10,20 por 15 con 355 kg; vaquillonas, $ 9,50 por 38 y 10 con 358 y 360 kg, respectivamente; terneros, $ 11,02 por 11 con 310 kg; vacas, $ 7,70 por 13 con 445 kg, y toros, $ 7,45 por 13 con 702 kg.<\/p>\n<p><span style=\"font-style: italic;\">Detalle de venta<\/span><br \/>Novillos 855; novillitos 2246; vaquillonas 793; vacas 881; conservas 979; terneros 2262, y toros 170. Quedaron 7 animales sin ser vendidos. Ventas de ayer en pesos por kilo vivo. Base 18 cabezas.<\/p>\n<p>Fuente: La Naci\u00f3n, 8 de febrero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>El \u00edndice de la categor\u00eda subi\u00f3 un 0,62 por ciento, al pasar de 8,364 a 8,416 pesos por kilo. La segunda rueda de ventas de la semana en el Mercado de Liniers se desarroll\u00f3 ayer con una oferta de 8259 cabezas, integrada en su mayor proporci\u00f3n por lotes con calidad y terminaci\u00f3n satisfactorias. Atento a ello, se impuso un ritmo \u00e1gil en las subastas y los precios ratificaron los registros satisfactorios de las jornadas precedentes, con valores destacados para los novillos y para las vaquillonas de feedlot medianas, muy disputadas por la demanda. En el caso particular de los novillos, con un total comercializado de 855 cabezas, prevaleci\u00f3 t\u00f3nica de invariable animaci\u00f3n y se lograron los siguientes registros destacados: $ 9,40 por livianos de 431, 442 y de 442 kg; $ 9,35 con 479 kg, y $ 9 por pesados de 506 y de 514 kg. El Indice Liniers, de $ 8,416, evidenci\u00f3 una mejora del 0,62% respecto del indicador del viernes, de 8,364 pesos. Los ganados del tipo consumo liviano constituyeron el 64,76% del total adjudicado. Entre los mejores valores se ubicaron los siguientes: en novillitos, $ 10,20 con 355 kilos; $ 10,04 con 362 kg; $ 9,70 con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1293,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leve mejora del valor de los novillos. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/leve-mejora-del-valor-de-los-novillos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leve mejora del valor de los novillos. | Proagro\" \/>\n<meta property=\"og:description\" content=\"El \u00edndice de la categor\u00eda subi\u00f3 un 0,62 por ciento, al pasar de 8,364 a 8,416 pesos por kilo. La segunda rueda de ventas de la semana en el Mercado de Liniers se desarroll\u00f3 ayer con una oferta de 8259 cabezas, integrada en su mayor proporci\u00f3n por lotes con calidad y terminaci\u00f3n satisfactorias. Atento a ello, se impuso un ritmo \u00e1gil en las subastas y los precios ratificaron los registros satisfactorios de las jornadas precedentes, con valores destacados para los novillos y para las vaquillonas de feedlot medianas, muy disputadas por la demanda. En el caso particular de los novillos, con un total comercializado de 855 cabezas, prevaleci\u00f3 t\u00f3nica de invariable animaci\u00f3n y se lograron los siguientes registros destacados: $ 9,40 por livianos de 431, 442 y de 442 kg; $ 9,35 con 479 kg, y $ 9 por pesados de 506 y de 514 kg. El Indice Liniers, de $ 8,416, evidenci\u00f3 una mejora del 0,62% respecto del indicador del viernes, de 8,364 pesos. Los ganados del tipo consumo liviano constituyeron el 64,76% del total adjudicado. Entre los mejores valores se ubicaron los siguientes: en novillitos, $ 10,20 con 355 kilos; $ 10,04 con 362 kg; $ 9,70 con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-08T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_4p4j4sjrz__Mercado-de-Liniers-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"Leve mejora del valor de los novillos.\",\"datePublished\":\"2012-02-08T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/\"},\"wordCount\":426,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_4p4j4sjrz__Mercado-de-Liniers-4.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/\",\"name\":\"Leve mejora del valor de los novillos. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_4p4j4sjrz__Mercado-de-Liniers-4.jpg\",\"datePublished\":\"2012-02-08T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_4p4j4sjrz__Mercado-de-Liniers-4.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_4p4j4sjrz__Mercado-de-Liniers-4.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/leve-mejora-del-valor-de-los-novillos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leve mejora del valor de los novillos.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leve mejora del valor de los novillos. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/leve-mejora-del-valor-de-los-novillos\/","og_locale":"en_US","og_type":"article","og_title":"Leve mejora del valor de los novillos. | Proagro","og_description":"El \u00edndice de la categor\u00eda subi\u00f3 un 0,62 por ciento, al pasar de 8,364 a 8,416 pesos por kilo. La segunda rueda de ventas de la semana en el Mercado de Liniers se desarroll\u00f3 ayer con una oferta de 8259 cabezas, integrada en su mayor proporci\u00f3n por lotes con calidad y terminaci\u00f3n satisfactorias. Atento a ello, se impuso un ritmo \u00e1gil en las subastas y los precios ratificaron los registros satisfactorios de las jornadas precedentes, con valores destacados para los novillos y para las vaquillonas de feedlot medianas, muy disputadas por la demanda. En el caso particular de los novillos, con un total comercializado de 855 cabezas, prevaleci\u00f3 t\u00f3nica de invariable animaci\u00f3n y se lograron los siguientes registros destacados: $ 9,40 por livianos de 431, 442 y de 442 kg; $ 9,35 con 479 kg, y $ 9 por pesados de 506 y de 514 kg. El Indice Liniers, de $ 8,416, evidenci\u00f3 una mejora del 0,62% respecto del indicador del viernes, de 8,364 pesos. Los ganados del tipo consumo liviano constituyeron el 64,76% del total adjudicado. Entre los mejores valores se ubicaron los siguientes: en novillitos, $ 10,20 con 355 kilos; $ 10,04 con 362 kg; $ 9,70 con [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-02-08T00:00:01+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_4p4j4sjrz__Mercado-de-Liniers-4.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"Leve mejora del valor de los novillos.","datePublished":"2012-02-08T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/"},"wordCount":426,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_4p4j4sjrz__Mercado-de-Liniers-4.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/","url":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/","name":"Leve mejora del valor de los novillos. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_4p4j4sjrz__Mercado-de-Liniers-4.jpg","datePublished":"2012-02-08T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_4p4j4sjrz__Mercado-de-Liniers-4.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_4p4j4sjrz__Mercado-de-Liniers-4.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/leve-mejora-del-valor-de-los-novillos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Leve mejora del valor de los novillos."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4770"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1293"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}