{"id":4760,"date":"2012-02-07T00:00:01","date_gmt":"2012-02-07T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/"},"modified":"2012-02-07T00:00:01","modified_gmt":"2012-02-07T00:00:01","slug":"rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/","title":{"rendered":"Rosgan arranca el primer remate de 2012 con buenas novedades."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>En un a\u00f1o que comenz\u00f3 con sequ\u00eda y con noticias ganaderas preocupantes por parte del sector exportador, el primer remate 2012 de Rosgan arranca con una oferta abundante: 22.290 cabezas. Esta buena oferta, donde por primera vez habr\u00e1 hacienda proveniente de R\u00edo Negro, aparece como una gran oportunidad para comenzar a completar corrales que est\u00e1n desabastecidos y tienen a la oferta de gordo bastante entonada. Por otro lado, este nuevo remate arranca en un momento donde el sector est\u00e1 a la espera de los valores que se van a pagar en este inicio de a\u00f1o.<\/p>\n<p>Respecto al contexto actual de la cadena de ganados y carnes el director Ejecutivo de Rosgan, Ra\u00fal Milano, analiza que \u0093la lenta recuperaci\u00f3n del stock ganadero, amenazado por lo que era un importante sequ\u00eda a comienzos de a\u00f1o aunque las lluvias de los \u00faltimos d\u00edas le cambi\u00f3 la cara a los productores, garantiza que seguir\u00e1 siendo un a\u00f1o sostenido. La desaparici\u00f3n de 10 millones de cabezas es el mayor reaseguro para un sector que despu\u00e9s de su debacle tiene garantizados varios a\u00f1os de buen precio, tal vez sin los m\u00e1ximos de 2010 y parte del 2011 pero lo suficientemente altos para saber que a\u00fan la inflaci\u00f3n no puede deteriorar una rentabilidad. La demanda de carne en el mercado interno pareciera estar cerca de su piso y seguramente se sostendr\u00e1 en kilos durante todo el 2012\u0094.<\/p>\n<p>La otra novedad de este Rosgan viene de la mano del primer lote de terneros y terneras proveniente de la provincia de R\u00edo Negro. Esto muestra el criterio federal de este mercado de gran conveniencia para los productores que encuentra en esta herramienta una forma de canalizar sus producciones. \u0093La distancia en un pa\u00eds tan extenso no debe ser un problema sino que debe convertirse en un desaf\u00edo para repoblar un interior tan apetecido por muchas naciones\u0094, agrega Milano.<\/p>\n<p><span style=\"font-style: italic;\">Toda la oferta<\/span><br \/>El \u00fanico mercado ganadero televisado de Argentina comienza esta edici\u00f3n el mi\u00e9rcoles de 13:30 a 20:00 hs y continuar\u00e1 el jueves de 10:00 a 12:30 y de 13:30 a 20:00 hs y el viernes de 10 hasta finalizar, siempre por la pantalla de Canal Rural.<\/p>\n<p>Se pondr\u00e1n a la venta los siguientes vol\u00famenes de estas categor\u00edas: terneros 5.678, terneras 2.713, terneros y terneras 3.265, novillos de invernada 2.384, novillitos de invernada 504, b\u00fafalos gordos 76, terneros y novillitos holando 1.622, vaquillonas de invernada 1.153,&nbsp; vaquillonas pre\u00f1adas 188, vaquillonas para cr\u00eda 345, vaquillonas para entorar 135, vientres holando 15, vacas gordas 126, vacas entoradas 14, vacas de invernada 663, vacas conserva 17, vacas con garant\u00eda de pre\u00f1ez 1.084, vacas con cr\u00eda al pie 2.190, toros para faena 51 y toros reproductores 25.<\/p>\n<p>Fuente: Rosgan.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>En un a\u00f1o que comenz\u00f3 con sequ\u00eda y con noticias ganaderas preocupantes por parte del sector exportador, el primer remate 2012 de Rosgan arranca con una oferta abundante: 22.290 cabezas. Esta buena oferta, donde por primera vez habr\u00e1 hacienda proveniente de R\u00edo Negro, aparece como una gran oportunidad para comenzar a completar corrales que est\u00e1n desabastecidos y tienen a la oferta de gordo bastante entonada. Por otro lado, este nuevo remate arranca en un momento donde el sector est\u00e1 a la espera de los valores que se van a pagar en este inicio de a\u00f1o. Respecto al contexto actual de la cadena de ganados y carnes el director Ejecutivo de Rosgan, Ra\u00fal Milano, analiza que \u0093la lenta recuperaci\u00f3n del stock ganadero, amenazado por lo que era un importante sequ\u00eda a comienzos de a\u00f1o aunque las lluvias de los \u00faltimos d\u00edas le cambi\u00f3 la cara a los productores, garantiza que seguir\u00e1 siendo un a\u00f1o sostenido. La desaparici\u00f3n de 10 millones de cabezas es el mayor reaseguro para un sector que despu\u00e9s de su debacle tiene garantizados varios a\u00f1os de buen precio, tal vez sin los m\u00e1ximos de 2010 y parte del 2011 pero lo suficientemente altos para saber que a\u00fan la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1284,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rosgan arranca el primer remate de 2012 con buenas novedades. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rosgan arranca el primer remate de 2012 con buenas novedades. | Proagro\" \/>\n<meta property=\"og:description\" content=\"En un a\u00f1o que comenz\u00f3 con sequ\u00eda y con noticias ganaderas preocupantes por parte del sector exportador, el primer remate 2012 de Rosgan arranca con una oferta abundante: 22.290 cabezas. Esta buena oferta, donde por primera vez habr\u00e1 hacienda proveniente de R\u00edo Negro, aparece como una gran oportunidad para comenzar a completar corrales que est\u00e1n desabastecidos y tienen a la oferta de gordo bastante entonada. Por otro lado, este nuevo remate arranca en un momento donde el sector est\u00e1 a la espera de los valores que se van a pagar en este inicio de a\u00f1o. Respecto al contexto actual de la cadena de ganados y carnes el director Ejecutivo de Rosgan, Ra\u00fal Milano, analiza que \u0093la lenta recuperaci\u00f3n del stock ganadero, amenazado por lo que era un importante sequ\u00eda a comienzos de a\u00f1o aunque las lluvias de los \u00faltimos d\u00edas le cambi\u00f3 la cara a los productores, garantiza que seguir\u00e1 siendo un a\u00f1o sostenido. La desaparici\u00f3n de 10 millones de cabezas es el mayor reaseguro para un sector que despu\u00e9s de su debacle tiene garantizados varios a\u00f1os de buen precio, tal vez sin los m\u00e1ximos de 2010 y parte del 2011 pero lo suficientemente altos para saber que a\u00fan la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-07T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_ur1euzhej__Rosgan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"Rosgan arranca el primer remate de 2012 con buenas novedades.\",\"datePublished\":\"2012-02-07T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/\"},\"wordCount\":453,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_ur1euzhej__Rosgan.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/\",\"name\":\"Rosgan arranca el primer remate de 2012 con buenas novedades. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_ur1euzhej__Rosgan.jpg\",\"datePublished\":\"2012-02-07T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_ur1euzhej__Rosgan.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_ur1euzhej__Rosgan.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rosgan arranca el primer remate de 2012 con buenas novedades.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rosgan arranca el primer remate de 2012 con buenas novedades. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/","og_locale":"en_US","og_type":"article","og_title":"Rosgan arranca el primer remate de 2012 con buenas novedades. | Proagro","og_description":"En un a\u00f1o que comenz\u00f3 con sequ\u00eda y con noticias ganaderas preocupantes por parte del sector exportador, el primer remate 2012 de Rosgan arranca con una oferta abundante: 22.290 cabezas. Esta buena oferta, donde por primera vez habr\u00e1 hacienda proveniente de R\u00edo Negro, aparece como una gran oportunidad para comenzar a completar corrales que est\u00e1n desabastecidos y tienen a la oferta de gordo bastante entonada. Por otro lado, este nuevo remate arranca en un momento donde el sector est\u00e1 a la espera de los valores que se van a pagar en este inicio de a\u00f1o. Respecto al contexto actual de la cadena de ganados y carnes el director Ejecutivo de Rosgan, Ra\u00fal Milano, analiza que \u0093la lenta recuperaci\u00f3n del stock ganadero, amenazado por lo que era un importante sequ\u00eda a comienzos de a\u00f1o aunque las lluvias de los \u00faltimos d\u00edas le cambi\u00f3 la cara a los productores, garantiza que seguir\u00e1 siendo un a\u00f1o sostenido. La desaparici\u00f3n de 10 millones de cabezas es el mayor reaseguro para un sector que despu\u00e9s de su debacle tiene garantizados varios a\u00f1os de buen precio, tal vez sin los m\u00e1ximos de 2010 y parte del 2011 pero lo suficientemente altos para saber que a\u00fan la [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-02-07T00:00:01+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_ur1euzhej__Rosgan.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"Rosgan arranca el primer remate de 2012 con buenas novedades.","datePublished":"2012-02-07T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/"},"wordCount":453,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_ur1euzhej__Rosgan.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/","url":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/","name":"Rosgan arranca el primer remate de 2012 con buenas novedades. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_ur1euzhej__Rosgan.jpg","datePublished":"2012-02-07T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_ur1euzhej__Rosgan.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_ur1euzhej__Rosgan.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/rosgan-arranca-el-primer-remate-de-2012-con-buenas-novedades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Rosgan arranca el primer remate de 2012 con buenas novedades."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4760"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1284"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}