{"id":4753,"date":"2012-02-06T00:00:01","date_gmt":"2012-02-06T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/"},"modified":"2012-02-06T00:00:01","modified_gmt":"2012-02-06T00:00:01","slug":"una-actividad-bien-posicionada","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/una-actividad-bien-posicionada\/","title":{"rendered":"Una actividad bien posicionada."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><span style=\"font-style: italic;\">Por Alejandro Sammartino.<\/span><\/p>\n<p>Generalizar sobre la situaci\u00f3n de la lecher\u00eda en tiempos tan poco estables puede ser complicado. Pero nada mejor que la reflexi\u00f3n de un tambero cordob\u00e9s que ya lleva varios a\u00f1os con su rodeo encerrado para entender los vientos de cambio que la intensificaci\u00f3n est\u00e1 generando en el negocio.<\/p>\n<p>Dec\u00eda este productor que ten\u00eda claro cu\u00e1les iban a ser los litros producidos por sus vacas y su ingreso, &#8220;no importa lo que me cueste, yo les brindo una dieta estable en cantidad y calidad por lo que las variaciones en las respuestas productivas son m\u00ednimas&#8221;, afirmaba. Es la l\u00f3gica de maximizar ingresos por sobre minimizar costos. Pero la previsi\u00f3n de los ingresos que aseguraba su modelo se contrastaba seg\u00fan \u00e9l, con la incertidumbre en los costos entre los cuales la alimentaci\u00f3n est\u00e1 condicionada por los rendimientos de los cultivos que se destinan a reservas forrajeras y a grano. Y las diferencias pueden ser notables seg\u00fan como acompa\u00f1e por ejemplo, el clima.<\/p>\n<p>Como la sequ\u00eda peg\u00f3 fuerte, eso har\u00e1 que los n\u00fameros est\u00e9n m\u00e1s que ajustados si no hay una mejora en el precio de la leche. Pero la intensificaci\u00f3n no es para tibios. Prueba de ello es la contundente demostraci\u00f3n de los tamberos que, a\u00fan con un precio estancado, lograron un crecimiento de la producci\u00f3n de m\u00e1s del 13% en relaci\u00f3n al a\u00f1o 2010. Estos datos del Centro de Industria Lechera (CIL), marcan un nuevo r\u00e9cord de producci\u00f3n, que nos ubica por encima de los 11.000 millones de litros\/a\u00f1o.<\/p>\n<p>Y parte de la explicaci\u00f3n se encuentra a que, frente al alza de los costos, los productores est\u00e1n lanzados a sacarle el mayor provecho a cada vaca de la mano de los concentrados. No olvidemos que aunque la excelente relaci\u00f3n del precio de la leche con el ma\u00edz se redujo, a\u00fan se puede comprar dos kg de ma\u00edz por cada litro de leche.<\/p>\n<p>\u00bfC\u00f3mo termina la pel\u00edcula? A diferencia de ejercicios anteriores, los n\u00fameros de las actividades agr\u00edcolas no deslumbran ni por lo rentables ni por sus expectativas. No parece tener tan mala la foto la lecher\u00eda despu\u00e9s de todo. Otro es el cantar cuando se miran los niveles de inversi\u00f3n que se est\u00e1n realizando en los tambos en el camino de la intensificaci\u00f3n y que plantean la necesidad de encontrar nuevas formas de analizar el negocio, ante el aumento de los riesgos.<\/p>\n<p>Por supuesto que la lecher\u00eda no escapa del desasosiego que provoca el escenario inflacionario y de retraso cambiario que carcome la competitividad de la econom\u00eda argentina, aunque pareciera que los ruidos estar\u00edan m\u00e1s centrados en lo que ocurra dentro de las propias fronteras. Y en este sentido, la mayor\u00eda de los productores sabe que las medidas de mayor impacto se encuentran en lo que puedan hacer tranqueras adentro, algo que confirmaron varios estudios.<\/p>\n<p>Aunque no le sobra nada, la lecher\u00eda se encuentra mejor posicionada ante la incertidumbre que genera el escenario mundial. La falta de reglas claras, la mejora en la capacidad exportadora de las pymes y el mayor riesgo que enfrentan los tambos por la mayor intensificaci\u00f3n, parecen ser los mayores desaf\u00edos hacia el futuro.<\/p>\n<p><span style=\"font-style: italic;\">El autor es ingeniero agr\u00f3nomo y director de la revista Infortambo .<\/span><\/p>\n<p>Fuente: La Naci\u00f3n, Suplemento Campo, 4 de febrero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Por Alejandro Sammartino. Generalizar sobre la situaci\u00f3n de la lecher\u00eda en tiempos tan poco estables puede ser complicado. Pero nada mejor que la reflexi\u00f3n de un tambero cordob\u00e9s que ya lleva varios a\u00f1os con su rodeo encerrado para entender los vientos de cambio que la intensificaci\u00f3n est\u00e1 generando en el negocio. Dec\u00eda este productor que ten\u00eda claro cu\u00e1les iban a ser los litros producidos por sus vacas y su ingreso, &#8220;no importa lo que me cueste, yo les brindo una dieta estable en cantidad y calidad por lo que las variaciones en las respuestas productivas son m\u00ednimas&#8221;, afirmaba. Es la l\u00f3gica de maximizar ingresos por sobre minimizar costos. Pero la previsi\u00f3n de los ingresos que aseguraba su modelo se contrastaba seg\u00fan \u00e9l, con la incertidumbre en los costos entre los cuales la alimentaci\u00f3n est\u00e1 condicionada por los rendimientos de los cultivos que se destinan a reservas forrajeras y a grano. Y las diferencias pueden ser notables seg\u00fan como acompa\u00f1e por ejemplo, el clima. Como la sequ\u00eda peg\u00f3 fuerte, eso har\u00e1 que los n\u00fameros est\u00e9n m\u00e1s que ajustados si no hay una mejora en el precio de la leche. Pero la intensificaci\u00f3n no es para tibios. Prueba de ello es la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1277,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una actividad bien posicionada. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/una-actividad-bien-posicionada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una actividad bien posicionada. | Proagro\" \/>\n<meta property=\"og:description\" content=\"Por Alejandro Sammartino. Generalizar sobre la situaci\u00f3n de la lecher\u00eda en tiempos tan poco estables puede ser complicado. Pero nada mejor que la reflexi\u00f3n de un tambero cordob\u00e9s que ya lleva varios a\u00f1os con su rodeo encerrado para entender los vientos de cambio que la intensificaci\u00f3n est\u00e1 generando en el negocio. Dec\u00eda este productor que ten\u00eda claro cu\u00e1les iban a ser los litros producidos por sus vacas y su ingreso, &#8220;no importa lo que me cueste, yo les brindo una dieta estable en cantidad y calidad por lo que las variaciones en las respuestas productivas son m\u00ednimas&#8221;, afirmaba. Es la l\u00f3gica de maximizar ingresos por sobre minimizar costos. Pero la previsi\u00f3n de los ingresos que aseguraba su modelo se contrastaba seg\u00fan \u00e9l, con la incertidumbre en los costos entre los cuales la alimentaci\u00f3n est\u00e1 condicionada por los rendimientos de los cultivos que se destinan a reservas forrajeras y a grano. Y las diferencias pueden ser notables seg\u00fan como acompa\u00f1e por ejemplo, el clima. Como la sequ\u00eda peg\u00f3 fuerte, eso har\u00e1 que los n\u00fameros est\u00e9n m\u00e1s que ajustados si no hay una mejora en el precio de la leche. Pero la intensificaci\u00f3n no es para tibios. Prueba de ello es la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-06T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w69lw0g4e__Lecheras-14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"Una actividad bien posicionada.\",\"datePublished\":\"2012-02-06T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/\"},\"wordCount\":595,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_w69lw0g4e__Lecheras-14.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/\",\"name\":\"Una actividad bien posicionada. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_w69lw0g4e__Lecheras-14.jpg\",\"datePublished\":\"2012-02-06T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_w69lw0g4e__Lecheras-14.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_w69lw0g4e__Lecheras-14.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/una-actividad-bien-posicionada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una actividad bien posicionada.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una actividad bien posicionada. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/una-actividad-bien-posicionada\/","og_locale":"en_US","og_type":"article","og_title":"Una actividad bien posicionada. | Proagro","og_description":"Por Alejandro Sammartino. Generalizar sobre la situaci\u00f3n de la lecher\u00eda en tiempos tan poco estables puede ser complicado. Pero nada mejor que la reflexi\u00f3n de un tambero cordob\u00e9s que ya lleva varios a\u00f1os con su rodeo encerrado para entender los vientos de cambio que la intensificaci\u00f3n est\u00e1 generando en el negocio. Dec\u00eda este productor que ten\u00eda claro cu\u00e1les iban a ser los litros producidos por sus vacas y su ingreso, &#8220;no importa lo que me cueste, yo les brindo una dieta estable en cantidad y calidad por lo que las variaciones en las respuestas productivas son m\u00ednimas&#8221;, afirmaba. Es la l\u00f3gica de maximizar ingresos por sobre minimizar costos. Pero la previsi\u00f3n de los ingresos que aseguraba su modelo se contrastaba seg\u00fan \u00e9l, con la incertidumbre en los costos entre los cuales la alimentaci\u00f3n est\u00e1 condicionada por los rendimientos de los cultivos que se destinan a reservas forrajeras y a grano. Y las diferencias pueden ser notables seg\u00fan como acompa\u00f1e por ejemplo, el clima. Como la sequ\u00eda peg\u00f3 fuerte, eso har\u00e1 que los n\u00fameros est\u00e9n m\u00e1s que ajustados si no hay una mejora en el precio de la leche. Pero la intensificaci\u00f3n no es para tibios. Prueba de ello es la [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-02-06T00:00:01+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w69lw0g4e__Lecheras-14.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"Una actividad bien posicionada.","datePublished":"2012-02-06T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/"},"wordCount":595,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w69lw0g4e__Lecheras-14.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/","url":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/","name":"Una actividad bien posicionada. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w69lw0g4e__Lecheras-14.jpg","datePublished":"2012-02-06T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w69lw0g4e__Lecheras-14.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w69lw0g4e__Lecheras-14.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/una-actividad-bien-posicionada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Una actividad bien posicionada."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4753"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1277"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}