{"id":4748,"date":"2012-02-02T00:00:01","date_gmt":"2012-02-02T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/"},"modified":"2012-02-02T00:00:01","modified_gmt":"2012-02-02T00:00:01","slug":"el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/","title":{"rendered":"El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>La industria porcina, que crece de manera sostenida de la mano del aumento del consumo, lidera los pedidos para obtener cr\u00e9ditos del Bicentenario. Seg\u00fan inform\u00f3 el Ministerio de Industria que comanda D\u00e9bora Giorgi, el sector ya obtuvo pr\u00e9stamos por m\u00e1s de $ 270 millones. De esta forma, m\u00e1s de la mitad de los desembolsos provendr\u00e1n de pr\u00e9stamos a tasa subsidiada, al 9,9 por ciento anual, fija en pesos y a cinco a\u00f1os de plazo.<\/p>\n<p>La ministra asegur\u00f3 que estos cr\u00e9ditos generar\u00e1n inversiones por $ 466 millones en cinco provincias y que esto permitir\u00e1 ampliar la producci\u00f3n.<\/p>\n<p>El sector porcino creci\u00f3 en el mercado interno de la mano del aumento del precio de la carne vacuna, proceso que acompa\u00f1\u00f3 con un salto en la calidad.<\/p>\n<p>Seg\u00fan datos de Industria, entre 2003 y 2010, la producci\u00f3n de carne porcina aument\u00f3 78 por ciento, y ya supera las 281.000 toneladas. En 2011 el sector faen\u00f3 cuatro millones de cabezas y planea incrementar ese volumen a 4,8 \u00f3 5 millones de cabezas en 2012.<\/p>\n<p>En ese mismo per\u00edodo, el consumo per c\u00e1pita pas\u00f3 de 5,33 kilos por habitante por a\u00f1o a los actuales 8,12 kilos, mostrando un incremento superior al 50 por ciento.<br \/>En paralelo, Ciccra, la c\u00e1mara de la industria de la carne vacuna, indic\u00f3 en su \u00faltimo informe que en promedio, en los primeros 11 meses de 2011, el consumo se ubic\u00f3 en 54,2 kilos por habitante por a\u00f1o, lo que signific\u00f3 una contracci\u00f3n de 5,8 por ciento anual y del 20,8 por ciento respecto de igual per\u00edodo de 2009.<\/p>\n<p>Contrariamente a la producci\u00f3n vacuna, el porcino es un sector concentrado. Los primeros 20 establecimientos porcinos son responsables de m\u00e1s del 80 por ciento de la faena y los primeros 10 acumulan el 65 por ciento.<\/p>\n<p>Los grandes jugadores son la familia Blaquier, due\u00f1a de Caba\u00f1a Argentina; Alejandro Quentin, de Pampa Capital, que compr\u00f3 en 2008 el frigor\u00edfico Campo Austral; y Paladini.<\/p>\n<p>Seg\u00fan el plan trazado por el Gobierno para el sector agroalimentario argentino, bautizado Plan Estrat\u00e9gico Agroalimentario, para 2020 el consumo de carne porcina alcanzar\u00e1 los 13 kilos por habitante por a\u00f1o y el pa\u00eds producir\u00e1 822.000 toneladas de carne porcina, de las que 255.000 ser\u00e1n para exportar.<\/p>\n<p>Las inversiones proyectadas por Industria se concentran en 20 proyectos (15 de producci\u00f3n de carne porcina y 5 de alimento balanceado) ubicados en Capital Federal, Buenos Aires, La Pampa. Santa Fe, C\u00f3rdoba y Santiago del Estero.<\/p>\n<p>Seg\u00fan la cartera, ?permitir\u00e1n crear m\u00e1s de 700 nuevos puestos de trabajo, sumar $ 21 millones anuales a las exportaciones del sector y sustituir importaciones por m\u00e1s de $ 100 millones al a\u00f1o?.<\/p>\n<p>Los mayores desembolsos corresponden a una firma de Villa Gobernador G\u00e1lvez, Santa Fe, que invertir\u00e1 $ 115 millones para un centro de producci\u00f3n porcina. Otra, de General Las Heras, est\u00e1 invirtiendo $ 93,4 millones en la construcci\u00f3n de una planta frigor\u00edfica para porcinos.<\/p>\n<p>Fuente: Agromeat, 2 de febrero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>La industria porcina, que crece de manera sostenida de la mano del aumento del consumo, lidera los pedidos para obtener cr\u00e9ditos del Bicentenario. Seg\u00fan inform\u00f3 el Ministerio de Industria que comanda D\u00e9bora Giorgi, el sector ya obtuvo pr\u00e9stamos por m\u00e1s de $ 270 millones. De esta forma, m\u00e1s de la mitad de los desembolsos provendr\u00e1n de pr\u00e9stamos a tasa subsidiada, al 9,9 por ciento anual, fija en pesos y a cinco a\u00f1os de plazo. La ministra asegur\u00f3 que estos cr\u00e9ditos generar\u00e1n inversiones por $ 466 millones en cinco provincias y que esto permitir\u00e1 ampliar la producci\u00f3n. El sector porcino creci\u00f3 en el mercado interno de la mano del aumento del precio de la carne vacuna, proceso que acompa\u00f1\u00f3 con un salto en la calidad. Seg\u00fan datos de Industria, entre 2003 y 2010, la producci\u00f3n de carne porcina aument\u00f3 78 por ciento, y ya supera las 281.000 toneladas. En 2011 el sector faen\u00f3 cuatro millones de cabezas y planea incrementar ese volumen a 4,8 \u00f3 5 millones de cabezas en 2012. En ese mismo per\u00edodo, el consumo per c\u00e1pita pas\u00f3 de 5,33 kilos por habitante por a\u00f1o a los actuales 8,12 kilos, mostrando un incremento superior al 50 por ciento.En paralelo, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1272,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda. | Proagro\" \/>\n<meta property=\"og:description\" content=\"La industria porcina, que crece de manera sostenida de la mano del aumento del consumo, lidera los pedidos para obtener cr\u00e9ditos del Bicentenario. Seg\u00fan inform\u00f3 el Ministerio de Industria que comanda D\u00e9bora Giorgi, el sector ya obtuvo pr\u00e9stamos por m\u00e1s de $ 270 millones. De esta forma, m\u00e1s de la mitad de los desembolsos provendr\u00e1n de pr\u00e9stamos a tasa subsidiada, al 9,9 por ciento anual, fija en pesos y a cinco a\u00f1os de plazo. La ministra asegur\u00f3 que estos cr\u00e9ditos generar\u00e1n inversiones por $ 466 millones en cinco provincias y que esto permitir\u00e1 ampliar la producci\u00f3n. El sector porcino creci\u00f3 en el mercado interno de la mano del aumento del precio de la carne vacuna, proceso que acompa\u00f1\u00f3 con un salto en la calidad. Seg\u00fan datos de Industria, entre 2003 y 2010, la producci\u00f3n de carne porcina aument\u00f3 78 por ciento, y ya supera las 281.000 toneladas. En 2011 el sector faen\u00f3 cuatro millones de cabezas y planea incrementar ese volumen a 4,8 \u00f3 5 millones de cabezas en 2012. En ese mismo per\u00edodo, el consumo per c\u00e1pita pas\u00f3 de 5,33 kilos por habitante por a\u00f1o a los actuales 8,12 kilos, mostrando un incremento superior al 50 por ciento.En paralelo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-02T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_8mumddygw__Porcinos-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda.\",\"datePublished\":\"2012-02-02T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/\"},\"wordCount\":493,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_8mumddygw__Porcinos-6.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/\",\"name\":\"El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_8mumddygw__Porcinos-6.jpg\",\"datePublished\":\"2012-02-02T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_8mumddygw__Porcinos-6.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_8mumddygw__Porcinos-6.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/","og_locale":"en_US","og_type":"article","og_title":"El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda. | Proagro","og_description":"La industria porcina, que crece de manera sostenida de la mano del aumento del consumo, lidera los pedidos para obtener cr\u00e9ditos del Bicentenario. Seg\u00fan inform\u00f3 el Ministerio de Industria que comanda D\u00e9bora Giorgi, el sector ya obtuvo pr\u00e9stamos por m\u00e1s de $ 270 millones. De esta forma, m\u00e1s de la mitad de los desembolsos provendr\u00e1n de pr\u00e9stamos a tasa subsidiada, al 9,9 por ciento anual, fija en pesos y a cinco a\u00f1os de plazo. La ministra asegur\u00f3 que estos cr\u00e9ditos generar\u00e1n inversiones por $ 466 millones en cinco provincias y que esto permitir\u00e1 ampliar la producci\u00f3n. El sector porcino creci\u00f3 en el mercado interno de la mano del aumento del precio de la carne vacuna, proceso que acompa\u00f1\u00f3 con un salto en la calidad. Seg\u00fan datos de Industria, entre 2003 y 2010, la producci\u00f3n de carne porcina aument\u00f3 78 por ciento, y ya supera las 281.000 toneladas. En 2011 el sector faen\u00f3 cuatro millones de cabezas y planea incrementar ese volumen a 4,8 \u00f3 5 millones de cabezas en 2012. En ese mismo per\u00edodo, el consumo per c\u00e1pita pas\u00f3 de 5,33 kilos por habitante por a\u00f1o a los actuales 8,12 kilos, mostrando un incremento superior al 50 por ciento.En paralelo, [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-02-02T00:00:01+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_8mumddygw__Porcinos-6.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda.","datePublished":"2012-02-02T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/"},"wordCount":493,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_8mumddygw__Porcinos-6.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/","url":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/","name":"El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_8mumddygw__Porcinos-6.jpg","datePublished":"2012-02-02T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_8mumddygw__Porcinos-6.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_8mumddygw__Porcinos-6.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/el-sector-porcino-invertira-460-millones-para-hacer-frente-a-la-mayor-demanda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"El sector porcino invertir\u00e1 $ 460 millones para hacer frente a la mayor demanda."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4748"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1272"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}