{"id":4745,"date":"2012-02-02T00:00:01","date_gmt":"2012-02-02T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/"},"modified":"2012-02-02T00:00:01","modified_gmt":"2012-02-02T00:00:01","slug":"nueva-mejora-de-las-cotizaciones","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/nueva-mejora-de-las-cotizaciones\/","title":{"rendered":"Nueva mejora de las cotizaciones."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>El Indice General aument\u00f3 1,32 por ciento, al pasar de 7,945 a 8,050 pesos por kilo.<\/p>\n<p>Otra oferta limitada se registr\u00f3 ayer en el Mercado de Liniers para la tercera rueda de negocios de la semana, dado que de 185 camiones fueron descargadas 6959 cabezas, frente a 5576 encerradas el martes. Y desde el primer turno de remates se impuso t\u00f3nica de firmeza por la efectiva gesti\u00f3n que desarrollaron los representantes del abasto local para cumplir sus faenas inmediatas. Pese al inter\u00e9s general, la mayor competencia se entabl\u00f3 por las remisiones de feedlot y racionadas del tipo consumo liviano, cuya colocaci\u00f3n result\u00f3 \u00e1gil y r\u00e1pida a precios calificados satisfactorios y superiores a los obtenidos en la jornada previa.<\/p>\n<p>En ese clima, se alcanzaron los siguientes valores destacados: en novillitos, $ 10,57 por un lote con 353 kilos; $ 10,50 con 356 kg; $ 9,92 con 371 kg; $ 9,74 con 388 kg; $ 9,72 con 400 kg, y $ 9,80 con 412 kg; en terneros, con ganancias estimadas de 20 centavos, $ 11,22 por livianos de 303 kg; $ 11,02 con 307 kg, y $ 10,57 con 337 kg, y en vaquillonas, $ 9,48 con 362 kg; $ 9,42 con 354 y con 366 kg; $ 9,21 con 372 kg; $ 9,17 con 379 kg; $ 9,10 con 381 kg, y $ 9 con 391 y con 398 kilos.<\/p>\n<p>Los 1262 novillos adjudicados, que representaron el 18,22% del total general, se cotizaron con subas de 10 centavos. Se pagaron $ 9,66 por medianos de 463 kg; $ 9,52 con 440 kg; $ 9,50 con 453 kg; $ 9,41 con 471 kg, y $ 9,38 por pesados de 513 kg.<\/p>\n<p>Los distintos tipos de vacas tuvieron demanda sostenida de la industria y de los usuarios de planta, y se negociaron sin alterar mayormente los promedios del martes. Por lotes de buena conformaci\u00f3n se pactaron $ 8,40 con 432 kg; $ 7,80 por pesadas de 517 kg; $ 7,70 con 462 y con 479 kg; $ 7,60 con 502 kg, y $ 7,36 con 534 kg.<\/p>\n<p>El Indice General del Mercado de Liniers SA fue de $ 8,050 y super\u00f3 en un 1,32% al anterior, de $ 7,945. El peso promedio general de los 6926 vacunos negociados result\u00f3 de 417 kilos. El Indice Novillo del Mercado de Liniers result\u00f3 de $ 8,286. En tanto que el precio promedio general de Mercados al D\u00eda fue de $ 8,363. El valor sugerido para arrendamientos qued\u00f3 en $ 8,569.<\/p>\n<p><span style=\"font-style: italic;\">Cotizaciones m\u00e1ximas<\/span><br \/>Novillos livianos, $ 9,52 por 34 animales con 440 kg; novillos medianos, $ 9,41 por 76 con 463 kg; novillos pesados, $ 9,38 por 15 con 513 kg; novillos muy pesados, $ 8,50 por 10 con 530 kg; novillitos, $ 10,50 por 18 con 352 kg; vaquillonas, $ 9,48 por 20 con 362 kg; terneros, $ 11,22 por 20 con 303 kg; vacas, $ 8,40 por 9 con 432 kg, y toros, $ 7,50 por 10 con 551 kg.<\/p>\n<p>A partir de las 8 se efectuar\u00e1n hoy remates especiales organizados por dos consignatarias. La firma Alzaga Unzu\u00e9 y C\u00eda. SA reanudar\u00e1 su tradicional encierre exclusivo de la raza Angus de los primeros jueves de mes, con el auspicio de la Asociaci\u00f3n Argentina de Angus, mientras que Colombo y Magliano SA expondr\u00e1 haciendas de feedlot.<\/p>\n<p><span style=\"font-style: italic;\">Detalle de venta<\/span><br \/>Novillos 1262; novillitos 1854; vaquillonas 668; vacas 943; conservas 588; terneros 1426, y toros 185. Quedaron 16 animales sin ser vendidos. Ventas de ayer en pesos por kilo vivo. Base 15 cabezas.<\/p>\n<p>Fuente: La Naci\u00f3n, 2 de febrero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>El Indice General aument\u00f3 1,32 por ciento, al pasar de 7,945 a 8,050 pesos por kilo. Otra oferta limitada se registr\u00f3 ayer en el Mercado de Liniers para la tercera rueda de negocios de la semana, dado que de 185 camiones fueron descargadas 6959 cabezas, frente a 5576 encerradas el martes. Y desde el primer turno de remates se impuso t\u00f3nica de firmeza por la efectiva gesti\u00f3n que desarrollaron los representantes del abasto local para cumplir sus faenas inmediatas. Pese al inter\u00e9s general, la mayor competencia se entabl\u00f3 por las remisiones de feedlot y racionadas del tipo consumo liviano, cuya colocaci\u00f3n result\u00f3 \u00e1gil y r\u00e1pida a precios calificados satisfactorios y superiores a los obtenidos en la jornada previa. En ese clima, se alcanzaron los siguientes valores destacados: en novillitos, $ 10,57 por un lote con 353 kilos; $ 10,50 con 356 kg; $ 9,92 con 371 kg; $ 9,74 con 388 kg; $ 9,72 con 400 kg, y $ 9,80 con 412 kg; en terneros, con ganancias estimadas de 20 centavos, $ 11,22 por livianos de 303 kg; $ 11,02 con 307 kg, y $ 10,57 con 337 kg, y en vaquillonas, $ 9,48 con 362 kg; $ 9,42 con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1269,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nueva mejora de las cotizaciones. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/nueva-mejora-de-las-cotizaciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva mejora de las cotizaciones. | Proagro\" \/>\n<meta property=\"og:description\" content=\"El Indice General aument\u00f3 1,32 por ciento, al pasar de 7,945 a 8,050 pesos por kilo. Otra oferta limitada se registr\u00f3 ayer en el Mercado de Liniers para la tercera rueda de negocios de la semana, dado que de 185 camiones fueron descargadas 6959 cabezas, frente a 5576 encerradas el martes. Y desde el primer turno de remates se impuso t\u00f3nica de firmeza por la efectiva gesti\u00f3n que desarrollaron los representantes del abasto local para cumplir sus faenas inmediatas. Pese al inter\u00e9s general, la mayor competencia se entabl\u00f3 por las remisiones de feedlot y racionadas del tipo consumo liviano, cuya colocaci\u00f3n result\u00f3 \u00e1gil y r\u00e1pida a precios calificados satisfactorios y superiores a los obtenidos en la jornada previa. En ese clima, se alcanzaron los siguientes valores destacados: en novillitos, $ 10,57 por un lote con 353 kilos; $ 10,50 con 356 kg; $ 9,92 con 371 kg; $ 9,74 con 388 kg; $ 9,72 con 400 kg, y $ 9,80 con 412 kg; en terneros, con ganancias estimadas de 20 centavos, $ 11,22 por livianos de 303 kg; $ 11,02 con 307 kg, y $ 10,57 con 337 kg, y en vaquillonas, $ 9,48 con 362 kg; $ 9,42 con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-02T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w3a97ltl8__Mercado-de-Liniers-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"Nueva mejora de las cotizaciones.\",\"datePublished\":\"2012-02-02T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/\"},\"wordCount\":460,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_w3a97ltl8__Mercado-de-Liniers-5.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/\",\"name\":\"Nueva mejora de las cotizaciones. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_w3a97ltl8__Mercado-de-Liniers-5.jpg\",\"datePublished\":\"2012-02-02T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_w3a97ltl8__Mercado-de-Liniers-5.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_w3a97ltl8__Mercado-de-Liniers-5.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/nueva-mejora-de-las-cotizaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva mejora de las cotizaciones.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva mejora de las cotizaciones. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/nueva-mejora-de-las-cotizaciones\/","og_locale":"en_US","og_type":"article","og_title":"Nueva mejora de las cotizaciones. | Proagro","og_description":"El Indice General aument\u00f3 1,32 por ciento, al pasar de 7,945 a 8,050 pesos por kilo. Otra oferta limitada se registr\u00f3 ayer en el Mercado de Liniers para la tercera rueda de negocios de la semana, dado que de 185 camiones fueron descargadas 6959 cabezas, frente a 5576 encerradas el martes. Y desde el primer turno de remates se impuso t\u00f3nica de firmeza por la efectiva gesti\u00f3n que desarrollaron los representantes del abasto local para cumplir sus faenas inmediatas. Pese al inter\u00e9s general, la mayor competencia se entabl\u00f3 por las remisiones de feedlot y racionadas del tipo consumo liviano, cuya colocaci\u00f3n result\u00f3 \u00e1gil y r\u00e1pida a precios calificados satisfactorios y superiores a los obtenidos en la jornada previa. En ese clima, se alcanzaron los siguientes valores destacados: en novillitos, $ 10,57 por un lote con 353 kilos; $ 10,50 con 356 kg; $ 9,92 con 371 kg; $ 9,74 con 388 kg; $ 9,72 con 400 kg, y $ 9,80 con 412 kg; en terneros, con ganancias estimadas de 20 centavos, $ 11,22 por livianos de 303 kg; $ 11,02 con 307 kg, y $ 10,57 con 337 kg, y en vaquillonas, $ 9,48 con 362 kg; $ 9,42 con [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-02-02T00:00:01+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w3a97ltl8__Mercado-de-Liniers-5.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"Nueva mejora de las cotizaciones.","datePublished":"2012-02-02T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/"},"wordCount":460,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w3a97ltl8__Mercado-de-Liniers-5.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/","url":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/","name":"Nueva mejora de las cotizaciones. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w3a97ltl8__Mercado-de-Liniers-5.jpg","datePublished":"2012-02-02T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w3a97ltl8__Mercado-de-Liniers-5.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_w3a97ltl8__Mercado-de-Liniers-5.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/nueva-mejora-de-las-cotizaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Nueva mejora de las cotizaciones."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4745"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1269"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}