{"id":4708,"date":"2012-01-23T00:00:01","date_gmt":"2012-01-23T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/"},"modified":"2012-01-23T00:00:01","modified_gmt":"2012-01-23T00:00:01","slug":"mejora-la-calidad-de-los-rodeos-caprinos-en-formosa","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/","title":{"rendered":"Mejora la calidad de los rodeos caprinos en Formosa."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>El Centro de Validaci\u00f3n de Tecnolog\u00edas Agropecuarias transfiere capacitaci\u00f3n a unos 800 productores de la provincia.<\/p>\n<p><span style=\"font-style: italic;\">Por Justo Urbieta.<\/span><\/p>\n<p>FORMOSA.- Un trabajo orientado a apoyar a los peque\u00f1os productores del centroeste de Formosa a mejorar sus majadas de caprinos se lleva a cabo en la Caba\u00f1a Provincial Caprina del Centro de Validaci\u00f3n de Tecnolog\u00edas Agropecuarias de Laguna Yema (Cedeva), a 400 kil\u00f3metros de esta ciudad, a tal punto que los t\u00e9cnicos se muestran satisfechos al considerar el mejoramiento de la calidad de los rodeos.<\/p>\n<p>Es considerado como un elemento motivador para avanzar hacia nuevas etapas de una tarea orientada a transferir conocimientos sobre un mejor manejo de las majadas y la utilizaci\u00f3n de gen\u00e9tica y de modernas tecnolog\u00edas.<\/p>\n<p>El jefe del \u00e1rea ganadera de dicho centro, Sebasti\u00e1n De la Rosa, revela que en la provincia hay unos 800 productores de caprinos y que m\u00e1s de la mitad de ellos introdujo gen\u00e9tica, de una u otra manera, en los \u00faltimos diez a\u00f1os.<\/p>\n<p>Se llevan entregados 140 reproductores desde el inicio de la Caba\u00f1a y se hace el seguimiento para verificar que sean majadas libres de brucelosis y del desempe\u00f1o reproductivo y productivo de los machos que se van entregando.<\/p>\n<p>&#8220;Lo que recomendamos es no trabajar con animales en pureza para las majadas generales sino con cruzamientos, que es donde se producen los mejores resultados, es decir que sobre el pie de cr\u00eda criollo, es decir las hembras criollas, primero se introduce alternativamente o Boer o Anglo Nubian, de acuerdo al ambiente donde se encuentre la majada, y despu\u00e9s se vuelve a cruzar con otra raza&#8221;, explic\u00f3.<\/p>\n<p>Cree, sin embargo, que a futuro se tendr\u00e1 que volver a cruzar con el criollo para que no se pierda rusticidad y adaptaci\u00f3n al ambiente que es la mejor caracter\u00edstica que tiene el criollo y por eso es que se presta atenci\u00f3n a la conservaci\u00f3n de esa gen\u00e9tica ya que, de lo contrario, ella se pierde y a la larga el productor va a tener problemas de adaptaci\u00f3n con sus animales en el ambiente donde producen y eso es lo que se trata de evitar con todo este trabajo.<\/p>\n<p>&#8220;Vemos que los resultados alcanzados son positivos, observamos una mejor calidad de los animales que ofrecen y en muchos de los casos redujeron el n\u00famero de cabezas aunque no la cantidad de producci\u00f3n. Ello quiere decir que con menos animales de mejor calidad est\u00e1n produciendo igual o m\u00e1s que lo que antes ten\u00edan con animales de mala calidad o mal manejados&#8221;, relata De la Rosa.<\/p>\n<p>Ahora se est\u00e1 trabajando con un grupo de productores vinculados a la Caba\u00f1a Caprina desde el inicio y que ya tienen animales de suficiente calidad como para venderlos como reproductores, percibiendo un ingreso m\u00e1s alto que si vendiesen los animales para carne.<\/p>\n<p>&#8220;Son productores de la zona de Laguna Yema a los que los llamamos multiplicadores , que es como un sistema de pir\u00e1mide que hab\u00edamos planteado desde el comienzo&#8221;, indic\u00f3 el profesional.<\/p>\n<p>Insisti\u00f3 en que lo que importa es c\u00f3mo el productor puede ir mejorando su sistema de manejo tanto en lo sanitario como en las \u00e9pocas de parici\u00f3n porque favorece a un mejor desarrollo de los animales siempre aferrados a los criterios de sustentabilidad ambiental, econ\u00f3mica y social de modo tal que puedan lograr un producto natural en el menor tiempo posible.<\/p>\n<p>Al comparar, consign\u00f3 que mientras antes se tardaba cinco o seis meses para tener un animal que vaya a faena, ahora los productores que aceptaron las propuestas tecnol\u00f3gicas del Cedeva est\u00e1n logr\u00e1ndolo en tres meses como m\u00e1ximo.<\/p>\n<p>&#8220;Ello quiere decir que tenemos un acortamiento importante no s\u00f3lo para que el productor se haga con dinero o con alimentos que proviene de ese animal en menos tiempo, sino que estamos quit\u00e1ndole presi\u00f3n al medio ambiente de animales que lo est\u00e1n erosionando, algo que tiene que ver con el criterio de sustentabilidad que promovemos&#8221;, se\u00f1ala.<\/p>\n<p>Refiere que la cultura del formose\u00f1o es comer un animal de unos 15 kilogramos en pie, es decir de unos seis o siete kilos faenados.<\/p>\n<p>Explic\u00f3 que para la reproducci\u00f3n se eval\u00faan distintos ciclos de sincronizaci\u00f3n de celos y otro tipo de manejo reproductivo, aunque reconoce que en la actualidad se tiende a que sea todo lo m\u00e1s naturalmente posible y manejado de acuerdo con las posibilidades del productor.<\/p>\n<p>Indica que la cabra entra naturalmente en celo en oto\u00f1o y las pariciones se producen a principios de la primavera.<\/p>\n<p>De la Rosa calcula que en la provincia que hay algo m\u00e1s de 240.000 caprinos y 80.000 ovinos.<\/p>\n<p>Fuente: La Naci\u00f3n, Suplemento Campo, 21 de enero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>El Centro de Validaci\u00f3n de Tecnolog\u00edas Agropecuarias transfiere capacitaci\u00f3n a unos 800 productores de la provincia. Por Justo Urbieta. FORMOSA.- Un trabajo orientado a apoyar a los peque\u00f1os productores del centroeste de Formosa a mejorar sus majadas de caprinos se lleva a cabo en la Caba\u00f1a Provincial Caprina del Centro de Validaci\u00f3n de Tecnolog\u00edas Agropecuarias de Laguna Yema (Cedeva), a 400 kil\u00f3metros de esta ciudad, a tal punto que los t\u00e9cnicos se muestran satisfechos al considerar el mejoramiento de la calidad de los rodeos. Es considerado como un elemento motivador para avanzar hacia nuevas etapas de una tarea orientada a transferir conocimientos sobre un mejor manejo de las majadas y la utilizaci\u00f3n de gen\u00e9tica y de modernas tecnolog\u00edas. El jefe del \u00e1rea ganadera de dicho centro, Sebasti\u00e1n De la Rosa, revela que en la provincia hay unos 800 productores de caprinos y que m\u00e1s de la mitad de ellos introdujo gen\u00e9tica, de una u otra manera, en los \u00faltimos diez a\u00f1os. Se llevan entregados 140 reproductores desde el inicio de la Caba\u00f1a y se hace el seguimiento para verificar que sean majadas libres de brucelosis y del desempe\u00f1o reproductivo y productivo de los machos que se van entregando. &#8220;Lo que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1232,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mejora la calidad de los rodeos caprinos en Formosa. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mejora la calidad de los rodeos caprinos en Formosa. | Proagro\" \/>\n<meta property=\"og:description\" content=\"El Centro de Validaci\u00f3n de Tecnolog\u00edas Agropecuarias transfiere capacitaci\u00f3n a unos 800 productores de la provincia. Por Justo Urbieta. FORMOSA.- Un trabajo orientado a apoyar a los peque\u00f1os productores del centroeste de Formosa a mejorar sus majadas de caprinos se lleva a cabo en la Caba\u00f1a Provincial Caprina del Centro de Validaci\u00f3n de Tecnolog\u00edas Agropecuarias de Laguna Yema (Cedeva), a 400 kil\u00f3metros de esta ciudad, a tal punto que los t\u00e9cnicos se muestran satisfechos al considerar el mejoramiento de la calidad de los rodeos. Es considerado como un elemento motivador para avanzar hacia nuevas etapas de una tarea orientada a transferir conocimientos sobre un mejor manejo de las majadas y la utilizaci\u00f3n de gen\u00e9tica y de modernas tecnolog\u00edas. El jefe del \u00e1rea ganadera de dicho centro, Sebasti\u00e1n De la Rosa, revela que en la provincia hay unos 800 productores de caprinos y que m\u00e1s de la mitad de ellos introdujo gen\u00e9tica, de una u otra manera, en los \u00faltimos diez a\u00f1os. Se llevan entregados 140 reproductores desde el inicio de la Caba\u00f1a y se hace el seguimiento para verificar que sean majadas libres de brucelosis y del desempe\u00f1o reproductivo y productivo de los machos que se van entregando. &#8220;Lo que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-23T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_xi3ogkggl__Caprinos-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"Mejora la calidad de los rodeos caprinos en Formosa.\",\"datePublished\":\"2012-01-23T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/\"},\"wordCount\":817,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_xi3ogkggl__Caprinos-4.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/\",\"name\":\"Mejora la calidad de los rodeos caprinos en Formosa. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_xi3ogkggl__Caprinos-4.jpg\",\"datePublished\":\"2012-01-23T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_xi3ogkggl__Caprinos-4.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_xi3ogkggl__Caprinos-4.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mejora la calidad de los rodeos caprinos en Formosa.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mejora la calidad de los rodeos caprinos en Formosa. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/","og_locale":"en_US","og_type":"article","og_title":"Mejora la calidad de los rodeos caprinos en Formosa. | Proagro","og_description":"El Centro de Validaci\u00f3n de Tecnolog\u00edas Agropecuarias transfiere capacitaci\u00f3n a unos 800 productores de la provincia. Por Justo Urbieta. FORMOSA.- Un trabajo orientado a apoyar a los peque\u00f1os productores del centroeste de Formosa a mejorar sus majadas de caprinos se lleva a cabo en la Caba\u00f1a Provincial Caprina del Centro de Validaci\u00f3n de Tecnolog\u00edas Agropecuarias de Laguna Yema (Cedeva), a 400 kil\u00f3metros de esta ciudad, a tal punto que los t\u00e9cnicos se muestran satisfechos al considerar el mejoramiento de la calidad de los rodeos. Es considerado como un elemento motivador para avanzar hacia nuevas etapas de una tarea orientada a transferir conocimientos sobre un mejor manejo de las majadas y la utilizaci\u00f3n de gen\u00e9tica y de modernas tecnolog\u00edas. El jefe del \u00e1rea ganadera de dicho centro, Sebasti\u00e1n De la Rosa, revela que en la provincia hay unos 800 productores de caprinos y que m\u00e1s de la mitad de ellos introdujo gen\u00e9tica, de una u otra manera, en los \u00faltimos diez a\u00f1os. Se llevan entregados 140 reproductores desde el inicio de la Caba\u00f1a y se hace el seguimiento para verificar que sean majadas libres de brucelosis y del desempe\u00f1o reproductivo y productivo de los machos que se van entregando. &#8220;Lo que [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-01-23T00:00:01+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_xi3ogkggl__Caprinos-4.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"Mejora la calidad de los rodeos caprinos en Formosa.","datePublished":"2012-01-23T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/"},"wordCount":817,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_xi3ogkggl__Caprinos-4.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/","url":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/","name":"Mejora la calidad de los rodeos caprinos en Formosa. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_xi3ogkggl__Caprinos-4.jpg","datePublished":"2012-01-23T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_xi3ogkggl__Caprinos-4.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_xi3ogkggl__Caprinos-4.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/mejora-la-calidad-de-los-rodeos-caprinos-en-formosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Mejora la calidad de los rodeos caprinos en Formosa."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4708"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1232"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}