{"id":4701,"date":"2012-01-20T00:00:01","date_gmt":"2012-01-20T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/"},"modified":"2012-01-20T00:00:01","modified_gmt":"2012-01-20T00:00:01","slug":"brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/","title":{"rendered":"Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>A pesar de las presiones de los productores nacionales para limitar la compra del producto l\u00e1cteo proveniente principalmente de Argentina y Uruguay, el pa\u00eds cerr\u00f3 el a\u00f1o con una balanza comercial negativa en l\u00e1cteos de 124.719 toneladas y pas\u00f3 del sexto al tercer lugar de la lista mundial de los mayores importadores de leche en polvo.<\/p>\n<p>Durante todo el 2011, Brasil estuvo negociando con la Argentina para limitar la cuota mensual de leche en polvo entera que hasta ese momento estaba establecida en 3.300 toneladas por un acuerdo p\u00fablico &#8211; privado entre ambos pa\u00edses. Tras su vencimiento en abril y luego de varias idas y vueltas, ambos estados acordaron fijar la cuota en 3600 toneladas. Sin embargo, y a pesar de la presi\u00f3n de los productores nacionales, el pa\u00eds carioca no redujo su compra de leche en polvo sino que la redireccion\u00f3 a Uruguay que &#8211; como Chile &#8211; no tiene l\u00edmite en la venta del producto.<\/p>\n<p>El aumento de sus compras de leche en polvo le dej\u00f3 saldo negativo de 124.719 toneladas, lo que reflej\u00f3 un d\u00e9ficit acumulado de 127,3% a comparaci\u00f3n de 2010, y lo hizo subir del sexto al tercer puesto de la lista mundial de importadores de leche en polvo.<\/p>\n<p>Fuente: Infortambo, 19 de enero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>A pesar de las presiones de los productores nacionales para limitar la compra del producto l\u00e1cteo proveniente principalmente de Argentina y Uruguay, el pa\u00eds cerr\u00f3 el a\u00f1o con una balanza comercial negativa en l\u00e1cteos de 124.719 toneladas y pas\u00f3 del sexto al tercer lugar de la lista mundial de los mayores importadores de leche en polvo. Durante todo el 2011, Brasil estuvo negociando con la Argentina para limitar la cuota mensual de leche en polvo entera que hasta ese momento estaba establecida en 3.300 toneladas por un acuerdo p\u00fablico &#8211; privado entre ambos pa\u00edses. Tras su vencimiento en abril y luego de varias idas y vueltas, ambos estados acordaron fijar la cuota en 3600 toneladas. Sin embargo, y a pesar de la presi\u00f3n de los productores nacionales, el pa\u00eds carioca no redujo su compra de leche en polvo sino que la redireccion\u00f3 a Uruguay que &#8211; como Chile &#8211; no tiene l\u00edmite en la venta del producto. El aumento de sus compras de leche en polvo le dej\u00f3 saldo negativo de 124.719 toneladas, lo que reflej\u00f3 un d\u00e9ficit acumulado de 127,3% a comparaci\u00f3n de 2010, y lo hizo subir del sexto al tercer puesto de la lista mundial de importadores [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1225,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera. | Proagro\" \/>\n<meta property=\"og:description\" content=\"A pesar de las presiones de los productores nacionales para limitar la compra del producto l\u00e1cteo proveniente principalmente de Argentina y Uruguay, el pa\u00eds cerr\u00f3 el a\u00f1o con una balanza comercial negativa en l\u00e1cteos de 124.719 toneladas y pas\u00f3 del sexto al tercer lugar de la lista mundial de los mayores importadores de leche en polvo. Durante todo el 2011, Brasil estuvo negociando con la Argentina para limitar la cuota mensual de leche en polvo entera que hasta ese momento estaba establecida en 3.300 toneladas por un acuerdo p\u00fablico &#8211; privado entre ambos pa\u00edses. Tras su vencimiento en abril y luego de varias idas y vueltas, ambos estados acordaron fijar la cuota en 3600 toneladas. Sin embargo, y a pesar de la presi\u00f3n de los productores nacionales, el pa\u00eds carioca no redujo su compra de leche en polvo sino que la redireccion\u00f3 a Uruguay que &#8211; como Chile &#8211; no tiene l\u00edmite en la venta del producto. El aumento de sus compras de leche en polvo le dej\u00f3 saldo negativo de 124.719 toneladas, lo que reflej\u00f3 un d\u00e9ficit acumulado de 127,3% a comparaci\u00f3n de 2010, y lo hizo subir del sexto al tercer puesto de la lista mundial de importadores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-20T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_n1w6ej0rv__Lecheras-20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera.\",\"datePublished\":\"2012-01-20T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_n1w6ej0rv__Lecheras-20.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/\",\"name\":\"Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_n1w6ej0rv__Lecheras-20.jpg\",\"datePublished\":\"2012-01-20T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_n1w6ej0rv__Lecheras-20.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_n1w6ej0rv__Lecheras-20.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/","og_locale":"en_US","og_type":"article","og_title":"Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera. | Proagro","og_description":"A pesar de las presiones de los productores nacionales para limitar la compra del producto l\u00e1cteo proveniente principalmente de Argentina y Uruguay, el pa\u00eds cerr\u00f3 el a\u00f1o con una balanza comercial negativa en l\u00e1cteos de 124.719 toneladas y pas\u00f3 del sexto al tercer lugar de la lista mundial de los mayores importadores de leche en polvo. Durante todo el 2011, Brasil estuvo negociando con la Argentina para limitar la cuota mensual de leche en polvo entera que hasta ese momento estaba establecida en 3.300 toneladas por un acuerdo p\u00fablico &#8211; privado entre ambos pa\u00edses. Tras su vencimiento en abril y luego de varias idas y vueltas, ambos estados acordaron fijar la cuota en 3600 toneladas. Sin embargo, y a pesar de la presi\u00f3n de los productores nacionales, el pa\u00eds carioca no redujo su compra de leche en polvo sino que la redireccion\u00f3 a Uruguay que &#8211; como Chile &#8211; no tiene l\u00edmite en la venta del producto. El aumento de sus compras de leche en polvo le dej\u00f3 saldo negativo de 124.719 toneladas, lo que reflej\u00f3 un d\u00e9ficit acumulado de 127,3% a comparaci\u00f3n de 2010, y lo hizo subir del sexto al tercer puesto de la lista mundial de importadores [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-01-20T00:00:01+00:00","og_image":[{"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_n1w6ej0rv__Lecheras-20.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera.","datePublished":"2012-01-20T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/"},"wordCount":225,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_n1w6ej0rv__Lecheras-20.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/","url":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/","name":"Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_n1w6ej0rv__Lecheras-20.jpg","datePublished":"2012-01-20T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_n1w6ej0rv__Lecheras-20.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_n1w6ej0rv__Lecheras-20.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/brasil-paso-a-ser-el-tercer-importador-mundial-de-leche-en-polvo-entera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Brasil pas\u00f3 a ser el tercer importador mundial de leche en polvo entera."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4701"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1225"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}