{"id":4698,"date":"2012-01-19T00:00:01","date_gmt":"2012-01-19T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/"},"modified":"2012-01-19T00:00:01","modified_gmt":"2012-01-19T00:00:01","slug":"se-duplica-el-consume-de-carne-en-chile","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/se-duplica-el-consume-de-carne-en-chile\/","title":{"rendered":"Se duplica el consume de carne en Chile."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>De acuerdo datos dados a conocer por la Oficina de Estudios y Pol\u00edticas Agropecuarias (ODEPA) de Chile, en 20 a\u00f1os el consume de carne se ha duplicado en el pa\u00eds, dice una nota del peri\u00f3dico local El Mercurio. En 1991, el consumo per c\u00e1pita de carne roja y blanca era de 39.6 kilos, pasando a 84.2 kilos per c\u00e1pita en 2011.<\/p>\n<p>ODEPA ha llevado un registro de consumo de distintos tipos de carne desde hace 28 a\u00f1os. El mayor consumo se registr\u00f3 en la carne de ave, que en 1986 era de 6.5 kilos per c\u00e1pita, y en 2011 se registr\u00f3 en 36.1 kilos. Le sigue la carne de porcino que se ha cuadruplicado pasando de 14.7 kilos per c\u00e1pita en 1986 a 21.7 kilos en 2011. La de bovino es la carne que ha registrado el menor crecimiento en consumo, aunque se ha duplicado pasando de 6.1 kilos per c\u00e1pita en 1986 a 25.7 kilos en 2011. <\/p>\n<p>Actualmente, del total de la carne consumida en Chile, el 46% es de pollo, 25% de porcino y 21% de bovino.<\/p>\n<p>Fuente: Carnetec, 19 de enero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>De acuerdo datos dados a conocer por la Oficina de Estudios y Pol\u00edticas Agropecuarias (ODEPA) de Chile, en 20 a\u00f1os el consume de carne se ha duplicado en el pa\u00eds, dice una nota del peri\u00f3dico local El Mercurio. En 1991, el consumo per c\u00e1pita de carne roja y blanca era de 39.6 kilos, pasando a 84.2 kilos per c\u00e1pita en 2011. ODEPA ha llevado un registro de consumo de distintos tipos de carne desde hace 28 a\u00f1os. El mayor consumo se registr\u00f3 en la carne de ave, que en 1986 era de 6.5 kilos per c\u00e1pita, y en 2011 se registr\u00f3 en 36.1 kilos. Le sigue la carne de porcino que se ha cuadruplicado pasando de 14.7 kilos per c\u00e1pita en 1986 a 21.7 kilos en 2011. La de bovino es la carne que ha registrado el menor crecimiento en consumo, aunque se ha duplicado pasando de 6.1 kilos per c\u00e1pita en 1986 a 25.7 kilos en 2011. Actualmente, del total de la carne consumida en Chile, el 46% es de pollo, 25% de porcino y 21% de bovino. Fuente: Carnetec, 19 de enero.<\/p>\n","protected":false},"author":2,"featured_media":1222,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se duplica el consume de carne en Chile. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/se-duplica-el-consume-de-carne-en-chile\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se duplica el consume de carne en Chile. | Proagro\" \/>\n<meta property=\"og:description\" content=\"De acuerdo datos dados a conocer por la Oficina de Estudios y Pol\u00edticas Agropecuarias (ODEPA) de Chile, en 20 a\u00f1os el consume de carne se ha duplicado en el pa\u00eds, dice una nota del peri\u00f3dico local El Mercurio. En 1991, el consumo per c\u00e1pita de carne roja y blanca era de 39.6 kilos, pasando a 84.2 kilos per c\u00e1pita en 2011. ODEPA ha llevado un registro de consumo de distintos tipos de carne desde hace 28 a\u00f1os. El mayor consumo se registr\u00f3 en la carne de ave, que en 1986 era de 6.5 kilos per c\u00e1pita, y en 2011 se registr\u00f3 en 36.1 kilos. Le sigue la carne de porcino que se ha cuadruplicado pasando de 14.7 kilos per c\u00e1pita en 1986 a 21.7 kilos en 2011. La de bovino es la carne que ha registrado el menor crecimiento en consumo, aunque se ha duplicado pasando de 6.1 kilos per c\u00e1pita en 1986 a 25.7 kilos en 2011. Actualmente, del total de la carne consumida en Chile, el 46% es de pollo, 25% de porcino y 21% de bovino. Fuente: Carnetec, 19 de enero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-19T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_2zgzel29x__Consumo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"208\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"Se duplica el consume de carne en Chile.\",\"datePublished\":\"2012-01-19T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/\"},\"wordCount\":180,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_2zgzel29x__Consumo.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/\",\"name\":\"Se duplica el consume de carne en Chile. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_2zgzel29x__Consumo.jpg\",\"datePublished\":\"2012-01-19T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_2zgzel29x__Consumo.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_2zgzel29x__Consumo.jpg\",\"width\":450,\"height\":208},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-duplica-el-consume-de-carne-en-chile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se duplica el consume de carne en Chile.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se duplica el consume de carne en Chile. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/se-duplica-el-consume-de-carne-en-chile\/","og_locale":"en_US","og_type":"article","og_title":"Se duplica el consume de carne en Chile. | Proagro","og_description":"De acuerdo datos dados a conocer por la Oficina de Estudios y Pol\u00edticas Agropecuarias (ODEPA) de Chile, en 20 a\u00f1os el consume de carne se ha duplicado en el pa\u00eds, dice una nota del peri\u00f3dico local El Mercurio. En 1991, el consumo per c\u00e1pita de carne roja y blanca era de 39.6 kilos, pasando a 84.2 kilos per c\u00e1pita en 2011. ODEPA ha llevado un registro de consumo de distintos tipos de carne desde hace 28 a\u00f1os. El mayor consumo se registr\u00f3 en la carne de ave, que en 1986 era de 6.5 kilos per c\u00e1pita, y en 2011 se registr\u00f3 en 36.1 kilos. Le sigue la carne de porcino que se ha cuadruplicado pasando de 14.7 kilos per c\u00e1pita en 1986 a 21.7 kilos en 2011. La de bovino es la carne que ha registrado el menor crecimiento en consumo, aunque se ha duplicado pasando de 6.1 kilos per c\u00e1pita en 1986 a 25.7 kilos en 2011. Actualmente, del total de la carne consumida en Chile, el 46% es de pollo, 25% de porcino y 21% de bovino. Fuente: Carnetec, 19 de enero.","og_url":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-01-19T00:00:01+00:00","og_image":[{"width":450,"height":208,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_2zgzel29x__Consumo.jpg","type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"Se duplica el consume de carne en Chile.","datePublished":"2012-01-19T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/"},"wordCount":180,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_2zgzel29x__Consumo.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/","url":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/","name":"Se duplica el consume de carne en Chile. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_2zgzel29x__Consumo.jpg","datePublished":"2012-01-19T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_2zgzel29x__Consumo.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_2zgzel29x__Consumo.jpg","width":450,"height":208},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/se-duplica-el-consume-de-carne-en-chile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Se duplica el consume de carne en Chile."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4698"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1222"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}