{"id":4693,"date":"2012-01-19T00:00:01","date_gmt":"2012-01-19T00:00:01","guid":{"rendered":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/"},"modified":"2012-01-19T00:00:01","modified_gmt":"2012-01-19T00:00:01","slug":"yauhar-se-reunio-con-industriales-de-la-lecheria","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/yauhar-se-reunio-con-industriales-de-la-lecheria\/","title":{"rendered":"Yauhar se reuni\u00f3 con industriales de la lecheria."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>El ministro de Agricultura, Ganader\u00eda y Pesca de la Naci\u00f3n, Norberto Yauhar y el subsecretario de Lecher\u00eda, Arturo Videla, se reunieron con representantes de industrias l\u00e1cteas, congregadas en el Centro de Industria Lechera (CIL), para analizar la situaci\u00f3n actual del sector y sus perspectivas.<\/p>\n<p>Durante el encuentro, llevado adelante en la sede de la cartera agropecuaria, se realiz\u00f3 un an\u00e1lisis de la competitividad de la industria l\u00e1ctea y una descripci\u00f3n de las inversiones en ejecuci\u00f3n y las proyectadas por los socios del CIL.<\/p>\n<p>\u0093Esta reuni\u00f3n con el sector l\u00e1cteo ha servido para escuchar sus inquietudes y dejar abierta una agenda de trabajo conjunto\u0094, sostuvo Yauhar, al tiempo que agreg\u00f3: \u0093las instancias de di\u00e1logo nos permitir\u00e1n acercarnos cada vez m\u00e1s a la realidad productiva de los mercados interno y externo\u0094.<\/p>\n<p>\u0093Desde el Estado nacional fomentamos la activa participaci\u00f3n de las industrias l\u00e1cteas en las \u00faltimas misiones comerciales y de Ferias Internacionales de Alimentos\u0094, ponder\u00f3 el Ministro.<\/p>\n<p>En esta oportunidad, adem\u00e1s, se realiz\u00f3 la presentaci\u00f3n de la nueva estructura de la Subsecretar\u00eda de Lecher\u00eda y de los planes de acci\u00f3n prioritarios, como as\u00ed tambi\u00e9n se evalu\u00f3 la implementaci\u00f3n integral de la Liquidaci\u00f3n \u00danica de pago de la materia prima por composici\u00f3n y atributos de calidad.<br \/>El presidente del Centro de Industria Lechera, Miguel Paul\u00f3n, subray\u00f3 \u0093la potencialidad y proyecci\u00f3n que tiene este sector que ha dado, en este a\u00f1o y medio \u00faltimo, un salto cuali y cuantitativo importante\u0094. Y a\u00f1adi\u00f3: \u0093se han superado niveles de producci\u00f3n hist\u00f3ricos en Argentina con m\u00e1s de 11 mil millones de litros. Estamos en un per\u00edodo realmente positivo y hay que seguir reforz\u00e1ndolo\u0094.<\/p>\n<p>Asimismo, el presidente de Williner S.A., Alfredo Curiotti, expres\u00f3 que \u0093es fundamental para los actores p\u00fablicos y privados buscar puntos de coincidencias, escucharnos y establecer las prioridades en esta actividad\u0094.<\/p>\n<p>\u0093La lecher\u00eda argentina tiene un futuro espectacular y hay que ver ese escenario para actuar en consecuencia. Tenemos que aprovechar esa posibilidad para que el sector l\u00e1cteo siga teniendo un crecimiento permanente y sostenido en el tiempo\u0094, afirm\u00f3 Curiotti.<\/p>\n<p>Los dirigentes del CIL tambi\u00e9n valoraron la decisi\u00f3n pol\u00edtica de la Presidenta Cristina Fern\u00e1ndez de Kirchner respecto a los Cr\u00e9ditos del Bicentenario y la busca de mercados de Exportaci\u00f3n.<\/p>\n<p>Por su parte, el subsecretario de Lecher\u00eda, Arturo Videla, se\u00f1al\u00f3 que \u0093la articulaci\u00f3n p\u00fablico-privada es fundamental para llevar adelante los objetivos para el sector y destac\u00f3 como eje de trabajo de la Subsecretar\u00eda \u0093la puesta en marcha de la segunda fase del \u0093Programa Inclusivo de Operadores L\u00e1cteos\u0094.<\/p>\n<p>Participaron por la empresa DPA Nestle Arg. S.A., Leonardo Cortese y Andrea Megger; por Danone Arg. S.A., Adri\u00e1n Bonelli; por Garc\u00eda Hnos. S.A, Pedro Garc\u00eda; por La L\u00e1cteo S.A, Ra\u00fal Filippi; por Lactear S.A, el presidente Roberto Bossio y Gustino Italo; por La Sibila S.A., Federico Boglione y Rodrigo Cochet; por Magnasco Hnos. S.A., Lucas Magnasco; por Manfrey Coop. De Com. e Ind. Ltda., el presidente Ercole Jos\u00e9 Felippa; por Mastellone Hnos. S.A, Osvaldo Capellini y Am\u00edlcar Brando; por Milkaut S.A., Jos\u00e9 Imwinkelried; por M.S.G.P., de Magnasco, Esteban Magnasco; por Remotti S.A., Eduardo Lloveras; por Sancor C.U.L., el presidente Oscar Carreras, el vicepresidente Rub\u00e9n Dar\u00edo Echavarr\u00eda, y Jorge Alberto Giraudo; por la Suc. de A. Williner S.A., el presidente Alfredo Curiotti y Nicol\u00e1s Curiotti; y por Ver\u00f3nica S.A, Alejandro Espi\u00f1eira y Gonzalo Espi\u00f1eira.<\/p>\n<p>Fuente: ON 24, 18 de enero.<br \/><\/p>","protected":false},"excerpt":{"rendered":"<p>El ministro de Agricultura, Ganader\u00eda y Pesca de la Naci\u00f3n, Norberto Yauhar y el subsecretario de Lecher\u00eda, Arturo Videla, se reunieron con representantes de industrias l\u00e1cteas, congregadas en el Centro de Industria Lechera (CIL), para analizar la situaci\u00f3n actual del sector y sus perspectivas. Durante el encuentro, llevado adelante en la sede de la cartera agropecuaria, se realiz\u00f3 un an\u00e1lisis de la competitividad de la industria l\u00e1ctea y una descripci\u00f3n de las inversiones en ejecuci\u00f3n y las proyectadas por los socios del CIL. \u0093Esta reuni\u00f3n con el sector l\u00e1cteo ha servido para escuchar sus inquietudes y dejar abierta una agenda de trabajo conjunto\u0094, sostuvo Yauhar, al tiempo que agreg\u00f3: \u0093las instancias de di\u00e1logo nos permitir\u00e1n acercarnos cada vez m\u00e1s a la realidad productiva de los mercados interno y externo\u0094. \u0093Desde el Estado nacional fomentamos la activa participaci\u00f3n de las industrias l\u00e1cteas en las \u00faltimas misiones comerciales y de Ferias Internacionales de Alimentos\u0094, ponder\u00f3 el Ministro. En esta oportunidad, adem\u00e1s, se realiz\u00f3 la presentaci\u00f3n de la nueva estructura de la Subsecretar\u00eda de Lecher\u00eda y de los planes de acci\u00f3n prioritarios, como as\u00ed tambi\u00e9n se evalu\u00f3 la implementaci\u00f3n integral de la Liquidaci\u00f3n \u00danica de pago de la materia prima por composici\u00f3n y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1217,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yauhar se reuni\u00f3 con industriales de la lecheria. | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/yauhar-se-reunio-con-industriales-de-la-lecheria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yauhar se reuni\u00f3 con industriales de la lecheria. | Proagro\" \/>\n<meta property=\"og:description\" content=\"El ministro de Agricultura, Ganader\u00eda y Pesca de la Naci\u00f3n, Norberto Yauhar y el subsecretario de Lecher\u00eda, Arturo Videla, se reunieron con representantes de industrias l\u00e1cteas, congregadas en el Centro de Industria Lechera (CIL), para analizar la situaci\u00f3n actual del sector y sus perspectivas. Durante el encuentro, llevado adelante en la sede de la cartera agropecuaria, se realiz\u00f3 un an\u00e1lisis de la competitividad de la industria l\u00e1ctea y una descripci\u00f3n de las inversiones en ejecuci\u00f3n y las proyectadas por los socios del CIL. \u0093Esta reuni\u00f3n con el sector l\u00e1cteo ha servido para escuchar sus inquietudes y dejar abierta una agenda de trabajo conjunto\u0094, sostuvo Yauhar, al tiempo que agreg\u00f3: \u0093las instancias de di\u00e1logo nos permitir\u00e1n acercarnos cada vez m\u00e1s a la realidad productiva de los mercados interno y externo\u0094. \u0093Desde el Estado nacional fomentamos la activa participaci\u00f3n de las industrias l\u00e1cteas en las \u00faltimas misiones comerciales y de Ferias Internacionales de Alimentos\u0094, ponder\u00f3 el Ministro. En esta oportunidad, adem\u00e1s, se realiz\u00f3 la presentaci\u00f3n de la nueva estructura de la Subsecretar\u00eda de Lecher\u00eda y de los planes de acci\u00f3n prioritarios, como as\u00ed tambi\u00e9n se evalu\u00f3 la implementaci\u00f3n integral de la Liquidaci\u00f3n \u00danica de pago de la materia prima por composici\u00f3n y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-19T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_sv1ujdecu__Lecheras-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"208\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"proagrolab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"proagrolab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/\"},\"author\":{\"name\":\"proagrolab\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\"},\"headline\":\"Yauhar se reuni\u00f3 con industriales de la lecheria.\",\"datePublished\":\"2012-01-19T00:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/\"},\"wordCount\":635,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_sv1ujdecu__Lecheras-10.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/\",\"name\":\"Yauhar se reuni\u00f3 con industriales de la lecheria. | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_sv1ujdecu__Lecheras-10.jpg\",\"datePublished\":\"2012-01-19T00:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_sv1ujdecu__Lecheras-10.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/g_sv1ujdecu__Lecheras-10.jpg\",\"width\":450,\"height\":208},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/yauhar-se-reunio-con-industriales-de-la-lecheria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yauhar se reuni\u00f3 con industriales de la lecheria.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/38003ff90bf80381f71c7d922d207444\",\"name\":\"proagrolab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yauhar se reuni\u00f3 con industriales de la lecheria. | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/yauhar-se-reunio-con-industriales-de-la-lecheria\/","og_locale":"en_US","og_type":"article","og_title":"Yauhar se reuni\u00f3 con industriales de la lecheria. | Proagro","og_description":"El ministro de Agricultura, Ganader\u00eda y Pesca de la Naci\u00f3n, Norberto Yauhar y el subsecretario de Lecher\u00eda, Arturo Videla, se reunieron con representantes de industrias l\u00e1cteas, congregadas en el Centro de Industria Lechera (CIL), para analizar la situaci\u00f3n actual del sector y sus perspectivas. Durante el encuentro, llevado adelante en la sede de la cartera agropecuaria, se realiz\u00f3 un an\u00e1lisis de la competitividad de la industria l\u00e1ctea y una descripci\u00f3n de las inversiones en ejecuci\u00f3n y las proyectadas por los socios del CIL. \u0093Esta reuni\u00f3n con el sector l\u00e1cteo ha servido para escuchar sus inquietudes y dejar abierta una agenda de trabajo conjunto\u0094, sostuvo Yauhar, al tiempo que agreg\u00f3: \u0093las instancias de di\u00e1logo nos permitir\u00e1n acercarnos cada vez m\u00e1s a la realidad productiva de los mercados interno y externo\u0094. \u0093Desde el Estado nacional fomentamos la activa participaci\u00f3n de las industrias l\u00e1cteas en las \u00faltimas misiones comerciales y de Ferias Internacionales de Alimentos\u0094, ponder\u00f3 el Ministro. En esta oportunidad, adem\u00e1s, se realiz\u00f3 la presentaci\u00f3n de la nueva estructura de la Subsecretar\u00eda de Lecher\u00eda y de los planes de acci\u00f3n prioritarios, como as\u00ed tambi\u00e9n se evalu\u00f3 la implementaci\u00f3n integral de la Liquidaci\u00f3n \u00danica de pago de la materia prima por composici\u00f3n y [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2012-01-19T00:00:01+00:00","og_image":[{"width":450,"height":208,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_sv1ujdecu__Lecheras-10.jpg","type":"image\/jpeg"}],"author":"proagrolab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"proagrolab","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/"},"author":{"name":"proagrolab","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444"},"headline":"Yauhar se reuni\u00f3 con industriales de la lecheria.","datePublished":"2012-01-19T00:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/"},"wordCount":635,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_sv1ujdecu__Lecheras-10.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/","url":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/","name":"Yauhar se reuni\u00f3 con industriales de la lecheria. | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_sv1ujdecu__Lecheras-10.jpg","datePublished":"2012-01-19T00:00:01+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_sv1ujdecu__Lecheras-10.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2015\/01\/g_sv1ujdecu__Lecheras-10.jpg","width":450,"height":208},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/yauhar-se-reunio-con-industriales-de-la-lecheria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Yauhar se reuni\u00f3 con industriales de la lecheria."}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/38003ff90bf80381f71c7d922d207444","name":"proagrolab"}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4693"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/4693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/1217"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}