{"id":11479,"date":"2019-05-31T18:07:07","date_gmt":"2019-05-31T18:07:07","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=11479"},"modified":"2019-05-31T19:30:00","modified_gmt":"2019-05-31T19:30:00","slug":"las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/","title":{"rendered":"Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20%"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p class=\"capital\">Una noticia positiva y otra negativa para el mercado de ganados y carnes. Por un lado, las ventas de carne vacuna a China, el mayor cliente del pa\u00eds, podr\u00edan crecer este a\u00f1o un 20%. Por otra parte, en 2020 el stock de vientres volver\u00eda a caer y lo har\u00eda un 0,3% luego de haber registrado una baja del 0,8% a marzo pasado.<\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/2838210w1033.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-11480 size-medium\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/2838210w1033-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/2838210w1033-300x200.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/2838210w1033-600x400.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/2838210w1033-768x512.jpg 768w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/2838210w1033-1024x682.jpg 1024w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/2838210w1033.jpg 1033w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Ambos datos los dio a conocer CREA (Consorcios Regionales de Experimentaci\u00f3n Agr\u00edcola), que organiz\u00f3 un Outlook Ganadero.<\/p>\n<p>El a\u00f1o pasado, seg\u00fan cifras del Instituto de Promoci\u00f3n de la Carne Vacuna Argentina (Ipcva), en peso producto se exportaron a China 206.607 toneladas (casi 310.000 toneladas llevadas a res con hueso), una suba del 115,2% respecto de 2017. China represent\u00f3 ventas por US$861,4 millones, sobre un total de US$1947,9 que entraron al pa\u00eds por la carne. En los primeros cuatro meses de 2019 a ese mercado se colocaron casi 92.727 toneladas, una mejora del 90,7 por ciento.<\/p>\n<p>Seg\u00fan CREA, China en todo el a\u00f1o se terminar\u00e1 llevando un 20 por ciento m\u00e1s que en 2018. Adem\u00e1s de la din\u00e1mica de compra que ya ten\u00eda ese mercado, por la mejora en la dieta de su poblaci\u00f3n, fundamentalmente de la clase media china, ahora se agreg\u00f3 el impacto de la peste porcina africana, que est\u00e1 provocando el sacrificio de millones de cerdos en ese pa\u00eds y derivando en una mayor presi\u00f3n de importaciones.<\/p>\n<p>Para destacar, los precios FOB promedio del conjunto de cortes de cogote, aguja y paleta (&#8220;chuck and blade&#8221;) destinados a China subieron un 27% en lo que va del a\u00f1o. El garr\u00f3n y brazuelo aumentaron 17%. Recientemente se hizo la feria SIAL en Shangh\u00e1i y all\u00ed los frigor\u00edficos argentinos vieron c\u00f3mo los precios subieron entre 1000 y 1500 d\u00f3lares la tonelada respecto de la anterior edici\u00f3n. Muchos frigor\u00edficos tienen negocios comprometidos ya hasta agosto y septiembre pr\u00f3ximo.<\/p>\n<div id=\"modalOverlay\">\u00a0<\/div>\n<figure id=\"figure_2938284\" class=\"L epigrafe\" data-is=\"imagen\"><picture><source srcset=\"\/\/bucket2.glanacion.com\/anexos\/fotos\/84\/2938284w740.jpg\" media=\"(min-width: 768px)\" \/><source srcset=\"\/\/bucket2.glanacion.com\/anexos\/fotos\/84\/2938284w768.jpg\" media=\"(min-width: 380px)\" \/><img decoding=\"async\" src=\"https:\/\/bucket2.glanacion.com\/anexos\/fotos\/84\/2938284w380.jpg\" alt=\"La peste porcina africana impacta sobre la producci\u00f3n de China\" \/><\/picture><figcaption>La peste porcina africana impacta sobre la producci\u00f3n de China\u00a0<span class=\"fuente\">Cr\u00e9dito: AP-Kin Cheung<\/span><\/figcaption><\/figure>\n<p>&#8220;China, si bien en los \u00faltimos a\u00f1os ya se ven\u00eda constituyendo como el principal comprador de carne argentina (y tambi\u00e9n del Mercosur), en 2019 seguir\u00e1 consolidando esa posici\u00f3n a partir del d\u00e9ficit de prote\u00ednas c\u00e1rnicas que experimentar\u00e1 por el impacto de la fiebre porcina africana, una enfermedad que oblig\u00f3 a la naci\u00f3n asi\u00e1tica a liquidar buena parte de su stock porcino&#8221;, indic\u00f3 CREA.<\/p>\n<p>Mientras tanto, seg\u00fan las cifras oficiales, a marzo pasado las existencias de vientres (vacas m\u00e1s vaquillonas) en la Argentina sumaban 31.053.342 cabezas, 259.073 animales menos que en igual mes de 2018. Hubo una baja del 0,8%.<\/p>\n<p>De acuerdo a la entidad, el pr\u00f3ximo a\u00f1o podr\u00eda haber otra reducci\u00f3n del 0,3%. Como motivo se destaca &#8220;la necesidad de generar liquidez en un contexto financiero restrictivo para el sector agropecuario&#8221;.<\/p>\n<figure id=\"figure_2838770\" class=\"L epigrafe\" data-is=\"imagen\"><picture><source srcset=\"\/\/bucket1.glanacion.com\/anexos\/fotos\/70\/2838770w740.jpg\" media=\"(min-width: 768px)\" \/><source srcset=\"\/\/bucket1.glanacion.com\/anexos\/fotos\/70\/2838770w768.jpg\" media=\"(min-width: 380px)\" \/><img decoding=\"async\" src=\"https:\/\/bucket1.glanacion.com\/anexos\/fotos\/70\/2838770w380.jpg\" alt=\"El stock de vientres podr\u00eda tener otra reducci\u00f3n\" \/><\/picture><figcaption>El stock de vientres podr\u00eda tener otra reducci\u00f3n<\/figcaption><\/figure>\n<p>CREA considera que la tasa de faena de hembras es muy alta, con un 52,5% sobre el total faenado en abril pasado, pero no ve necesariamente un proceso de liquidaci\u00f3n.<\/p>\n<p>&#8220;En el Outlook Ganadero CREA no se consider\u00f3 que eso necesariamente represente un proceso de liquidaci\u00f3n, dado que la cantidad nominal de vientres faenados se mantiene pr\u00e1cticamente constante; el crecimiento relativo obedece a una ca\u00edda importante de la faena de machos&#8221;, afirma.<\/p>\n<p>Luego explica: &#8220;La principal variable que explica la reducci\u00f3n de oferta es la aceleraci\u00f3n de la tasa de extracci\u00f3n de novillitos y novillos, la cual, mientras que en el per\u00edodo 2003\/2009 se ubic\u00f3 en un promedio de 71%, en 2010\/2015 creci\u00f3 hasta el 92% para alcanzar el 100% en 2016 y superar esa cifra a partir de 2017. Es decir: desde entonces se faenan terneros una vez liquidado todo el stock anual de novillitos y novillos&#8221;.<\/p>\n<div class=\"firma\">Por:\u00a0<a href=\"https:\/\/www.lanacion.com.ar\/autor\/fernando-bertello-228\">Fernando Bertello<\/a><\/div>\n<div>Fuente:\u00a0https:\/\/www.lanacion.com.ar\/economia\/campo\/las-exportaciones-carne-vacuna-china-siguen-imparables-nid2253418<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Una noticia positiva y otra negativa para el mercado de ganados y carnes. Por un lado, las ventas de carne vacuna a China, el mayor cliente del pa\u00eds, podr\u00edan crecer este a\u00f1o un 20%. Por otra parte, en 2020 el stock de vientres volver\u00eda a caer y lo har\u00eda un 0,3% luego de haber registrado una baja del 0,8% a marzo pasado. Ambos datos los dio a conocer CREA (Consorcios Regionales de Experimentaci\u00f3n Agr\u00edcola), que organiz\u00f3 un Outlook Ganadero. El a\u00f1o pasado, seg\u00fan cifras del Instituto de Promoci\u00f3n de la Carne Vacuna Argentina (Ipcva), en peso producto se exportaron a China 206.607 toneladas (casi 310.000 toneladas llevadas a res con hueso), una suba del 115,2% respecto de 2017. China represent\u00f3 ventas por US$861,4 millones, sobre un total de US$1947,9 que entraron al pa\u00eds por la carne. En los primeros cuatro meses de 2019 a ese mercado se colocaron casi 92.727 toneladas, una mejora del 90,7 por ciento. Seg\u00fan CREA, China en todo el a\u00f1o se terminar\u00e1 llevando un 20 por ciento m\u00e1s que en 2018. Adem\u00e1s de la din\u00e1mica de compra que ya ten\u00eda ese mercado, por la mejora en la dieta de su poblaci\u00f3n, fundamentalmente de la clase media [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11482,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-11479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20% | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20% | Proagro\" \/>\n<meta property=\"og:description\" content=\"Una noticia positiva y otra negativa para el mercado de ganados y carnes. Por un lado, las ventas de carne vacuna a China, el mayor cliente del pa\u00eds, podr\u00edan crecer este a\u00f1o un 20%. Por otra parte, en 2020 el stock de vientres volver\u00eda a caer y lo har\u00eda un 0,3% luego de haber registrado una baja del 0,8% a marzo pasado. Ambos datos los dio a conocer CREA (Consorcios Regionales de Experimentaci\u00f3n Agr\u00edcola), que organiz\u00f3 un Outlook Ganadero. El a\u00f1o pasado, seg\u00fan cifras del Instituto de Promoci\u00f3n de la Carne Vacuna Argentina (Ipcva), en peso producto se exportaron a China 206.607 toneladas (casi 310.000 toneladas llevadas a res con hueso), una suba del 115,2% respecto de 2017. China represent\u00f3 ventas por US$861,4 millones, sobre un total de US$1947,9 que entraron al pa\u00eds por la carne. En los primeros cuatro meses de 2019 a ese mercado se colocaron casi 92.727 toneladas, una mejora del 90,7 por ciento. Seg\u00fan CREA, China en todo el a\u00f1o se terminar\u00e1 llevando un 20 por ciento m\u00e1s que en 2018. Adem\u00e1s de la din\u00e1mica de compra que ya ten\u00eda ese mercado, por la mejora en la dieta de su poblaci\u00f3n, fundamentalmente de la clase media [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-31T18:07:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-31T19:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/infoganadero-31052019-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20%\",\"datePublished\":\"2019-05-31T18:07:07+00:00\",\"dateModified\":\"2019-05-31T19:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/\"},\"wordCount\":661,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/infoganadero-31052019-1.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/\",\"name\":\"Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20% | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/infoganadero-31052019-1.jpg\",\"datePublished\":\"2019-05-31T18:07:07+00:00\",\"dateModified\":\"2019-05-31T19:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/infoganadero-31052019-1.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/infoganadero-31052019-1.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20% | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/","og_locale":"en_US","og_type":"article","og_title":"Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20% | Proagro","og_description":"Una noticia positiva y otra negativa para el mercado de ganados y carnes. Por un lado, las ventas de carne vacuna a China, el mayor cliente del pa\u00eds, podr\u00edan crecer este a\u00f1o un 20%. Por otra parte, en 2020 el stock de vientres volver\u00eda a caer y lo har\u00eda un 0,3% luego de haber registrado una baja del 0,8% a marzo pasado. Ambos datos los dio a conocer CREA (Consorcios Regionales de Experimentaci\u00f3n Agr\u00edcola), que organiz\u00f3 un Outlook Ganadero. El a\u00f1o pasado, seg\u00fan cifras del Instituto de Promoci\u00f3n de la Carne Vacuna Argentina (Ipcva), en peso producto se exportaron a China 206.607 toneladas (casi 310.000 toneladas llevadas a res con hueso), una suba del 115,2% respecto de 2017. China represent\u00f3 ventas por US$861,4 millones, sobre un total de US$1947,9 que entraron al pa\u00eds por la carne. En los primeros cuatro meses de 2019 a ese mercado se colocaron casi 92.727 toneladas, una mejora del 90,7 por ciento. Seg\u00fan CREA, China en todo el a\u00f1o se terminar\u00e1 llevando un 20 por ciento m\u00e1s que en 2018. Adem\u00e1s de la din\u00e1mica de compra que ya ten\u00eda ese mercado, por la mejora en la dieta de su poblaci\u00f3n, fundamentalmente de la clase media [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2019-05-31T18:07:07+00:00","article_modified_time":"2019-05-31T19:30:00+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/infoganadero-31052019-1.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20%","datePublished":"2019-05-31T18:07:07+00:00","dateModified":"2019-05-31T19:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/"},"wordCount":661,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/infoganadero-31052019-1.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/","url":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/","name":"Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20% | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/infoganadero-31052019-1.jpg","datePublished":"2019-05-31T18:07:07+00:00","dateModified":"2019-05-31T19:30:00+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/infoganadero-31052019-1.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/05\/infoganadero-31052019-1.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-carne-vacuna-a-china-siguen-imparables-y-podrian-crecer-otro-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Las exportaciones de carne vacuna a China siguen imparables y podr\u00edan crecer otro 20%"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=11479"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/11482"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=11479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=11479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=11479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}