{"id":11177,"date":"2019-03-15T13:05:19","date_gmt":"2019-03-15T13:05:19","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=11177"},"modified":"2019-03-15T13:52:56","modified_gmt":"2019-03-15T13:52:56","slug":"la-vaquillona-comienza-a-recuperar-su-valor-historico","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/","title":{"rendered":"La vaquillona comienza a recuperar su valor hist\u00f3rico"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>La vaquillona de tambo ya se acerca a su valor hist\u00f3rico de 5.000 litros de leche. Se evidenci\u00f3 en dos remates en La Playosa y Pozo del Molle.<\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/5c71ac9bada9f_837_627.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-11178 size-medium\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/5c71ac9bada9f_837_627-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/5c71ac9bada9f_837_627-300x225.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/5c71ac9bada9f_837_627-600x449.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/5c71ac9bada9f_837_627-768x575.jpg 768w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/5c71ac9bada9f_837_627.jpg 837w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>En un remate realizado en la Sociedad Rural de Pozo del Molle, y organizado por Remates Rurales SA. donde se vendieron 835 ejemplares Holando en poco m\u00e1s de 2 horas, la vaquillona de tambo, marca l\u00edquida, libre de brucelosis y tuberculosis se comercializ\u00f3 con un promedio de 5.000 litros de leche.<\/p>\n<p>Esto significa que al valor de febrero ($10,40 el litro promedio), la vaquillona promedi\u00f3 los $52.000, aunque los mejores ejemplares promediaron los $55.000.<\/p>\n<p>Oscar Mercol, martillero de la firma consignataria indic\u00f3 a TodoAgro cu\u00e1les son los elementos que est\u00e1n jugando a favor de una recomposici\u00f3n del precio: &#8220;Ha llovido bien, los productores han hecho buenas reservas, la leche est\u00e1 muy buscada y ya est\u00e1 en 11 y 12 pesos el litros&#8221;.<\/p>\n<p>La vaquillona pre\u00f1ada o parida, marca l\u00edquida, de buena calidad -que es lo que entra en nuestros remates de Pozo del Molle, dijo Mercol- se vendi\u00f3 entre $55.000 y $57.000, las vaquillonas m\u00e1s atrasadas en torno a los $45.000, las vaquillonas para entorar en torno a los $20.000, y la vaca de tambo hizo un promedio de $40.000 (vacas secas y paridas). Las terneras en tanto se vendieron a un promedio de $70 el kilo. &#8220;Si ten\u00eda 500 piezas m\u00e1s, las vend\u00eda sin problemas&#8221;.<\/p>\n<p>Las ventas se realizaron con plazos de 6 cuotas, y en casos de compras mayores (m\u00e1s de 28 animales), los plazos se extienden a 8 cuotas, y los productores compradores eran de Canals, Pozo del Molle, Villa Mar\u00eda, Morteros y de zonas productoras de Entre R\u00edos.<\/p>\n<p>El martillero destac\u00f3 la calidad de lo que se comercializ\u00f3 y aport\u00f3 otro elemento que juega a favor de la agilidad de las ventas de vaquillonas, que es el buen precio de la vaca gorda, que est\u00e1 en torno a los $42 el kilo. &#8220;Nunca se dio que con 2 vacas gordas puedas comprar una vaquillona de calidad&#8221;.<\/p>\n<p>Precios m\u00e1s bajos, aunque con una hacienda de menor calidad se lograron en las instalaciones de la firma Scaglia de Villa Nueva (C\u00f3rdoba) el mismo viernes 1 de marzo, donde se vendieron m\u00e1s de 300 ejemplares. Las vaquillonas de acopio, promediaron $42.000, aunque hab\u00eda algunos conjuntos provenientes de tambos en saneamiento, en tanto las vacas (provenientes de un tambo en saneamiento) apenas superaron los $30.000.<\/p>\n<p><b>BUENOS PRECIOS<\/b><\/p>\n<p>Los primeros indicios de la recuperaci\u00f3n del precio de la vaquillona se dieron en el remate escenificado una semana antes en la localidad de La Playosa donde 10 activos compradores (Rosso Fabricio y Federico, Salort, Sagaro SA, Marcelo Fabro, El Productor SRL, Elvira Julia SRL, Hugo Ciorda y Los Macollos, entre otros), compraron 536 animales.<\/p>\n<p>En ese \u00e1gil remate, organizado por la Cooperativa Guillermo Lehmann, el martillero Miguel Romano, vendi\u00f3 lotes de punta de buena calidad a $55.000, aunque el promedio de las vaquillonas buena estuvo apenas debajo de los $50.000, y el promedio general donde entran muchas vaquillonas de acopio y algunas atrasadas, fue de $39.554.<\/p>\n<p>Si bien es claro que los productores est\u00e1n desfinanciados y con falta de l\u00edquido, el remate fue \u00e1gil y los precios se entonaron con relaci\u00f3n a las primeras ventas de 2019. Los lotes de punta promediaron $55.000, la vaquillona de acopio, de menor calidad se movi\u00f3 entre $40.000 y $44.000, la vaquillona para entorar, entre $20.000 y $24.000, mientras la vaca de tambo se vendi\u00f3 entre $30.000 y $33.000 y la ternera se pag\u00f3 entre $70 y $80. &#8220;Cabe destacar que en esta semana hicimos 3 negocios ajustable a 5.000 litros de leche&#8221;, indic\u00f3 Romano.<\/p>\n<p><b>PROXIMOS REMATES<\/b><\/p>\n<p>UNO EN RAFAELA<\/p>\n<p>A juicio del experimentado martillero, el remate del pr\u00f3ximo 22 de marzo en Las Tunas (Santa Fe), organizado por la AUT-Milkaut, ser\u00e1 un buen term\u00f3metro, al igual que el remate especial del mi\u00e9rcoles 17 de Abril en la Sociedad Rural de Rafaela donde se llevar\u00e1 a cabo el Remate Especial Holando Argentino &#8220;La Vigilancia&#8221; organizado por la firma Agramin junto con la Cooperativa Guillermo Lehmann. Se subastar\u00e1n 80 vaquillonas y 25 toros con prueba gen\u00f3mica oficial y destacados \u00edndices.<\/p>\n<p>Fuente:\u00a0http:\/\/www.revistachacra.com.ar\/\/nota\/25621-la-vaquillona-comienza-a-recuperar-su-valor-historico\/<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La vaquillona de tambo ya se acerca a su valor hist\u00f3rico de 5.000 litros de leche. Se evidenci\u00f3 en dos remates en La Playosa y Pozo del Molle. &nbsp; En un remate realizado en la Sociedad Rural de Pozo del Molle, y organizado por Remates Rurales SA. donde se vendieron 835 ejemplares Holando en poco m\u00e1s de 2 horas, la vaquillona de tambo, marca l\u00edquida, libre de brucelosis y tuberculosis se comercializ\u00f3 con un promedio de 5.000 litros de leche. Esto significa que al valor de febrero ($10,40 el litro promedio), la vaquillona promedi\u00f3 los $52.000, aunque los mejores ejemplares promediaron los $55.000. Oscar Mercol, martillero de la firma consignataria indic\u00f3 a TodoAgro cu\u00e1les son los elementos que est\u00e1n jugando a favor de una recomposici\u00f3n del precio: &#8220;Ha llovido bien, los productores han hecho buenas reservas, la leche est\u00e1 muy buscada y ya est\u00e1 en 11 y 12 pesos el litros&#8221;. La vaquillona pre\u00f1ada o parida, marca l\u00edquida, de buena calidad -que es lo que entra en nuestros remates de Pozo del Molle, dijo Mercol- se vendi\u00f3 entre $55.000 y $57.000, las vaquillonas m\u00e1s atrasadas en torno a los $45.000, las vaquillonas para entorar en torno a los $20.000, y [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11186,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-11177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vaquillona comienza a recuperar su valor hist\u00f3rico | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vaquillona comienza a recuperar su valor hist\u00f3rico | Proagro\" \/>\n<meta property=\"og:description\" content=\"La vaquillona de tambo ya se acerca a su valor hist\u00f3rico de 5.000 litros de leche. Se evidenci\u00f3 en dos remates en La Playosa y Pozo del Molle. &nbsp; En un remate realizado en la Sociedad Rural de Pozo del Molle, y organizado por Remates Rurales SA. donde se vendieron 835 ejemplares Holando en poco m\u00e1s de 2 horas, la vaquillona de tambo, marca l\u00edquida, libre de brucelosis y tuberculosis se comercializ\u00f3 con un promedio de 5.000 litros de leche. Esto significa que al valor de febrero ($10,40 el litro promedio), la vaquillona promedi\u00f3 los $52.000, aunque los mejores ejemplares promediaron los $55.000. Oscar Mercol, martillero de la firma consignataria indic\u00f3 a TodoAgro cu\u00e1les son los elementos que est\u00e1n jugando a favor de una recomposici\u00f3n del precio: &#8220;Ha llovido bien, los productores han hecho buenas reservas, la leche est\u00e1 muy buscada y ya est\u00e1 en 11 y 12 pesos el litros&#8221;. La vaquillona pre\u00f1ada o parida, marca l\u00edquida, de buena calidad -que es lo que entra en nuestros remates de Pozo del Molle, dijo Mercol- se vendi\u00f3 entre $55.000 y $57.000, las vaquillonas m\u00e1s atrasadas en torno a los $45.000, las vaquillonas para entorar en torno a los $20.000, y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-15T13:05:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-15T13:52:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/15032019-1145x395-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"La vaquillona comienza a recuperar su valor hist\u00f3rico\",\"datePublished\":\"2019-03-15T13:05:19+00:00\",\"dateModified\":\"2019-03-15T13:52:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/\"},\"wordCount\":693,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/15032019-1145x395-.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/\",\"name\":\"La vaquillona comienza a recuperar su valor hist\u00f3rico | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/15032019-1145x395-.jpg\",\"datePublished\":\"2019-03-15T13:05:19+00:00\",\"dateModified\":\"2019-03-15T13:52:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/15032019-1145x395-.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/15032019-1145x395-.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-vaquillona-comienza-a-recuperar-su-valor-historico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vaquillona comienza a recuperar su valor hist\u00f3rico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vaquillona comienza a recuperar su valor hist\u00f3rico | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/","og_locale":"en_US","og_type":"article","og_title":"La vaquillona comienza a recuperar su valor hist\u00f3rico | Proagro","og_description":"La vaquillona de tambo ya se acerca a su valor hist\u00f3rico de 5.000 litros de leche. Se evidenci\u00f3 en dos remates en La Playosa y Pozo del Molle. &nbsp; En un remate realizado en la Sociedad Rural de Pozo del Molle, y organizado por Remates Rurales SA. donde se vendieron 835 ejemplares Holando en poco m\u00e1s de 2 horas, la vaquillona de tambo, marca l\u00edquida, libre de brucelosis y tuberculosis se comercializ\u00f3 con un promedio de 5.000 litros de leche. Esto significa que al valor de febrero ($10,40 el litro promedio), la vaquillona promedi\u00f3 los $52.000, aunque los mejores ejemplares promediaron los $55.000. Oscar Mercol, martillero de la firma consignataria indic\u00f3 a TodoAgro cu\u00e1les son los elementos que est\u00e1n jugando a favor de una recomposici\u00f3n del precio: &#8220;Ha llovido bien, los productores han hecho buenas reservas, la leche est\u00e1 muy buscada y ya est\u00e1 en 11 y 12 pesos el litros&#8221;. La vaquillona pre\u00f1ada o parida, marca l\u00edquida, de buena calidad -que es lo que entra en nuestros remates de Pozo del Molle, dijo Mercol- se vendi\u00f3 entre $55.000 y $57.000, las vaquillonas m\u00e1s atrasadas en torno a los $45.000, las vaquillonas para entorar en torno a los $20.000, y [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2019-03-15T13:05:19+00:00","article_modified_time":"2019-03-15T13:52:56+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/15032019-1145x395-.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"La vaquillona comienza a recuperar su valor hist\u00f3rico","datePublished":"2019-03-15T13:05:19+00:00","dateModified":"2019-03-15T13:52:56+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/"},"wordCount":693,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/15032019-1145x395-.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/","url":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/","name":"La vaquillona comienza a recuperar su valor hist\u00f3rico | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/15032019-1145x395-.jpg","datePublished":"2019-03-15T13:05:19+00:00","dateModified":"2019-03-15T13:52:56+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/15032019-1145x395-.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/15032019-1145x395-.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/la-vaquillona-comienza-a-recuperar-su-valor-historico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"La vaquillona comienza a recuperar su valor hist\u00f3rico"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=11177"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/11186"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=11177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=11177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=11177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}