{"id":11148,"date":"2019-03-01T13:39:54","date_gmt":"2019-03-01T13:39:54","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=11148"},"modified":"2019-03-01T14:53:55","modified_gmt":"2019-03-01T14:53:55","slug":"carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/","title":{"rendered":"Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Los japoneses pagan valores altos por cortes enfriados y achuras como la lengua. En EE.UU. m\u00e1s del 50% de la carne se consume picada.\u00a0<\/p>\n<p><strong>Por Ignacio Iriarte<\/strong><\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/B1_9SAkwx_1256x620.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-11149 size-medium\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/B1_9SAkwx_1256x620-300x148.jpg\" alt=\"\" width=\"300\" height=\"148\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/B1_9SAkwx_1256x620-300x148.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/B1_9SAkwx_1256x620-600x296.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/B1_9SAkwx_1256x620-768x379.jpg 768w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/B1_9SAkwx_1256x620-1024x505.jpg 1024w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/B1_9SAkwx_1256x620.jpg 1256w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Uruguay har\u00e1 en las pr\u00f3ximas semanas sus primeros embarques de carne vacuna a Jap\u00f3n.\u00a0<strong>La carne uruguaya de feedlot deber\u00e1 competir con la de Australia y Estados Unidos<\/strong>, cuyos cortes de abundante marbling est\u00e1n muy impuestos hace d\u00e9cadas entre los consumidores japoneses.<\/p>\n<p>Se piensa en el vecino pa\u00eds que se dar\u00e1n oportunidades, al principio en peque\u00f1os vol\u00famenes, tanto para la carne a grano como para la de pasto,<strong>\u00a0nicho este \u00faltimo en que Uruguay podr\u00eda tener ventajas.<\/strong>\u00a0Adem\u00e1s, se proyecta una r\u00e1pida concreci\u00f3n de negocios con carne manufactura para hamburguesas, producto muy difundido en Jap\u00f3n.<\/p>\n<p>Uruguay tiene como desventaja en relaci\u00f3n a Australia \u2013el competidor m\u00e1s probable\u2013\u00a0<strong>los altos aranceles\u00a0<\/strong>que deber\u00e1 pagar para la introducci\u00f3n de la carne: 38,5 por ciento ad valorem, contra 27 que paga Australia, que tiene un TLC con Jap\u00f3n. Adem\u00e1s, y esto es muy importante en el caso del enfriado, hay 45-50 d\u00edas de flete mar\u00edtimo, que reduce mucho la \u201cventana\u201d de vida \u00fatil de los cortes envasados al vac\u00edo.<\/p>\n<p>Jap\u00f3n consume 1,32 millones de toneladas anuales, de las cuales 60 por ciento (unas 860 mil toneladas) son importadas.\u00a0<strong>Paga valores muy altos por los cortes enfriados<\/strong>, en especial de feedlot, que compra a Estados Unidos y Australia.<\/p>\n<p>En el acuerdo sanitario entre Jap\u00f3n y Uruguay, qued\u00f3 fuera la admisi\u00f3n de algunas menudencias, entre ellas la lengua, que tiene una alta demanda \u2013como delicatessen\u2013 y altos precios: cuando hace unos 15 a\u00f1os, a causa de la BSE en Estados Unidos faltaron lenguas de ese pa\u00eds,\u00a0<strong>el kilo de esta achura en el mercado japon\u00e9s lleg\u00f3 a los 33 d\u00f3lares por kilo.<\/strong><\/p>\n<p><strong>En Estados Unidos, entre 50 y 60 por ciento de la carne vacuna se consume bajo la forma de picada<\/strong>, con destino a la fabricaci\u00f3n de hamburguesas, pan de carne, alb\u00f3ndigas (meatballs) o chacinados.<\/p>\n<p>La demanda creciente por carne magra para picar no puede ser satisfecha totalmente con la oferta local de carne de vaca, de toro, o de cortes magros de novillos. Esto obliga a Estados Unidos a\u00a0<strong>importar 1,3 millones de toneladas anuales de carne magra\u00a0<\/strong>(90 CL) para mezclar con los cortes y trimmings ultragrasos (50 por ciento grasa y el resto) que es lo que produce la mayor\u00eda de la industria frigor\u00edfica.<\/p>\n<p>Muchos analistas cuestionan el hecho de que en la b\u00fasqueda de un novillo con el mayor marbling posible, y con el aumento del peso de faena registrado en los \u00faltimos a\u00f1os, se llega a novillos y vaquillonas con un elevado desperdicio de grasa; el mercado premia el engrasamiento en los cortes finos (ribs &amp; loins), pero en el resto de la res, que es la mayor parte,\u00a0<strong>necesita cortes magros para satisfacer la creciente demanda por hamburguesas.<\/strong><\/p>\n<p>Hace un tiempo, un destacado profesor universitario y analista del mercado ganadero, sugiri\u00f3 la necesidad de producir (y tipificar) un nuevo novillo, criado enteramente a pasto, a bajo costo, que su totalidad (todos los cortes) sirviera\u00a0<strong>para satisfacer la demanda creciente por carne magra.<\/strong><\/p>\n<p>Fuente: Especial de La Voz para\u00a0<strong>Clar\u00edn Rural.\u200b\u00a0https:\/\/www.clarin.com\/rural\/carne-japon-unidos-mercados-demanda-bien-diferenciada_0_Nv7c9tgwB.html<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Los japoneses pagan valores altos por cortes enfriados y achuras como la lengua. En EE.UU. m\u00e1s del 50% de la carne se consume picada.\u00a0 Por Ignacio Iriarte Uruguay har\u00e1 en las pr\u00f3ximas semanas sus primeros embarques de carne vacuna a Jap\u00f3n.\u00a0La carne uruguaya de feedlot deber\u00e1 competir con la de Australia y Estados Unidos, cuyos cortes de abundante marbling est\u00e1n muy impuestos hace d\u00e9cadas entre los consumidores japoneses. Se piensa en el vecino pa\u00eds que se dar\u00e1n oportunidades, al principio en peque\u00f1os vol\u00famenes, tanto para la carne a grano como para la de pasto,\u00a0nicho este \u00faltimo en que Uruguay podr\u00eda tener ventajas.\u00a0Adem\u00e1s, se proyecta una r\u00e1pida concreci\u00f3n de negocios con carne manufactura para hamburguesas, producto muy difundido en Jap\u00f3n. Uruguay tiene como desventaja en relaci\u00f3n a Australia \u2013el competidor m\u00e1s probable\u2013\u00a0los altos aranceles\u00a0que deber\u00e1 pagar para la introducci\u00f3n de la carne: 38,5 por ciento ad valorem, contra 27 que paga Australia, que tiene un TLC con Jap\u00f3n. Adem\u00e1s, y esto es muy importante en el caso del enfriado, hay 45-50 d\u00edas de flete mar\u00edtimo, que reduce mucho la \u201cventana\u201d de vida \u00fatil de los cortes envasados al vac\u00edo. Jap\u00f3n consume 1,32 millones de toneladas anuales, de las cuales 60 por [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11154,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-11148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada | Proagro\" \/>\n<meta property=\"og:description\" content=\"Los japoneses pagan valores altos por cortes enfriados y achuras como la lengua. En EE.UU. m\u00e1s del 50% de la carne se consume picada.\u00a0 Por Ignacio Iriarte Uruguay har\u00e1 en las pr\u00f3ximas semanas sus primeros embarques de carne vacuna a Jap\u00f3n.\u00a0La carne uruguaya de feedlot deber\u00e1 competir con la de Australia y Estados Unidos, cuyos cortes de abundante marbling est\u00e1n muy impuestos hace d\u00e9cadas entre los consumidores japoneses. Se piensa en el vecino pa\u00eds que se dar\u00e1n oportunidades, al principio en peque\u00f1os vol\u00famenes, tanto para la carne a grano como para la de pasto,\u00a0nicho este \u00faltimo en que Uruguay podr\u00eda tener ventajas.\u00a0Adem\u00e1s, se proyecta una r\u00e1pida concreci\u00f3n de negocios con carne manufactura para hamburguesas, producto muy difundido en Jap\u00f3n. Uruguay tiene como desventaja en relaci\u00f3n a Australia \u2013el competidor m\u00e1s probable\u2013\u00a0los altos aranceles\u00a0que deber\u00e1 pagar para la introducci\u00f3n de la carne: 38,5 por ciento ad valorem, contra 27 que paga Australia, que tiene un TLC con Jap\u00f3n. Adem\u00e1s, y esto es muy importante en el caso del enfriado, hay 45-50 d\u00edas de flete mar\u00edtimo, que reduce mucho la \u201cventana\u201d de vida \u00fatil de los cortes envasados al vac\u00edo. Jap\u00f3n consume 1,32 millones de toneladas anuales, de las cuales 60 por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-01T13:39:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-01T14:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/25022019-1145x395-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada\",\"datePublished\":\"2019-03-01T13:39:54+00:00\",\"dateModified\":\"2019-03-01T14:53:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/\"},\"wordCount\":579,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/25022019-1145x395-.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/\",\"name\":\"Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/25022019-1145x395-.jpg\",\"datePublished\":\"2019-03-01T13:39:54+00:00\",\"dateModified\":\"2019-03-01T14:53:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/25022019-1145x395-.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/25022019-1145x395-.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/","og_locale":"en_US","og_type":"article","og_title":"Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada | Proagro","og_description":"Los japoneses pagan valores altos por cortes enfriados y achuras como la lengua. En EE.UU. m\u00e1s del 50% de la carne se consume picada.\u00a0 Por Ignacio Iriarte Uruguay har\u00e1 en las pr\u00f3ximas semanas sus primeros embarques de carne vacuna a Jap\u00f3n.\u00a0La carne uruguaya de feedlot deber\u00e1 competir con la de Australia y Estados Unidos, cuyos cortes de abundante marbling est\u00e1n muy impuestos hace d\u00e9cadas entre los consumidores japoneses. Se piensa en el vecino pa\u00eds que se dar\u00e1n oportunidades, al principio en peque\u00f1os vol\u00famenes, tanto para la carne a grano como para la de pasto,\u00a0nicho este \u00faltimo en que Uruguay podr\u00eda tener ventajas.\u00a0Adem\u00e1s, se proyecta una r\u00e1pida concreci\u00f3n de negocios con carne manufactura para hamburguesas, producto muy difundido en Jap\u00f3n. Uruguay tiene como desventaja en relaci\u00f3n a Australia \u2013el competidor m\u00e1s probable\u2013\u00a0los altos aranceles\u00a0que deber\u00e1 pagar para la introducci\u00f3n de la carne: 38,5 por ciento ad valorem, contra 27 que paga Australia, que tiene un TLC con Jap\u00f3n. Adem\u00e1s, y esto es muy importante en el caso del enfriado, hay 45-50 d\u00edas de flete mar\u00edtimo, que reduce mucho la \u201cventana\u201d de vida \u00fatil de los cortes envasados al vac\u00edo. Jap\u00f3n consume 1,32 millones de toneladas anuales, de las cuales 60 por [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2019-03-01T13:39:54+00:00","article_modified_time":"2019-03-01T14:53:55+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/25022019-1145x395-.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada","datePublished":"2019-03-01T13:39:54+00:00","dateModified":"2019-03-01T14:53:55+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/"},"wordCount":579,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/25022019-1145x395-.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/","url":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/","name":"Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/25022019-1145x395-.jpg","datePublished":"2019-03-01T13:39:54+00:00","dateModified":"2019-03-01T14:53:55+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/25022019-1145x395-.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/03\/25022019-1145x395-.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/carne-japon-y-estados-unidos-dos-mercados-con-una-demanda-bien-diferenciada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Carne: Jap\u00f3n y Estados Unidos, dos mercados con una demanda bien diferenciada"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=11148"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/11154"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=11148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=11148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=11148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}