{"id":11138,"date":"2019-02-22T14:42:30","date_gmt":"2019-02-22T14:42:30","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=11138"},"modified":"2019-02-22T19:21:51","modified_gmt":"2019-02-22T19:21:51","slug":"jujuy-apuesta-a-la-genetica-para-mejorar-su-carne","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/","title":{"rendered":"Jujuy apuesta a la gen\u00e9tica para mejorar su carne"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>En el marco de un plan provincial, peque\u00f1os productores ganaderos recibieron reproductores Braford y Bonsmara para mejorar las cualidades carniceras de sus rodeos.<\/p>\n<p>Peque\u00f1os productores de ganado bovino de Jujuy\u00a0<strong>lograron los primeros nacimientos de teneros con gen\u00e9tica de alta calidad<\/strong>, en el marco de un plan provincial de fomento del sector por el que fueron entregados terneros machos Braford y Bonsmara, informaron hoy autoridades del ministerio de Desarrollo Econ\u00f3mico provincial.<\/p>\n<p>El \u00e9xito\u00a0del plan de mejoramiento gen\u00e9tico se produjo por la\u00a0<strong>cesi\u00f3n de terneros pr\u00f3ximos a servicio en vez de toros<\/strong>, que fueron adquiridos en la provincia sorteando los riesgos de mortandad en lo que tiene que ver con la adaptaci\u00f3n a la zona, explic\u00f3 a la agencia\u00a0T\u00e9lam el director provincial de Desarrollo Ganadero, Javier Giubergia.<\/p>\n<p>&#8220;La gen\u00e9tica la estamos comprando en Jujuy, con animales ya adaptados, que fue uno de los fracasos en otras provincias del noroeste, donde a su vez se otorgaron toros, mientras nosotros entregamos terneros y el productor deb\u00eda cuidarlos hasta reci\u00e9n largarlos a servicio&#8221;, detall\u00f3 Giubergia.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger pointer\" data-index=\"1\">\n<figure><img decoding=\"async\" src=\"https:\/\/images.clarin.com\/2018\/09\/24\/aXS51t8xj_720x0__1.jpg\" alt=\"La raza Bonsmara tiene mucho potencial en el norte del pa\u00eds.\" data-big=\"https:\/\/images.clarin.com\/2018\/09\/24\/aXS51t8xj_720x0__1.jpg\" data-small=\"https:\/\/images.clarin.com\/2018\/09\/24\/aXS51t8xj_720x0__1.jpg\" data-observer-function=\"loadLazyImg\" \/><i class=\"fa fa-circle fa-stack-2x icon-background1\"><\/i><i class=\"fa fa-circle-o fa-stack-2x icon-background2\"><\/i><\/figure>\n<p><strong>Unos 150 establecimientos ya fueron beneficiados con la entrega de animales en 2018 y se prev\u00e9 pr\u00f3ximamente una entrega a otros 44 de terneros Braford, Bangus y sus cruzas<\/strong>, la mitad de ellos adquiridos a trav\u00e9s de una inversi\u00f3n de unos 400 mil pesos y la otra producidos en campos experimentales a los que apost\u00f3 la provincia.<\/p>\n<p>Las zonas beneficiadas est\u00e1n ubicadas hacia el este y el sur provincial, entre los departamentos de Santa B\u00e1rbara, Valle Grande y San Antonio, donde se concentran unos 200 productores de bovinos, la mayor\u00eda de ellos con un ganado criollo que es muy castigado cuando va a realizar la venta de su carne.<\/p>\n<p>&#8220;Lo que pretendemos es potenciar\u00a0<strong>un choque h\u00edbrido que mejore el cuarto trasero del animal, la cantidad de kilos de carnes que se pueden obtener<\/strong>&#8220;, sostuvo Giubergia sobre los objetivos del plan y se\u00f1al\u00f3 que se impulsa armar una red para trabajar en el tema de pasturas, sanidad y la regularizaci\u00f3n de la situaci\u00f3n de los productores.<\/p>\n<p>Al poner en valor la &#8220;satisfacci\u00f3n&#8221; de contar con los primeros nacimientos, que aseguran que &#8220;ya le quede la gen\u00e9tica en su campo al productor&#8221;, el funcionario dijo que se proyecta la reproducci\u00f3n de ejemplares para el termino de cuatro a\u00f1os, plazo en el que los productores deben cambiar sus toros y la provincia pueda proveerselos.<\/p>\n<p>Fuente:\u00a0https:\/\/www.clarin.com\/rural\/jujuy-apuesta-genetica-mejorar-carne_0_DT3eV6eMn.html<\/p>\n<\/div>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>En el marco de un plan provincial, peque\u00f1os productores ganaderos recibieron reproductores Braford y Bonsmara para mejorar las cualidades carniceras de sus rodeos. Peque\u00f1os productores de ganado bovino de Jujuy\u00a0lograron los primeros nacimientos de teneros con gen\u00e9tica de alta calidad, en el marco de un plan provincial de fomento del sector por el que fueron entregados terneros machos Braford y Bonsmara, informaron hoy autoridades del ministerio de Desarrollo Econ\u00f3mico provincial. El \u00e9xito\u00a0del plan de mejoramiento gen\u00e9tico se produjo por la\u00a0cesi\u00f3n de terneros pr\u00f3ximos a servicio en vez de toros, que fueron adquiridos en la provincia sorteando los riesgos de mortandad en lo que tiene que ver con la adaptaci\u00f3n a la zona, explic\u00f3 a la agencia\u00a0T\u00e9lam el director provincial de Desarrollo Ganadero, Javier Giubergia. &#8220;La gen\u00e9tica la estamos comprando en Jujuy, con animales ya adaptados, que fue uno de los fracasos en otras provincias del noroeste, donde a su vez se otorgaron toros, mientras nosotros entregamos terneros y el productor deb\u00eda cuidarlos hasta reci\u00e9n largarlos a servicio&#8221;, detall\u00f3 Giubergia. Unos 150 establecimientos ya fueron beneficiados con la entrega de animales en 2018 y se prev\u00e9 pr\u00f3ximamente una entrega a otros 44 de terneros Braford, Bangus y sus cruzas, la mitad [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11143,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-11138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jujuy apuesta a la gen\u00e9tica para mejorar su carne | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jujuy apuesta a la gen\u00e9tica para mejorar su carne | Proagro\" \/>\n<meta property=\"og:description\" content=\"En el marco de un plan provincial, peque\u00f1os productores ganaderos recibieron reproductores Braford y Bonsmara para mejorar las cualidades carniceras de sus rodeos. Peque\u00f1os productores de ganado bovino de Jujuy\u00a0lograron los primeros nacimientos de teneros con gen\u00e9tica de alta calidad, en el marco de un plan provincial de fomento del sector por el que fueron entregados terneros machos Braford y Bonsmara, informaron hoy autoridades del ministerio de Desarrollo Econ\u00f3mico provincial. El \u00e9xito\u00a0del plan de mejoramiento gen\u00e9tico se produjo por la\u00a0cesi\u00f3n de terneros pr\u00f3ximos a servicio en vez de toros, que fueron adquiridos en la provincia sorteando los riesgos de mortandad en lo que tiene que ver con la adaptaci\u00f3n a la zona, explic\u00f3 a la agencia\u00a0T\u00e9lam el director provincial de Desarrollo Ganadero, Javier Giubergia. &#8220;La gen\u00e9tica la estamos comprando en Jujuy, con animales ya adaptados, que fue uno de los fracasos en otras provincias del noroeste, donde a su vez se otorgaron toros, mientras nosotros entregamos terneros y el productor deb\u00eda cuidarlos hasta reci\u00e9n largarlos a servicio&#8221;, detall\u00f3 Giubergia. Unos 150 establecimientos ya fueron beneficiados con la entrega de animales en 2018 y se prev\u00e9 pr\u00f3ximamente una entrega a otros 44 de terneros Braford, Bangus y sus cruzas, la mitad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-22T14:42:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-22T19:21:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/22022019-1145x395-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Jujuy apuesta a la gen\u00e9tica para mejorar su carne\",\"datePublished\":\"2019-02-22T14:42:30+00:00\",\"dateModified\":\"2019-02-22T19:21:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/\"},\"wordCount\":439,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/22022019-1145x395-.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/\",\"name\":\"Jujuy apuesta a la gen\u00e9tica para mejorar su carne | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/22022019-1145x395-.jpg\",\"datePublished\":\"2019-02-22T14:42:30+00:00\",\"dateModified\":\"2019-02-22T19:21:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/22022019-1145x395-.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/22022019-1145x395-.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jujuy apuesta a la gen\u00e9tica para mejorar su carne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jujuy apuesta a la gen\u00e9tica para mejorar su carne | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/","og_locale":"en_US","og_type":"article","og_title":"Jujuy apuesta a la gen\u00e9tica para mejorar su carne | Proagro","og_description":"En el marco de un plan provincial, peque\u00f1os productores ganaderos recibieron reproductores Braford y Bonsmara para mejorar las cualidades carniceras de sus rodeos. Peque\u00f1os productores de ganado bovino de Jujuy\u00a0lograron los primeros nacimientos de teneros con gen\u00e9tica de alta calidad, en el marco de un plan provincial de fomento del sector por el que fueron entregados terneros machos Braford y Bonsmara, informaron hoy autoridades del ministerio de Desarrollo Econ\u00f3mico provincial. El \u00e9xito\u00a0del plan de mejoramiento gen\u00e9tico se produjo por la\u00a0cesi\u00f3n de terneros pr\u00f3ximos a servicio en vez de toros, que fueron adquiridos en la provincia sorteando los riesgos de mortandad en lo que tiene que ver con la adaptaci\u00f3n a la zona, explic\u00f3 a la agencia\u00a0T\u00e9lam el director provincial de Desarrollo Ganadero, Javier Giubergia. &#8220;La gen\u00e9tica la estamos comprando en Jujuy, con animales ya adaptados, que fue uno de los fracasos en otras provincias del noroeste, donde a su vez se otorgaron toros, mientras nosotros entregamos terneros y el productor deb\u00eda cuidarlos hasta reci\u00e9n largarlos a servicio&#8221;, detall\u00f3 Giubergia. Unos 150 establecimientos ya fueron beneficiados con la entrega de animales en 2018 y se prev\u00e9 pr\u00f3ximamente una entrega a otros 44 de terneros Braford, Bangus y sus cruzas, la mitad [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2019-02-22T14:42:30+00:00","article_modified_time":"2019-02-22T19:21:51+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/22022019-1145x395-.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Jujuy apuesta a la gen\u00e9tica para mejorar su carne","datePublished":"2019-02-22T14:42:30+00:00","dateModified":"2019-02-22T19:21:51+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/"},"wordCount":439,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/22022019-1145x395-.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/","url":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/","name":"Jujuy apuesta a la gen\u00e9tica para mejorar su carne | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/22022019-1145x395-.jpg","datePublished":"2019-02-22T14:42:30+00:00","dateModified":"2019-02-22T19:21:51+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/22022019-1145x395-.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/22022019-1145x395-.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/jujuy-apuesta-a-la-genetica-para-mejorar-su-carne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Jujuy apuesta a la gen\u00e9tica para mejorar su carne"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=11138"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/11143"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=11138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=11138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=11138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}