{"id":11112,"date":"2019-02-08T13:44:23","date_gmt":"2019-02-08T13:44:23","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=11112"},"modified":"2019-02-08T14:54:10","modified_gmt":"2019-02-08T14:54:10","slug":"las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/","title":{"rendered":"Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Se comercializaron 334.400 toneladas por 1.008 millones de d\u00f3lares a 69 destinos de todo el mundo. El incremento fue por una recuperaci\u00f3n de la remisi\u00f3n de leche a nivel nacional.<a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/industria-lechera-editada.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-11113 size-medium\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/industria-lechera-editada-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/industria-lechera-editada-300x200.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/industria-lechera-editada-600x400.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/industria-lechera-editada-768x512.jpg 768w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/industria-lechera-editada-1024x683.jpg 1024w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/industria-lechera-editada.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La Secretar\u00eda de Gobierno de Agroindustria de la Naci\u00f3n informa que durante 2018, las exportaciones de l\u00e1cteos aumentaron 38,2% en volumen respecto al 2017, al crecer de 243.500 toneladas a 334.400 toneladas.<\/p>\n<p>De acuerdo a los datos relevados por la Direcci\u00f3n Nacional L\u00e1ctea, el a\u00f1o pasado se comercializaron productos por un valor total superior a 1.008 millones de d\u00f3lares, que representan un incremento cercano al 30%, al considerar los 776 millones de d\u00f3lares facturados en 2017.<\/p>\n<p>Al respecto, el secretario de Gobierno de Agroindustria, Luis Miguel Etchevehere puntualiz\u00f3 que &#8220;Las exportaciones son el camino para una lecher\u00eda ordenada que tenga previsibilidad. Este crecimiento est\u00e1 confirmando que m\u00e1s all\u00e1 de la coyuntura de precios o clim\u00e1tica la leche tiene una politica p\u00fablica de transparencia, ordenamiento y protagonismo de los mercados&#8221;.<\/p>\n<p>Las ventas al exterior se canalizaron a 69 pa\u00edses en todo el mundo donde se destacan por su participaci\u00f3n: Brasil, Argelia, China, Rusia y China. Mientras que entre los principales productos comercializados se encuentran: leche en polvo entera (40%), suero (18%), quesos (17%), leche en polvo descremada (7%) y leches con f\u00f3rmulas infantiles (6%).<\/p>\n<p>El crecimiento se explica por una recuperaci\u00f3n de la remisi\u00f3n de leche a nivel nacional, tal como lo demuestran los registros oficiales obtenidos a trav\u00e9s del Sistema Integrado de Gesti\u00f3n de la Lecher\u00eda Argentina (SIGLeA): en el 2018 se alcanz\u00f3 una producci\u00f3n de 10.527 millones de litros de leche, lo que represent\u00f3 un alza del 4,3% en relaci\u00f3n a los 10.097 millones producidos en el 2017. De esta forma se consolid\u00f3 un crecimiento tanto de la producci\u00f3n a nivel nacional como de la participaci\u00f3n de las exportaciones en relaci\u00f3n al total elaborado, que aument\u00f3 del 16 al 22%.<\/p>\n<p>Fuente:\u00a0http:\/\/www.revistachacra.com.ar\/\/nota\/24890-las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Se comercializaron 334.400 toneladas por 1.008 millones de d\u00f3lares a 69 destinos de todo el mundo. El incremento fue por una recuperaci\u00f3n de la remisi\u00f3n de leche a nivel nacional. La Secretar\u00eda de Gobierno de Agroindustria de la Naci\u00f3n informa que durante 2018, las exportaciones de l\u00e1cteos aumentaron 38,2% en volumen respecto al 2017, al crecer de 243.500 toneladas a 334.400 toneladas. De acuerdo a los datos relevados por la Direcci\u00f3n Nacional L\u00e1ctea, el a\u00f1o pasado se comercializaron productos por un valor total superior a 1.008 millones de d\u00f3lares, que representan un incremento cercano al 30%, al considerar los 776 millones de d\u00f3lares facturados en 2017. Al respecto, el secretario de Gobierno de Agroindustria, Luis Miguel Etchevehere puntualiz\u00f3 que &#8220;Las exportaciones son el camino para una lecher\u00eda ordenada que tenga previsibilidad. Este crecimiento est\u00e1 confirmando que m\u00e1s all\u00e1 de la coyuntura de precios o clim\u00e1tica la leche tiene una politica p\u00fablica de transparencia, ordenamiento y protagonismo de los mercados&#8221;. Las ventas al exterior se canalizaron a 69 pa\u00edses en todo el mundo donde se destacan por su participaci\u00f3n: Brasil, Argelia, China, Rusia y China. Mientras que entre los principales productos comercializados se encuentran: leche en polvo entera (40%), suero (18%), [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11115,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-11112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018 | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018 | Proagro\" \/>\n<meta property=\"og:description\" content=\"Se comercializaron 334.400 toneladas por 1.008 millones de d\u00f3lares a 69 destinos de todo el mundo. El incremento fue por una recuperaci\u00f3n de la remisi\u00f3n de leche a nivel nacional. La Secretar\u00eda de Gobierno de Agroindustria de la Naci\u00f3n informa que durante 2018, las exportaciones de l\u00e1cteos aumentaron 38,2% en volumen respecto al 2017, al crecer de 243.500 toneladas a 334.400 toneladas. De acuerdo a los datos relevados por la Direcci\u00f3n Nacional L\u00e1ctea, el a\u00f1o pasado se comercializaron productos por un valor total superior a 1.008 millones de d\u00f3lares, que representan un incremento cercano al 30%, al considerar los 776 millones de d\u00f3lares facturados en 2017. Al respecto, el secretario de Gobierno de Agroindustria, Luis Miguel Etchevehere puntualiz\u00f3 que &#8220;Las exportaciones son el camino para una lecher\u00eda ordenada que tenga previsibilidad. Este crecimiento est\u00e1 confirmando que m\u00e1s all\u00e1 de la coyuntura de precios o clim\u00e1tica la leche tiene una politica p\u00fablica de transparencia, ordenamiento y protagonismo de los mercados&#8221;. Las ventas al exterior se canalizaron a 69 pa\u00edses en todo el mundo donde se destacan por su participaci\u00f3n: Brasil, Argelia, China, Rusia y China. Mientras que entre los principales productos comercializados se encuentran: leche en polvo entera (40%), suero (18%), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-08T13:44:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-08T14:54:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/08022019-1145x395-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018\",\"datePublished\":\"2019-02-08T13:44:23+00:00\",\"dateModified\":\"2019-02-08T14:54:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/\"},\"wordCount\":335,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/08022019-1145x395-.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/\",\"name\":\"Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018 | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/08022019-1145x395-.jpg\",\"datePublished\":\"2019-02-08T13:44:23+00:00\",\"dateModified\":\"2019-02-08T14:54:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/08022019-1145x395-.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/08022019-1145x395-.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018 | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/","og_locale":"en_US","og_type":"article","og_title":"Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018 | Proagro","og_description":"Se comercializaron 334.400 toneladas por 1.008 millones de d\u00f3lares a 69 destinos de todo el mundo. El incremento fue por una recuperaci\u00f3n de la remisi\u00f3n de leche a nivel nacional. La Secretar\u00eda de Gobierno de Agroindustria de la Naci\u00f3n informa que durante 2018, las exportaciones de l\u00e1cteos aumentaron 38,2% en volumen respecto al 2017, al crecer de 243.500 toneladas a 334.400 toneladas. De acuerdo a los datos relevados por la Direcci\u00f3n Nacional L\u00e1ctea, el a\u00f1o pasado se comercializaron productos por un valor total superior a 1.008 millones de d\u00f3lares, que representan un incremento cercano al 30%, al considerar los 776 millones de d\u00f3lares facturados en 2017. Al respecto, el secretario de Gobierno de Agroindustria, Luis Miguel Etchevehere puntualiz\u00f3 que &#8220;Las exportaciones son el camino para una lecher\u00eda ordenada que tenga previsibilidad. Este crecimiento est\u00e1 confirmando que m\u00e1s all\u00e1 de la coyuntura de precios o clim\u00e1tica la leche tiene una politica p\u00fablica de transparencia, ordenamiento y protagonismo de los mercados&#8221;. Las ventas al exterior se canalizaron a 69 pa\u00edses en todo el mundo donde se destacan por su participaci\u00f3n: Brasil, Argelia, China, Rusia y China. Mientras que entre los principales productos comercializados se encuentran: leche en polvo entera (40%), suero (18%), [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2019-02-08T13:44:23+00:00","article_modified_time":"2019-02-08T14:54:10+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/08022019-1145x395-.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018","datePublished":"2019-02-08T13:44:23+00:00","dateModified":"2019-02-08T14:54:10+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/"},"wordCount":335,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/08022019-1145x395-.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/","url":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/","name":"Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018 | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/08022019-1145x395-.jpg","datePublished":"2019-02-08T13:44:23+00:00","dateModified":"2019-02-08T14:54:10+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/08022019-1145x395-.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/02\/08022019-1145x395-.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/las-exportaciones-de-lacteos-crecieron-mas-del-38-en-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Las exportaciones de l\u00e1cteos crecieron m\u00e1s del 38% en 2018"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=11112"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11112\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/11115"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=11112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=11112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=11112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}