{"id":11059,"date":"2019-01-18T15:40:49","date_gmt":"2019-01-18T15:40:49","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=11059"},"modified":"2019-01-18T19:28:35","modified_gmt":"2019-01-18T19:28:35","slug":"todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/","title":{"rendered":"Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Esta enfermedad afecta la calidad de la lana y el cuero, causando en algunos casos la muerte del animal. Desde el INTA EEA Bariloche explican los aspectos a considerar para el correcto manejo de la majada.<a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/ovejas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11061 size-full\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/ovejas.jpg\" alt=\"\" width=\"800\" height=\"500\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/ovejas.jpg 800w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/ovejas-600x375.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/ovejas-300x188.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/ovejas-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>La\u00a0<strong>sarna com\u00fan ovina<\/strong>, es producida por un\u00a0<strong>\u00e1caro<\/strong>\u00a0denominado\u00a0<strong><em>Psoroptes ovis<\/em><\/strong>, y se trata de una de las parasitosis que mayor da\u00f1o causa en la\u00a0<strong>producci\u00f3n ovina<\/strong>. La investigadora\u00a0<strong>Marcela Larroza<\/strong>, investigadora de\u00a0<strong>INTA EEA Bariloche<\/strong>, dio a conocer todo acerca de esta enfermedad.<\/p>\n<p>Indic\u00f3 que la enfermedad es\u00a0<strong>altamente contagiosa<\/strong>, y se\u00a0<strong>transmite<\/strong>\u00a0principalmente por contacto directo con ovinos afectados, y por la presencia de\u00a0<strong>\u00e1caros vivos<\/strong>\u00a0en la r<strong>opa del personal de campo, instalaciones, o maquinaria de esquila<\/strong>.<\/p>\n<p>Aunque en las etapas iniciales de la infestaci\u00f3n las lesiones son pr\u00e1cticamente\u00a0<strong>indetectables<\/strong>, una vez que avanza, los signos pueden ser: los animales sufren una intensa\u00a0<strong>picaz\u00f3n<\/strong>\u00a0y se rascan permanentemente, incluso contra postes y alambrados, se afecta severamente la\u00a0<strong>calidad de la lana<\/strong>\u00a0y del\u00a0<strong>cuero<\/strong>, pudiendo llegar a la\u00a0<strong>muerte<\/strong>\u00a0en los casos m\u00e1s graves.<\/p>\n<p>Las\u00a0<strong>condiciones predisponentes<\/strong>\u00a0para los\u00a0<strong>\u00e1caros,<\/strong>\u00a0son favorecida por el\u00a0<strong>fr\u00edo<\/strong>\u00a0y la\u00a0<strong>humedad,<\/strong>\u00a0por lo cual la sarna psor\u00f3ptica se manifiesta cl\u00e1sicamente en invierno. Esto determina que las majadas patag\u00f3nicas sufran una\u00a0<strong>mayor exposici\u00f3n<\/strong>, ya que el ambiente fr\u00edo se mantiene constante durante muchos meses del a\u00f1o.<\/p>\n<p>En este marco, aseguran que la presencia de sarna provoca\u00a0<strong>graves p\u00e9rdidas econ\u00f3micas<\/strong>, debido a la disminuci\u00f3n de la\u00a0<strong>cantidad y calidad de lana<\/strong>, la\u00a0<strong>mortandad<\/strong>\u00a0de animales, la\u00a0<strong>p\u00e9rdida de peso<\/strong>\u00a0y de condici\u00f3n corporal, y los costos de tratamiento para su control.<\/p>\n<p>En funci\u00f3n al alto n\u00famero de casos de sarna en la\u00a0<strong>Patagonia<\/strong>, el\u00a0<strong>GSA\u00a0<\/strong>realiz\u00f3 pruebas en ovinos para determinar la eficacia de algunos de los\u00a0<strong>productos antis\u00e1rnicos<\/strong>\u00a0disponibles en el mercado, y si bien hasta el momento no se detect\u00f3 resistencia antiparasitaria, se observ\u00f3 que el tiempo requerido para lograr la efectividad m\u00e1xima fue mayor al esperado, en algunos casos aproximadamente un mes.<\/p>\n<p>Por este motivo, se destaca la importancia de\u00a0<strong>prevenir el ingreso de sarna en los establecimientos<\/strong>, y para esto se resumen algunas medidas relativamente simples pero fundamentales a tener en cuenta:<\/p>\n<h5><strong>LAS MEDIDAS PREVENTIVAS DEL INTA EEA BARILOCHE<\/strong><\/h5>\n<p>\u2022 Considerar que todos los animales que ingresan al establecimiento representan un riesgo de contagio para la majada: aunque no se observen s\u00edntomas o lesiones, pueden tener infestaciones recientes que a\u00fan no sean evidentes.<\/p>\n<p>Por lo tanto todos los animales que ingresen, ya sean ovinos comprados, carneros obtenidos en pr\u00e9stamo o devueltos, ovinos que regresen de ferias o exposiciones, deber\u00e1n mantenerse en cuarentena separados de la majada general durante al menos tres semanas, lo que permite examinarlos, observar signos de infestaci\u00f3n y tratarlos si fuese necesario.<\/p>\n<p>\u2022 Contar con buenos alambrados perimetrales y realizar el mantenimiento de los mismos, con el fin de evitar el ingreso de animales sin control sanitario al establecimiento.<\/p>\n<p>\u2022 Revisar la majada al menos dos veces al a\u00f1o, aunque no se observe rascado, pudiendo aprovechar los momentos donde los animales se re\u00fanen (preservicio, se\u00f1alada, vacunaciones, esquila). Esto permite detectar la presencia de \u00e1caros as\u00ed como tambi\u00e9n otros par\u00e1sitos externos, como mel\u00f3fagos (\u201cfalsa garrapata\u201d) o piojos, en los estadios iniciales de la infestaci\u00f3n, por lo cual se podr\u00e1 aplicar un tratamiento temprano acorde al par\u00e1sito encontrado y evitar as\u00ed mayores p\u00e9rdidas.<\/p>\n<p>\u2022 Adem\u00e1s de las revisiones \u201cprogramadas\u201d, se debe revisar urgentemente a la majada si se observan s\u00edntomas de picaz\u00f3n en los animales (si se rascan, se frotan contra postes o se muerden), o con el vell\u00f3n \u201cdesprolijo\u201d, o con mechones sueltos.<\/p>\n<p>\u2022 Controlar la desinfecci\u00f3n de maquinaria, indumentaria y accesorios utilizados para la esquila.<\/p>\n<p>Fuente:\u00a0https:\/\/www.infocampo.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Esta enfermedad afecta la calidad de la lana y el cuero, causando en algunos casos la muerte del animal. Desde el INTA EEA Bariloche explican los aspectos a considerar para el correcto manejo de la majada. &nbsp; La\u00a0sarna com\u00fan ovina, es producida por un\u00a0\u00e1caro\u00a0denominado\u00a0Psoroptes ovis, y se trata de una de las parasitosis que mayor da\u00f1o causa en la\u00a0producci\u00f3n ovina. La investigadora\u00a0Marcela Larroza, investigadora de\u00a0INTA EEA Bariloche, dio a conocer todo acerca de esta enfermedad. Indic\u00f3 que la enfermedad es\u00a0altamente contagiosa, y se\u00a0transmite\u00a0principalmente por contacto directo con ovinos afectados, y por la presencia de\u00a0\u00e1caros vivos\u00a0en la ropa del personal de campo, instalaciones, o maquinaria de esquila. Aunque en las etapas iniciales de la infestaci\u00f3n las lesiones son pr\u00e1cticamente\u00a0indetectables, una vez que avanza, los signos pueden ser: los animales sufren una intensa\u00a0picaz\u00f3n\u00a0y se rascan permanentemente, incluso contra postes y alambrados, se afecta severamente la\u00a0calidad de la lana\u00a0y del\u00a0cuero, pudiendo llegar a la\u00a0muerte\u00a0en los casos m\u00e1s graves. Las\u00a0condiciones predisponentes\u00a0para los\u00a0\u00e1caros,\u00a0son favorecida por el\u00a0fr\u00edo\u00a0y la\u00a0humedad,\u00a0por lo cual la sarna psor\u00f3ptica se manifiesta cl\u00e1sicamente en invierno. Esto determina que las majadas patag\u00f3nicas sufran una\u00a0mayor exposici\u00f3n, ya que el ambiente fr\u00edo se mantiene constante durante muchos meses del a\u00f1o. En este marco, aseguran que la [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11072,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-11059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n | Proagro\" \/>\n<meta property=\"og:description\" content=\"Esta enfermedad afecta la calidad de la lana y el cuero, causando en algunos casos la muerte del animal. Desde el INTA EEA Bariloche explican los aspectos a considerar para el correcto manejo de la majada. &nbsp; La\u00a0sarna com\u00fan ovina, es producida por un\u00a0\u00e1caro\u00a0denominado\u00a0Psoroptes ovis, y se trata de una de las parasitosis que mayor da\u00f1o causa en la\u00a0producci\u00f3n ovina. La investigadora\u00a0Marcela Larroza, investigadora de\u00a0INTA EEA Bariloche, dio a conocer todo acerca de esta enfermedad. Indic\u00f3 que la enfermedad es\u00a0altamente contagiosa, y se\u00a0transmite\u00a0principalmente por contacto directo con ovinos afectados, y por la presencia de\u00a0\u00e1caros vivos\u00a0en la ropa del personal de campo, instalaciones, o maquinaria de esquila. Aunque en las etapas iniciales de la infestaci\u00f3n las lesiones son pr\u00e1cticamente\u00a0indetectables, una vez que avanza, los signos pueden ser: los animales sufren una intensa\u00a0picaz\u00f3n\u00a0y se rascan permanentemente, incluso contra postes y alambrados, se afecta severamente la\u00a0calidad de la lana\u00a0y del\u00a0cuero, pudiendo llegar a la\u00a0muerte\u00a0en los casos m\u00e1s graves. Las\u00a0condiciones predisponentes\u00a0para los\u00a0\u00e1caros,\u00a0son favorecida por el\u00a0fr\u00edo\u00a0y la\u00a0humedad,\u00a0por lo cual la sarna psor\u00f3ptica se manifiesta cl\u00e1sicamente en invierno. Esto determina que las majadas patag\u00f3nicas sufran una\u00a0mayor exposici\u00f3n, ya que el ambiente fr\u00edo se mantiene constante durante muchos meses del a\u00f1o. En este marco, aseguran que la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-18T15:40:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-18T19:28:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/18012019-1145x395-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n\",\"datePublished\":\"2019-01-18T15:40:49+00:00\",\"dateModified\":\"2019-01-18T19:28:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/\"},\"wordCount\":666,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/18012019-1145x395-.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/\",\"name\":\"Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/18012019-1145x395-.jpg\",\"datePublished\":\"2019-01-18T15:40:49+00:00\",\"dateModified\":\"2019-01-18T19:28:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/18012019-1145x395-.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/18012019-1145x395-.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/","og_locale":"en_US","og_type":"article","og_title":"Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n | Proagro","og_description":"Esta enfermedad afecta la calidad de la lana y el cuero, causando en algunos casos la muerte del animal. Desde el INTA EEA Bariloche explican los aspectos a considerar para el correcto manejo de la majada. &nbsp; La\u00a0sarna com\u00fan ovina, es producida por un\u00a0\u00e1caro\u00a0denominado\u00a0Psoroptes ovis, y se trata de una de las parasitosis que mayor da\u00f1o causa en la\u00a0producci\u00f3n ovina. La investigadora\u00a0Marcela Larroza, investigadora de\u00a0INTA EEA Bariloche, dio a conocer todo acerca de esta enfermedad. Indic\u00f3 que la enfermedad es\u00a0altamente contagiosa, y se\u00a0transmite\u00a0principalmente por contacto directo con ovinos afectados, y por la presencia de\u00a0\u00e1caros vivos\u00a0en la ropa del personal de campo, instalaciones, o maquinaria de esquila. Aunque en las etapas iniciales de la infestaci\u00f3n las lesiones son pr\u00e1cticamente\u00a0indetectables, una vez que avanza, los signos pueden ser: los animales sufren una intensa\u00a0picaz\u00f3n\u00a0y se rascan permanentemente, incluso contra postes y alambrados, se afecta severamente la\u00a0calidad de la lana\u00a0y del\u00a0cuero, pudiendo llegar a la\u00a0muerte\u00a0en los casos m\u00e1s graves. Las\u00a0condiciones predisponentes\u00a0para los\u00a0\u00e1caros,\u00a0son favorecida por el\u00a0fr\u00edo\u00a0y la\u00a0humedad,\u00a0por lo cual la sarna psor\u00f3ptica se manifiesta cl\u00e1sicamente en invierno. Esto determina que las majadas patag\u00f3nicas sufran una\u00a0mayor exposici\u00f3n, ya que el ambiente fr\u00edo se mantiene constante durante muchos meses del a\u00f1o. En este marco, aseguran que la [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2019-01-18T15:40:49+00:00","article_modified_time":"2019-01-18T19:28:35+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/18012019-1145x395-.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n","datePublished":"2019-01-18T15:40:49+00:00","dateModified":"2019-01-18T19:28:35+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/"},"wordCount":666,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/18012019-1145x395-.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/","url":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/","name":"Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/18012019-1145x395-.jpg","datePublished":"2019-01-18T15:40:49+00:00","dateModified":"2019-01-18T19:28:35+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/18012019-1145x395-.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2019\/01\/18012019-1145x395-.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/todo-sobre-la-sarna-comun-en-ovinos-y-su-prevencion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Todo sobre la sarna com\u00fan en ovinos y su prevenci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=11059"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/11059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/11072"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=11059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=11059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=11059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}