{"id":10979,"date":"2018-12-07T12:27:38","date_gmt":"2018-12-07T12:27:38","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=10979"},"modified":"2018-12-07T12:33:39","modified_gmt":"2018-12-07T12:33:39","slug":"el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/","title":{"rendered":"El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Las exportaciones argentinas de carne bovina se ubicar\u00e1n cerca de los US$1.880 millones este a\u00f1o, creciendo 45% respecto de 2017.<\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/screenhunter_3096_dec._07_08.23_0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10980 size-full\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/screenhunter_3096_dec._07_08.23_0.jpg\" alt=\"\" width=\"620\" height=\"375\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/screenhunter_3096_dec._07_08.23_0.jpg 620w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/screenhunter_3096_dec._07_08.23_0-600x363.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/screenhunter_3096_dec._07_08.23_0-300x181.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p>Las exportaciones argentinas de carne bovina se ubicar\u00e1n cerca de los US$1.880 millones este a\u00f1o, creciendo 45% respecto de 2017 (+US$ 580 millones) y 120% respecto de 2015 (+ US$ 1.015 millones). El dato se desprende de una estimaci\u00f3n del Instituto de Estudios sobre la Realidad Argentina y Latinoamericana (IERAL) de la Fundaci\u00f3n Mediterr\u00e1nea.<\/p>\n<p>&#8220;En divisas, se trata de la cifra m\u00e1s alta de las \u00faltimas d\u00e9cadas; en vol\u00famenes, se habr\u00e1 m\u00e1s que duplicado el promedio de los \u00faltimos 8 a\u00f1os&#8221;, se\u00f1al\u00f3\u00a0Juan Manuel Garz\u00f3n, autor del informe.<\/p>\n<p>La participaci\u00f3n del pa\u00eds en el mercado global se aproximar\u00e1 al 5%, un porcentaje m\u00e1s acorde con la dotaci\u00f3n de recursos naturales, infraestructura, calidad y prestigio del producto local: &#8220;Todo indica que Argentina se ubicar\u00e1 en la 6ta posici\u00f3n en el ranking mundial de exportadores, avanzando 5 posiciones respecto del lugar que ocupaba s\u00f3lo 3 a\u00f1os atr\u00e1s&#8221;.<\/p>\n<p>Nuestro pa\u00eds superar\u00e1 este a\u00f1o a Bielorrusia, la Uni\u00f3n Europea Extrazona, Uruguay, Paraguay y Canad\u00e1.<\/p>\n<p>La recuperaci\u00f3n de las exportaciones no hubiese sido tan r\u00e1pida sin la demanda creciente de prote\u00ednas animales de China: &#8220;El pa\u00eds estar\u00e1 colocando unas 190 mil toneladas este a\u00f1o (peso producto) en el gigante (incluyendo env\u00edos a Hong Kong)&#8221;.<\/p>\n<p>El impacto de China es contundente: &#8220;Casi el 70% del crecimiento de las exportaciones del per\u00edodo 2015\/2018 se explica por los mayores env\u00edos a ese pa\u00eds&#8221;.<\/p>\n<p>Desde Ieral se\u00f1alaron que el boom de exportaciones no ha tenido, al menos hasta el momento, un impacto sobre los precios de la carne a nivel consumidor. De hecho, los valores de la carne en los primeros 10 meses de este a\u00f1o se han ubicado 4% abajo (ajustados por inflaci\u00f3n) del precio promedio 2017, y en el nivel m\u00e1s bajo de los \u00faltimos 8 a\u00f1os.<\/p>\n<p>&#8220;Sin embargo, es elevada la tasa de faena de hembras (46% del total), un fen\u00f3meno que debe revertirse para consolidar las tendencias descriptas. Esto s\u00f3lo ser\u00e1 posible con precios de hacienda m\u00e1s atractivos&#8221;, concluy\u00f3 Garz\u00f3n.<\/p>\n<p>Fuente:\u00a0https:\/\/news.agrofy.com.ar\/noticia\/178522\/regreso-argentina-mercado-mundial-carne-bovina-avanzo-5-puestos-tres-anos<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Las exportaciones argentinas de carne bovina se ubicar\u00e1n cerca de los US$1.880 millones este a\u00f1o, creciendo 45% respecto de 2017. Las exportaciones argentinas de carne bovina se ubicar\u00e1n cerca de los US$1.880 millones este a\u00f1o, creciendo 45% respecto de 2017 (+US$ 580 millones) y 120% respecto de 2015 (+ US$ 1.015 millones). El dato se desprende de una estimaci\u00f3n del Instituto de Estudios sobre la Realidad Argentina y Latinoamericana (IERAL) de la Fundaci\u00f3n Mediterr\u00e1nea. &#8220;En divisas, se trata de la cifra m\u00e1s alta de las \u00faltimas d\u00e9cadas; en vol\u00famenes, se habr\u00e1 m\u00e1s que duplicado el promedio de los \u00faltimos 8 a\u00f1os&#8221;, se\u00f1al\u00f3\u00a0Juan Manuel Garz\u00f3n, autor del informe. La participaci\u00f3n del pa\u00eds en el mercado global se aproximar\u00e1 al 5%, un porcentaje m\u00e1s acorde con la dotaci\u00f3n de recursos naturales, infraestructura, calidad y prestigio del producto local: &#8220;Todo indica que Argentina se ubicar\u00e1 en la 6ta posici\u00f3n en el ranking mundial de exportadores, avanzando 5 posiciones respecto del lugar que ocupaba s\u00f3lo 3 a\u00f1os atr\u00e1s&#8221;. Nuestro pa\u00eds superar\u00e1 este a\u00f1o a Bielorrusia, la Uni\u00f3n Europea Extrazona, Uruguay, Paraguay y Canad\u00e1. La recuperaci\u00f3n de las exportaciones no hubiese sido tan r\u00e1pida sin la demanda creciente de prote\u00ednas animales de China: &#8220;El pa\u00eds [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":10982,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-10979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os | Proagro\" \/>\n<meta property=\"og:description\" content=\"Las exportaciones argentinas de carne bovina se ubicar\u00e1n cerca de los US$1.880 millones este a\u00f1o, creciendo 45% respecto de 2017. Las exportaciones argentinas de carne bovina se ubicar\u00e1n cerca de los US$1.880 millones este a\u00f1o, creciendo 45% respecto de 2017 (+US$ 580 millones) y 120% respecto de 2015 (+ US$ 1.015 millones). El dato se desprende de una estimaci\u00f3n del Instituto de Estudios sobre la Realidad Argentina y Latinoamericana (IERAL) de la Fundaci\u00f3n Mediterr\u00e1nea. &#8220;En divisas, se trata de la cifra m\u00e1s alta de las \u00faltimas d\u00e9cadas; en vol\u00famenes, se habr\u00e1 m\u00e1s que duplicado el promedio de los \u00faltimos 8 a\u00f1os&#8221;, se\u00f1al\u00f3\u00a0Juan Manuel Garz\u00f3n, autor del informe. La participaci\u00f3n del pa\u00eds en el mercado global se aproximar\u00e1 al 5%, un porcentaje m\u00e1s acorde con la dotaci\u00f3n de recursos naturales, infraestructura, calidad y prestigio del producto local: &#8220;Todo indica que Argentina se ubicar\u00e1 en la 6ta posici\u00f3n en el ranking mundial de exportadores, avanzando 5 posiciones respecto del lugar que ocupaba s\u00f3lo 3 a\u00f1os atr\u00e1s&#8221;. Nuestro pa\u00eds superar\u00e1 este a\u00f1o a Bielorrusia, la Uni\u00f3n Europea Extrazona, Uruguay, Paraguay y Canad\u00e1. La recuperaci\u00f3n de las exportaciones no hubiese sido tan r\u00e1pida sin la demanda creciente de prote\u00ednas animales de China: &#8220;El pa\u00eds [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-07T12:27:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-07T12:33:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/07122018-1145x395-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os\",\"datePublished\":\"2018-12-07T12:27:38+00:00\",\"dateModified\":\"2018-12-07T12:33:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/\"},\"wordCount\":394,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/07122018-1145x395-.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/\",\"name\":\"El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/07122018-1145x395-.jpg\",\"datePublished\":\"2018-12-07T12:27:38+00:00\",\"dateModified\":\"2018-12-07T12:33:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/07122018-1145x395-.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/07122018-1145x395-.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/","og_locale":"en_US","og_type":"article","og_title":"El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os | Proagro","og_description":"Las exportaciones argentinas de carne bovina se ubicar\u00e1n cerca de los US$1.880 millones este a\u00f1o, creciendo 45% respecto de 2017. Las exportaciones argentinas de carne bovina se ubicar\u00e1n cerca de los US$1.880 millones este a\u00f1o, creciendo 45% respecto de 2017 (+US$ 580 millones) y 120% respecto de 2015 (+ US$ 1.015 millones). El dato se desprende de una estimaci\u00f3n del Instituto de Estudios sobre la Realidad Argentina y Latinoamericana (IERAL) de la Fundaci\u00f3n Mediterr\u00e1nea. &#8220;En divisas, se trata de la cifra m\u00e1s alta de las \u00faltimas d\u00e9cadas; en vol\u00famenes, se habr\u00e1 m\u00e1s que duplicado el promedio de los \u00faltimos 8 a\u00f1os&#8221;, se\u00f1al\u00f3\u00a0Juan Manuel Garz\u00f3n, autor del informe. La participaci\u00f3n del pa\u00eds en el mercado global se aproximar\u00e1 al 5%, un porcentaje m\u00e1s acorde con la dotaci\u00f3n de recursos naturales, infraestructura, calidad y prestigio del producto local: &#8220;Todo indica que Argentina se ubicar\u00e1 en la 6ta posici\u00f3n en el ranking mundial de exportadores, avanzando 5 posiciones respecto del lugar que ocupaba s\u00f3lo 3 a\u00f1os atr\u00e1s&#8221;. Nuestro pa\u00eds superar\u00e1 este a\u00f1o a Bielorrusia, la Uni\u00f3n Europea Extrazona, Uruguay, Paraguay y Canad\u00e1. La recuperaci\u00f3n de las exportaciones no hubiese sido tan r\u00e1pida sin la demanda creciente de prote\u00ednas animales de China: &#8220;El pa\u00eds [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2018-12-07T12:27:38+00:00","article_modified_time":"2018-12-07T12:33:39+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/07122018-1145x395-.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os","datePublished":"2018-12-07T12:27:38+00:00","dateModified":"2018-12-07T12:33:39+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/"},"wordCount":394,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/07122018-1145x395-.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/","url":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/","name":"El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/07122018-1145x395-.jpg","datePublished":"2018-12-07T12:27:38+00:00","dateModified":"2018-12-07T12:33:39+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/07122018-1145x395-.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/12\/07122018-1145x395-.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/el-regreso-de-argentina-al-mercado-mundial-de-carne-bovina-avanzo-5-puestos-en-tres-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"El regreso de Argentina al mercado mundial de carne bovina: avanz\u00f3 5 puestos en tres a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=10979"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/10982"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=10979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=10979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=10979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}