{"id":10924,"date":"2018-11-09T14:17:06","date_gmt":"2018-11-09T14:17:06","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=10924"},"modified":"2018-11-09T15:20:42","modified_gmt":"2018-11-09T15:20:42","slug":"se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/","title":{"rendered":"Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Tras haber registrado una fuerte ca\u00edda en la faena y los env\u00edos de carne al mercado interno (-16,7%) en septiembre pasado, ahora la C\u00e1mara de la Industria y el Comercio de Carnes (Ciccra) reflej\u00f3 un rebote de la actividad en octubre \u00faltimo. Adem\u00e1s, destac\u00f3 que China sigue traccionando fuerte, llev\u00e1ndose 6 de cada 10 kilos que se exportan.<\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808684w1033.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10926 size-full\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808684w1033.jpg\" alt=\"\" width=\"1033\" height=\"688\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808684w1033.jpg 1033w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808684w1033-600x400.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808684w1033-300x200.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808684w1033-768x512.jpg 768w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808684w1033-1024x682.jpg 1024w\" sizes=\"auto, (max-width: 1033px) 100vw, 1033px\" \/><\/a><\/p>\n<p>Estos son los puntos sobresalientes del \u00faltimo informe de Ciccra:<\/p>\n<p>Se faenaron 1,184 millones de cabezas, una suba del 14,7%, tras la baja de 13,1% observada entre agosto y septiembre pasado.<\/p>\n<ul>\n<li>La producci\u00f3n de carne vacuna ascendi\u00f3 a 272 mil toneladas res con hueso (tn r\/c\/h). En comparaci\u00f3n con octubre de 2017 aument\u00f3 6,8%.<\/li>\n<li>El env\u00edo de carne vacuna al mercado interno habr\u00eda regresado a los casi 60 kg\/hab\/a\u00f1o, tras caer &#8220;temporariamente&#8221; a 50,9 kg\/hab\/a\u00f1o en septiembre.<\/li>\n<li>Las exportaciones fueron de 429,8 mil tn r\/c\/h en los primeros diez meses de 2018, una suba de 69,5% interanual.<\/li>\n<li>Entre enero y septiembre China compr\u00f3 6 de cada 10 kilos de carne vacuna exportados por la Argentina.<\/li>\n<li>El precio promedio de la hacienda en pie baj\u00f3 3,9% mensual, a $ 40,213 por kilo en octubre pasado.<\/li>\n<li>En octubre la carne porcina aument\u00f3 5,8%, contra 1,2% de la vacuna y 0,7% la aviar. En tanto en los \u00faltimos seis meses, el precio de la carne aviar subi\u00f3 40,2%, la vacuna 25,9% y la porcina 25,4%.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808686w740.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10927 size-full\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808686w740.png\" alt=\"\" width=\"740\" height=\"496\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808686w740.png 740w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808686w740-600x402.png 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808686w740-300x201.png 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808689w740.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10928 size-full\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808689w740.png\" alt=\"\" width=\"740\" height=\"496\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808689w740.png 740w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808689w740-600x402.png 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808689w740-300x201.png 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808690w740.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10929 size-full\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808690w740.png\" alt=\"\" width=\"740\" height=\"496\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808690w740.png 740w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808690w740-600x402.png 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/2808690w740-300x201.png 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/a><\/p>\n<p>Fuente:\u00a0https:\/\/www.lanacion.com.ar\/2189339-se-recupero-venta-carne-al-mercado-interno#comentarios<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Tras haber registrado una fuerte ca\u00edda en la faena y los env\u00edos de carne al mercado interno (-16,7%) en septiembre pasado, ahora la C\u00e1mara de la Industria y el Comercio de Carnes (Ciccra) reflej\u00f3 un rebote de la actividad en octubre \u00faltimo. Adem\u00e1s, destac\u00f3 que China sigue traccionando fuerte, llev\u00e1ndose 6 de cada 10 kilos que se exportan. Estos son los puntos sobresalientes del \u00faltimo informe de Ciccra: Se faenaron 1,184 millones de cabezas, una suba del 14,7%, tras la baja de 13,1% observada entre agosto y septiembre pasado. La producci\u00f3n de carne vacuna ascendi\u00f3 a 272 mil toneladas res con hueso (tn r\/c\/h). En comparaci\u00f3n con octubre de 2017 aument\u00f3 6,8%. El env\u00edo de carne vacuna al mercado interno habr\u00eda regresado a los casi 60 kg\/hab\/a\u00f1o, tras caer &#8220;temporariamente&#8221; a 50,9 kg\/hab\/a\u00f1o en septiembre. Las exportaciones fueron de 429,8 mil tn r\/c\/h en los primeros diez meses de 2018, una suba de 69,5% interanual. Entre enero y septiembre China compr\u00f3 6 de cada 10 kilos de carne vacuna exportados por la Argentina. El precio promedio de la hacienda en pie baj\u00f3 3,9% mensual, a $ 40,213 por kilo en octubre pasado. En octubre la carne porcina aument\u00f3 5,8%, contra [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":10931,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-10924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados | Proagro\" \/>\n<meta property=\"og:description\" content=\"Tras haber registrado una fuerte ca\u00edda en la faena y los env\u00edos de carne al mercado interno (-16,7%) en septiembre pasado, ahora la C\u00e1mara de la Industria y el Comercio de Carnes (Ciccra) reflej\u00f3 un rebote de la actividad en octubre \u00faltimo. Adem\u00e1s, destac\u00f3 que China sigue traccionando fuerte, llev\u00e1ndose 6 de cada 10 kilos que se exportan. Estos son los puntos sobresalientes del \u00faltimo informe de Ciccra: Se faenaron 1,184 millones de cabezas, una suba del 14,7%, tras la baja de 13,1% observada entre agosto y septiembre pasado. La producci\u00f3n de carne vacuna ascendi\u00f3 a 272 mil toneladas res con hueso (tn r\/c\/h). En comparaci\u00f3n con octubre de 2017 aument\u00f3 6,8%. El env\u00edo de carne vacuna al mercado interno habr\u00eda regresado a los casi 60 kg\/hab\/a\u00f1o, tras caer &#8220;temporariamente&#8221; a 50,9 kg\/hab\/a\u00f1o en septiembre. Las exportaciones fueron de 429,8 mil tn r\/c\/h en los primeros diez meses de 2018, una suba de 69,5% interanual. Entre enero y septiembre China compr\u00f3 6 de cada 10 kilos de carne vacuna exportados por la Argentina. El precio promedio de la hacienda en pie baj\u00f3 3,9% mensual, a $ 40,213 por kilo en octubre pasado. En octubre la carne porcina aument\u00f3 5,8%, contra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-09T14:17:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-09T15:20:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/09112018-1145x395-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados\",\"datePublished\":\"2018-11-09T14:17:06+00:00\",\"dateModified\":\"2018-11-09T15:20:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/\"},\"wordCount\":253,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/09112018-1145x395-.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/\",\"name\":\"Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/09112018-1145x395-.jpg\",\"datePublished\":\"2018-11-09T14:17:06+00:00\",\"dateModified\":\"2018-11-09T15:20:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/09112018-1145x395-.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/09112018-1145x395-.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/","og_locale":"en_US","og_type":"article","og_title":"Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados | Proagro","og_description":"Tras haber registrado una fuerte ca\u00edda en la faena y los env\u00edos de carne al mercado interno (-16,7%) en septiembre pasado, ahora la C\u00e1mara de la Industria y el Comercio de Carnes (Ciccra) reflej\u00f3 un rebote de la actividad en octubre \u00faltimo. Adem\u00e1s, destac\u00f3 que China sigue traccionando fuerte, llev\u00e1ndose 6 de cada 10 kilos que se exportan. Estos son los puntos sobresalientes del \u00faltimo informe de Ciccra: Se faenaron 1,184 millones de cabezas, una suba del 14,7%, tras la baja de 13,1% observada entre agosto y septiembre pasado. La producci\u00f3n de carne vacuna ascendi\u00f3 a 272 mil toneladas res con hueso (tn r\/c\/h). En comparaci\u00f3n con octubre de 2017 aument\u00f3 6,8%. El env\u00edo de carne vacuna al mercado interno habr\u00eda regresado a los casi 60 kg\/hab\/a\u00f1o, tras caer &#8220;temporariamente&#8221; a 50,9 kg\/hab\/a\u00f1o en septiembre. Las exportaciones fueron de 429,8 mil tn r\/c\/h en los primeros diez meses de 2018, una suba de 69,5% interanual. Entre enero y septiembre China compr\u00f3 6 de cada 10 kilos de carne vacuna exportados por la Argentina. El precio promedio de la hacienda en pie baj\u00f3 3,9% mensual, a $ 40,213 por kilo en octubre pasado. En octubre la carne porcina aument\u00f3 5,8%, contra [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2018-11-09T14:17:06+00:00","article_modified_time":"2018-11-09T15:20:42+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/09112018-1145x395-.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados","datePublished":"2018-11-09T14:17:06+00:00","dateModified":"2018-11-09T15:20:42+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/"},"wordCount":253,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/09112018-1145x395-.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/","url":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/","name":"Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/09112018-1145x395-.jpg","datePublished":"2018-11-09T14:17:06+00:00","dateModified":"2018-11-09T15:20:42+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/09112018-1145x395-.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/11\/09112018-1145x395-.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/se-recupero-la-venta-de-carne-al-mercado-interno-y-china-ya-se-lleva-6-de-cada-10-kilos-exportados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Se recuper\u00f3 la venta de carne al mercado interno y China ya se lleva 6 de cada 10 kilos exportados"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=10924"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/10931"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=10924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=10924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=10924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}