{"id":10895,"date":"2018-10-26T13:50:29","date_gmt":"2018-10-26T13:50:29","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=10895"},"modified":"2018-10-26T15:11:30","modified_gmt":"2018-10-26T15:11:30","slug":"la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/","title":{"rendered":"La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>Se posiciona como segundo exportador de este producto, por detr\u00e1s de Uruguay.<a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/5b7m3UbJj_930x525__1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10896 size-full\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/5b7m3UbJj_930x525__1.jpg\" alt=\"\" width=\"930\" height=\"525\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/5b7m3UbJj_930x525__1.jpg 930w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/5b7m3UbJj_930x525__1-600x339.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/5b7m3UbJj_930x525__1-300x169.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/5b7m3UbJj_930x525__1-768x434.jpg 768w\" sizes=\"auto, (max-width: 930px) 100vw, 930px\" \/><\/a><\/p>\n<p>Tras el acuerdo alcanzado en enero entre ambos los gobiernos de Argentina y de Israel, que se fij\u00f3 el nuevo plazo a partir de marzo de 35 a 85 d\u00edas desde la producci\u00f3n, en solo cinco meses el pa\u00eds export\u00f3 a Israel m\u00e1s de siete 7,5 millones de kilos de carne bovina deshuesada, ya sea refrigerada o congelada, por un total de U$S 49.9 millones, seg\u00fan datos del Instituto de Promoci\u00f3n de la Carne Vacuna Argentina (IPCVA).<\/p>\n<p>Esto fue tras un estudio de vida \u00fatil realizado por el INTI, en su centro de Carnes, y de negociaciones que comenzaron en 2016, encabezadas por el Servicio Nacional de Sanidad y Calidad Agroalimentaria (SENASA) y el Ministerio de Relaciones Exteriores, el gobierno de Israel ampli\u00f3 considerablemente los plazos establecidos para la importaci\u00f3n.<\/p>\n<p>A su vez, uno de los principales cambios es que se incrementaron notablemente las posibilidades de\u00a0<strong>enviar la producci\u00f3n en barco<\/strong>, ya que antes, con el plazo de 35 d\u00edas, era muy dif\u00edcil garantizar la vida \u00fatil si no se transportaba en avi\u00f3n, un medio mucho m\u00e1s costoso.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"widget content-new\">\n<div class=\"mg\">\n<div class=\"wrap-figure\">El trabajo que llevaron adelante especialistas del Centro -Carnes surgi\u00f3 a partir del pedido de exportadore. El an\u00e1lisis de vida \u00fatil completado en el instituto tecnol\u00f3gico arroj\u00f3 como resultado 90 d\u00edas, mientras que el trabajo an\u00e1logo realizado en Israel dio 85, cifra que finalmente result\u00f3 definitiva en el acuerdo.<\/div>\n<div>\u00a0<\/div>\n<div>\u201cEstos nuevos plazos posibilitan a los frigor\u00edficos argentinos poder exportar la carne por v\u00eda mar\u00edtima, y de esta manera se reducen los costos de log\u00edstica. Por un lado, permite competir en precios con otros mercados oferentes y, por otro, abre nuevos mercados internacionales que favorecen a la industria c\u00e1rnica argentina\u201d, asegur\u00f3 el director del Centro INTI-Carnes, Javier Echazarreta.<\/div>\n<div>\u00a0<\/div>\n<div>Fue a principio de este a\u00f1o cuando el presidente israel\u00ed, Reuven Rivlin, hizo el anuncio sobre el nuevo plazo, durante la visita que realiz\u00f3 la vicepresidenta de la Naci\u00f3n, Gabriela Michetti. Argentina se posiciona como segundo pa\u00eds en volumen de exportaci\u00f3n de carne kosher a Israel, luego de Uruguay: registr\u00f3 el 23 por ciento de las 10.430 toneladas de carne enfriada y las 80.536 toneladas de carne congelada que import\u00f3 Israel en 2017, lo que a su vez representa aproximadamente 21 mil toneladas exportadas.<\/div>\n<div>\u00a0<\/div>\n<\/div>\n<\/div>\n<div>Fuente:\u00a0https:\/\/www.clarin.com\/rural\/argentina-exporto-carne-kosher-israel-us-50-millones-meses_0_aUUE3bxpD.html<\/div>\n<\/div>\n<div>\u00a0<\/div>\n<p>&nbsp;<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Se posiciona como segundo exportador de este producto, por detr\u00e1s de Uruguay. Tras el acuerdo alcanzado en enero entre ambos los gobiernos de Argentina y de Israel, que se fij\u00f3 el nuevo plazo a partir de marzo de 35 a 85 d\u00edas desde la producci\u00f3n, en solo cinco meses el pa\u00eds export\u00f3 a Israel m\u00e1s de siete 7,5 millones de kilos de carne bovina deshuesada, ya sea refrigerada o congelada, por un total de U$S 49.9 millones, seg\u00fan datos del Instituto de Promoci\u00f3n de la Carne Vacuna Argentina (IPCVA). Esto fue tras un estudio de vida \u00fatil realizado por el INTI, en su centro de Carnes, y de negociaciones que comenzaron en 2016, encabezadas por el Servicio Nacional de Sanidad y Calidad Agroalimentaria (SENASA) y el Ministerio de Relaciones Exteriores, el gobierno de Israel ampli\u00f3 considerablemente los plazos establecidos para la importaci\u00f3n. A su vez, uno de los principales cambios es que se incrementaron notablemente las posibilidades de\u00a0enviar la producci\u00f3n en barco, ya que antes, con el plazo de 35 d\u00edas, era muy dif\u00edcil garantizar la vida \u00fatil si no se transportaba en avi\u00f3n, un medio mucho m\u00e1s costoso. El trabajo que llevaron adelante especialistas del Centro -Carnes surgi\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":10904,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-10895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses | Proagro\" \/>\n<meta property=\"og:description\" content=\"Se posiciona como segundo exportador de este producto, por detr\u00e1s de Uruguay. Tras el acuerdo alcanzado en enero entre ambos los gobiernos de Argentina y de Israel, que se fij\u00f3 el nuevo plazo a partir de marzo de 35 a 85 d\u00edas desde la producci\u00f3n, en solo cinco meses el pa\u00eds export\u00f3 a Israel m\u00e1s de siete 7,5 millones de kilos de carne bovina deshuesada, ya sea refrigerada o congelada, por un total de U$S 49.9 millones, seg\u00fan datos del Instituto de Promoci\u00f3n de la Carne Vacuna Argentina (IPCVA). Esto fue tras un estudio de vida \u00fatil realizado por el INTI, en su centro de Carnes, y de negociaciones que comenzaron en 2016, encabezadas por el Servicio Nacional de Sanidad y Calidad Agroalimentaria (SENASA) y el Ministerio de Relaciones Exteriores, el gobierno de Israel ampli\u00f3 considerablemente los plazos establecidos para la importaci\u00f3n. A su vez, uno de los principales cambios es que se incrementaron notablemente las posibilidades de\u00a0enviar la producci\u00f3n en barco, ya que antes, con el plazo de 35 d\u00edas, era muy dif\u00edcil garantizar la vida \u00fatil si no se transportaba en avi\u00f3n, un medio mucho m\u00e1s costoso. El trabajo que llevaron adelante especialistas del Centro -Carnes surgi\u00f3 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-26T13:50:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-26T15:11:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/26102018-1145x395-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses\",\"datePublished\":\"2018-10-26T13:50:29+00:00\",\"dateModified\":\"2018-10-26T15:11:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/\"},\"wordCount\":421,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/26102018-1145x395-.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/\",\"name\":\"La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/26102018-1145x395-.jpg\",\"datePublished\":\"2018-10-26T13:50:29+00:00\",\"dateModified\":\"2018-10-26T15:11:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/26102018-1145x395-.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/26102018-1145x395-.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/","og_locale":"en_US","og_type":"article","og_title":"La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses | Proagro","og_description":"Se posiciona como segundo exportador de este producto, por detr\u00e1s de Uruguay. Tras el acuerdo alcanzado en enero entre ambos los gobiernos de Argentina y de Israel, que se fij\u00f3 el nuevo plazo a partir de marzo de 35 a 85 d\u00edas desde la producci\u00f3n, en solo cinco meses el pa\u00eds export\u00f3 a Israel m\u00e1s de siete 7,5 millones de kilos de carne bovina deshuesada, ya sea refrigerada o congelada, por un total de U$S 49.9 millones, seg\u00fan datos del Instituto de Promoci\u00f3n de la Carne Vacuna Argentina (IPCVA). Esto fue tras un estudio de vida \u00fatil realizado por el INTI, en su centro de Carnes, y de negociaciones que comenzaron en 2016, encabezadas por el Servicio Nacional de Sanidad y Calidad Agroalimentaria (SENASA) y el Ministerio de Relaciones Exteriores, el gobierno de Israel ampli\u00f3 considerablemente los plazos establecidos para la importaci\u00f3n. A su vez, uno de los principales cambios es que se incrementaron notablemente las posibilidades de\u00a0enviar la producci\u00f3n en barco, ya que antes, con el plazo de 35 d\u00edas, era muy dif\u00edcil garantizar la vida \u00fatil si no se transportaba en avi\u00f3n, un medio mucho m\u00e1s costoso. El trabajo que llevaron adelante especialistas del Centro -Carnes surgi\u00f3 a [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2018-10-26T13:50:29+00:00","article_modified_time":"2018-10-26T15:11:30+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/26102018-1145x395-.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses","datePublished":"2018-10-26T13:50:29+00:00","dateModified":"2018-10-26T15:11:30+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/"},"wordCount":421,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/26102018-1145x395-.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/","url":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/","name":"La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/26102018-1145x395-.jpg","datePublished":"2018-10-26T13:50:29+00:00","dateModified":"2018-10-26T15:11:30+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/26102018-1145x395-.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/10\/26102018-1145x395-.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/la-argentina-exporto-carne-kosher-a-israel-por-us-50-millones-en-5-meses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"La Argentina export\u00f3 carne kosher a Israel por U$S 50 millones en 5 meses"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=10895"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/10904"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=10895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=10895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=10895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}