{"id":10830,"date":"2018-09-20T18:15:51","date_gmt":"2018-09-20T18:15:51","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=10830"},"modified":"2018-09-20T19:44:58","modified_gmt":"2018-09-20T19:44:58","slug":"la-lecheria-en-busca-de-la-intensificacion-para-renovarse","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/","title":{"rendered":"La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<div class=\"single-teaser\">sta semana se desarroll\u00f3 el 15\u00ba Congreso Panamericano de la Leche donde se coincidi\u00f3 las oportunidades que tiene la regi\u00f3n para crecer en producci\u00f3n<\/div>\n<div class=\"single-detail\">\n<p>\u201cLa lecher\u00eda en Latinoam\u00e9rica es un negocio en potencia\u201d. Esta frase resume los tres intensos d\u00edas en el 15\u00ba Congreso Panamericano de la Leche que se realiz\u00f3 en Buenos Aires donde se reunieron los principales eslabones de la cadena lechera de la regi\u00f3n para analizar las oportunidades que tiene el sector de capa ca\u00edda, sobre todo en la Argentina. Daniel Pelegrina, presidente de la Federaci\u00f3n Panamericana de Lecher\u00eda (Fepale), y a su vez, titular de la Sociedad Rural Argentina, fue quien pronunci\u00f3 las oportunidades que se vienen.<\/p>\n<p>El directivo, quien fue reelecto esta semana como titular de Fepale por dos a\u00f1os m\u00e1s, comenz\u00f3 dando datos del sector para poner en contexto. En Am\u00e9rica Latina hay 625 millones de personas (8% de la poblaci\u00f3n mundial) de los cuales 3 millones se dedican a la producci\u00f3n de leche. En total, se producen de forma anual 80.000 millones de litros con sistemas de producci\u00f3n heterog\u00e9neos.<\/p>\n<p>Seg\u00fan Pelegrina, Latinoam\u00e9rica se puede dividir en dos subregiones: por un lado, Argentina, Chile, sur de Brasil, Uruguay y Paraguay, donde predominan una lecher\u00eda especializada con campos m\u00e1s grandes y estructura productiva m\u00e1s homog\u00e9neas, en contraposici\u00f3n a lo que sucede en el resto de Brasil, Regi\u00f3n Andina,Caribe y Centroam\u00e9rica, donde la producci\u00f3n de leche es menor.<\/p>\n<p>\u201cEn 6 pa\u00edses, como Argentina, M\u00e9xico, Chile, Brasil,Panam\u00e1 y Uruguay, la industrializaci\u00f3n es de 80%, pero en el resto de los pa\u00edses empieza a caer este porcentaje\u201d, se\u00f1al\u00f3.<\/p>\n<p>Latinoam\u00e9rica, describi\u00f3, representa el 12% de la producci\u00f3n de leche a nivel mundial. En los \u00faltimos 26 a\u00f1os, la participaci\u00f3n de la regi\u00f3n creci\u00f3 33%. \u201cLa producci\u00f3n de leche aument\u00f3 el doble de lo que sucedi\u00f3 en el mundo\u201d, grafic\u00f3. En este sentido, el comercio de l\u00e1cteos (exportaciones\/importaciones) viene aumentando por a\u00f1o 6,% desde 2001.<\/p>\n<p>Para Pelegrina, por el lado de la demanda es donde surge el triple desaf\u00edo: para \u00e9l hay que fidelizar el consumo local de l\u00e1cteos, integrar los sistemas de abastecimiento con la demanda regional de lacteos y buscar mejorar la productividad para poder ganar mercados globales. \u201cSalvo los casos de Uruguay Nicaragua, la mayor parte de los pa\u00edses de Latinoam\u00e9rica destina m\u00e1s del 80% de lo que produce al mercado local\u201d. Sin embargo, aclar\u00f3, excepto Argentina, Uruguay, Costa Rica y Brasil, los consumidores del resto de los pa\u00edses no ha llegado a su nivel de satisfacci\u00f3n de consumo de l\u00e1cteos.<\/p>\n<p>Ante este contexto, Pelegrina asegur\u00f3 que Latinoam\u00e9rica tiene potencial para seguir creciendo por las tierras disponibles y el agua, la situaci\u00f3n agroecol\u00f3gica, el medio ambiente conservado, las pasturas, la poblaci\u00f3n joven que se dedica al negocio, la baja emisi\u00f3n de CO2, las fuertes inversiones en el sector y la tecnolog\u00eda.<\/p>\n<p>Es as\u00ed como la tecnolog\u00eda jugar\u00e1 un rol fundamental en este objetivo de eficientizar la producci\u00f3n de leche para ser m\u00e1s rentable y poder satisfacer la demanda interna y profundizar las exportaciones. As\u00ed lo hicieron saber en el congreso. Uno de los disertantes que abord\u00f3 esta tem\u00e1tica fue Nicol\u00e1s Lyons, quien se desempe\u00f1a como coordinador de Desarrollo de Lecher\u00eda en Australia.<\/p>\n<p>En esta l\u00ednea, describi\u00f3 que hay muchas tecnolog\u00edas disponibles, espec\u00edficamente de dos tipos: una es la automatizaci\u00f3n que reemplaza a la mano de obra. Y del otro lado est\u00e1n los sensores, en la mayor\u00eda de los casos relacionados a collares de vacas o sensores en l\u00ednea en la sala de orde\u00f1e. \u201cArgentina tiene las mismas posibilidades de incorporar estas tecnolog\u00edas que el resto del mundo. No tiene fronteras. Lo que s\u00ed es un hecho es la poca accesibilidad al cr\u00e9dito para poder adoptarlas\u201d, alert\u00f3.<\/p>\n<p>Ya mirando al futuro, el referente, de nacionalidad argentina, proyect\u00f3 que se vienen las c\u00e1maras para detectar problemas de patas, condici\u00f3n corporal y disponibilidad de pasturas, entre otros. Y a su vez, el uso de los datos que largan los sensores a nivel de predicci\u00f3n, no tanto para decir lo que est\u00e1 pasando en el momento, sino para decir lo que puede pasar o sugerir acciones mirando hacia el futuro.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-trigger pointer\" data-index=\"1\">\n<figure><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/images.clarin.com\/2018\/09\/14\/CSxVVIMDs_720x0__1.jpg\" alt=\"El Inta Rafaela comenz\u00f3 con el proyecto del robot en el tambo en 2015. Mensualmente muestra los beneficios de la tecnolog\u00eda.\" data-observer-function=\"loadLazyImg\" data-big=\"https:\/\/images.clarin.com\/2018\/09\/14\/CSxVVIMDs_720x0__1.jpg\" data-small=\"https:\/\/images.clarin.com\/2018\/09\/14\/CSxVVIMDs_720x0__1.jpg\" \/><i class=\"fa fa-circle fa-stack-2x icon-background1\"><\/i><i class=\"fa fa-circle-o fa-stack-2x icon-background2\"><\/i><i class=\"fa fa-arrows-alt fa-stack-1x\"><\/i><\/figure>\n<p>El Inta Rafaela comenz\u00f3 con el proyecto del robot en el tambo en 2015. Mensualmente muestra los beneficios de la tecnolog\u00eda.<\/p>\n<\/div>\n<\/div>\n<p>Haciendo foco en una de ellas, un panel estuvo dedicado al orde\u00f1e robotizado, una tecnolog\u00eda que crece de forma paulatina tanto en el mundo como en la Argentina.Esta innovaci\u00f3n se caracteriza por realizar las pr\u00e1cticas de rutina, orde\u00f1ar las vacas en forma autom\u00e1tica, medir la producci\u00f3n, detectar problemas de mastitis y suministra alimentos, entre otras funciones. Aqu\u00ed, se expusieron dos ejemplos concretos. Uno fue de un productor de Brasil y el otro, el caso del INTA Rafaela.<\/p>\n<p>Armando Rabbers es un tambero de Castro, en el Estado de Paran\u00e1, Brasil, que produce leche desde hace 6 a\u00f1os con la particularidad que invirti\u00f3 desde el comienzo en el robot. \u201cLa mano de obra disponible en ese momento era escasa porque la econom\u00eda ven\u00eda creciendo. Y adem\u00e1s, hab\u00eda visitado diferentes tambos a nivel mundial que hicieron que invierta en esta tecnolog\u00eda\u201d, desarroll\u00f3 el tambero.<\/p>\n<p>En su campo, predomina el sistema free stall con 144 vacas en orde\u00f1e. Utiliza cabinas para que coman los animales porque reduce los costos, que seg\u00fan el productor, representan el 50% del total de los mismos. Y adem\u00e1s, resalt\u00f3 la conversi\u00f3n: 1 kilo de grano en 3,20 a 3,40 kilos de leche. \u201cLa amortizaci\u00f3n del equipo de robot es de 8 a 10 a\u00f1os\u201d, indic\u00f3 el productor.<\/p>\n<p>El otro ejemplo es del tambo robotizado en el Inta Rafaela, inaugurado en 2015. Miguel Taverna, referente lechero de la instituci\u00f3n, destac\u00f3 que todos los meses hacen un informe sobre los indicadores de esta tecnolog\u00eda en la cual cuentan con 75 vacas. Para resaltar, en julio, en promedio cada vaca produjo 36 litros de leche.<\/p>\n<p>El mismo Lyons agreg\u00f3 que en Australia se instal\u00f3 el primer tambo robotizado en 2001 y ahora hay 39 productores con robots. Hay 174 unidades (var\u00edan de 2 a 16 unidades por tambo).<\/p>\n<p>Por \u00faltimo, otro de los oradores del 15\u00ba Congreso Panamericano de la Leche fue Sergio Yani Garc\u00eda, tambi\u00e9n de nacionalidad argentina y que tiene un largo curr\u00edculum en Australia. Actualmente es profesor de ciencias l\u00e1cteas en la Facultad de Ciencias de la Vida y del Medio Ambiente de la Universidad de Sydney, entre otros cargos. El especialista hizo foco en los factores que van a condicionar la existencia de cada tambero en los pr\u00f3ximos 10 a\u00f1os. \u201cAlgunos ser\u00e1n determinantes\u201d, advirti\u00f3.<\/p>\n<p>Seg\u00fan el referente, las dos principales a corto plazo vienen del lado del ambiente y del bienestar animal. Y por el otro lado, mirando a largo plazo, tiene que ver con 4 ejes. En primer lugar, se asocia a la rentabilidad. \u201cEsto est\u00e1 asociado a eficiencia t\u00e9cnica: cu\u00e1nto alcanza un productor hoy en t\u00e9rminos de productividad con respecto a lo que podr\u00eda alcanzar\u201d. Asimismo, otra clave ser\u00e1 la flexibilidad y elasticidad que tengan los tamberos para los sistemas. \u201cLos de base pastoril, por ejemplo, pueden en los a\u00f1os dif\u00edciles pasar a sistemas confinados. y a su vez, volver a dieta pastoril con algo de granos si el a\u00f1o viene bien. Esto va a dar m\u00e1s chances de estar en los grupos de los ganadores\u201d, resumi\u00f3.<\/p>\n<p>A continuaci\u00f3n, se\u00f1al\u00f3 que la autosuficiencia es el tercer factor ya que para Yani Garc\u00eda, \u201ces f\u00e1cil comprar comida pero en general como oportunidad hay mucho m\u00e1s m\u00e1rgenes si se hace la comida en casa\u201d. Y por \u00faltimo, la automatizaci\u00f3n y tecnificaci\u00f3n. \u201cLas cosas cambian tan r\u00e1pidamente que se viene un gran cambio en el uso de datos y c\u00f3mo se aplican eso datos en acciones concretas. No sirve tener datos, tiene que tener sistemas que le optimicen el manejo para jerarquizar la toma de decisiones\u201d.<\/p>\n<p>Por otro lado, hizo referencia a los atributos de cada sistema de producci\u00f3n. Para \u00e9l, los productores est\u00e1n yendo hacia la intensificaci\u00f3n, que tiene muchas ventajas: m\u00e1s leche por vaca y mejor confort del animal. A su vez, se logra m\u00e1s consistencia en la producci\u00f3n y ayuda a una mejor planificaci\u00f3n de los insumos.<\/p>\n<p>Pero aclar\u00f3 que no compiten ambos sistemas entre s\u00ed. \u201cNo hay uno mejor que otro, sino que hay buenos o malos manejadores\u201d, apunt\u00f3. \u201cEl problema es que cuando se cambian a sistemas intensivos lo hacen pensando que no pueden sacar m\u00e1s leche a base pastoril porque ya llegaron al techo. Pero los techos est\u00e1n mucho m\u00e1s arriba en los dos sistemas de producci\u00f3n\u201d, cerr\u00f3.<\/p>\n<p>Fuente:\u00a0http:\/\/www.agromeat.com\/249038\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse<\/p>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>sta semana se desarroll\u00f3 el 15\u00ba Congreso Panamericano de la Leche donde se coincidi\u00f3 las oportunidades que tiene la regi\u00f3n para crecer en producci\u00f3n \u201cLa lecher\u00eda en Latinoam\u00e9rica es un negocio en potencia\u201d. Esta frase resume los tres intensos d\u00edas en el 15\u00ba Congreso Panamericano de la Leche que se realiz\u00f3 en Buenos Aires donde se reunieron los principales eslabones de la cadena lechera de la regi\u00f3n para analizar las oportunidades que tiene el sector de capa ca\u00edda, sobre todo en la Argentina. Daniel Pelegrina, presidente de la Federaci\u00f3n Panamericana de Lecher\u00eda (Fepale), y a su vez, titular de la Sociedad Rural Argentina, fue quien pronunci\u00f3 las oportunidades que se vienen. El directivo, quien fue reelecto esta semana como titular de Fepale por dos a\u00f1os m\u00e1s, comenz\u00f3 dando datos del sector para poner en contexto. En Am\u00e9rica Latina hay 625 millones de personas (8% de la poblaci\u00f3n mundial) de los cuales 3 millones se dedican a la producci\u00f3n de leche. En total, se producen de forma anual 80.000 millones de litros con sistemas de producci\u00f3n heterog\u00e9neos. Seg\u00fan Pelegrina, Latinoam\u00e9rica se puede dividir en dos subregiones: por un lado, Argentina, Chile, sur de Brasil, Uruguay y Paraguay, donde predominan una lecher\u00eda [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":10845,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-10830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse | Proagro\" \/>\n<meta property=\"og:description\" content=\"sta semana se desarroll\u00f3 el 15\u00ba Congreso Panamericano de la Leche donde se coincidi\u00f3 las oportunidades que tiene la regi\u00f3n para crecer en producci\u00f3n \u201cLa lecher\u00eda en Latinoam\u00e9rica es un negocio en potencia\u201d. Esta frase resume los tres intensos d\u00edas en el 15\u00ba Congreso Panamericano de la Leche que se realiz\u00f3 en Buenos Aires donde se reunieron los principales eslabones de la cadena lechera de la regi\u00f3n para analizar las oportunidades que tiene el sector de capa ca\u00edda, sobre todo en la Argentina. Daniel Pelegrina, presidente de la Federaci\u00f3n Panamericana de Lecher\u00eda (Fepale), y a su vez, titular de la Sociedad Rural Argentina, fue quien pronunci\u00f3 las oportunidades que se vienen. El directivo, quien fue reelecto esta semana como titular de Fepale por dos a\u00f1os m\u00e1s, comenz\u00f3 dando datos del sector para poner en contexto. En Am\u00e9rica Latina hay 625 millones de personas (8% de la poblaci\u00f3n mundial) de los cuales 3 millones se dedican a la producci\u00f3n de leche. En total, se producen de forma anual 80.000 millones de litros con sistemas de producci\u00f3n heterog\u00e9neos. Seg\u00fan Pelegrina, Latinoam\u00e9rica se puede dividir en dos subregiones: por un lado, Argentina, Chile, sur de Brasil, Uruguay y Paraguay, donde predominan una lecher\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-20T18:15:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-20T19:44:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/09\/20092018-1145x395.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse\",\"datePublished\":\"2018-09-20T18:15:51+00:00\",\"dateModified\":\"2018-09-20T19:44:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/\"},\"wordCount\":1528,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/20092018-1145x395.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/\",\"name\":\"La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/20092018-1145x395.jpg\",\"datePublished\":\"2018-09-20T18:15:51+00:00\",\"dateModified\":\"2018-09-20T19:44:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/20092018-1145x395.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/20092018-1145x395.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/","og_locale":"en_US","og_type":"article","og_title":"La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse | Proagro","og_description":"sta semana se desarroll\u00f3 el 15\u00ba Congreso Panamericano de la Leche donde se coincidi\u00f3 las oportunidades que tiene la regi\u00f3n para crecer en producci\u00f3n \u201cLa lecher\u00eda en Latinoam\u00e9rica es un negocio en potencia\u201d. Esta frase resume los tres intensos d\u00edas en el 15\u00ba Congreso Panamericano de la Leche que se realiz\u00f3 en Buenos Aires donde se reunieron los principales eslabones de la cadena lechera de la regi\u00f3n para analizar las oportunidades que tiene el sector de capa ca\u00edda, sobre todo en la Argentina. Daniel Pelegrina, presidente de la Federaci\u00f3n Panamericana de Lecher\u00eda (Fepale), y a su vez, titular de la Sociedad Rural Argentina, fue quien pronunci\u00f3 las oportunidades que se vienen. El directivo, quien fue reelecto esta semana como titular de Fepale por dos a\u00f1os m\u00e1s, comenz\u00f3 dando datos del sector para poner en contexto. En Am\u00e9rica Latina hay 625 millones de personas (8% de la poblaci\u00f3n mundial) de los cuales 3 millones se dedican a la producci\u00f3n de leche. En total, se producen de forma anual 80.000 millones de litros con sistemas de producci\u00f3n heterog\u00e9neos. Seg\u00fan Pelegrina, Latinoam\u00e9rica se puede dividir en dos subregiones: por un lado, Argentina, Chile, sur de Brasil, Uruguay y Paraguay, donde predominan una lecher\u00eda [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2018-09-20T18:15:51+00:00","article_modified_time":"2018-09-20T19:44:58+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/09\/20092018-1145x395.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse","datePublished":"2018-09-20T18:15:51+00:00","dateModified":"2018-09-20T19:44:58+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/"},"wordCount":1528,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/09\/20092018-1145x395.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/","url":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/","name":"La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/09\/20092018-1145x395.jpg","datePublished":"2018-09-20T18:15:51+00:00","dateModified":"2018-09-20T19:44:58+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/09\/20092018-1145x395.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/09\/20092018-1145x395.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/la-lecheria-en-busca-de-la-intensificacion-para-renovarse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"La lecher\u00eda, en busca de la intensificaci\u00f3n para renovarse"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=10830"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10830\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/10845"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=10830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=10830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=10830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}