{"id":10724,"date":"2018-07-27T14:26:51","date_gmt":"2018-07-27T14:26:51","guid":{"rendered":"https:\/\/proagrolab.com.ar\/?p=10724"},"modified":"2018-07-27T17:16:07","modified_gmt":"2018-07-27T17:16:07","slug":"un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon","status":"publish","type":"post","link":"https:\/\/proagrolab.com.ar\/en\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/","title":{"rendered":"Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><\/p>\n<p>24-07<\/p>\n<p class=\"capital\">El Frigor\u00edfico del Valle Inferior, Fridevi SA, concret\u00f3 hoy la primera exportaci\u00f3n de carne vacuna de la Argentina a Jap\u00f3n. Fue con una partida de 200 kilos de prueba de cortes especiales -bifes y lomos de alta calidad- por avi\u00f3n. En los pr\u00f3ximos d\u00edas, en tanto, saldr\u00e1 un contenedor con 10 toneladas que incluye 13 cortes.<\/p>\n<p><a href=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/2724939w1033.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10725 size-full\" src=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/2724939w1033.jpg\" alt=\"\" width=\"1033\" height=\"688\" srcset=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/2724939w1033.jpg 1033w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/2724939w1033-600x400.jpg 600w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/2724939w1033-300x200.jpg 300w, https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/2724939w1033-768x512.jpg 768w\" sizes=\"auto, (max-width: 1033px) 100vw, 1033px\" \/><\/a><\/p>\n<p>Con la exportaci\u00f3n, por primera vez en la historia, la carne argentina, en este caso de la Patagonia, podr\u00e1 ser degustada en Jap\u00f3n. Vale recordar que recientemente\u00a0<a class=\"link\" href=\"https:\/\/www.lanacion.com.ar\/2148560-se-oficializo-la-apertura-de-japon-para-la-carne-ovina-y-bovina-de-la-patagonia\">se habilit\u00f3 la apertura simult\u00e1nea<\/a>\u00a0de carne bovina y ovina desde la Patagonia y, rec\u00edprocamente, de la carne bovina japonesa. En 2017 Jap\u00f3n import\u00f3 desde diversos or\u00edgenes carne bovina deshuesada por US$3100 millones.<\/p>\n<p>&#8220;En mayo (cuando se firm\u00f3 el convenio) prometimos que este mes comenzar\u00eda el env\u00edo de carne argentina a Jap\u00f3n y cumplimos con nuestra palabra&#8221;, se\u00f1al\u00f3 Luis Miguel Etchevehere, ministro de Agroindustria de la Naci\u00f3n.<\/p>\n<p>Desde la sede del frigor\u00edfico en Viedma, R\u00edo Negro, el gerente general Sergio Seisdedos indic\u00f3: &#8220;Luego de evaluados los env\u00edos por los clientes japoneses, estimamos poder terminar de dise\u00f1ar el negocio global que deseamos desarrollar con los socios comerciales m\u00e1s convenientes. Esto es diagramar un negocio permanente durante todo el a\u00f1o y con un set de cortes tal que haga posible el mismo&#8221;.<\/p>\n<p>El frigor\u00edfico rionegrino produce carne bovina para el mercado interno desde 1983 y est\u00e1 calificado como el proveedor m\u00e1s importante de carne vacuna de toda la Patagonia, abasteciendo a firmas como La An\u00f3nima, Coto y Cencosud con la faena de m\u00e1s de 6000 cabezas de ganado por mes.<\/p>\n<p>En di\u00e1logo con\u00a0<b>LA NACION<\/b>, Seisdedos detall\u00f3 que desde febrero pasado\u00a0<a class=\"link\" href=\"https:\/\/www.lanacion.com.ar\/2141961-japon-proximo-destino-la-carne-de-la-patagonia-apunta-a-ganar-en-un-mercado-exigente\">recibieron visitas de dos traders multinacionales<\/a>\u00a0de Jap\u00f3n. &#8220;Se les ha explicado en estos meses nuestras realidades, y, en especial, el escaso stock existente en la Patagonia, las reales posibilidades en vol\u00famenes y el hecho de que Fridevi viene desarrollando desde hace cuatro a\u00f1os un grupo de productores que engorda novillos para exportaci\u00f3n y se les pagan beneficios adicionales a los valores de la hacienda de exportaci\u00f3n al norte del r\u00edo Colorado&#8221;.<\/p>\n<p>Luego a\u00f1adi\u00f3: &#8220;A trav\u00e9s de la Cooperativa de Patagones y Viedma se suscribieron acuerdos de abastecimiento que permitieron que estos a\u00f1os, luego de 2013 -cierre de la barrera del r\u00edo Colorado-, pudi\u00e9ramos igualmente seguir exportando a Europa entre 200\/250 toneladas de cuota Hilton&#8221;.<\/p>\n<p>Desde la empresa apuntan a consolidar el acuerdo con los productores regionales y poder as\u00ed armar un esquema de provisi\u00f3n de mayor volumen de hacienda, todo de las razas Hereford, Angus o cruzas de ambas.<\/p>\n<p>La operaci\u00f3n comercial con Jap\u00f3n genera expectativas, aunque son tomadas con moderaci\u00f3n. &#8220;En la empresa, si bien tomamos con mucha prudencia este tema, ya que todav\u00eda no podemos hablar de negocios consolidados y queda mucho por hacer, es claro que consideramos esto como una posibilidad hist\u00f3rica para poder mejorar nuestra matriz de negocios exportaci\u00f3n\/consumo&#8221;, dijo el ejecutivo.<\/p>\n<p>&#8220;Para nuestros dos accionistas, la Asociaci\u00f3n de Cooperativas Argentinas y la Cooperativa de Patagones y Viedma, es un verdadero reconocimiento a a\u00f1os de inversiones en los momentos no tan buenos para la exportaci\u00f3n la oportunidad que hoy tiene Fridevi de estar en condiciones de ser habilitado para exportar a Jap\u00f3n y ser la primera planta en hacerlo desde Argentina en toda su historia, dada su ubicaci\u00f3n en la Patagonia&#8221;, precis\u00f3.<\/p>\n<p>La firma invirti\u00f3 m\u00e1s de US$6,5 millones entre 2003 y 2007 para remodelar toda la planta y obtener la habilitaci\u00f3n para exportar a la Uni\u00f3n Europea.<\/p>\n<p>Fuente:\u00a0https:\/\/www.lanacion.com.ar\/2151899-un-frigorifico-de-rio-negro-hara-la-primera-exportacion-de-carne-vacuna-a-japon<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>24-07 El Frigor\u00edfico del Valle Inferior, Fridevi SA, concret\u00f3 hoy la primera exportaci\u00f3n de carne vacuna de la Argentina a Jap\u00f3n. Fue con una partida de 200 kilos de prueba de cortes especiales -bifes y lomos de alta calidad- por avi\u00f3n. En los pr\u00f3ximos d\u00edas, en tanto, saldr\u00e1 un contenedor con 10 toneladas que incluye 13 cortes. Con la exportaci\u00f3n, por primera vez en la historia, la carne argentina, en este caso de la Patagonia, podr\u00e1 ser degustada en Jap\u00f3n. Vale recordar que recientemente\u00a0se habilit\u00f3 la apertura simult\u00e1nea\u00a0de carne bovina y ovina desde la Patagonia y, rec\u00edprocamente, de la carne bovina japonesa. En 2017 Jap\u00f3n import\u00f3 desde diversos or\u00edgenes carne bovina deshuesada por US$3100 millones. &#8220;En mayo (cuando se firm\u00f3 el convenio) prometimos que este mes comenzar\u00eda el env\u00edo de carne argentina a Jap\u00f3n y cumplimos con nuestra palabra&#8221;, se\u00f1al\u00f3 Luis Miguel Etchevehere, ministro de Agroindustria de la Naci\u00f3n. Desde la sede del frigor\u00edfico en Viedma, R\u00edo Negro, el gerente general Sergio Seisdedos indic\u00f3: &#8220;Luego de evaluados los env\u00edos por los clientes japoneses, estimamos poder terminar de dise\u00f1ar el negocio global que deseamos desarrollar con los socios comerciales m\u00e1s convenientes. Esto es diagramar un negocio permanente durante todo el a\u00f1o [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":10733,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-10724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infoganadero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n | Proagro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proagrolab.com.ar\/en\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n | Proagro\" \/>\n<meta property=\"og:description\" content=\"24-07 El Frigor\u00edfico del Valle Inferior, Fridevi SA, concret\u00f3 hoy la primera exportaci\u00f3n de carne vacuna de la Argentina a Jap\u00f3n. Fue con una partida de 200 kilos de prueba de cortes especiales -bifes y lomos de alta calidad- por avi\u00f3n. En los pr\u00f3ximos d\u00edas, en tanto, saldr\u00e1 un contenedor con 10 toneladas que incluye 13 cortes. Con la exportaci\u00f3n, por primera vez en la historia, la carne argentina, en este caso de la Patagonia, podr\u00e1 ser degustada en Jap\u00f3n. Vale recordar que recientemente\u00a0se habilit\u00f3 la apertura simult\u00e1nea\u00a0de carne bovina y ovina desde la Patagonia y, rec\u00edprocamente, de la carne bovina japonesa. En 2017 Jap\u00f3n import\u00f3 desde diversos or\u00edgenes carne bovina deshuesada por US$3100 millones. &#8220;En mayo (cuando se firm\u00f3 el convenio) prometimos que este mes comenzar\u00eda el env\u00edo de carne argentina a Jap\u00f3n y cumplimos con nuestra palabra&#8221;, se\u00f1al\u00f3 Luis Miguel Etchevehere, ministro de Agroindustria de la Naci\u00f3n. Desde la sede del frigor\u00edfico en Viedma, R\u00edo Negro, el gerente general Sergio Seisdedos indic\u00f3: &#8220;Luego de evaluados los env\u00edos por los clientes japoneses, estimamos poder terminar de dise\u00f1ar el negocio global que deseamos desarrollar con los socios comerciales m\u00e1s convenientes. Esto es diagramar un negocio permanente durante todo el a\u00f1o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/\" \/>\n<meta property=\"og:site_name\" content=\"Proagro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/proagrolab\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-27T14:26:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-27T17:16:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-27072018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1145\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin Proagro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin Proagro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/\"},\"author\":{\"name\":\"Admin Proagro\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\"},\"headline\":\"Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n\",\"datePublished\":\"2018-07-27T14:26:51+00:00\",\"dateModified\":\"2018-07-27T17:16:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/\"},\"wordCount\":648,\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1145x395-27072018.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/\",\"name\":\"Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n | Proagro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1145x395-27072018.jpg\",\"datePublished\":\"2018-07-27T14:26:51+00:00\",\"dateModified\":\"2018-07-27T17:16:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1145x395-27072018.jpg\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1145x395-27072018.jpg\",\"width\":1145,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/proagrolab.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"name\":\"Proagro Laboratorio Veterinario\",\"description\":\"Veterinary laboratory\",\"publisher\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proagrolab.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#organization\",\"name\":\"Proagro\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/proagrolab.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-retina.png\",\"width\":478,\"height\":120,\"caption\":\"Proagro\"},\"image\":{\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/proagrolab\",\"https:\\\/\\\/www.instagram.com\\\/proagrolab\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/laboratorio-proagro-s-a\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proagrolab.com.ar\\\/#\\\/schema\\\/person\\\/3e30f2f0f9eadcc02d50ed3664562373\",\"name\":\"Admin Proagro\",\"sameAs\":[\"http:\\\/\\\/www.sistemas7g.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n | Proagro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proagrolab.com.ar\/en\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/","og_locale":"en_US","og_type":"article","og_title":"Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n | Proagro","og_description":"24-07 El Frigor\u00edfico del Valle Inferior, Fridevi SA, concret\u00f3 hoy la primera exportaci\u00f3n de carne vacuna de la Argentina a Jap\u00f3n. Fue con una partida de 200 kilos de prueba de cortes especiales -bifes y lomos de alta calidad- por avi\u00f3n. En los pr\u00f3ximos d\u00edas, en tanto, saldr\u00e1 un contenedor con 10 toneladas que incluye 13 cortes. Con la exportaci\u00f3n, por primera vez en la historia, la carne argentina, en este caso de la Patagonia, podr\u00e1 ser degustada en Jap\u00f3n. Vale recordar que recientemente\u00a0se habilit\u00f3 la apertura simult\u00e1nea\u00a0de carne bovina y ovina desde la Patagonia y, rec\u00edprocamente, de la carne bovina japonesa. En 2017 Jap\u00f3n import\u00f3 desde diversos or\u00edgenes carne bovina deshuesada por US$3100 millones. &#8220;En mayo (cuando se firm\u00f3 el convenio) prometimos que este mes comenzar\u00eda el env\u00edo de carne argentina a Jap\u00f3n y cumplimos con nuestra palabra&#8221;, se\u00f1al\u00f3 Luis Miguel Etchevehere, ministro de Agroindustria de la Naci\u00f3n. Desde la sede del frigor\u00edfico en Viedma, R\u00edo Negro, el gerente general Sergio Seisdedos indic\u00f3: &#8220;Luego de evaluados los env\u00edos por los clientes japoneses, estimamos poder terminar de dise\u00f1ar el negocio global que deseamos desarrollar con los socios comerciales m\u00e1s convenientes. Esto es diagramar un negocio permanente durante todo el a\u00f1o [&hellip;]","og_url":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/","og_site_name":"Proagro","article_publisher":"http:\/\/www.facebook.com\/proagrolab","article_published_time":"2018-07-27T14:26:51+00:00","article_modified_time":"2018-07-27T17:16:07+00:00","og_image":[{"width":1145,"height":395,"url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-27072018.jpg","type":"image\/jpeg"}],"author":"Admin Proagro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin Proagro","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/#article","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/"},"author":{"name":"Admin Proagro","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373"},"headline":"Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n","datePublished":"2018-07-27T14:26:51+00:00","dateModified":"2018-07-27T17:16:07+00:00","mainEntityOfPage":{"@id":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/"},"wordCount":648,"publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"image":{"@id":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-27072018.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/","url":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/","name":"Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n | Proagro","isPartOf":{"@id":"https:\/\/proagrolab.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/#primaryimage"},"image":{"@id":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/#primaryimage"},"thumbnailUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-27072018.jpg","datePublished":"2018-07-27T14:26:51+00:00","dateModified":"2018-07-27T17:16:07+00:00","breadcrumb":{"@id":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/#primaryimage","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-27072018.jpg","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2018\/07\/1145x395-27072018.jpg","width":1145,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/proagrolab.com.ar\/un-frigorifico-de-rio-negro-realizo-la-primera-exportacion-de-carne-vacuna-a-japon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proagrolab.com.ar\/"},{"@type":"ListItem","position":2,"name":"Un frigor\u00edfico de R\u00edo Negro realiz\u00f3 la primera exportaci\u00f3n de carne vacuna a Jap\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/proagrolab.com.ar\/#website","url":"https:\/\/proagrolab.com.ar\/","name":"Proagro Laboratorio Veterinario","description":"Veterinary laboratory","publisher":{"@id":"https:\/\/proagrolab.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proagrolab.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/proagrolab.com.ar\/#organization","name":"Proagro","url":"https:\/\/proagrolab.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","contentUrl":"https:\/\/proagrolab.com.ar\/wp-content\/uploads\/2020\/04\/logo-retina.png","width":478,"height":120,"caption":"Proagro"},"image":{"@id":"https:\/\/proagrolab.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/proagrolab","https:\/\/www.instagram.com\/proagrolab\/","https:\/\/www.linkedin.com\/company\/laboratorio-proagro-s-a\/"]},{"@type":"Person","@id":"https:\/\/proagrolab.com.ar\/#\/schema\/person\/3e30f2f0f9eadcc02d50ed3664562373","name":"Admin Proagro","sameAs":["http:\/\/www.sistemas7g.com"]}]}},"_links":{"self":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/comments?post=10724"}],"version-history":[{"count":0,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/posts\/10724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media\/10733"}],"wp:attachment":[{"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/media?parent=10724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/categories?post=10724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proagrolab.com.ar\/en\/wp-json\/wp\/v2\/tags?post=10724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}